{"id":849286,"date":"2021-09-28T06:49:00","date_gmt":"2021-09-28T06:49:00","guid":{"rendered":"https:\/\/www.capgemini.com\/no-no\/?page_id=849286&#038;preview_id=849286"},"modified":"2026-04-16T09:46:17","modified_gmt":"2026-04-16T09:46:17","slug":"retail-and-commercial-banking","status":"publish","type":"page","link":"https:\/\/www.capgemini.com\/no-no\/industries\/banking-and-capital-markets\/retail-and-commercial-banking\/","title":{"rendered":"Retail and commercial banking"},"content":{"rendered":"\n<div class=\"wp-block-cg-blocks-hero-picture-card undefined  heroPictureCard\"><div class=\"heroPictureCardBgs\"><picture><source srcset=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2021\/12\/Capgemini_Industries_Capital-Markets_Retail-banking-e1638447185800.jpg?w=2880&amp;quality=70 1x, https:\/\/www.capgemini.com\/wp-content\/uploads\/2021\/12\/Capgemini_Industries_Capital-Markets_Retail-banking-e1638447185800.jpg?w=2880&amp;quality=70 2x\" media=\"(min-width: 1500px)\"\/><source srcset=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2021\/12\/Capgemini_Industries_Capital-Markets_Retail-banking-e1638447185800.jpg?w=1440&amp;quality=70 1x, https:\/\/www.capgemini.com\/wp-content\/uploads\/2021\/12\/Capgemini_Industries_Capital-Markets_Retail-banking-e1638447185800.jpg?w=2880&amp;quality=70 2x\" media=\"(min-width: 992px)\"\/><source srcset=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2021\/12\/Capgemini_Industries_Capital-Markets_Retail-banking-e1638447185800.jpg?w=1024&amp;quality=70 1x, https:\/\/www.capgemini.com\/wp-content\/uploads\/2021\/12\/Capgemini_Industries_Capital-Markets_Retail-banking-e1638447185800.jpg?w=1024&amp;quality=70 2x\" media=\"(min-width: 768px)\"\/><source srcset=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2021\/12\/Capgemini_Industries_Capital-Markets_Retail-banking-e1638447185800.jpg?w=768&amp;quality=70 1x, https:\/\/www.capgemini.com\/wp-content\/uploads\/2021\/12\/Capgemini_Industries_Capital-Markets_Retail-banking-e1638447185800.jpg?w=768&amp;quality=70 2x\" media=\"(min-width: 0)\"\/><img decoding=\"async\" src=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2021\/12\/Capgemini_Industries_Capital-Markets_Retail-banking-e1638447185800.jpg\" class=\"desktopImage\" alt=\"\" style=\"object-fit:cover;object-position:50% 50%\" loading=\"eager\"\/><\/picture><picture><source srcset=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2021\/12\/Capgemini_Industries_Capital-Markets_Retail-banking-e1638447185800.jpg?w=2880&amp;quality=70 1x, https:\/\/www.capgemini.com\/wp-content\/uploads\/2021\/12\/Capgemini_Industries_Capital-Markets_Retail-banking-e1638447185800.jpg?w=2880&amp;quality=70 2x\" media=\"(min-width: 1500px)\"\/><source srcset=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2021\/12\/Capgemini_Industries_Capital-Markets_Retail-banking-e1638447185800.jpg?w=1440&amp;quality=70 1x, https:\/\/www.capgemini.com\/wp-content\/uploads\/2021\/12\/Capgemini_Industries_Capital-Markets_Retail-banking-e1638447185800.jpg?w=2880&amp;quality=70 2x\" media=\"(min-width: 992px)\"\/><source srcset=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2021\/12\/Capgemini_Industries_Capital-Markets_Retail-banking-e1638447185800.jpg?w=1024&amp;quality=70 1x, https:\/\/www.capgemini.com\/wp-content\/uploads\/2021\/12\/Capgemini_Industries_Capital-Markets_Retail-banking-e1638447185800.jpg?w=1024&amp;quality=70 2x\" media=\"(min-width: 768px)\"\/><source srcset=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2021\/12\/Capgemini_Industries_Capital-Markets_Retail-banking-e1638447185800.jpg?w=768&amp;quality=70 1x, https:\/\/www.capgemini.com\/wp-content\/uploads\/2021\/12\/Capgemini_Industries_Capital-Markets_Retail-banking-e1638447185800.jpg?w=768&amp;quality=70 2x\" media=\"(min-width: 0)\"\/><img decoding=\"async\" src=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2021\/12\/Capgemini_Industries_Capital-Markets_Retail-banking-e1638447185800.jpg\" class=\"mobileImage\" alt=\"\" style=\"object-fit:cover;object-position:50% 50%\" loading=\"eager\"\/><\/picture><\/div><div class=\"heroPictureCardHeaderShape\"><\/div><div class=\"container\"><div class=\"row\"><div class=\"col-md-8 col-lg-6\"><div class=\"heroPictureCardBox\"><div class=\"heroPictureCardBoxTitle\"><h1 data-maxlength=\"144\">Retail and commercial banking<\/h1><\/div><\/div><\/div><\/div><\/div><div class=\"small-device\"><div class=\"brandLogoWrapper\"> <\/div><\/div><\/div>\n\n\n\n<section class=\"wp-block-cg-blocks-intro-para undefined section section--intro\"><div class=\"intro-para\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-md-2\"><nav class=\"article-social\"><ul class=\"social-nav\"><li class=\"ip-order-fb\"><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https:\/\/www.capgemini.com\/no-no\/industries\/banking-and-capital-markets\/retail-and-commercial-banking\/\" target=\"_blank\" rel=\"noopener noreferrer\" title=\"opens in a new window\"><i aria-hidden=\"true\" class=\"icon-fb\"><\/i><span class=\"sr-only\">Facebook<\/span><\/a><\/li><li class=\"ip-order-li\"><a href=\"https:\/\/www.linkedin.com\/sharing\/share-offsite\/?url=https:\/\/www.capgemini.com\/no-no\/industries\/banking-and-capital-markets\/retail-and-commercial-banking\/\" target=\"_blank\" rel=\"noopener noreferrer\" title=\"opens in a new window\"><i aria-hidden=\"true\" class=\"icon-li\"><\/i><span class=\"sr-only\">Linkedin<\/span><\/a><\/li><\/ul><\/nav><\/div><div class=\"col-12 col-md-8\"><h2 class=\"intro-para-title\">Traditional industry boundaries are blurring as banks become virtually invisible. Across the retail and business segments, banks need to enrich their customer value and create agile business models. We can accompany you in becoming a truly global bank. <\/h2><p class=\"intro-para-content\">We are helping banks deliver sustainable, personalized customer experiences, adopt platform-based models, unlock the value of open ecosystems, and harvest data-driven insights.<br><br>For your commercial customers, you\u2019ll create quicker, cost-effective and value-added solutions. For your retail customers, you\u2019ll drive hyper-personalized, humanized banking experiences. And for your bank? You\u2019ll maximize your potential, and achieve a greater return on investment.<\/p><\/div><\/div><\/div><\/div><\/section>\n\n\n\n\t\t\t\t<section\n\t\t\t\t\tclass=\"section section--lifeatcap-learning section--event-slider-careerInvent \">\n\n\t\t\t\t\t<div class=\"container\">\n\t\t\t\t\t\t<div class='career-invent-header'>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"slider slider-fader 813e1958-137f-48f3-9de4-48cf8f3c41d8\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"slider-nav-wrapper smallDevice\">\n\t\t\t\t\t\t\t\t\t<div class=\"row\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"col-md-12 text-center\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"slider-nav\">\n\t\t\t\t\t\t\t\t\t\t\t\t<button class=\"slider-prev inactive\"\n\t\t\t\t\t\t\t\t\t\t\t\t\taria-label=\"slider prev\"><\/button>\n\t\t\t\t\t\t\t\t\t\t\t\t<ul class=\"slider-paginator\"><\/ul>\n\t\t\t\t\t\t\t\t\t\t\t\t<button class=\"slider-next \"\n\t\t\t\t\t\t\t\t\t\t\t\t\taria-label=\"slider next\"><\/button>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div\n\t\t\t\t\t\t\tclass=\"slider-list \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div\n\t\t\t\t\t\t\t\t\t\tclass=\"slide active \">\n\t\t\t\t\t\t\t\t\t\t<div\n\t\t\t\t\t\t\t\t\t\t\tclass=\"slide-bg-wrapper wp-block-cg-blocks-career-invent is-style-sapphire2\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"bgImagesection\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"bgColor\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"container slide-info-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"col-md-6 col-sm-12 box-inner \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"bgColor\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"content-title \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"explore-header\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tdata-maxlength=\"68\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\ttitle=\"World Retail Banking Report 2025\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tWorld Retail Banking Report 2025\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"box-title \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h4 data-maxlength=\"144\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\ttitle=\"Learn how banks are adapting to digital trends and evolving customer needs in the latest World Retail Banking Report\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tstyle=\"white-space: pre-wrap;\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tLearn how banks are adapting to digital trends and evolving customer needs in the latest World Retail Banking Report\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div >\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"btnDiv\"> <a class=\"more2\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tdata-maxlength=\"24\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\taria-label=\"Read more about World Retail Banking Report 2025\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\ttitle=\"Opens in new window\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\ttabindex=\"0\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"https:\/\/www.capgemini.com\/no-no\/insights\/research-library\/world-retail-banking-report\/\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\ttarget=\"\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tRead more\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a> <\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-md-6 col-sm-12 text-right box-img-wrapper escaper escaper-right\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<picture>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<source\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tsrcset=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2025\/03\/Website-hero-banner-2880x1800-1.jpg?w=1200&amp;quality=90 1x, https:\/\/www.capgemini.com\/wp-content\/uploads\/2025\/03\/Website-hero-banner-2880x1800-1.jpg?w=1200&amp;quality=90 2x\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tmedia=\"(min-width: 1500px)\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<source\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tsrcset=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2025\/03\/Website-hero-banner-2880x1800-1.jpg?w=600&amp;quality=90 1x, https:\/\/www.capgemini.com\/wp-content\/uploads\/2025\/03\/Website-hero-banner-2880x1800-1.jpg?w=1200&amp;quality=90 2x\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tmedia=\"(min-width: 992px)\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<source\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tsrcset=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2025\/03\/Website-hero-banner-2880x1800-1.jpg?w=400&amp;quality=90 1x, https:\/\/www.capgemini.com\/wp-content\/uploads\/2025\/03\/Website-hero-banner-2880x1800-1.jpg?w=800&amp;quality=90 2x\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tmedia=\"(min-width: 768px)\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<source\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tsrcset=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2025\/03\/Website-hero-banner-2880x1800-1.jpg?w=400&amp;quality=90 1x, https:\/\/www.capgemini.com\/wp-content\/uploads\/2025\/03\/Website-hero-banner-2880x1800-1.jpg?w=800&amp;quality=90 2x\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tmedia=\"(min-width: 0)\" \/>\n\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" class=\"box-img\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tsrc=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2025\/03\/Website-hero-banner-2880x1800-1.jpg\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tstyle=\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\tobject-position: 52% 40%; object-fit: cover;\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\" alt=\"\" \/>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/picture>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<!-- <img decoding=\"async\" class=\"box-img\" src=\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\"\n\t\t\t\t\t\t\t\t\t\t\tstyle=\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\" alt=\"\"\n\t\t\t\t\t\t\t\t\t\t\/> -->\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div\n\t\t\t\t\t\t\t\t\t\t\t\tclass=\"\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"slide-reveal\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div\n\t\t\t\t\t\t\t\t\t\tclass=\"slide active \">\n\t\t\t\t\t\t\t\t\t\t<div\n\t\t\t\t\t\t\t\t\t\t\tclass=\"slide-bg-wrapper wp-block-cg-blocks-career-invent is-style-sapphire2\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"bgImagesection\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"bgColor\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"container slide-info-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"col-md-6 col-sm-12 box-inner \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"bgColor\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"content-title \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"explore-header\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tdata-maxlength=\"68\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\ttitle=\"Elevating card experiences to deepen customer loyalty\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tElevating card experiences to deepen customer loyalty\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"box-title \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h4 data-maxlength=\"144\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\ttitle=\"Banks can enhance customer trust by refining card services, creating seamless experiences, and fostering long-term relationships\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tstyle=\"white-space: pre-wrap;\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tBanks can enhance customer trust by refining card services, creating seamless experiences, and fostering long-term relationships\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div >\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"btnDiv\"> <a class=\"more2\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tdata-maxlength=\"24\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\taria-label=\"Read more about Elevating card experiences to deepen customer loyalty\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\ttitle=\"Opens in new window\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\ttabindex=\"-1\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"https:\/\/fintechmagazine.com\/articles\/capgemini-banks-face-loyalty-crisis-over-card-services\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\ttarget=\"_blank\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tRead more\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a> <\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-md-6 col-sm-12 text-right box-img-wrapper escaper escaper-right\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<picture>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<source\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tsrcset=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2025\/03\/Card-services.jpeg?w=1200&amp;quality=90 1x, https:\/\/www.capgemini.com\/wp-content\/uploads\/2025\/03\/Card-services.jpeg?w=1200&amp;quality=90 2x\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tmedia=\"(min-width: 1500px)\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<source\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tsrcset=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2025\/03\/Card-services.jpeg?w=600&amp;quality=90 1x, https:\/\/www.capgemini.com\/wp-content\/uploads\/2025\/03\/Card-services.jpeg?w=1200&amp;quality=90 2x\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tmedia=\"(min-width: 992px)\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<source\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tsrcset=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2025\/03\/Card-services.jpeg?w=400&amp;quality=90 1x, https:\/\/www.capgemini.com\/wp-content\/uploads\/2025\/03\/Card-services.jpeg?w=800&amp;quality=90 2x\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tmedia=\"(min-width: 768px)\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<source\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tsrcset=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2025\/03\/Card-services.jpeg?w=400&amp;quality=90 1x, https:\/\/www.capgemini.com\/wp-content\/uploads\/2025\/03\/Card-services.jpeg?w=800&amp;quality=90 2x\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tmedia=\"(min-width: 0)\" \/>\n\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" class=\"box-img\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tsrc=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2025\/03\/Card-services.jpeg\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tstyle=\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\tobject-position: 34% 46%; object-fit: cover;\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\" alt=\"\" \/>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/picture>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<!-- <img decoding=\"async\" class=\"box-img\" src=\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\"\n\t\t\t\t\t\t\t\t\t\t\tstyle=\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\" alt=\"\"\n\t\t\t\t\t\t\t\t\t\t\/> -->\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div\n\t\t\t\t\t\t\t\t\t\t\t\tclass=\"\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"slide-reveal\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div\n\t\t\t\t\t\t\t\t\t\tclass=\"slide active \">\n\t\t\t\t\t\t\t\t\t\t<div\n\t\t\t\t\t\t\t\t\t\t\tclass=\"slide-bg-wrapper wp-block-cg-blocks-career-invent is-style-sapphire2\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"bgImagesection\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"bgColor\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"container slide-info-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"col-md-6 col-sm-12 box-inner \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"bgColor\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"content-title \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"explore-header\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tdata-maxlength=\"68\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\ttitle=\"Transforming credit card experiences for lasting trust\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tTransforming credit card experiences for lasting trust\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"box-title \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h4 data-maxlength=\"144\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\ttitle=\"By reducing friction and enhancing service quality, banks can strengthen customer relationships and drive long-term loyalty\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tstyle=\"white-space: pre-wrap;\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tBy reducing friction and enhancing service quality, banks can strengthen customer relationships and drive long-term loyalty\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div >\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"btnDiv\"> <a class=\"more2\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tdata-maxlength=\"24\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\taria-label=\"Read more about Transforming credit card experiences for lasting trust\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\ttitle=\"Opens in new window\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\ttabindex=\"-1\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"https:\/\/www.customerexperiencedive.com\/news\/bank-credit-card-experiences-fall-short-risking-loyalty\/742509\/\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\ttarget=\"_blank\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tRead more\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a> <\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-md-6 col-sm-12 text-right box-img-wrapper escaper escaper-right\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<picture>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<source\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tsrcset=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2025\/03\/bank-customer-1.jpeg?w=1200&amp;quality=90 1x, https:\/\/www.capgemini.com\/wp-content\/uploads\/2025\/03\/bank-customer-1.jpeg?w=1200&amp;quality=90 2x\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tmedia=\"(min-width: 1500px)\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<source\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tsrcset=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2025\/03\/bank-customer-1.jpeg?w=600&amp;quality=90 1x, https:\/\/www.capgemini.com\/wp-content\/uploads\/2025\/03\/bank-customer-1.jpeg?w=1200&amp;quality=90 2x\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tmedia=\"(min-width: 992px)\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<source\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tsrcset=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2025\/03\/bank-customer-1.jpeg?w=400&amp;quality=90 1x, https:\/\/www.capgemini.com\/wp-content\/uploads\/2025\/03\/bank-customer-1.jpeg?w=800&amp;quality=90 2x\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tmedia=\"(min-width: 768px)\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<source\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tsrcset=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2025\/03\/bank-customer-1.jpeg?w=400&amp;quality=90 1x, https:\/\/www.capgemini.com\/wp-content\/uploads\/2025\/03\/bank-customer-1.jpeg?w=800&amp;quality=90 2x\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tmedia=\"(min-width: 0)\" \/>\n\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" class=\"box-img\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tsrc=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2025\/03\/bank-customer-1.jpeg\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tstyle=\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\tobject-position: 49% 44%; object-fit: cover;\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\" alt=\"\" \/>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/picture>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<!-- <img decoding=\"async\" class=\"box-img\" src=\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\"\n\t\t\t\t\t\t\t\t\t\t\tstyle=\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\" alt=\"\"\n\t\t\t\t\t\t\t\t\t\t\/> -->\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div\n\t\t\t\t\t\t\t\t\t\t\t\tclass=\"\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"slide-reveal\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div\n\t\t\t\t\t\t\t\t\t\tclass=\"slide active \">\n\t\t\t\t\t\t\t\t\t\t<div\n\t\t\t\t\t\t\t\t\t\t\tclass=\"slide-bg-wrapper wp-block-cg-blocks-career-invent is-style-sapphire2\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"bgImagesection\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"bgColor\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"container slide-info-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"col-md-6 col-sm-12 box-inner \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"bgColor\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"content-title \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"explore-header\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tdata-maxlength=\"68\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\ttitle=\"Retail banking top trends 2025\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tRetail banking top trends 2025\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"box-title \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h4 data-maxlength=\"144\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\ttitle=\"Discover 2025's top retail banking trends to stay ahead in a dynamic market and drive customer-centric innovation\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tstyle=\"white-space: pre-wrap;\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tDiscover 2025&#8217;s top retail banking trends to stay ahead in a dynamic market and drive customer-centric innovation\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div >\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"btnDiv\"> <a class=\"more2\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tdata-maxlength=\"24\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\taria-label=\"Read more about Retail banking top trends 2025\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\ttitle=\"Opens in new window\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\ttabindex=\"-1\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"https:\/\/www.capgemini.com\/no-no\/insights\/research-library\/top-retail-banking-trends-2025\/\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\ttarget=\"\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tRead more\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a> <\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-md-6 col-sm-12 text-right box-img-wrapper escaper escaper-right\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<picture>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<source\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tsrcset=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2024\/12\/Retail-Banking-Landing-page-banner_2880x1800_07.jpg?w=1200&amp;quality=90 1x, https:\/\/www.capgemini.com\/wp-content\/uploads\/2024\/12\/Retail-Banking-Landing-page-banner_2880x1800_07.jpg?w=1200&amp;quality=90 2x\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tmedia=\"(min-width: 1500px)\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<source\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tsrcset=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2024\/12\/Retail-Banking-Landing-page-banner_2880x1800_07.jpg?w=600&amp;quality=90 1x, https:\/\/www.capgemini.com\/wp-content\/uploads\/2024\/12\/Retail-Banking-Landing-page-banner_2880x1800_07.jpg?w=1200&amp;quality=90 2x\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tmedia=\"(min-width: 992px)\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<source\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tsrcset=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2024\/12\/Retail-Banking-Landing-page-banner_2880x1800_07.jpg?w=400&amp;quality=90 1x, https:\/\/www.capgemini.com\/wp-content\/uploads\/2024\/12\/Retail-Banking-Landing-page-banner_2880x1800_07.jpg?w=800&amp;quality=90 2x\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tmedia=\"(min-width: 768px)\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<source\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tsrcset=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2024\/12\/Retail-Banking-Landing-page-banner_2880x1800_07.jpg?w=400&amp;quality=90 1x, https:\/\/www.capgemini.com\/wp-content\/uploads\/2024\/12\/Retail-Banking-Landing-page-banner_2880x1800_07.jpg?w=800&amp;quality=90 2x\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tmedia=\"(min-width: 0)\" \/>\n\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" class=\"box-img\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tsrc=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2024\/12\/Retail-Banking-Landing-page-banner_2880x1800_07.jpg\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tstyle=\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\tobject-position: 33% 55%; object-fit: cover;\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\" alt=\"\" \/>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/picture>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<!-- <img decoding=\"async\" class=\"box-img\" src=\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\"\n\t\t\t\t\t\t\t\t\t\t\tstyle=\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\" alt=\"\"\n\t\t\t\t\t\t\t\t\t\t\/> -->\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div\n\t\t\t\t\t\t\t\t\t\t\t\tclass=\"\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"slide-reveal\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"slider-nav-wrapper largeDevice\">\n\t\t\t\t\t\t\t\t\t<div class=\"row\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"col-md-12 text-center\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"slider-nav\">\n\t\t\t\t\t\t\t\t\t\t\t\t<button class=\"slider-prev inactive\"\n\t\t\t\t\t\t\t\t\t\t\t\t\taria-label=\"slider prev\"><\/button>\n\t\t\t\t\t\t\t\t\t\t\t\t<ul class=\"slider-paginator\"><\/ul>\n\t\t\t\t\t\t\t\t\t\t\t\t<button class=\"slider-next\"\n\t\t\t\t\t\t\t\t\t\t\t\t\taria-label=\"slider next\"><\/button>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t<\/section>\n\n\t\t\t\t\n\n\n<section class=\"wp-block-cg-blocks-how-we-do-it section section--howwedoit block-howwedoit\"><div class=\"container\"><div><div class=\"row\"><div class=\"content-title col-12 col-md-8\"><h2 data-maxlength=\"72\" class=\"expandable-heading-tag\">What we do<\/h2><\/div><\/div><div class=\"row\"><div class=\"col-12 col-md-8\"><p><\/p><\/div><\/div><\/div><div class=\"row\"><div class=\"col-12 col-md-8\"><div class=\"section-content\">\n<div class=\"wp-block-cg-blocks-card-howwedoit expanders\"><div class=\"box card-regulated-agreements card-howwedoit\"><div class=\"expander-box filter-box tag-active \"><div class=\"expander-title\" tabindex=\"0\" role=\"button\" aria-expanded=\"false\"><h3 class=\"expander-heading-title\">Connected marketing for financial services<\/h3><\/div><div class=\"expander-subtitle\"><p class=\"small-description\">Customer-First for banking<\/p><\/div><div class=\"expander-content\"><p>Banking customers have spoken. They expect accessible, personalized services tailored to their individual needs and lifestyles. Ready to unlock the power of customer-centricity?<\/p><div class=\"bg-color video-align-right\"><div class=\"container\"><div class=\"row video-align-left\"><div class=\"col-md-12\"><div class=\"video-align-left row box box--4 box--mini\"><div class=\"col-md-3\"><\/div><div class=\"col-md-8 box-img-wrapper\"><div class=\"video-box\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"content-more\"><a class=\"more2\" aria-label=\"Read more link\" href=\"https:\/\/www.capgemini.com\/no-no\/solutions\/driving-customer-centricity-in-banking-and-capital-markets\/\" target=\"_blank\" title=\"Opens in a new window\" rel=\"noopener noreferrer\">Read more<\/a><\/div><\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-cg-blocks-card-howwedoit expanders\"><div class=\"box card-regulated-agreements card-howwedoit\"><div class=\"expander-box filter-box tag-active \"><div class=\"expander-title\" tabindex=\"0\" role=\"button\" aria-expanded=\"false\"><h3 class=\"expander-heading-title\">Contact center transformation<\/h3><\/div><div class=\"expander-subtitle\"><p class=\"small-description\">Create a sustainable, next generation contact center experience.<\/p><\/div><div class=\"expander-content\"><p>Heightened customer expectations and a renewed focus on cost efficiency is pushing organizations to look differently at roles and operations of contact centers.<br><br>We use leading edge technologies built with cloud, omnichannel, self-service, and advanced AI\/cognitive capabilities to help you drive impactful customer and agent experiences.<\/p><div class=\"bg-color video-align-right\"><div class=\"container\"><div class=\"row video-align-left\"><div class=\"col-md-12\"><div class=\"video-align-left row box box--4 box--mini\"><div class=\"col-md-3\"><\/div><div class=\"col-md-8 box-img-wrapper\"><div class=\"video-box\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"content-more\"><a class=\"more2\" aria-label=\"Read more link\" href=\"https:\/\/www.capgemini.com\/no-no\/solutions\/contact-center-transformation\/\" target=\"\" title=\"\" rel=\"noopener noreferrer\">Read more<\/a><\/div><\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-cg-blocks-card-howwedoit expanders\"><div class=\"box card-regulated-agreements card-howwedoit\"><div class=\"expander-box filter-box tag-active \"><div class=\"expander-title\" tabindex=\"0\" role=\"button\" aria-expanded=\"false\"><h3 class=\"expander-heading-title\">Digital core modernization<\/h3><\/div><div class=\"expander-subtitle\"><p class=\"small-description\">Fintechs, neobanks, and challenger banks are making it difficult for traditional banks to keep up with rising customer expectations for hyper-personalized and seamless services.<\/p><\/div><div class=\"expander-content\"><p>Our banking solutions provide the tightly integrated, omnichannel experiences that customers expect, and the actionable business information that banks need.<br><br>We offer modern design and implementation solutions that optimize the customer experience, reduce operating costs and enhance service quality, while managing risk and regulatory compliance more effectively.<br><br>As a result, banks can reduce total cost of ownership, boost operational efficiency and flexibility, and put in place an IT platform that will be sustainable into the future.<\/p><div class=\"bg-color video-align-right\"><div class=\"container\"><div class=\"row video-align-left\"><div class=\"col-md-12\"><div class=\"video-align-left row box box--4 box--mini\"><div class=\"col-md-3\"><\/div><div class=\"col-md-8 box-img-wrapper\"><div class=\"video-box\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"content-more\"><a class=\"more2\" aria-label=\"Core Banking link\" href=\"https:\/\/www.capgemini.com\/no-no\/solutions\/core-banking\/\" target=\"\" title=\"\" rel=\"noopener noreferrer\">Core Banking<\/a><\/div><\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-cg-blocks-card-howwedoit expanders\"><div class=\"box card-regulated-agreements card-howwedoit\"><div class=\"expander-box filter-box tag-active \"><div class=\"expander-title\" tabindex=\"0\" role=\"button\" aria-expanded=\"false\"><h3 class=\"expander-heading-title\">Digital working capital finance platform<\/h3><\/div><div class=\"expander-subtitle\"><p class=\"small-description\">Digitalize your complete trade finance value chain \u2013 including traditional trade (loans, letters of credit, collections and guarantees) and structured trade (receivable and payable financing).<\/p><\/div><div class=\"expander-content\"><p>With our trade-as-a-service, powered by Finastra and delivered on Microsoft Azure, you can innovate at speed, lower the total cost of ownership, and minimize risk.<br><br><strong>Capgemini\u2019s end-to-end working capital finance services can help you:<\/strong><br>\u2022 Engage your corporate customers with personalized experiences<br>\u2022 Eliminate, automate, and optimize business processes<br>\u2022 Seamlessly transition from manual processes to intelligent zero-touch processing<br>\u2022 Harness data-driven insights with machine learning and artificial intelligence<br>\u2022 Reduce TCO by utilizing managed services.<\/p><div class=\"bg-color video-align-right\"><div class=\"container\"><div class=\"row video-align-left\"><div class=\"col-md-12\"><div class=\"video-align-left row box box--4 box--mini\"><div class=\"col-md-3\"><\/div><div class=\"col-md-8 box-img-wrapper\"><div class=\"video-box\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"content-more\"><a class=\"more2\" aria-label=\"Visit Finastra link\" href=\"http:\/\/www.finastra.com\/ \" target=\"_blank\" title=\"Opens in a new window\" rel=\"noopener noreferrer\">Visit Finastra<\/a><\/div><\/div><\/div><\/div><\/div>\n<\/div><\/div><\/div><\/div><\/section>\n\n\n\n\t\t\t\t<section\n\t\t\t\t\tclass=\"section section--lifeatcap-learning section--event-slider-careerInvent \">\n\n\t\t\t\t\t<div class=\"container\">\n\t\t\t\t\t\t<div class='career-invent-header'>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"row\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"heading col-12 col-md-8\">\n\t\t\t\t\t\t\t\t\t\t\t<h2>Discover our solutions<\/h2>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"slider slider-fader 5b5b1382-6aa2-44e8-82c6-361e45e50ec8\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"slider-nav-wrapper smallDevice\">\n\t\t\t\t\t\t\t\t\t<div class=\"row\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"col-md-12 text-center\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"slider-nav\">\n\t\t\t\t\t\t\t\t\t\t\t\t<button class=\"slider-prev inactive\"\n\t\t\t\t\t\t\t\t\t\t\t\t\taria-label=\"slider prev\"><\/button>\n\t\t\t\t\t\t\t\t\t\t\t\t<ul class=\"slider-paginator\"><\/ul>\n\t\t\t\t\t\t\t\t\t\t\t\t<button class=\"slider-next \"\n\t\t\t\t\t\t\t\t\t\t\t\t\taria-label=\"slider next\"><\/button>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div\n\t\t\t\t\t\t\tclass=\"slider-list \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div\n\t\t\t\t\t\t\t\t\t\tclass=\"slide active \">\n\t\t\t\t\t\t\t\t\t\t<div\n\t\t\t\t\t\t\t\t\t\t\tclass=\"slide-bg-wrapper wp-block-cg-blocks-career-invent is-style-sapphire2\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"bgImagesection\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"bgColor\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"container slide-info-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"col-md-6 col-sm-12 box-inner \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"bgColor\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"content-title \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"explore-header\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tdata-maxlength=\"68\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\ttitle=\"Customer first, banking and capital markets\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tCustomer first, banking and capital markets\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"box-title \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h4 data-maxlength=\"144\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\ttitle=\"Banking customers have spoken. They expect accessible, personalized services tailored to their individual needs and lifestyles. Ready to unlock the power of customer-centricity?\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tstyle=\"white-space: pre-wrap;\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tBanking customers have spoken. They expect accessible, personalized services tailored to their individual needs and lifestyles. Ready to unlock the power of customer-centricity?<br>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div >\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"btnDiv\"> <a class=\"more2\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tdata-maxlength=\"24\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\taria-label=\"Read more about Customer first, banking and capital markets\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\ttitle=\"Opens in new window\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\ttabindex=\"0\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"https:\/\/www.capgemini.com\/no-no\/solutions\/driving-customer-centricity-in-banking-and-capital-markets\/\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\ttarget=\"\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tRead more\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a> <\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-md-6 col-sm-12 text-right box-img-wrapper escaper escaper-right\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<picture>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<source\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tsrcset=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2023\/04\/The-metrics-that-matter.jpg?w=1200&amp;quality=90 1x, https:\/\/www.capgemini.com\/wp-content\/uploads\/2023\/04\/The-metrics-that-matter.jpg?w=1200&amp;quality=90 2x\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tmedia=\"(min-width: 1500px)\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<source\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tsrcset=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2023\/04\/The-metrics-that-matter.jpg?w=600&amp;quality=90 1x, https:\/\/www.capgemini.com\/wp-content\/uploads\/2023\/04\/The-metrics-that-matter.jpg?w=1200&amp;quality=90 2x\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tmedia=\"(min-width: 992px)\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<source\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tsrcset=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2023\/04\/The-metrics-that-matter.jpg?w=400&amp;quality=90 1x, https:\/\/www.capgemini.com\/wp-content\/uploads\/2023\/04\/The-metrics-that-matter.jpg?w=800&amp;quality=90 2x\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tmedia=\"(min-width: 768px)\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<source\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tsrcset=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2023\/04\/The-metrics-that-matter.jpg?w=400&amp;quality=90 1x, https:\/\/www.capgemini.com\/wp-content\/uploads\/2023\/04\/The-metrics-that-matter.jpg?w=800&amp;quality=90 2x\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tmedia=\"(min-width: 0)\" \/>\n\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" class=\"box-img\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tsrc=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2023\/04\/The-metrics-that-matter.jpg\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tstyle=\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\" alt=\"\" \/>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/picture>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<!-- <img decoding=\"async\" class=\"box-img\" src=\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\"\n\t\t\t\t\t\t\t\t\t\t\tstyle=\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\" alt=\"\"\n\t\t\t\t\t\t\t\t\t\t\/> -->\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div\n\t\t\t\t\t\t\t\t\t\t\t\tclass=\"\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"slide-reveal\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div\n\t\t\t\t\t\t\t\t\t\tclass=\"slide active \">\n\t\t\t\t\t\t\t\t\t\t<div\n\t\t\t\t\t\t\t\t\t\t\tclass=\"slide-bg-wrapper wp-block-cg-blocks-career-invent is-style-sapphire2\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"bgImagesection\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"bgColor\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"container slide-info-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"col-md-6 col-sm-12 box-inner \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"bgColor\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"content-title \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"explore-header\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tdata-maxlength=\"68\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\ttitle=\"Contact center transformation\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tContact center transformation\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"box-title \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h4 data-maxlength=\"144\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\ttitle=\"Learn how a people-focused approach combined with cloud, omnichannel, self-service, and advanced AI\/cognitive capabilities delivers value.\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tstyle=\"white-space: pre-wrap;\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tLearn how a people-focused approach combined with cloud, omnichannel, self-service, and advanced AI\/cognitive capabilities delivers value.\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div >\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"btnDiv\"> <a class=\"more2\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tdata-maxlength=\"24\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\taria-label=\"Read more about Contact center transformation\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\ttitle=\"Opens in new window\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\ttabindex=\"-1\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"https:\/\/www.capgemini.com\/no-no\/solutions\/contact-center-transformation\/\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\ttarget=\"\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tRead more\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a> <\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-md-6 col-sm-12 text-right box-img-wrapper escaper escaper-right\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<picture>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<source\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tsrcset=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2022\/10\/CustomerServiceContactCenter-1200x630-1.jpg?w=1200&amp;quality=90 1x, https:\/\/www.capgemini.com\/wp-content\/uploads\/2022\/10\/CustomerServiceContactCenter-1200x630-1.jpg?w=1200&amp;quality=90 2x\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tmedia=\"(min-width: 1500px)\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<source\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tsrcset=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2022\/10\/CustomerServiceContactCenter-1200x630-1.jpg?w=600&amp;quality=90 1x, https:\/\/www.capgemini.com\/wp-content\/uploads\/2022\/10\/CustomerServiceContactCenter-1200x630-1.jpg?w=1200&amp;quality=90 2x\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tmedia=\"(min-width: 992px)\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<source\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tsrcset=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2022\/10\/CustomerServiceContactCenter-1200x630-1.jpg?w=400&amp;quality=90 1x, https:\/\/www.capgemini.com\/wp-content\/uploads\/2022\/10\/CustomerServiceContactCenter-1200x630-1.jpg?w=800&amp;quality=90 2x\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tmedia=\"(min-width: 768px)\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<source\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tsrcset=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2022\/10\/CustomerServiceContactCenter-1200x630-1.jpg?w=400&amp;quality=90 1x, https:\/\/www.capgemini.com\/wp-content\/uploads\/2022\/10\/CustomerServiceContactCenter-1200x630-1.jpg?w=800&amp;quality=90 2x\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tmedia=\"(min-width: 0)\" \/>\n\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" class=\"box-img\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tsrc=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2022\/10\/CustomerServiceContactCenter-1200x630-1.jpg\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tstyle=\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\tobject-position: 52% 38%; object-fit: cover;\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\" alt=\"\" \/>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/picture>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<!-- <img decoding=\"async\" class=\"box-img\" src=\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\"\n\t\t\t\t\t\t\t\t\t\t\tstyle=\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\" alt=\"\"\n\t\t\t\t\t\t\t\t\t\t\/> -->\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div\n\t\t\t\t\t\t\t\t\t\t\t\tclass=\"\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"slide-reveal\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div\n\t\t\t\t\t\t\t\t\t\tclass=\"slide active \">\n\t\t\t\t\t\t\t\t\t\t<div\n\t\t\t\t\t\t\t\t\t\t\tclass=\"slide-bg-wrapper wp-block-cg-blocks-career-invent is-style-sapphire2\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"bgImagesection\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"bgColor\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"container slide-info-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"col-md-6 col-sm-12 box-inner \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"bgColor\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"content-title \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"explore-header\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tdata-maxlength=\"68\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\ttitle=\"Marketing transformation for financial services\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tMarketing transformation for financial services\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"box-title \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h4 data-maxlength=\"144\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\ttitle=\"Yesterday\u2019s marketing strategies have stopped working. How can you empower your marketing teams to deliver contextual and personalized experiences that your customers expect ?\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tstyle=\"white-space: pre-wrap;\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tYesterday\u2019s marketing strategies have stopped working. How can you empower your marketing teams to deliver contextual and personalized experiences that your customers expect ?\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div >\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"btnDiv\"> <a class=\"more2\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tdata-maxlength=\"24\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\taria-label=\"Read more about Marketing transformation for financial services\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\ttitle=\"Opens in new window\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\ttabindex=\"-1\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"\/solutions\/marketing-transformation\/\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\ttarget=\"_blank\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tRead more\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a> <\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-md-6 col-sm-12 text-right box-img-wrapper escaper escaper-right\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<picture>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<source\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tsrcset=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2023\/11\/Marketing-Transformation.jpg?w=1200&amp;quality=90 1x, https:\/\/www.capgemini.com\/wp-content\/uploads\/2023\/11\/Marketing-Transformation.jpg?w=1200&amp;quality=90 2x\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tmedia=\"(min-width: 1500px)\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<source\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tsrcset=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2023\/11\/Marketing-Transformation.jpg?w=600&amp;quality=90 1x, https:\/\/www.capgemini.com\/wp-content\/uploads\/2023\/11\/Marketing-Transformation.jpg?w=1200&amp;quality=90 2x\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tmedia=\"(min-width: 992px)\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<source\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tsrcset=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2023\/11\/Marketing-Transformation.jpg?w=400&amp;quality=90 1x, https:\/\/www.capgemini.com\/wp-content\/uploads\/2023\/11\/Marketing-Transformation.jpg?w=800&amp;quality=90 2x\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tmedia=\"(min-width: 768px)\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<source\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tsrcset=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2023\/11\/Marketing-Transformation.jpg?w=400&amp;quality=90 1x, https:\/\/www.capgemini.com\/wp-content\/uploads\/2023\/11\/Marketing-Transformation.jpg?w=800&amp;quality=90 2x\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tmedia=\"(min-width: 0)\" \/>\n\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" class=\"box-img\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tsrc=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2023\/11\/Marketing-Transformation.jpg\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tstyle=\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\" alt=\"\" \/>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/picture>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<!-- <img decoding=\"async\" class=\"box-img\" src=\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\"\n\t\t\t\t\t\t\t\t\t\t\tstyle=\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\" alt=\"\"\n\t\t\t\t\t\t\t\t\t\t\/> -->\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div\n\t\t\t\t\t\t\t\t\t\t\t\tclass=\"\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"slide-reveal\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div\n\t\t\t\t\t\t\t\t\t\tclass=\"slide active \">\n\t\t\t\t\t\t\t\t\t\t<div\n\t\t\t\t\t\t\t\t\t\t\tclass=\"slide-bg-wrapper wp-block-cg-blocks-career-invent is-style-sapphire2\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"bgImagesection\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"bgColor\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"container slide-info-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"col-md-6 col-sm-12 box-inner \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"bgColor\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"content-title \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"explore-header\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tdata-maxlength=\"68\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\ttitle=\"Core banking\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tCore banking\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"box-title \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h4 data-maxlength=\"144\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\ttitle=\"Transform the core for your digital future with our core banking modernization solutions.\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tstyle=\"white-space: pre-wrap;\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tTransform the core for your digital future with our core banking modernization solutions.\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div >\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"btnDiv\"> <a class=\"more2\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tdata-maxlength=\"24\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\taria-label=\"Read more about Core banking\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\ttitle=\"Opens in new window\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\ttabindex=\"-1\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"https:\/\/www.capgemini.com\/no-no\/solutions\/core-banking\/\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\ttarget=\"\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tRead more\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a> <\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-md-6 col-sm-12 text-right box-img-wrapper escaper escaper-right\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<picture>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<source\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tsrcset=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2021\/08\/Capgemini_Industries-Banking.jpg?w=1200&amp;quality=90 1x, https:\/\/www.capgemini.com\/wp-content\/uploads\/2021\/08\/Capgemini_Industries-Banking.jpg?w=1200&amp;quality=90 2x\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tmedia=\"(min-width: 1500px)\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<source\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tsrcset=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2021\/08\/Capgemini_Industries-Banking.jpg?w=600&amp;quality=90 1x, https:\/\/www.capgemini.com\/wp-content\/uploads\/2021\/08\/Capgemini_Industries-Banking.jpg?w=1200&amp;quality=90 2x\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tmedia=\"(min-width: 992px)\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<source\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tsrcset=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2021\/08\/Capgemini_Industries-Banking.jpg?w=400&amp;quality=90 1x, https:\/\/www.capgemini.com\/wp-content\/uploads\/2021\/08\/Capgemini_Industries-Banking.jpg?w=800&amp;quality=90 2x\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tmedia=\"(min-width: 768px)\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<source\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tsrcset=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2021\/08\/Capgemini_Industries-Banking.jpg?w=400&amp;quality=90 1x, https:\/\/www.capgemini.com\/wp-content\/uploads\/2021\/08\/Capgemini_Industries-Banking.jpg?w=800&amp;quality=90 2x\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tmedia=\"(min-width: 0)\" \/>\n\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" class=\"box-img\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tsrc=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2021\/08\/Capgemini_Industries-Banking.jpg\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tstyle=\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\tobject-position: 38% 85%; object-fit: cover;\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\" alt=\"\" \/>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/picture>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<!-- <img decoding=\"async\" class=\"box-img\" src=\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\"\n\t\t\t\t\t\t\t\t\t\t\tstyle=\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\" alt=\"\"\n\t\t\t\t\t\t\t\t\t\t\/> -->\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div\n\t\t\t\t\t\t\t\t\t\t\t\tclass=\"\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"slide-reveal\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"slider-nav-wrapper largeDevice\">\n\t\t\t\t\t\t\t\t\t<div class=\"row\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"col-md-12 text-center\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"slider-nav\">\n\t\t\t\t\t\t\t\t\t\t\t\t<button class=\"slider-prev inactive\"\n\t\t\t\t\t\t\t\t\t\t\t\t\taria-label=\"slider prev\"><\/button>\n\t\t\t\t\t\t\t\t\t\t\t\t<ul class=\"slider-paginator\"><\/ul>\n\t\t\t\t\t\t\t\t\t\t\t\t<button class=\"slider-next\"\n\t\t\t\t\t\t\t\t\t\t\t\t\taria-label=\"slider next\"><\/button>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t<\/section>\n\n\t\t\t\t\n\n<section class=\"latest-insights layout-even layout-even-all-purple-cards \"><div class=\"container\"><div class=\"insight-title\"><h2 class=\"latest-insight-title\">Research and insights<\/h2><\/div><div class=\"layout-two-card cards-normal\">\n                                <div class=\"row align-items-center\"><div class=\"card-image-wrapper\">\n                                <div class=\"card-image\" data-image-url=\"https:\/\/www.capgemini.com\/no-no\/insights\/research-library\/human-led-ai-powered-cx-transformation\/\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<picture>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<source srcset=\"https:\/\/www.capgemini.com\/no-no\/wp-content\/uploads\/sites\/23\/2026\/04\/Human-led-AI-powered_CRI-2880X1800.jpg?w=800&#038;quality=70 1x, https:\/\/www.capgemini.com\/no-no\/wp-content\/uploads\/sites\/23\/2026\/04\/Human-led-AI-powered_CRI-2880X1800.jpg?w=800&#038;quality=70 2x\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tmedia=\"(min-width: 1500px)\"\/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<source srcset=\"https:\/\/www.capgemini.com\/no-no\/wp-content\/uploads\/sites\/23\/2026\/04\/Human-led-AI-powered_CRI-2880X1800.jpg?w=800&#038;quality=70 1x, https:\/\/www.capgemini.com\/no-no\/wp-content\/uploads\/sites\/23\/2026\/04\/Human-led-AI-powered_CRI-2880X1800.jpg?w=800&#038;quality=70 2x\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tmedia=\"(min-width: 992px)\"\/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<source srcset=\"https:\/\/www.capgemini.com\/no-no\/wp-content\/uploads\/sites\/23\/2026\/04\/Human-led-AI-powered_CRI-2880X1800.jpg?w=800&#038;quality=70 1x, https:\/\/www.capgemini.com\/no-no\/wp-content\/uploads\/sites\/23\/2026\/04\/Human-led-AI-powered_CRI-2880X1800.jpg?w=800&#038;quality=70 2x\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tmedia=\"(min-width: 768px)\"\/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<source srcset=\"https:\/\/www.capgemini.com\/no-no\/wp-content\/uploads\/sites\/23\/2026\/04\/Human-led-AI-powered_CRI-2880X1800.jpg?w=350&#038;quality=70 1x, https:\/\/www.capgemini.com\/no-no\/wp-content\/uploads\/sites\/23\/2026\/04\/Human-led-AI-powered_CRI-2880X1800.jpg?w=700&#038;quality=70 2x\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tmedia=\"(min-width: 0)\"\/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.capgemini.com\/no-no\/wp-content\/uploads\/sites\/23\/2026\/04\/Human-led-AI-powered_CRI-2880X1800.jpg\" alt=\"\" style=\"object-position: 50% 50%; object-fit: cover;\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/picture>\n                                <\/div>\n                            <\/div><div class=\"col-12 col-lg-4 d-md-none d-lg-block\"><\/div><div class=\"col-12 col-md-6 col-lg-4\">\n                           <a href=\"https:\/\/www.capgemini.com\/no-no\/insights\/research-library\/human-led-ai-powered-cx-transformation\/\" aria-label=\"Reimagining customer experience: Human-led, AI-powered\" class=\"card-link-holder\">\n                            <div class=\"insight-card insight-card-center\">\n                                <div class=\"card-tag\">Capgemini Research Institute<\/div>\n                                <h3 class=\"card-title\">Reimagining customer experience: Human-led, AI-powered<\/h3>\n                                <div class=\"insight-card-footer\">\n                                    <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.capgemini.com\/no-no\/wp-content\/themes\/capgemini2025\/assets\/images\/capgemini-research-institute.svg\" alt=\"capgemini-research-institute\" class=\"light\">\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.capgemini.com\/no-no\/wp-content\/themes\/capgemini2025\/assets\/images\/capgemini-research-institute-white.svg\" alt=\"capgemini-research-institute\" class=\"dark\">\n                                <\/div>\n                            <\/div>\n                            <\/a>\n                        <\/div>\n                    <div class=\"col-12 col-md-6 col-lg-4\">\n                            <a href=\"https:\/\/www.capgemini.com\/no-no\/insights\/research-library\/driving-loyalty-with-experience\/\" aria-label=\"Driving loyalty with experience\" class=\"card-link-holder\">\n                            <div class=\"insight-card insight-card-start\">\n                                <div class=\"card-tag\">Point of view<\/div>\n                                <h3 class=\"card-title\">Driving loyalty with experience<\/h3>\n                                <div class=\"insight-card-footer\">\n                                    <img decoding=\"async\" loading=\"lazy\" src=\"\" alt=\"\" class=\"light\">\n                                    <img decoding=\"async\" loading=\"lazy\" src=\"\" alt=\"\" class=\"dark\">\n                                <\/div>\n                            <\/div>\n                            <\/a>\n                        <\/div>\n                    <\/div>\n                    <\/div><div class=\"layout-two-card cards-reversed\">\n                                <div class=\"row align-items-center\"><div class=\"card-image-wrapper\">\n                                <div class=\"card-image\" data-image-url=\"https:\/\/www.capgemini.com\/no-no\/insights\/research-library\/ramping-up-customer-experience-cx-from-interaction-to-engagement\/\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<picture>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<source srcset=\"https:\/\/www.capgemini.com\/no-no\/wp-content\/uploads\/sites\/23\/2024\/04\/2024-03-27_Genesys_PoV-Assets_web-banner-2880x1800px_FINAL_JJ.jpg?w=800&#038;quality=70 1x, https:\/\/www.capgemini.com\/no-no\/wp-content\/uploads\/sites\/23\/2024\/04\/2024-03-27_Genesys_PoV-Assets_web-banner-2880x1800px_FINAL_JJ.jpg?w=800&#038;quality=70 2x\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tmedia=\"(min-width: 1500px)\"\/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<source srcset=\"https:\/\/www.capgemini.com\/no-no\/wp-content\/uploads\/sites\/23\/2024\/04\/2024-03-27_Genesys_PoV-Assets_web-banner-2880x1800px_FINAL_JJ.jpg?w=800&#038;quality=70 1x, https:\/\/www.capgemini.com\/no-no\/wp-content\/uploads\/sites\/23\/2024\/04\/2024-03-27_Genesys_PoV-Assets_web-banner-2880x1800px_FINAL_JJ.jpg?w=800&#038;quality=70 2x\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tmedia=\"(min-width: 992px)\"\/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<source srcset=\"https:\/\/www.capgemini.com\/no-no\/wp-content\/uploads\/sites\/23\/2024\/04\/2024-03-27_Genesys_PoV-Assets_web-banner-2880x1800px_FINAL_JJ.jpg?w=800&#038;quality=70 1x, https:\/\/www.capgemini.com\/no-no\/wp-content\/uploads\/sites\/23\/2024\/04\/2024-03-27_Genesys_PoV-Assets_web-banner-2880x1800px_FINAL_JJ.jpg?w=800&#038;quality=70 2x\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tmedia=\"(min-width: 768px)\"\/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<source srcset=\"https:\/\/www.capgemini.com\/no-no\/wp-content\/uploads\/sites\/23\/2024\/04\/2024-03-27_Genesys_PoV-Assets_web-banner-2880x1800px_FINAL_JJ.jpg?w=350&#038;quality=70 1x, https:\/\/www.capgemini.com\/no-no\/wp-content\/uploads\/sites\/23\/2024\/04\/2024-03-27_Genesys_PoV-Assets_web-banner-2880x1800px_FINAL_JJ.jpg?w=700&#038;quality=70 2x\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tmedia=\"(min-width: 0)\"\/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.capgemini.com\/no-no\/wp-content\/uploads\/sites\/23\/2024\/04\/2024-03-27_Genesys_PoV-Assets_web-banner-2880x1800px_FINAL_JJ.jpg\" alt=\"\" style=\"object-position: 50% 50%; object-fit: cover;\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/picture>\n                                <\/div>\n                            <\/div><div class=\"col-12 col-md-6 col-lg-4 flex-sm-order-reverse\">\n                            <a href=\"https:\/\/www.capgemini.com\/no-no\/insights\/research-library\/how-banks-can-use-generative-ai-to-enhance-marketing-disclosures\/\" aria-label=\"How banks can use generative AI to enhance marketing disclosures\" class=\"card-link-holder\">\n                            <div class=\"insight-card insight-card-start\">\n                                <div class=\"card-tag\">Point of view<\/div>\n                                <h3 class=\"card-title\">How banks can use generative AI to enhance marketing disclosures<\/h3>\n                                <div class=\"insight-card-footer\">\n                                    <img decoding=\"async\" loading=\"lazy\" src=\"\" alt=\"\" class=\"light\">\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" loading=\"lazy\" src=\"\" alt=\"\" class=\"dark\">\n                                <\/div>\n                            <\/div>\n                            <\/a>\n                        <\/div>\n                    <div class=\"col-12 col-md-6 col-lg-4\">\n                           <a href=\"https:\/\/www.capgemini.com\/no-no\/insights\/research-library\/ramping-up-customer-experience-cx-from-interaction-to-engagement\/\" aria-label=\"Ramping up customer experience (CX) \u2013 from interaction to engagement\" class=\"card-link-holder\">\n                            <div class=\"insight-card insight-card-center\">\n                                <div class=\"card-tag\">Point of view<\/div>\n                                <h3 class=\"card-title\">Ramping up customer experience (CX) \u2013 from interaction to engagement<\/h3>\n                                <div class=\"insight-card-footer\">\n                                    <img decoding=\"async\" loading=\"lazy\" src=\"\" alt=\"\" class=\"light\">\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" loading=\"lazy\" src=\"\" alt=\"\" class=\"dark\">\n                                <\/div>\n                            <\/div>\n                            <\/a>\n                        <\/div>\n                    <div class=\"col-12 col-lg-4 d-md-none d-lg-block\"><\/div><\/div>\n                    <\/div><\/div><\/section>\n\n\n<section class=\"wp-block-cg-blocks-call-to-action undefined is-style-cg-secondary-3 call-to-action-block\"><div class=\"container\"><div class=\"call-to-action-block-content-wrapper has-description\"><div class=\"text-wrapper has-description\"><h3 class=\"title\" data-maxlength=\"144\">Stay informed<\/h3><p class=\"description\" data-maxlength=\"210\">Subscribe to receive our retail banking related thought leadership.<\/p><\/div><div class=\"button-wrapper has-description\"><a class=\"cta-btn action-valid\" data-bs-toggle=\"modal\" data-bs-target=\"#CTA45d9ca87_8ecb_495e_baa5_1bcd601bf729\" data-maxlength=\"24\" tabindex=\"0\" href=\"#\"> Subscribe <\/a><\/div><div class=\"modal cta-frontend-modal-wrapper\" id=\"CTA45d9ca87_8ecb_495e_baa5_1bcd601bf729\"><div class=\"modal-dialog modal-lg modal-dialog-centered modal-dialog-scrollable cta-frontend-modal\"><div class=\"modal-content\"><div class=\"modal-header\"><button type=\"button\" class=\"btn-close\" data-bs-dismiss=\"modal\" aria-label=\"close\"> <\/button><\/div><div class=\"modal-body\"><div class=\"logo-wrapper\"><img decoding=\"async\" loading=\"lazy\" src=\"\/wp-content\/themes\/capgemini2025\/assets\/images\/logo-white.svg\" alt=\"logo\" class=\"dark\"\/><img decoding=\"async\" loading=\"lazy\" src=\"\/wp-content\/themes\/capgemini2025\/assets\/images\/logo.svg\" alt=\"logo\" class=\"light\"\/><\/div><h4 class=\"form-title\">Subscribe<\/h4>\t\t<div class=\"mf_forms__container \">\n\t\t\t\t\t\t\t\t<form id=\"mf_form_859904_3782925071\" class=\"mf_form__form row needs-validation\" action=\"\" method=\"post\" enctype=\"multipart\/form-data\" data-nosnippet>\n\t\t\t<div class=\"col-12\">\n\t\t\t\t<div class=\"asterisk_title\">\n\t\t\t\t\t<p><span class=\"star-required\">*<\/span> Mandatory field<\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"col-12\">\n\t\t\t\t<div class=\"mf_form__errors mf_form__errors--top\" role=\"alert\" aria-live=\"polite\">\n\t\t\t\t\t<ul class=\"mf_form__errors__list\"><\/ul>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t<div class=\"mf-field-wrapper form-floating col-sm-12\"><input type=\"text\" class=\"form-control\" id=\"_mf_344330_4305_198880444\" name=\"_mf_344330_4305\" placeholder=\"First name\" required \/><label for=\"_mf_344330_4305_198880444\" class=\"form-label\">First name <span class=\"star-required\">*<\/span><\/label><div class=\"invalid-feedback-frm\">First name is not valid.<\/div><\/div><div class=\"mf-field-wrapper form-floating col-sm-12\"><input type=\"text\" class=\"form-control\" id=\"_mf_344330_8620_3382086164\" name=\"_mf_344330_8620\" placeholder=\"Last name\" required \/><label for=\"_mf_344330_8620_3382086164\" class=\"form-label\">Last name <span class=\"star-required\">*<\/span><\/label><div class=\"invalid-feedback-frm\">Last name is not valid.<\/div><\/div><div class=\"mf-field-wrapper form-floating col-sm-12\"><input type=\"email\" class=\"form-control\" id=\"_mf_344330_7336_1005616338\" name=\"_mf_344330_7336\" placeholder=\"Email\" required \/><label for=\"_mf_344330_7336_1005616338\" class=\"form-label\">Email <span class=\"star-required\">*<\/span><\/label><div class=\"invalid-feedback-frm\">Email is not valid.<\/div><\/div><div class=\"mf-field-wrapper form-floating col-sm-12\"><input type=\"text\" class=\"form-control\" id=\"_mf_344330_4673_379748504\" name=\"_mf_344330_4673\" placeholder=\"Company\" required \/><label for=\"_mf_344330_4673_379748504\" class=\"form-label\">Company <span class=\"star-required\">*<\/span><\/label><div class=\"invalid-feedback-frm\">Company is not valid.<\/div><\/div><div class=\"mf-field-wrapper form-floating col-sm-12\"><input type=\"text\" class=\"form-control\" id=\"_mf_344330_1886_3933210317\" name=\"_mf_344330_1886\" placeholder=\"Job title\" required \/><label for=\"_mf_344330_1886_3933210317\" class=\"form-label\">Job title <span class=\"star-required\">*<\/span><\/label><div class=\"invalid-feedback-frm\">Job title is not valid.<\/div><\/div>\t\t<div class=\"mf_field mf_field--country mf_field--select floating form-country-select-parent mf-required\">\n\n\t\t\t<label for=\"_mf_886400_9618_3408615737\" class=\"floating__label form-country-select-label\" data-content=\"Country\">\n\t\t\t\t<span class=\"floating-label-content\">Country<\/span>\n\t\t\t<\/label>\n\n\t\t\t<div class=\"select-wrap\">\n<i class=\"icon icon-zodiak-chevron-down\"><\/i>\n\t\t\t\t<select id=\"_mf_886400_9618_3408615737\" class=\"mf_field__input empty mf-country-selectbox form_country_select\" name=\"_mf_886400_9618\" data-validate=\"select\" required>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"\"  selected='selected'>Country<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"AF\" >Afghanistan<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"AX\" >Aland Islands<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"AL\" >Albania<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"DZ\" >Algeria<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"AS\" >American Samoa<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"AD\" >Andorra<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"AO\" >Angola<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"AI\" >Anguilla<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"AQ\" >Antarctica<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"AG\" >Antigua And Barbuda<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"AR\" >Argentina<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"AM\" >Armenia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"AW\" >Aruba<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"AU\" >Australia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"AT\" >Austria<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"AZ\" >Azerbaijan<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"BS\" >Bahamas<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"BH\" >Bahrain<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"BD\" >Bangladesh<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"BB\" >Barbados<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"BY\" >Belarus<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"BE\" >Belgium<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"BZ\" >Belize<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"BJ\" >Benin<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"BM\" >Bermuda<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"BT\" >Bhutan<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"BO\" >Bolivia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"BA\" >Bosnia And Herzegovina<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"BW\" >Botswana<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"BV\" >Bouvet Island<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"BR\" >Brazil<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"IO\" >British Indian Ocean Territory<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"BN\" >Brunei Darussalam<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"BG\" >Bulgaria<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"BF\" >Burkina Faso<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"BI\" >Burundi<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"KH\" >Cambodia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"CM\" >Cameroon<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"CA\" >Canada<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"CV\" >Cape Verde<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"KY\" >Cayman Islands<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"CF\" >Central African Republic<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"TD\" >Chad<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"CL\" >Chile<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"CN\" >China<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"CX\" >Christmas Island<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"CC\" >Cocos (Keeling) Islands<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"CO\" >Colombia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"KM\" >Comoros<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"CG\" >Congo<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"CD\" >Congo, Democratic Republic<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"CK\" >Cook Islands<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"CR\" >Costa Rica<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"CI\" >Cote D&#039;Ivoire<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"HR\" >Croatia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"CU\" >Cuba<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"CY\" >Cyprus<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"CZ\" >Czech Republic<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"DK\" >Denmark<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"DJ\" >Djibouti<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"DM\" >Dominica<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"DO\" >Dominican Republic<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"EC\" >Ecuador<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"EG\" >Egypt<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"SV\" >El Salvador<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"GQ\" >Equatorial Guinea<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"ER\" >Eritrea<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"EE\" >Estonia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"ET\" >Ethiopia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"FK\" >Falkland Islands (Malvinas)<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"FO\" >Faroe Islands<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"FJ\" >Fiji<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"FI\" >Finland<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"FR\" >France<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"GF\" >French Guiana<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"PF\" >French Polynesia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"TF\" >French Southern Territories<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"GA\" >Gabon<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"GM\" >Gambia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"GE\" >Georgia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"DE\" >Germany<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"GH\" >Ghana<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"GI\" >Gibraltar<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"GR\" >Greece<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"GL\" >Greenland<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"GD\" >Grenada<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"GP\" >Guadeloupe<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"GU\" >Guam<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"GT\" >Guatemala<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"GG\" >Guernsey<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"GN\" >Guinea<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"GW\" >Guinea-Bissau<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"GY\" >Guyana<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"HT\" >Haiti<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"HM\" >Heard Island &amp; Mcdonald Islands<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"VA\" >Holy See (Vatican City State)<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"HN\" >Honduras<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"HK\" >Hong Kong<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"HU\" >Hungary<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"IS\" >Iceland<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"IN\" >India<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"ID\" >Indonesia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"IR\" >Iran, Islamic Republic Of<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"IQ\" >Iraq<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"IE\" >Ireland<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"IM\" >Isle Of Man<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"IL\" >Israel<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"IT\" >Italy<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"JM\" >Jamaica<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"JP\" >Japan<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"JE\" >Jersey<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"JO\" >Jordan<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"KZ\" >Kazakhstan<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"KE\" >Kenya<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"KI\" >Kiribati<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"KR\" >Korea<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"KW\" >Kuwait<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"KG\" >Kyrgyzstan<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"LA\" >Lao People&#039;s Democratic Republic<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"LV\" >Latvia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"LB\" >Lebanon<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"LS\" >Lesotho<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"LR\" >Liberia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"LY\" >Libyan Arab Jamahiriya<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"LI\" >Liechtenstein<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"LT\" >Lithuania<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"LU\" >Luxembourg<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"MO\" >Macao<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"MK\" >Macedonia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"MG\" >Madagascar<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"MW\" >Malawi<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"MY\" >Malaysia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"MV\" >Maldives<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"ML\" >Mali<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"MT\" >Malta<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"MH\" >Marshall Islands<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"MQ\" >Martinique<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"MR\" >Mauritania<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"MU\" >Mauritius<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"YT\" >Mayotte<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"MX\" >Mexico<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"FM\" >Micronesia, Federated States Of<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"MD\" >Moldova<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"MC\" >Monaco<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"MN\" >Mongolia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"ME\" >Montenegro<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"MS\" >Montserrat<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"MA\" >Morocco<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"MZ\" >Mozambique<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"MM\" >Myanmar<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"NA\" >Namibia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"NR\" >Nauru<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"NP\" >Nepal<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"NL\" >Netherlands<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"AN\" >Netherlands Antilles<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"NC\" >New Caledonia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"NZ\" >New Zealand<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"NI\" >Nicaragua<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"NE\" >Niger<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"NG\" >Nigeria<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"NU\" >Niue<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"NF\" >Norfolk Island<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"MP\" >Northern Mariana Islands<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"NO\" >Norway<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"OM\" >Oman<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"PK\" >Pakistan<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"PW\" >Palau<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"PS\" >Palestinian Territory, Occupied<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"PA\" >Panama<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"PG\" >Papua New Guinea<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"PY\" >Paraguay<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"PE\" >Peru<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"PH\" >Philippines<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"PN\" >Pitcairn<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"PL\" >Poland<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"PT\" >Portugal<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"PR\" >Puerto Rico<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"QA\" >Qatar<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"RE\" >Reunion<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"RO\" >Romania<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"RU\" >Russian Federation<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"RW\" >Rwanda<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"BL\" >Saint Barthelemy<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"SH\" >Saint Helena<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"KN\" >Saint Kitts And Nevis<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"LC\" >Saint Lucia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"MF\" >Saint Martin<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"PM\" >Saint Pierre And Miquelon<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"VC\" >Saint Vincent And Grenadines<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"WS\" >Samoa<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"SM\" >San Marino<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"ST\" >Sao Tome And Principe<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"SA\" >Saudi Arabia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"SN\" >Senegal<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"RS\" >Serbia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"SC\" >Seychelles<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"SL\" >Sierra Leone<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"SG\" >Singapore<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"SK\" >Slovakia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"SI\" >Slovenia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"SB\" >Solomon Islands<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"SO\" >Somalia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"ZA\" >South Africa<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"GS\" >South Georgia And Sandwich Isl.<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"ES\" >Spain<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"LK\" >Sri Lanka<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"SD\" >Sudan<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"SR\" >Suriname<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"SJ\" >Svalbard And Jan Mayen<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"SZ\" >Swaziland<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"SE\" >Sweden<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"CH\" >Switzerland<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"SY\" >Syrian Arab Republic<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"TW\" >Taiwan<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"TJ\" >Tajikistan<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"TZ\" >Tanzania<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"TH\" >Thailand<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"TL\" >Timor-Leste<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"TG\" >Togo<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"TK\" >Tokelau<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"TO\" >Tonga<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"TT\" >Trinidad And Tobago<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"TN\" >Tunisia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"TR\" >Turkey<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"TM\" >Turkmenistan<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"TC\" >Turks And Caicos Islands<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"TV\" >Tuvalu<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"UG\" >Uganda<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"UA\" >Ukraine<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"AE\" >United Arab Emirates<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"GB\" >United Kingdom<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"US\" >United States<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"UM\" >United States Outlying Islands<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"UY\" >Uruguay<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"UZ\" >Uzbekistan<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"VU\" >Vanuatu<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"VE\" >Venezuela<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"VN\" >Viet Nam<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"VG\" >Virgin Islands, British<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"VI\" >Virgin Islands, U.S.<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"WF\" >Wallis And Futuna<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"EH\" >Western Sahara<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"YE\" >Yemen<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"ZM\" >Zambia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"ZW\" >Zimbabwe<\/option>\n\t\t\t\t\t\t\t\t\t<\/select>\n\n\t\t\t\t<div class=\"invalid-feedback-frm\">Country is not valid.<\/div>\n\t\t\t<\/div>\n\n\t\t<\/div>\n\n\t\t<script type=\"text\/javascript\">\n            jQuery(document).ready(function($) {\n                $('.mf_form__form').each(function() {\n                    var $form = $(this); \/\/ This specific form instance\n\n                    \/\/ Find the country select in this form\n                    $form.find('.form_country_select').each(function() {\n                        var $select = $(this);\n\t\t\t\t\t\tvar clickCount = 0;\n                        \/\/ On change\n                        $select.on('click', function() {\n\t\t\t\t\t\t\tclickCount++;\n\t\t\t\t\t\t\tif (clickCount === 1) {\n\t\t\t\t\t\t\t\t$(this).parent().find('.icon-zodiak-chevron-down').addClass('active');\n\t\t\t\t\t\t\t} else {\n\t\t\t\t\t\t\t\tclickCount = 0;\n\t\t\t\t\t\t\t\t$(this).parent().find('.icon-zodiak-chevron-down').removeClass('active');\n\t\t\t\t\t\t\t}\n\t\t\t\t\t\t});\n\t\t\t\t\t\t$select.on('blur', function() {\n\t\t\t\t\t\t\tclickCount = 0;\n\t\t\t\t\t\t\t$(this).parent().find('.icon-zodiak-chevron-down').removeClass('active');\n\t\t\t\t\t\t});\n                    });\n                });\n            });\n        <\/script>\n\n\t\t<div class=\"mf-field-wrapper  col-sm-12\">\n\t\t<label for=\"_mf_344330_7304_354988021\" class=\"form-label\">\n\t\t\t \t\t<\/label>\n\n\t\t\n\t\t<div class=\"checkbox-controls checkboxrequired\">\n\n\t\t\t\n\t\t\t\t<div class=\"form-check\">\n\n\t\t\t\t\t<input class=\"form-check-input\" type=\"checkbox\"\n\t\t\t\t\t\tname=\"_mf_344330_7304[]\"\n\t\t\t\t\t\tid=\"_mf_344330_7304_0_354988021\"\n\t\t\t\t\t\tvalue=\"retailbankingsubscription\"\n\t\t\t\t\t\t\t\t\t\t\t\trequired\t\t\t\t\t>\n\n\t\t\t\t\t<label class=\"form-check-label\" for=\"_mf_344330_7304_0_354988021\">\n\t\t\t\t\t\tBy submitting this form, I agree to the processing of my personal data by Capgemini to be contacted regarding offers on retail banking and related information.\t\t\t\t\t<\/label>\n\n\t\t\t\t<\/div>\n\n\t\t\t\t\n\t\t<\/div>\n\n\t\t<div class=\"invalid-feedback-frm\">Field is not valid.<\/div><\/div><div class=\"mf-field-wrapper  col-sm-12\">\n\t\t<div class=\"form-check checkbox-controls\">\n\n\t\t\t<input type=\"checkbox\" id=\"_mf_344330_7525_3046872618\" class=\"form-check-input\"\n\t\t\t\tname=\"_mf_344330_7525[]\"\n\t\t\t\tvalue=\"1\"\n\t\t\t\trequired\n\t\t\t>\n\n\t\t\t<label for=\"_mf_344330_7525_3046872618\" class=\"form-check-label consent-text\">\n\t\t\t\tI agree to Capgemini collecting &amp; processing my personal data to allow me to receive information on Capgemini services. For further information, please see our<a href=\"https:\/\/www.capgemini.com\/privacy-notice\/\"> Privacy Notice<\/a>.  &nbsp;\t\t\t<\/label>\n\n\t\t<\/div>\n\t\t<\/div>\t\t\t<div class=\"mf_field mf_field--recaptcha\">\n\t\t\t\t<div class=\"g-recaptcha\" data-sitekey=\"6Lc3OpIUAAAAADY4ErEHF0HF6Tr7vuknduDU-fbl\"><\/div>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t<div class=\"mf_field mf_field--submit\" >\n\t\t\t\t<div class=\"slide-button-background button-background\">\n\t\t\t\t\t<label for=\"slider-submit-_mf_344330_1680\" class=\"slide-text\">\n\t\t\t\t\t\tSlide to submit\t\t\t\t\t<\/label>\n\t\t\t\t\t<input\n\t\t\t\t\t\tid=\"slider-submit-_mf_344330_1680\"\n\t\t\t\t\t\ttype=\"range\"\n\t\t\t\t\t\tclass=\"mf_field__input slider-frm-btn\"\n\t\t\t\t\t\trel=\"_mf_344330_1680\"\n\t\t\t\t\t\tmin=\"0\"\n\t\t\t\t\t\tmax=\"100\"\n\t\t\t\t\t\tvalue=\"0\"\n\t\t\t\t\t\taria-label=\"Slide to submit\"\n\t\t\t\t\t\taria-describedby=\"slide-instruction-_mf_344330_1680\"\n\t\t\t\t\t\taria-valuenow=\"0\"\n\t\t\t\t\t\taria-valuemin=\"0\"\n\t\t\t\t\t\taria-valuemax=\"100\"\n\t\t\t\t\t\taria-orientation=\"horizontal\"\n\t\t\t\t\t\trole=\"slider\"\n\t\t\t\t\t\ttabindex=\"0\"\n\t\t\t\t\t\/>\n\t\t\t\t\t<!-- Icon element for Firefox (doesn't support ::before\/::after on inputs) -->\n\t\t\t\t\t<span class=\"slider-icon\" aria-hidden=\"true\"><\/span>\n\t\t\t\t\t<span id=\"slide-instruction-_mf_344330_1680\" class=\"sr-only\">\n\t\t\t\t\t\tUse right arrow keys to slide, or drag right with your finger. When you reach 100 percent, the form is submitted.\t\t\t\t\t<\/span>\n\t\t\t\t\t<!-- Mobile-only submit button fallback -->\n\t\t\t\t\t<button type=\"submit\" class=\"mf-mobile-submit-btn\" disabled>\n\t\t\t\t\t\t<span class=\"sr-only\">If you use a screen reader or VoiceOver, double-tap this button to submit the form.<\/span>\n\t\t\t\t\t\tSlide to submit\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t\t<input type=\"hidden\" name=\"submit_btn_txt\" class=\"submit_btn_txt\" value=\"Slide to submit\"\/>\n\t\t\t\t<input type=\"hidden\" name=\"submitted_state_txt\" class=\"submitted_state_txt\" value=\"Submitted\"\/>\n\t\t\t<\/div>\n\t\t\t\t\t\t<input type=\"hidden\" name=\"form_id\" data-validate=\"number\" class=\"mf_form__id\" value=\"859904\" \/>\n\t\t\t\t<input type=\"hidden\" name=\"form_title\" class=\"mf_form__title\" value=\"revamp-2025-world-retail-banking-subscription-form\" \/>\n\t\t\t\t<input type=\"hidden\" name=\"wp_rest_nonce\" class=\"mf_form__wp_rest_nonce\" value=\"3fb441f171\" \/>\n\n\t\t\t\t<input type=\"hidden\" name=\"mf_form_conditional_logic\" class=\"mf_form__title conditional_logic\" value=\"\" \/>\n\t\t\t\t\n\t\t\t\t<input type=\"hidden\" name=\"mf_form_fields_country_dpo_field\" class=\"mf_form__title conditional_logic mf_form_fields_country_dpo_field\" value=\"\" \/>\n\n\t\t\t\t<!-- Anti-spam field -->\n\t\t\t\t<input type=\"text\" \n\t\t\t\t\tname=\"website_url\" \n\t\t\t\t\tclass=\"mf_field__url\" \n\t\t\t\t\tautocomplete=\"off\"\n\t\t\t\t\ttabindex=\"-1\"\n\t\t\t\t\taria-hidden=\"true\"\n\t\t\t\t\tstyle=\"position:absolute;left:-9999px;width:1px;height:1px;opacity:0;pointer-events:none;\" \n\t\t\t\t\/>\n\t\t\t<\/form>\n\n\t\t\t<div class=\"mf_form__success\" tabindex=\"0\" role=\"alert\">\n\t\t\t\t<h2>Thank you for subscribing.<\/h2><\/p>\n\t\t\t<\/div>\n\t\t\t<div class=\"mf_form__errors\">\n\t\t\t\t<p>We are sorry, the form submission failed. Please try again.<\/p>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t<script>\n\t\t\twindow.MF_CONFIG859904 = {\"859904\":{\"errors\":[],\"redirect\":\"\"}};\n\t\t<\/script>\n\t<\/div><\/div><\/div><\/div><\/div><\/div><\/section>\n\n\n\n<section class=\"wp-block-cg-blocks-intro-para undefined section section--intro\"><div class=\"intro-para\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-md-8 offset-md-2\"><h2 class=\"intro-para-title\">Client stories<\/h2><\/div><\/div><\/div><\/div><\/section>\n\n\n\t<section class=\"wp-block-cg-blocks-wrapper-learning-slider section learning-slider\">\n\t\t<div class=\"container\">\n\t\t\t<div class=\"learning-header\">\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<div class=\"slider slider-fader\">\n\t\t\t\t<div class=\"slider-list\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"slide active card-learning-slide right-card short-copy\" data-align-right=\"false\" data-long-copy=\"false\">\n\t\t\t\t\t\t\t\t<div>\n\t\t\t\t\t\t\t\t\t<div class=\"slide-bg-wrapper\">\n\n                                        \n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n                                            \n                                            \n                                            \n                                            <img decoding=\"async\" loading=\"lazy\" class=\"slide-bg d-md-block\" src=\"https:\/\/www.capgemini.com\/dk-en\/wp-content\/uploads\/sites\/7\/2025\/08\/Barclay-client-story-web-page-banner.jpg\" alt=\"\" style=\"object-position: 60% 6%;object-fit: cover\" \/>\n                                        \n\n                  \t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"slide-reveal\"><\/div>\n\n\t\t\t\t\t\t\t\t\t\t<div class=\"container slide-info-wrapper card-learning-slider\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-12 col-lg-10 col-xl-6 col-xxl-6 right-card\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"slide-info short-copy\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"box\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"title-link\" href=\"https:\/\/www.capgemini.com\/no-no\/news\/client-stories\/barclays-partners-with-capgemini-to-reimagine-client-experience-for-investment-research\/\" target=\"\" rel=\"noopener noreferrer\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"title-text\" data-maxlength=\"88\">Barclays taps Capgemini to elevate investment research UX<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p data-maxlength=\"330\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tBarclays partners with Capgemini to transform investment research delivery, enhancing client experience through digital innovation\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"box-bottom\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-12 col-md-6\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"slide-info-footer\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"brand-logo-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-12 col-md-6\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"btnDiv\">\t<a class=\"more2\" aria-label=\"Read more about Barclays taps Capgemini to elevate investment research UX\" href=\"https:\/\/www.capgemini.com\/no-no\/news\/client-stories\/barclays-partners-with-capgemini-to-reimagine-client-experience-for-investment-research\/\" target=\"\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tRead more\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t         \t\t\t<\/div>\n\n\n\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"slide active card-learning-slide right-card short-copy\" data-align-right=\"false\" data-long-copy=\"false\">\n\t\t\t\t\t\t\t\t<div>\n\t\t\t\t\t\t\t\t\t<div class=\"slide-bg-wrapper\">\n\n                                        \n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n                                            \n                                            \n                                            \n                                            <img decoding=\"async\" loading=\"lazy\" class=\"slide-bg d-md-block\" src=\"https:\/\/www.capgemini.com\/dk-en\/wp-content\/uploads\/sites\/7\/2025\/08\/Riverty_client_story_web_page_ba.jpg\" alt=\"\" style=\"object-position: 60% 6%;object-fit: cover\" \/>\n                                        \n\n                  \t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"slide-reveal\"><\/div>\n\n\t\t\t\t\t\t\t\t\t\t<div class=\"container slide-info-wrapper card-learning-slider\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-12 col-lg-10 col-xl-6 col-xxl-6 right-card\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"slide-info short-copy\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"box\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"title-link\" href=\"https:\/\/www.capgemini.com\/no-no\/news\/client-stories\/revolutionizing-rivertys-crm-capabilities-with-copilot-for-sales\/\" target=\"\" rel=\"noopener noreferrer\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"title-text\" data-maxlength=\"88\">Revolutionizing Riverty\u2019s CRM capabilities with Copilot for Sales<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p data-maxlength=\"330\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tCapgemini and Riverty redefined CRM engagement, including integrating Microsoft Copilot for Sales to drive efficiency and innovation in sales operations\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"box-bottom\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-12 col-md-6\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"slide-info-footer\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"brand-logo-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-12 col-md-6\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"btnDiv\">\t<a class=\"more2\" aria-label=\"Read more about Revolutionizing Riverty\u2019s CRM capabilities with Copilot for Sales\" href=\"https:\/\/www.capgemini.com\/no-no\/news\/client-stories\/revolutionizing-rivertys-crm-capabilities-with-copilot-for-sales\/\" target=\"\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tRead more\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t         \t\t\t<\/div>\n\n\n\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"slide active card-learning-slide right-card short-copy\" data-align-right=\"false\" data-long-copy=\"false\">\n\t\t\t\t\t\t\t\t<div>\n\t\t\t\t\t\t\t\t\t<div class=\"slide-bg-wrapper\">\n\n                                        \n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n                                            \n                                            \n                                            \n                                            <img decoding=\"async\" loading=\"lazy\" class=\"slide-bg d-md-block\" src=\"https:\/\/www.capgemini.com\/se-en\/wp-content\/uploads\/sites\/20\/2025\/03\/Client-story-Banking-and-financial-services-web-Banner_2880x1800.jpg\" alt=\"\" style=\"object-position: 58% 13%;object-fit: cover\" \/>\n                                        \n\n                  \t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"slide-reveal\"><\/div>\n\n\t\t\t\t\t\t\t\t\t\t<div class=\"container slide-info-wrapper card-learning-slider\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-12 col-lg-10 col-xl-6 col-xxl-6 right-card\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"slide-info short-copy\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"box\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"title-link\" href=\"https:\/\/www.capgemini.com\/no-no\/news\/client-stories\/how-a-leading-financial-services-firm-set-the-stage-for-hyper-personalization\/\" target=\"\" rel=\"noopener noreferrer\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"title-text\" data-maxlength=\"88\">How a leading financial services firm set the stage for hyper-personalization<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p data-maxlength=\"200\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tA new consent management platform goes beyond compliance, enabling a new level of targeted offers\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"box-bottom\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-12 col-md-6\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"slide-info-footer\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"brand-logo-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-12 col-md-6\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"btnDiv\">\t<a class=\"more2\" aria-label=\"Read more about How a leading financial services firm set the stage for hyper-personalization\" href=\"https:\/\/www.capgemini.com\/no-no\/news\/client-stories\/how-a-leading-financial-services-firm-set-the-stage-for-hyper-personalization\/\" target=\"\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tRead more\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t         \t\t\t<\/div>\n\n\n\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"slide active card-learning-slide right-card short-copy\" data-align-right=\"false\" data-long-copy=\"false\">\n\t\t\t\t\t\t\t\t<div>\n\t\t\t\t\t\t\t\t\t<div class=\"slide-bg-wrapper\">\n\n                                        \n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n                                            \n                                            \n                                            \n                                            <img decoding=\"async\" loading=\"lazy\" class=\"slide-bg d-md-block\" src=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2024\/10\/Leading-bank-client-story-web-banner.jpg\" alt=\"\" style=\"object-position: 60% 6%;object-fit: cover\" \/>\n                                        \n\n                  \t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"slide-reveal\"><\/div>\n\n\t\t\t\t\t\t\t\t\t\t<div class=\"container slide-info-wrapper card-learning-slider\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-12 col-lg-10 col-xl-6 col-xxl-6 right-card\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"slide-info short-copy\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"box\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"title-link\" href=\"https:\/\/www.capgemini.com\/no-no\/news\/client-stories\/a-leading-bank-becomes-more-customer-centric-with-personalized-offer-management\/\" target=\"\" rel=\"noopener noreferrer\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"title-text\" data-maxlength=\"88\">Becoming more customer-centric with personalized offer management<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p data-maxlength=\"330\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tA leading bank transformation: plan, build, and implement end-to-end offer management platform leveraging Naehas and Adobe solutions, powered by AI.\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"box-bottom\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-12 col-md-6\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"slide-info-footer\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"brand-logo-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-12 col-md-6\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"btnDiv\">\t<a class=\"more2\" aria-label=\"Read more about Becoming more customer-centric with personalized offer management\" href=\"https:\/\/www.capgemini.com\/no-no\/news\/client-stories\/a-leading-bank-becomes-more-customer-centric-with-personalized-offer-management\/\" target=\"\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tRead more\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t         \t\t\t<\/div>\n\n\n\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"slide active card-learning-slide right-card short-copy\" data-align-right=\"false\" data-long-copy=\"false\">\n\t\t\t\t\t\t\t\t<div>\n\t\t\t\t\t\t\t\t\t<div class=\"slide-bg-wrapper\">\n\n                                        \n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n                                            \n                                            \n                                            \n                                            <img decoding=\"async\" loading=\"lazy\" class=\"slide-bg d-md-block\" src=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2024\/06\/Leading-international-banking-group-client-story-web-banner.jpg\" alt=\"\" style=\"object-position: 50% 50%;object-fit: cover\" \/>\n                                        \n\n                  \t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"slide-reveal\"><\/div>\n\n\t\t\t\t\t\t\t\t\t\t<div class=\"container slide-info-wrapper card-learning-slider\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-12 col-lg-10 col-xl-6 col-xxl-6 right-card\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"slide-info short-copy\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"box\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"title-link\" href=\"https:\/\/www.capgemini.com\/no-no\/news\/client-stories\/a-leading-international-banking-group-catalyzes-customer-engagement-with-investment-research-platform\/\" target=\"\" rel=\"noopener noreferrer\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"title-text\" data-maxlength=\"88\">International banking group grows customer engagement with investment research platform<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p data-maxlength=\"330\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tRevenue growth driven by attracting more customers through a customer-centric digital research platform.\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"box-bottom\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-12 col-md-6\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"slide-info-footer\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"brand-logo-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-12 col-md-6\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"btnDiv\">\t<a class=\"more2\" aria-label=\"Read more about International banking group grows customer engagement with investment research platform\" href=\"https:\/\/www.capgemini.com\/no-no\/news\/client-stories\/a-leading-international-banking-group-catalyzes-customer-engagement-with-investment-research-platform\/\" target=\"\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tRead more\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t         \t\t\t<\/div>\n\n\n\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"slide active card-learning-slide right-card short-copy\" data-align-right=\"false\" data-long-copy=\"false\">\n\t\t\t\t\t\t\t\t<div>\n\t\t\t\t\t\t\t\t\t<div class=\"slide-bg-wrapper\">\n\n                                        \n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n                                            \n                                            \n                                            \n                                            <img decoding=\"async\" loading=\"lazy\" class=\"slide-bg d-md-block\" src=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2024\/05\/UK-based-bank-case-study-_Capcom-Banner_2880x1800px.jpg\" alt=\"\" style=\"object-position: 31% 34%;object-fit: cover\" \/>\n                                        \n\n                  \t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"slide-reveal\"><\/div>\n\n\t\t\t\t\t\t\t\t\t\t<div class=\"container slide-info-wrapper card-learning-slider\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-12 col-lg-10 col-xl-6 col-xxl-6 right-card\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"slide-info short-copy\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"box\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"title-link\" href=\"\/news\/client-stories\/streamlining-customer-and-user-experiences-for-a-leading-financial-institution-improves-overall-satisfaction\/\" target=\"_blank\" rel=\"noopener noreferrer\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"title-text\" data-maxlength=\"88\">Streamlining customer and user experiences for a leading financial institution<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p data-maxlength=\"200\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tDeveloping a new service experience review methodology that helped unlock opportunities to reduce costs and improve customer service.\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"box-bottom\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-12 col-md-6\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"slide-info-footer\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"brand-logo-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-12 col-md-6\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"btnDiv\">\t<a class=\"more2\" aria-label=\"Read more about Streamlining customer and user experiences for a leading financial institution\" href=\"\/news\/client-stories\/streamlining-customer-and-user-experiences-for-a-leading-financial-institution-improves-overall-satisfaction\/\" target=\"_blank\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tRead more\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t         \t\t\t<\/div>\n\n\n\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"slide active card-learning-slide right-card short-copy\" data-align-right=\"false\" data-long-copy=\"false\">\n\t\t\t\t\t\t\t\t<div>\n\t\t\t\t\t\t\t\t\t<div class=\"slide-bg-wrapper\">\n\n                                        \n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n                                            \n                                            \n                                            \n                                            <img decoding=\"async\" loading=\"lazy\" class=\"slide-bg d-md-block\" src=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2024\/02\/Societe-Generale-client-story-web-banner.jpg\" alt=\"\" style=\"object-position: 31% 34%;object-fit: cover\" \/>\n                                        \n\n                  \t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"slide-reveal\"><\/div>\n\n\t\t\t\t\t\t\t\t\t\t<div class=\"container slide-info-wrapper card-learning-slider\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-12 col-lg-10 col-xl-6 col-xxl-6 right-card\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"slide-info short-copy\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"box\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"title-link\" href=\"\/news\/client-stories\/societe-generales-unprecedented-it-merger-creates-sg-a-new-french-retail-bank\/\" target=\"_blank\" rel=\"noopener noreferrer\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"title-text\" data-maxlength=\"88\">Soci\u00e9t\u00e9 G\u00e9n\u00e9rale\u2019s unprecedented IT merger creates SG, a new French retail bank<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p data-maxlength=\"200\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\u201cThe strength of Capgemini\u2019s tools reassured us and enabled us to bring our project to fruition.\u201d Bruno Delas, CIO Soci\u00e9t\u00e9 G\u00e9n\u00e9rale Group\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"box-bottom\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-12 col-md-6\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"slide-info-footer\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"brand-logo-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-12 col-md-6\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"btnDiv\">\t<a class=\"more2\" aria-label=\"Read more about Soci\u00e9t\u00e9 G\u00e9n\u00e9rale\u2019s unprecedented IT merger creates SG, a new French retail bank\" href=\"\/news\/client-stories\/societe-generales-unprecedented-it-merger-creates-sg-a-new-french-retail-bank\/\" target=\"_blank\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tRead more\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t         \t\t\t<\/div>\n\n\n\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"slider-nav-wrapper container\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"row\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"slider-nav-content col-12 col-lg-10 col-xl-6 col-xxl-6\" data-nav-content>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"slide-nav-container\">\n                                                                                                                    <div class=\"slider-nav\">\n                                                                <button class=\"slider-prev inactive\" aria-label=\"Slider-previous\"><\/button>\n\n                                                                <button class=\"slider-next\" aria-label=\"Slider-next\"><\/button>\n                                                            <\/div>\n                                                                                                            <\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t<\/section>\n\n\t\n\n<section class=\"section section--expert-perspectives\"><div class=\"container\"><div class=\"row\"><div class=\"content-title col-12 col-md-8\"><h2 class=\"expert-heading\">Expert perspectives<\/h2><\/div><\/div><div class=\"expert-prospective-container\"><div class=\"row\"><div class=\"col-12 col-md-4 row-space\"><div class=\"box\"><div class=\"box-img-wrapper\"><a href=\"https:\/\/www.capgemini.com\/no-no\/insights\/expert-perspectives\/creating-a-loyal-experience-for-customers-in-banking\/\" aria-label=\"Creating a loyal experience for customers in banking\" tabindex=\"-1\"><img decoding=\"async\" class=\"box-img\" alt=\"\" src=\"https:\/\/www.capgemini.com\/no-no\/wp-content\/uploads\/sites\/23\/2024\/10\/Blog_Capcom2880x1800px.jpg?w=600&#038;quality=70\" style=\"object-position: 50% 50%; object-fit: cover;\" loading=\"lazy\" \/><\/a><\/div><div class=\"box-inner\"><div class=\"box-tag\">Customer experience<\/div><a class=\"content-box-title\" href=\"https:\/\/www.capgemini.com\/no-no\/insights\/expert-perspectives\/creating-a-loyal-experience-for-customers-in-banking\/\" aria-label=\"Creating a loyal experience for customers in banking\"><h3 class=\"expert-subtitle\">Creating a loyal experience for customers in banking<\/h3><\/a><div class=\"box-bottom\">\n\t\t   <div class=\"box-logo\"><img decoding=\"async\" class=\"\" loading=\"lazy\" alt=\"\" src=\"https:\/\/www.capgemini.com\/no-no\/wp-content\/uploads\/sites\/23\/2022\/10\/Vinay-Patel-1.jpg?w=960\" \/><\/div><div class=\"date-name-info\"><div class=\"author-text\">Vinay Patel<\/div><div class=\"date-text\">Sep 25, 2024<\/div><\/div><\/div><\/div><\/div><\/div><div class=\"col-12 col-md-4 row-space\"><div class=\"box\"><div class=\"box-img-wrapper\"><a href=\"https:\/\/www.capgemini.com\/no-no\/insights\/expert-perspectives\/precision-in-personalization-the-power-of-bpm-platforms\/\" aria-label=\"Precision in personalization: The power of BPM platforms\" tabindex=\"-1\"><img decoding=\"async\" class=\"box-img\" alt=\"\" src=\"https:\/\/www.capgemini.com\/no-no\/wp-content\/uploads\/sites\/23\/2024\/07\/MicrosoftTeams-image-11.png?w=600&#038;quality=70\" style=\"object-position: 50% 50%; object-fit: cover;\" loading=\"lazy\" \/><\/a><\/div><div class=\"box-inner\"><div class=\"box-tag\">Customer experience, Technology<\/div><a class=\"content-box-title\" href=\"https:\/\/www.capgemini.com\/no-no\/insights\/expert-perspectives\/precision-in-personalization-the-power-of-bpm-platforms\/\" aria-label=\"Precision in personalization: The power of BPM platforms\"><h3 class=\"expert-subtitle\">Precision in personalization: The power of BPM platforms<\/h3><\/a><div class=\"box-bottom\">\n\t\t   <div class=\"box-logo\"><img decoding=\"async\" class=\"\" loading=\"lazy\" alt=\"\" src=\"https:\/\/www.capgemini.com\/no-no\/wp-content\/uploads\/sites\/23\/2024\/07\/Dinesh-Karanam-1.jpg?w=960\" \/><\/div><div class=\"date-name-info\"><div class=\"author-text\">Dinesh Karanam<\/div><div class=\"date-text\">May 29, 2024<\/div><\/div><\/div><\/div><\/div><\/div><div class=\"col-12 col-md-4 row-space\"><div class=\"box\"><div class=\"box-img-wrapper\"><a href=\"https:\/\/www.capgemini.com\/no-no\/insights\/expert-perspectives\/empowering-customers-with-behavioral-data-and-ai-driven-personalization\/\" aria-label=\"Empowering customers with behavioral data and AI-driven personalization\" tabindex=\"-1\"><img decoding=\"async\" class=\"box-img\" alt=\"\" src=\"https:\/\/www.capgemini.com\/no-no\/wp-content\/uploads\/sites\/23\/2024\/05\/Empowering.jpg?w=600&#038;quality=70\" style=\"object-position: 50% 50%; object-fit: cover;\" loading=\"lazy\" \/><\/a><\/div><div class=\"box-inner\"><div class=\"box-tag\">Customer experience, Data and AI<\/div><a class=\"content-box-title\" href=\"https:\/\/www.capgemini.com\/no-no\/insights\/expert-perspectives\/empowering-customers-with-behavioral-data-and-ai-driven-personalization\/\" aria-label=\"Empowering customers with behavioral data and AI-driven personalization\"><h3 class=\"expert-subtitle\">Empowering customers with behavioral data and AI-driven personalization<\/h3><\/a><div class=\"box-bottom\">\n\t\t   <div class=\"box-logo\"><img decoding=\"async\" class=\"light\" loading=\"lazy\" alt=\"Capgemini\" src=\"https:\/\/www.capgemini.com\/no-no\/wp-content\/themes\/capgemini2025\/assets\/images\/cg-logo-blue.svg\" \/><img decoding=\"async\" class=\"dark\" loading=\"lazy\" alt=\"Capgemini\" src=\"https:\/\/www.capgemini.com\/no-no\/wp-content\/themes\/capgemini2025\/assets\/images\/cg-logo-white.svg\" \/><\/div><div class=\"date-name-info\"><div class=\"author-text\">Capgemini<\/div><div class=\"date-text\">May 3, 2024<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section>\n\n\n<section class=\" section section--expert-slider wrapper-people-slider wp-block-cg-blocks-wrapper-people-slider undefined\"><div class=\"container\"><div class=\"row\"><div class=\"content-title col-12 col-md-8\"><h2 data-maxlength=\"34\" class=\"people-heading-title\">Meet our experts<\/h2><\/div><\/div><\/div><div class=\"slider slider-boxed\"><div class=\"container\"><div class=\"slider-window\"><div class=\"slider-list\">\t\t<div class=\"slide\">\n\t\t\t<div class=\"box\">\n\t\t\t\t<div class=\"row\">\n\t\t\t\t\t<div class=\"col-md-6 col-lg-4 box-img-wrapper\">\n\t\t\t\t\t\t<img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.capgemini.com\/no-no\/wp-content\/uploads\/sites\/23\/2023\/08\/Expert_Tine-Gevelt.jpg\" alt=\"Tine Gevelt\"\/>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"col-md-6 col-lg-8 box-inner\">\n\t\t\t\t\t\t<div class=\"row title-social-media-header\">\n\t\t\t\t\t\t\t<div class=\"col-md-12 col-lg-6 mbl-social-icon\">\n\t\t\t\t\t\t\t\t<ul class=\"social-nav\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t\t\t\t\t\t<a class=\"subnav-button--form\" href=\"javascript:void(0)\" aria-label=\"contact us\" data-bs-toggle=\"modal\" data-bs-target=\"#WPB5d3b91d9_e7fb_4c8c_b70c_bc9f5bc53d25\" data-bs-expert-title=\"1\">\n\t\t\t\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"ico-form\"><\/i>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><a aria-label=\"Linkedin\" target=\"_blank\" title=\"Opens in a new window\" href=\"https:\/\/www.linkedin.com\/in\/tine-gevelt-5530232\/\"><i aria-hidden=\"true\" class=\"icon-li\"><\/i><\/a><\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"col-md-12 col-lg-6 box-container\">\n\t\t\t\t\t\t\t\t<div class=\"box-title\">\n\t\t\t\t\t\t\t\t\t<h3 class=\"people-profile-title\">Tine Gevelt<\/h3>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span>Head of Financial Services Norway &amp; Chief Sales and Portfolio Officer Financial Service Nordics<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"col-md-12 col-lg-6 social-box-container dkt-social-icon\">\n\t\t\t\t\t\t\t\t<ul class=\"social-nav\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t\t\t\t\t\t<a class=\"subnav-button--form\" href=\"javascript:void(0)\" aria-label=\"contact us\" data-bs-toggle=\"modal\" data-bs-target=\"#WPB5d3b91d9_e7fb_4c8c_b70c_bc9f5bc53d25\" data-bs-expert-title=\"Tine Gevelt\">\n\t\t\t\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"ico-form\"><\/i>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><a aria-label=\"Linkedin\" target=\"_blank\" title=\"Opens in a new window\" href=\"https:\/\/www.linkedin.com\/in\/tine-gevelt-5530232\/\"><i aria-hidden=\"true\" class=\"icon-li\"><\/i><\/a><\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"people-info\">Experienced leader within Financial Services with a demonstrated track record of creating sustainable results working across domains and disciplines. Skilled in Advisory services, IT Strategy, Digitalization, Business Transformation, Management and Business Development.<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"modal\" id=\"WPB5d3b91d9_e7fb_4c8c_b70c_bc9f5bc53d25\">\n\t\t\t\t\t<div class=\"modal-dialog modal-dialog-centered modal-lg modal-dialog-scrollable landing-page-modals\">\n\t\t\t\t\t\t<div class=\"modal-content\">\n\t\t\t\t\t\t\t<div class=\"modal-header\">\n\t\t\t\t\t\t\t\t<button type=\"button\" class=\"btn-close\" aria-label=\"close\" data-bs-dismiss=\"modal\"><\/button>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"modal-body\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"logo-wrapper\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.capgemini.com\/no-no\/wp-content\/themes\/capgemini2025\/assets\/images\/logo.svg\"\n\t\t\t\t\t\t\t\t\t\talt=\"Connect with us\" class=\"light\" \/>\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.capgemini.com\/no-no\/wp-content\/themes\/capgemini2025\/assets\/images\/logo-white.svg\"\n\t\t\t\t\t\t\t\t\t\talt=\"Connect with us\" class=\"dark\" \/>\n\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"form-title\">Connect with us<\/h4>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"mf_forms__container \">\n\t\t\t\t\t\t\t\t<form id=\"mf_form_344241_1863726228\" class=\"mf_form__form row needs-validation\" action=\"\" method=\"post\" enctype=\"multipart\/form-data\" data-nosnippet>\n\t\t\t<div class=\"col-12\">\n\t\t\t\t<div class=\"asterisk_title\">\n\t\t\t\t\t<p><span class=\"star-required\">*<\/span> Mandatory field<\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"col-12\">\n\t\t\t\t<div class=\"mf_form__errors mf_form__errors--top\" role=\"alert\" aria-live=\"polite\">\n\t\t\t\t\t<ul class=\"mf_form__errors__list\"><\/ul>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t<div class=\"mf-field-wrapper form-floating col-sm-12\"><input type=\"text\" class=\"form-control\" id=\"_mf_344241_8430_3871130020\" name=\"_mf_344241_8430\" placeholder=\"First Name\" required \/><label for=\"_mf_344241_8430_3871130020\" class=\"form-label\">First Name <span class=\"star-required\">*<\/span><\/label><div class=\"invalid-feedback-frm\">First Name is not valid.<\/div><\/div><div class=\"mf-field-wrapper form-floating col-sm-12\"><input type=\"text\" class=\"form-control\" id=\"_mf_344241_7950_4064089269\" name=\"_mf_344241_7950\" placeholder=\"Last Name\" required \/><label for=\"_mf_344241_7950_4064089269\" class=\"form-label\">Last Name <span class=\"star-required\">*<\/span><\/label><div class=\"invalid-feedback-frm\">Last Name is not valid.<\/div><\/div><div class=\"mf-field-wrapper form-floating col-sm-12\"><input type=\"email\" class=\"form-control\" id=\"_mf_344241_6828_1448965823\" name=\"_mf_344241_6828\" placeholder=\"Email\" required \/><label for=\"_mf_344241_6828_1448965823\" class=\"form-label\">Email <span class=\"star-required\">*<\/span><\/label><div class=\"invalid-feedback-frm\">Email is not valid.<\/div><\/div><div class=\"mf-field-wrapper form-floating col-sm-12\"><input type=\"text\" class=\"form-control\" id=\"_mf_344241_448_3243915204\" name=\"_mf_344241_448\" placeholder=\"Company\" required \/><label for=\"_mf_344241_448_3243915204\" class=\"form-label\">Company <span class=\"star-required\">*<\/span><\/label><div class=\"invalid-feedback-frm\">Company is not valid.<\/div><\/div>\t\t<div class=\"mf_field mf_field--country mf_field--select floating form-country-select-parent mf-required\">\n\n\t\t\t<label for=\"_mf_344241_7028_2070633106\" class=\"floating__label form-country-select-label\" data-content=\"Country\">\n\t\t\t\t<span class=\"floating-label-content\">Country<\/span>\n\t\t\t<\/label>\n\n\t\t\t<div class=\"select-wrap\">\n<i class=\"icon icon-zodiak-chevron-down\"><\/i>\n\t\t\t\t<select id=\"_mf_344241_7028_2070633106\" class=\"mf_field__input empty mf-country-selectbox form_country_select\" name=\"_mf_344241_7028\" data-validate=\"select\" required>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"\"  selected='selected'>Country<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"AF\" >Afghanistan<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"AX\" >Aland Islands<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"AL\" >Albania<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"DZ\" >Algeria<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"AS\" >American Samoa<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"AD\" >Andorra<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"AO\" >Angola<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"AI\" >Anguilla<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"AQ\" >Antarctica<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"AG\" >Antigua And Barbuda<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"AR\" >Argentina<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"AM\" >Armenia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"AW\" >Aruba<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"AU\" >Australia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"AT\" >Austria<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"AZ\" >Azerbaijan<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"BS\" >Bahamas<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"BH\" >Bahrain<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"BD\" >Bangladesh<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"BB\" >Barbados<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"BY\" >Belarus<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"BE\" >Belgium<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"BZ\" >Belize<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"BJ\" >Benin<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"BM\" >Bermuda<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"BT\" >Bhutan<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"BO\" >Bolivia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"BA\" >Bosnia And Herzegovina<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"BW\" >Botswana<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"BV\" >Bouvet Island<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"BR\" >Brazil<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"IO\" >British Indian Ocean Territory<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"BN\" >Brunei Darussalam<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"BG\" >Bulgaria<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"BF\" >Burkina Faso<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"BI\" >Burundi<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"KH\" >Cambodia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"CM\" >Cameroon<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"CA\" >Canada<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"CV\" >Cape Verde<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"KY\" >Cayman Islands<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"CF\" >Central African Republic<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"TD\" >Chad<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"CL\" >Chile<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"CN\" >China<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"CX\" >Christmas Island<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"CC\" >Cocos (Keeling) Islands<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"CO\" >Colombia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"KM\" >Comoros<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"CG\" >Congo<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"CD\" >Congo, Democratic Republic<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"CK\" >Cook Islands<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"CR\" >Costa Rica<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"CI\" >Cote D&#039;Ivoire<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"HR\" >Croatia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"CU\" >Cuba<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"CY\" >Cyprus<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"CZ\" >Czech Republic<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"DK\" >Denmark<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"DJ\" >Djibouti<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"DM\" >Dominica<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"DO\" >Dominican Republic<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"EC\" >Ecuador<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"EG\" >Egypt<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"SV\" >El Salvador<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"GQ\" >Equatorial Guinea<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"ER\" >Eritrea<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"EE\" >Estonia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"ET\" >Ethiopia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"FK\" >Falkland Islands (Malvinas)<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"FO\" >Faroe Islands<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"FJ\" >Fiji<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"FI\" >Finland<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"FR\" >France<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"GF\" >French Guiana<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"PF\" >French Polynesia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"TF\" >French Southern Territories<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"GA\" >Gabon<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"GM\" >Gambia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"GE\" >Georgia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"DE\" >Germany<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"GH\" >Ghana<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"GI\" >Gibraltar<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"GR\" >Greece<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"GL\" >Greenland<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"GD\" >Grenada<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"GP\" >Guadeloupe<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"GU\" >Guam<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"GT\" >Guatemala<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"GG\" >Guernsey<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"GN\" >Guinea<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"GW\" >Guinea-Bissau<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"GY\" >Guyana<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"HT\" >Haiti<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"HM\" >Heard Island &amp; Mcdonald Islands<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"VA\" >Holy See (Vatican City State)<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"HN\" >Honduras<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"HK\" >Hong Kong<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"HU\" >Hungary<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"IS\" >Iceland<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"IN\" >India<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"ID\" >Indonesia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"IR\" >Iran, Islamic Republic Of<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"IQ\" >Iraq<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"IE\" >Ireland<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"IM\" >Isle Of Man<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"IL\" >Israel<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"IT\" >Italy<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"JM\" >Jamaica<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"JP\" >Japan<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"JE\" >Jersey<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"JO\" >Jordan<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"KZ\" >Kazakhstan<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"KE\" >Kenya<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"KI\" >Kiribati<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"KR\" >Korea<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"KW\" >Kuwait<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"KG\" >Kyrgyzstan<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"LA\" >Lao People&#039;s Democratic Republic<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"LV\" >Latvia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"LB\" >Lebanon<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"LS\" >Lesotho<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"LR\" >Liberia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"LY\" >Libyan Arab Jamahiriya<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"LI\" >Liechtenstein<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"LT\" >Lithuania<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"LU\" >Luxembourg<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"MO\" >Macao<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"MK\" >Macedonia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"MG\" >Madagascar<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"MW\" >Malawi<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"MY\" >Malaysia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"MV\" >Maldives<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"ML\" >Mali<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"MT\" >Malta<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"MH\" >Marshall Islands<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"MQ\" >Martinique<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"MR\" >Mauritania<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"MU\" >Mauritius<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"YT\" >Mayotte<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"MX\" >Mexico<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"FM\" >Micronesia, Federated States Of<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"MD\" >Moldova<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"MC\" >Monaco<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"MN\" >Mongolia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"ME\" >Montenegro<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"MS\" >Montserrat<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"MA\" >Morocco<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"MZ\" >Mozambique<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"MM\" >Myanmar<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"NA\" >Namibia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"NR\" >Nauru<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"NP\" >Nepal<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"NL\" >Netherlands<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"AN\" >Netherlands Antilles<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"NC\" >New Caledonia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"NZ\" >New Zealand<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"NI\" >Nicaragua<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"NE\" >Niger<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"NG\" >Nigeria<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"NU\" >Niue<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"NF\" >Norfolk Island<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"MP\" >Northern Mariana Islands<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"NO\" >Norway<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"OM\" >Oman<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"PK\" >Pakistan<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"PW\" >Palau<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"PS\" >Palestinian Territory, Occupied<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"PA\" >Panama<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"PG\" >Papua New Guinea<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"PY\" >Paraguay<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"PE\" >Peru<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"PH\" >Philippines<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"PN\" >Pitcairn<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"PL\" >Poland<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"PT\" >Portugal<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"PR\" >Puerto Rico<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"QA\" >Qatar<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"RE\" >Reunion<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"RO\" >Romania<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"RU\" >Russian Federation<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"RW\" >Rwanda<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"BL\" >Saint Barthelemy<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"SH\" >Saint Helena<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"KN\" >Saint Kitts And Nevis<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"LC\" >Saint Lucia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"MF\" >Saint Martin<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"PM\" >Saint Pierre And Miquelon<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"VC\" >Saint Vincent And Grenadines<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"WS\" >Samoa<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"SM\" >San Marino<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"ST\" >Sao Tome And Principe<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"SA\" >Saudi Arabia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"SN\" >Senegal<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"RS\" >Serbia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"SC\" >Seychelles<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"SL\" >Sierra Leone<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"SG\" >Singapore<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"SK\" >Slovakia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"SI\" >Slovenia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"SB\" >Solomon Islands<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"SO\" >Somalia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"ZA\" >South Africa<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"GS\" >South Georgia And Sandwich Isl.<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"ES\" >Spain<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"LK\" >Sri Lanka<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"SD\" >Sudan<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"SR\" >Suriname<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"SJ\" >Svalbard And Jan Mayen<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"SZ\" >Swaziland<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"SE\" >Sweden<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"CH\" >Switzerland<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"SY\" >Syrian Arab Republic<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"TW\" >Taiwan<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"TJ\" >Tajikistan<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"TZ\" >Tanzania<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"TH\" >Thailand<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"TL\" >Timor-Leste<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"TG\" >Togo<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"TK\" >Tokelau<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"TO\" >Tonga<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"TT\" >Trinidad And Tobago<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"TN\" >Tunisia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"TR\" >Turkey<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"TM\" >Turkmenistan<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"TC\" >Turks And Caicos Islands<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"TV\" >Tuvalu<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"UG\" >Uganda<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"UA\" >Ukraine<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"AE\" >United Arab Emirates<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"GB\" >United Kingdom<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"US\" >United States<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"UM\" >United States Outlying Islands<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"UY\" >Uruguay<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"UZ\" >Uzbekistan<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"VU\" >Vanuatu<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"VE\" >Venezuela<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"VN\" >Viet Nam<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"VG\" >Virgin Islands, British<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"VI\" >Virgin Islands, U.S.<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"WF\" >Wallis And Futuna<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"EH\" >Western Sahara<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"YE\" >Yemen<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"ZM\" >Zambia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"ZW\" >Zimbabwe<\/option>\n\t\t\t\t\t\t\t\t\t<\/select>\n\n\t\t\t\t<div class=\"invalid-feedback-frm\">Country is not valid.<\/div>\n\t\t\t<\/div>\n\n\t\t<\/div>\n\n\t\t<script type=\"text\/javascript\">\n            jQuery(document).ready(function($) {\n                $('.mf_form__form').each(function() {\n                    var $form = $(this); \/\/ This specific form instance\n\n                    \/\/ Find the country select in this form\n                    $form.find('.form_country_select').each(function() {\n                        var $select = $(this);\n\t\t\t\t\t\tvar clickCount = 0;\n                        \/\/ On change\n                        $select.on('click', function() {\n\t\t\t\t\t\t\tclickCount++;\n\t\t\t\t\t\t\tif (clickCount === 1) {\n\t\t\t\t\t\t\t\t$(this).parent().find('.icon-zodiak-chevron-down').addClass('active');\n\t\t\t\t\t\t\t} else {\n\t\t\t\t\t\t\t\tclickCount = 0;\n\t\t\t\t\t\t\t\t$(this).parent().find('.icon-zodiak-chevron-down').removeClass('active');\n\t\t\t\t\t\t\t}\n\t\t\t\t\t\t});\n\t\t\t\t\t\t$select.on('blur', function() {\n\t\t\t\t\t\t\tclickCount = 0;\n\t\t\t\t\t\t\t$(this).parent().find('.icon-zodiak-chevron-down').removeClass('active');\n\t\t\t\t\t\t});\n                    });\n                });\n            });\n        <\/script>\n\n\t\t<div class=\"mf-field-wrapper form-floating col-sm-12\"><input type=\"text\" pattern=\"^[0-9\\-\\+\\s]+$\"  class=\"form-control\" id=\"_mf_344241_4361_2722560160\" name=\"_mf_344241_4361\" oninput=\"validateInput(this)\" maxlength=\"14\" placeholder=\"Phone\"  \/><label for=\"_mf_344241_4361_2722560160\" class=\"form-label\">Phone (optional)<\/label><\/div><div class=\"mf-field-wrapper form-floating col-sm-12\"><textarea type=\"text\" class=\"form-control\" id=\"_mf_344241_6784_510989939\" name=\"_mf_344241_6784\" placeholder=\"Your Message\" required><\/textarea><label for=\"_mf_344241_6784_510989939\" class=\"form-label\">Your Message <span class=\"star-required\">*<\/span><\/label><div class=\"invalid-feedback-frm\">Your Message is not valid.<\/div><\/div><div class=\"mf-field-wrapper  col-sm-12\">\n\t\t<div class=\"form-check checkbox-controls\">\n\n\t\t\t<input type=\"checkbox\" id=\"_mf_344241_781_761418689\" class=\"form-check-input\"\n\t\t\t\tname=\"_mf_344241_781[]\"\n\t\t\t\tvalue=\"1\"\n\t\t\t\trequired\n\t\t\t>\n\n\t\t\t<label for=\"_mf_344241_781_761418689\" class=\"form-check-label consent-text\">\n\t\t\t\tI agree to Capgemini collecting and processing my personal data to allow me to receive information on Capgemini services. For further information, please see <a href=\"https:\/\/www.capgemini.com\/no-no\/privacy-notice\/\" target=\"_blank\">our Privacy Notice<\/a>.  &nbsp;\t\t\t<\/label>\n\n\t\t<\/div>\n\t\t<\/div>\t\t\t<div class=\"mf_field mf_field--hidden \">\n\t\t\t\t<label for=\"_mf_344241_1688_1761174939\">Expert title\t\t\t\t\t<\/label>\n\t\t\t\t<input type=\"hidden\" id=\"_mf_344241_1688_1761174939\" class=\"mf_field__input empty\" name=\"_mf_344241_1688\" data-validate=\"text\" data-hidden-field-tag=\"expert_title\" value=\"\"  \/>\n\t\t\t<\/div>\n\t\t\t\t\t<div class=\"mf_field mf_field--hidden \">\n\t\t\t\t<label for=\"_mf_344241_7135_4188075696\">Page URL\t\t\t\t\t<\/label>\n\t\t\t\t<input\n\t\t\t\t\ttype=\"hidden\"\n\t\t\t\t\tid=\"_mf_344241_7135_4188075696\"\n\t\t\t\t\tclass=\"mf_field__input empty\"\n\t\t\t\t\tname=\"_mf_344241_7135\"\n\t\t\t\t\tdata-validate=\"text\"\n\t\t\t\t\tvalue=\"https:\/\/www.capgemini.com\/no-no\/industries\/banking-and-capital-markets\/retail-and-commercial-banking\/\"\n\t\t\t\t\t\t\t\t\t\/>\n\t\t\t<\/div>\n\t\t\t\t\t<div class=\"mf_field mf_field--recaptcha\">\n\t\t\t\t<div class=\"g-recaptcha\" data-sitekey=\"6Lc3OpIUAAAAADY4ErEHF0HF6Tr7vuknduDU-fbl\"><\/div>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t<div class=\"mf_field mf_field--submit\" >\n\t\t\t\t<div class=\"slide-button-background button-background\">\n\t\t\t\t\t<label for=\"slider-submit-_mf_344241_1145\" class=\"slide-text\">\n\t\t\t\t\t\tSlide to submit\t\t\t\t\t<\/label>\n\t\t\t\t\t<input\n\t\t\t\t\t\tid=\"slider-submit-_mf_344241_1145\"\n\t\t\t\t\t\ttype=\"range\"\n\t\t\t\t\t\tclass=\"mf_field__input slider-frm-btn\"\n\t\t\t\t\t\trel=\"_mf_344241_1145\"\n\t\t\t\t\t\tmin=\"0\"\n\t\t\t\t\t\tmax=\"100\"\n\t\t\t\t\t\tvalue=\"0\"\n\t\t\t\t\t\taria-label=\"Slide to submit\"\n\t\t\t\t\t\taria-describedby=\"slide-instruction-_mf_344241_1145\"\n\t\t\t\t\t\taria-valuenow=\"0\"\n\t\t\t\t\t\taria-valuemin=\"0\"\n\t\t\t\t\t\taria-valuemax=\"100\"\n\t\t\t\t\t\taria-orientation=\"horizontal\"\n\t\t\t\t\t\trole=\"slider\"\n\t\t\t\t\t\ttabindex=\"0\"\n\t\t\t\t\t\/>\n\t\t\t\t\t<!-- Icon element for Firefox (doesn't support ::before\/::after on inputs) -->\n\t\t\t\t\t<span class=\"slider-icon\" aria-hidden=\"true\"><\/span>\n\t\t\t\t\t<span id=\"slide-instruction-_mf_344241_1145\" class=\"sr-only\">\n\t\t\t\t\t\tUse right arrow keys to slide, or drag right with your finger. When you reach 100 percent, the form is submitted.\t\t\t\t\t<\/span>\n\t\t\t\t\t<!-- Mobile-only submit button fallback -->\n\t\t\t\t\t<button type=\"submit\" class=\"mf-mobile-submit-btn\" disabled>\n\t\t\t\t\t\t<span class=\"sr-only\">If you use a screen reader or VoiceOver, double-tap this button to submit the form.<\/span>\n\t\t\t\t\t\tSlide to submit\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t\t<input type=\"hidden\" name=\"submit_btn_txt\" class=\"submit_btn_txt\" value=\"Slide to submit\"\/>\n\t\t\t\t<input type=\"hidden\" name=\"submitted_state_txt\" class=\"submitted_state_txt\" value=\"Submitted\"\/>\n\t\t\t<\/div>\n\t\t\t\t\t\t<input type=\"hidden\" name=\"form_id\" data-validate=\"number\" class=\"mf_form__id\" value=\"344241\" \/>\n\t\t\t\t<input type=\"hidden\" name=\"form_title\" class=\"mf_form__title\" value=\"revamp-new-expert-form\" \/>\n\t\t\t\t<input type=\"hidden\" name=\"wp_rest_nonce\" class=\"mf_form__wp_rest_nonce\" value=\"3fb441f171\" \/>\n\n\t\t\t\t<input type=\"hidden\" name=\"mf_form_conditional_logic\" class=\"mf_form__title conditional_logic\" value=\"\" \/>\n\t\t\t\t\n\t\t\t\t<input type=\"hidden\" name=\"mf_form_fields_country_dpo_field\" class=\"mf_form__title conditional_logic mf_form_fields_country_dpo_field\" value=\"\" \/>\n\n\t\t\t\t<!-- Anti-spam field -->\n\t\t\t\t<input type=\"text\" \n\t\t\t\t\tname=\"website_url\" \n\t\t\t\t\tclass=\"mf_field__url\" \n\t\t\t\t\tautocomplete=\"off\"\n\t\t\t\t\ttabindex=\"-1\"\n\t\t\t\t\taria-hidden=\"true\"\n\t\t\t\t\tstyle=\"position:absolute;left:-9999px;width:1px;height:1px;opacity:0;pointer-events:none;\" \n\t\t\t\t\/>\n\t\t\t<\/form>\n\n\t\t\t<div class=\"mf_form__success\" tabindex=\"0\" role=\"alert\">\n\t\t\t\tThank you for your submission. We will be in touch with you soon!<\/p>\n\t\t\t<\/div>\n\t\t\t<div class=\"mf_form__errors\">\n\t\t\t\t<p>We are sorry, the form submission failed. Please try again.<\/p>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t<script>\n\t\t\twindow.MF_CONFIG344241 = {\"344241\":{\"errors\":[],\"redirect\":\"\"}};\n\t\t<\/script>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\n\n\t\t<div class=\"slide\">\n\t\t\t<div class=\"box\">\n\t\t\t\t<div class=\"row\">\n\t\t\t\t\t<div class=\"col-md-6 col-lg-4 box-img-wrapper\">\n\t\t\t\t\t\t<img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.capgemini.com\/no-no\/wp-content\/uploads\/sites\/23\/2022\/12\/Espen-Stokke.jpg\" alt=\"Espen Stokke\"\/>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"col-md-6 col-lg-8 box-inner\">\n\t\t\t\t\t\t<div class=\"row title-social-media-header\">\n\t\t\t\t\t\t\t<div class=\"col-md-12 col-lg-6 mbl-social-icon\">\n\t\t\t\t\t\t\t\t<ul class=\"social-nav\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t\t\t\t\t\t<a class=\"subnav-button--form\" href=\"javascript:void(0)\" aria-label=\"contact us\" data-bs-toggle=\"modal\" data-bs-target=\"#WPB5d3b91d9_e7fb_4c8c_b70c_bc9f5bc53d25\" data-bs-expert-title=\"1\">\n\t\t\t\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"ico-form\"><\/i>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"col-md-12 col-lg-6 box-container\">\n\t\t\t\t\t\t\t\t<div class=\"box-title\">\n\t\t\t\t\t\t\t\t\t<h3 class=\"people-profile-title\">Espen Stokke<\/h3>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span>Director, Banking &amp; Insurance, Retail banking<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"col-md-12 col-lg-6 social-box-container dkt-social-icon\">\n\t\t\t\t\t\t\t\t<ul class=\"social-nav\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t\t\t\t\t\t<a class=\"subnav-button--form\" href=\"javascript:void(0)\" aria-label=\"contact us\" data-bs-toggle=\"modal\" data-bs-target=\"#WPB5d3b91d9_e7fb_4c8c_b70c_bc9f5bc53d25\" data-bs-expert-title=\"Espen Stokke\">\n\t\t\t\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"ico-form\"><\/i>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"people-info\">Espen has 18 years of experience from the banking industry, both from various positions in Norway&#8217;s largest bank and as management consultant. His main areas of expertise are digital transformation\/IT implementation projects, retail banking, customer experience, and payments<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"modal\" id=\"WPB5d3b91d9_e7fb_4c8c_b70c_bc9f5bc53d25\">\n\t\t\t\t\t<div class=\"modal-dialog modal-dialog-centered modal-lg modal-dialog-scrollable landing-page-modals\">\n\t\t\t\t\t\t<div class=\"modal-content\">\n\t\t\t\t\t\t\t<div class=\"modal-header\">\n\t\t\t\t\t\t\t\t<button type=\"button\" class=\"btn-close\" aria-label=\"close\" data-bs-dismiss=\"modal\"><\/button>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"modal-body\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"logo-wrapper\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.capgemini.com\/no-no\/wp-content\/themes\/capgemini2025\/assets\/images\/logo.svg\"\n\t\t\t\t\t\t\t\t\t\talt=\"Connect with us\" class=\"light\" \/>\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.capgemini.com\/no-no\/wp-content\/themes\/capgemini2025\/assets\/images\/logo-white.svg\"\n\t\t\t\t\t\t\t\t\t\talt=\"Connect with us\" class=\"dark\" \/>\n\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"form-title\">Connect with us<\/h4>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"mf_forms__container \">\n\t\t\t\t\t\t\t\t<form id=\"mf_form_344241_1473652453\" class=\"mf_form__form row needs-validation\" action=\"\" method=\"post\" enctype=\"multipart\/form-data\" data-nosnippet>\n\t\t\t<div class=\"col-12\">\n\t\t\t\t<div class=\"asterisk_title\">\n\t\t\t\t\t<p><span class=\"star-required\">*<\/span> Mandatory field<\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"col-12\">\n\t\t\t\t<div class=\"mf_form__errors mf_form__errors--top\" role=\"alert\" aria-live=\"polite\">\n\t\t\t\t\t<ul class=\"mf_form__errors__list\"><\/ul>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t<div class=\"mf-field-wrapper form-floating col-sm-12\"><input type=\"text\" class=\"form-control\" id=\"_mf_344241_8430_1267137533\" name=\"_mf_344241_8430\" placeholder=\"First Name\" required \/><label for=\"_mf_344241_8430_1267137533\" class=\"form-label\">First Name <span class=\"star-required\">*<\/span><\/label><div class=\"invalid-feedback-frm\">First Name is not valid.<\/div><\/div><div class=\"mf-field-wrapper form-floating col-sm-12\"><input type=\"text\" class=\"form-control\" id=\"_mf_344241_7950_462524840\" name=\"_mf_344241_7950\" placeholder=\"Last Name\" required \/><label for=\"_mf_344241_7950_462524840\" class=\"form-label\">Last Name <span class=\"star-required\">*<\/span><\/label><div class=\"invalid-feedback-frm\">Last Name is not valid.<\/div><\/div><div class=\"mf-field-wrapper form-floating col-sm-12\"><input type=\"email\" class=\"form-control\" id=\"_mf_344241_6828_2969111970\" name=\"_mf_344241_6828\" placeholder=\"Email\" required \/><label for=\"_mf_344241_6828_2969111970\" class=\"form-label\">Email <span class=\"star-required\">*<\/span><\/label><div class=\"invalid-feedback-frm\">Email is not valid.<\/div><\/div><div class=\"mf-field-wrapper form-floating col-sm-12\"><input type=\"text\" class=\"form-control\" id=\"_mf_344241_448_2717093592\" name=\"_mf_344241_448\" placeholder=\"Company\" required \/><label for=\"_mf_344241_448_2717093592\" class=\"form-label\">Company <span class=\"star-required\">*<\/span><\/label><div class=\"invalid-feedback-frm\">Company is not valid.<\/div><\/div>\t\t<div class=\"mf_field mf_field--country mf_field--select floating form-country-select-parent mf-required\">\n\n\t\t\t<label for=\"_mf_344241_7028_3904015023\" class=\"floating__label form-country-select-label\" data-content=\"Country\">\n\t\t\t\t<span class=\"floating-label-content\">Country<\/span>\n\t\t\t<\/label>\n\n\t\t\t<div class=\"select-wrap\">\n<i class=\"icon icon-zodiak-chevron-down\"><\/i>\n\t\t\t\t<select id=\"_mf_344241_7028_3904015023\" class=\"mf_field__input empty mf-country-selectbox form_country_select\" name=\"_mf_344241_7028\" data-validate=\"select\" required>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"\"  selected='selected'>Country<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"AF\" >Afghanistan<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"AX\" >Aland Islands<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"AL\" >Albania<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"DZ\" >Algeria<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"AS\" >American Samoa<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"AD\" >Andorra<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"AO\" >Angola<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"AI\" >Anguilla<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"AQ\" >Antarctica<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"AG\" >Antigua And Barbuda<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"AR\" >Argentina<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"AM\" >Armenia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"AW\" >Aruba<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"AU\" >Australia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"AT\" >Austria<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"AZ\" >Azerbaijan<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"BS\" >Bahamas<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"BH\" >Bahrain<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"BD\" >Bangladesh<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"BB\" >Barbados<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"BY\" >Belarus<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"BE\" >Belgium<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"BZ\" >Belize<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"BJ\" >Benin<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"BM\" >Bermuda<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"BT\" >Bhutan<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"BO\" >Bolivia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"BA\" >Bosnia And Herzegovina<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"BW\" >Botswana<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"BV\" >Bouvet Island<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"BR\" >Brazil<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"IO\" >British Indian Ocean Territory<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"BN\" >Brunei Darussalam<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"BG\" >Bulgaria<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"BF\" >Burkina Faso<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"BI\" >Burundi<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"KH\" >Cambodia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"CM\" >Cameroon<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"CA\" >Canada<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"CV\" >Cape Verde<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"KY\" >Cayman Islands<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"CF\" >Central African Republic<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"TD\" >Chad<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"CL\" >Chile<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"CN\" >China<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"CX\" >Christmas Island<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"CC\" >Cocos (Keeling) Islands<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"CO\" >Colombia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"KM\" >Comoros<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"CG\" >Congo<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"CD\" >Congo, Democratic Republic<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"CK\" >Cook Islands<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"CR\" >Costa Rica<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"CI\" >Cote D&#039;Ivoire<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"HR\" >Croatia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"CU\" >Cuba<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"CY\" >Cyprus<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"CZ\" >Czech Republic<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"DK\" >Denmark<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"DJ\" >Djibouti<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"DM\" >Dominica<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"DO\" >Dominican Republic<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"EC\" >Ecuador<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"EG\" >Egypt<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"SV\" >El Salvador<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"GQ\" >Equatorial Guinea<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"ER\" >Eritrea<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"EE\" >Estonia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"ET\" >Ethiopia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"FK\" >Falkland Islands (Malvinas)<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"FO\" >Faroe Islands<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"FJ\" >Fiji<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"FI\" >Finland<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"FR\" >France<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"GF\" >French Guiana<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"PF\" >French Polynesia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"TF\" >French Southern Territories<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"GA\" >Gabon<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"GM\" >Gambia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"GE\" >Georgia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"DE\" >Germany<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"GH\" >Ghana<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"GI\" >Gibraltar<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"GR\" >Greece<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"GL\" >Greenland<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"GD\" >Grenada<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"GP\" >Guadeloupe<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"GU\" >Guam<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"GT\" >Guatemala<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"GG\" >Guernsey<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"GN\" >Guinea<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"GW\" >Guinea-Bissau<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"GY\" >Guyana<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"HT\" >Haiti<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"HM\" >Heard Island &amp; Mcdonald Islands<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"VA\" >Holy See (Vatican City State)<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"HN\" >Honduras<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"HK\" >Hong Kong<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"HU\" >Hungary<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"IS\" >Iceland<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"IN\" >India<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"ID\" >Indonesia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"IR\" >Iran, Islamic Republic Of<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"IQ\" >Iraq<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"IE\" >Ireland<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"IM\" >Isle Of Man<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"IL\" >Israel<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"IT\" >Italy<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"JM\" >Jamaica<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"JP\" >Japan<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"JE\" >Jersey<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"JO\" >Jordan<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"KZ\" >Kazakhstan<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"KE\" >Kenya<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"KI\" >Kiribati<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"KR\" >Korea<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"KW\" >Kuwait<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"KG\" >Kyrgyzstan<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"LA\" >Lao People&#039;s Democratic Republic<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"LV\" >Latvia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"LB\" >Lebanon<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"LS\" >Lesotho<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"LR\" >Liberia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"LY\" >Libyan Arab Jamahiriya<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"LI\" >Liechtenstein<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"LT\" >Lithuania<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"LU\" >Luxembourg<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"MO\" >Macao<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"MK\" >Macedonia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"MG\" >Madagascar<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"MW\" >Malawi<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"MY\" >Malaysia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"MV\" >Maldives<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"ML\" >Mali<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"MT\" >Malta<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"MH\" >Marshall Islands<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"MQ\" >Martinique<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"MR\" >Mauritania<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"MU\" >Mauritius<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"YT\" >Mayotte<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"MX\" >Mexico<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"FM\" >Micronesia, Federated States Of<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"MD\" >Moldova<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"MC\" >Monaco<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"MN\" >Mongolia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"ME\" >Montenegro<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"MS\" >Montserrat<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"MA\" >Morocco<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"MZ\" >Mozambique<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"MM\" >Myanmar<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"NA\" >Namibia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"NR\" >Nauru<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"NP\" >Nepal<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"NL\" >Netherlands<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"AN\" >Netherlands Antilles<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"NC\" >New Caledonia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"NZ\" >New Zealand<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"NI\" >Nicaragua<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"NE\" >Niger<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"NG\" >Nigeria<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"NU\" >Niue<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"NF\" >Norfolk Island<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"MP\" >Northern Mariana Islands<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"NO\" >Norway<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"OM\" >Oman<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"PK\" >Pakistan<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"PW\" >Palau<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"PS\" >Palestinian Territory, Occupied<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"PA\" >Panama<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"PG\" >Papua New Guinea<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"PY\" >Paraguay<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"PE\" >Peru<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"PH\" >Philippines<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"PN\" >Pitcairn<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"PL\" >Poland<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"PT\" >Portugal<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"PR\" >Puerto Rico<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"QA\" >Qatar<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"RE\" >Reunion<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"RO\" >Romania<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"RU\" >Russian Federation<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"RW\" >Rwanda<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"BL\" >Saint Barthelemy<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"SH\" >Saint Helena<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"KN\" >Saint Kitts And Nevis<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"LC\" >Saint Lucia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"MF\" >Saint Martin<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"PM\" >Saint Pierre And Miquelon<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"VC\" >Saint Vincent And Grenadines<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"WS\" >Samoa<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"SM\" >San Marino<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"ST\" >Sao Tome And Principe<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"SA\" >Saudi Arabia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"SN\" >Senegal<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"RS\" >Serbia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"SC\" >Seychelles<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"SL\" >Sierra Leone<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"SG\" >Singapore<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"SK\" >Slovakia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"SI\" >Slovenia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"SB\" >Solomon Islands<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"SO\" >Somalia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"ZA\" >South Africa<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"GS\" >South Georgia And Sandwich Isl.<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"ES\" >Spain<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"LK\" >Sri Lanka<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"SD\" >Sudan<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"SR\" >Suriname<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"SJ\" >Svalbard And Jan Mayen<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"SZ\" >Swaziland<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"SE\" >Sweden<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"CH\" >Switzerland<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"SY\" >Syrian Arab Republic<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"TW\" >Taiwan<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"TJ\" >Tajikistan<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"TZ\" >Tanzania<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"TH\" >Thailand<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"TL\" >Timor-Leste<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"TG\" >Togo<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"TK\" >Tokelau<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"TO\" >Tonga<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"TT\" >Trinidad And Tobago<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"TN\" >Tunisia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"TR\" >Turkey<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"TM\" >Turkmenistan<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"TC\" >Turks And Caicos Islands<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"TV\" >Tuvalu<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"UG\" >Uganda<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"UA\" >Ukraine<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"AE\" >United Arab Emirates<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"GB\" >United Kingdom<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"US\" >United States<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"UM\" >United States Outlying Islands<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"UY\" >Uruguay<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"UZ\" >Uzbekistan<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"VU\" >Vanuatu<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"VE\" >Venezuela<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"VN\" >Viet Nam<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"VG\" >Virgin Islands, British<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"VI\" >Virgin Islands, U.S.<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"WF\" >Wallis And Futuna<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"EH\" >Western Sahara<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"YE\" >Yemen<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"ZM\" >Zambia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"ZW\" >Zimbabwe<\/option>\n\t\t\t\t\t\t\t\t\t<\/select>\n\n\t\t\t\t<div class=\"invalid-feedback-frm\">Country is not valid.<\/div>\n\t\t\t<\/div>\n\n\t\t<\/div>\n\n\t\t<script type=\"text\/javascript\">\n            jQuery(document).ready(function($) {\n                $('.mf_form__form').each(function() {\n                    var $form = $(this); \/\/ This specific form instance\n\n                    \/\/ Find the country select in this form\n                    $form.find('.form_country_select').each(function() {\n                        var $select = $(this);\n\t\t\t\t\t\tvar clickCount = 0;\n                        \/\/ On change\n                        $select.on('click', function() {\n\t\t\t\t\t\t\tclickCount++;\n\t\t\t\t\t\t\tif (clickCount === 1) {\n\t\t\t\t\t\t\t\t$(this).parent().find('.icon-zodiak-chevron-down').addClass('active');\n\t\t\t\t\t\t\t} else {\n\t\t\t\t\t\t\t\tclickCount = 0;\n\t\t\t\t\t\t\t\t$(this).parent().find('.icon-zodiak-chevron-down').removeClass('active');\n\t\t\t\t\t\t\t}\n\t\t\t\t\t\t});\n\t\t\t\t\t\t$select.on('blur', function() {\n\t\t\t\t\t\t\tclickCount = 0;\n\t\t\t\t\t\t\t$(this).parent().find('.icon-zodiak-chevron-down').removeClass('active');\n\t\t\t\t\t\t});\n                    });\n                });\n            });\n        <\/script>\n\n\t\t<div class=\"mf-field-wrapper form-floating col-sm-12\"><input type=\"text\" pattern=\"^[0-9\\-\\+\\s]+$\"  class=\"form-control\" id=\"_mf_344241_4361_4043438805\" name=\"_mf_344241_4361\" oninput=\"validateInput(this)\" maxlength=\"14\" placeholder=\"Phone\"  \/><label for=\"_mf_344241_4361_4043438805\" class=\"form-label\">Phone (optional)<\/label><\/div><div class=\"mf-field-wrapper form-floating col-sm-12\"><textarea type=\"text\" class=\"form-control\" id=\"_mf_344241_6784_3314229613\" name=\"_mf_344241_6784\" placeholder=\"Your Message\" required><\/textarea><label for=\"_mf_344241_6784_3314229613\" class=\"form-label\">Your Message <span class=\"star-required\">*<\/span><\/label><div class=\"invalid-feedback-frm\">Your Message is not valid.<\/div><\/div><div class=\"mf-field-wrapper  col-sm-12\">\n\t\t<div class=\"form-check checkbox-controls\">\n\n\t\t\t<input type=\"checkbox\" id=\"_mf_344241_781_326991810\" class=\"form-check-input\"\n\t\t\t\tname=\"_mf_344241_781[]\"\n\t\t\t\tvalue=\"1\"\n\t\t\t\trequired\n\t\t\t>\n\n\t\t\t<label for=\"_mf_344241_781_326991810\" class=\"form-check-label consent-text\">\n\t\t\t\tI agree to Capgemini collecting and processing my personal data to allow me to receive information on Capgemini services. For further information, please see <a href=\"https:\/\/www.capgemini.com\/no-no\/privacy-notice\/\" target=\"_blank\">our Privacy Notice<\/a>.  &nbsp;\t\t\t<\/label>\n\n\t\t<\/div>\n\t\t<\/div>\t\t\t<div class=\"mf_field mf_field--hidden \">\n\t\t\t\t<label for=\"_mf_344241_1688_1983746655\">Expert title\t\t\t\t\t<\/label>\n\t\t\t\t<input type=\"hidden\" id=\"_mf_344241_1688_1983746655\" class=\"mf_field__input empty\" name=\"_mf_344241_1688\" data-validate=\"text\" data-hidden-field-tag=\"expert_title\" value=\"\"  \/>\n\t\t\t<\/div>\n\t\t\t\t\t<div class=\"mf_field mf_field--hidden \">\n\t\t\t\t<label for=\"_mf_344241_7135_2630163341\">Page URL\t\t\t\t\t<\/label>\n\t\t\t\t<input\n\t\t\t\t\ttype=\"hidden\"\n\t\t\t\t\tid=\"_mf_344241_7135_2630163341\"\n\t\t\t\t\tclass=\"mf_field__input empty\"\n\t\t\t\t\tname=\"_mf_344241_7135\"\n\t\t\t\t\tdata-validate=\"text\"\n\t\t\t\t\tvalue=\"https:\/\/www.capgemini.com\/no-no\/industries\/banking-and-capital-markets\/retail-and-commercial-banking\/\"\n\t\t\t\t\t\t\t\t\t\/>\n\t\t\t<\/div>\n\t\t\t\t\t<div class=\"mf_field mf_field--recaptcha\">\n\t\t\t\t<div class=\"g-recaptcha\" data-sitekey=\"6Lc3OpIUAAAAADY4ErEHF0HF6Tr7vuknduDU-fbl\"><\/div>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t<div class=\"mf_field mf_field--submit\" >\n\t\t\t\t<div class=\"slide-button-background button-background\">\n\t\t\t\t\t<label for=\"slider-submit-_mf_344241_1145\" class=\"slide-text\">\n\t\t\t\t\t\tSlide to submit\t\t\t\t\t<\/label>\n\t\t\t\t\t<input\n\t\t\t\t\t\tid=\"slider-submit-_mf_344241_1145\"\n\t\t\t\t\t\ttype=\"range\"\n\t\t\t\t\t\tclass=\"mf_field__input slider-frm-btn\"\n\t\t\t\t\t\trel=\"_mf_344241_1145\"\n\t\t\t\t\t\tmin=\"0\"\n\t\t\t\t\t\tmax=\"100\"\n\t\t\t\t\t\tvalue=\"0\"\n\t\t\t\t\t\taria-label=\"Slide to submit\"\n\t\t\t\t\t\taria-describedby=\"slide-instruction-_mf_344241_1145\"\n\t\t\t\t\t\taria-valuenow=\"0\"\n\t\t\t\t\t\taria-valuemin=\"0\"\n\t\t\t\t\t\taria-valuemax=\"100\"\n\t\t\t\t\t\taria-orientation=\"horizontal\"\n\t\t\t\t\t\trole=\"slider\"\n\t\t\t\t\t\ttabindex=\"0\"\n\t\t\t\t\t\/>\n\t\t\t\t\t<!-- Icon element for Firefox (doesn't support ::before\/::after on inputs) -->\n\t\t\t\t\t<span class=\"slider-icon\" aria-hidden=\"true\"><\/span>\n\t\t\t\t\t<span id=\"slide-instruction-_mf_344241_1145\" class=\"sr-only\">\n\t\t\t\t\t\tUse right arrow keys to slide, or drag right with your finger. When you reach 100 percent, the form is submitted.\t\t\t\t\t<\/span>\n\t\t\t\t\t<!-- Mobile-only submit button fallback -->\n\t\t\t\t\t<button type=\"submit\" class=\"mf-mobile-submit-btn\" disabled>\n\t\t\t\t\t\t<span class=\"sr-only\">If you use a screen reader or VoiceOver, double-tap this button to submit the form.<\/span>\n\t\t\t\t\t\tSlide to submit\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t\t<input type=\"hidden\" name=\"submit_btn_txt\" class=\"submit_btn_txt\" value=\"Slide to submit\"\/>\n\t\t\t\t<input type=\"hidden\" name=\"submitted_state_txt\" class=\"submitted_state_txt\" value=\"Submitted\"\/>\n\t\t\t<\/div>\n\t\t\t\t\t\t<input type=\"hidden\" name=\"form_id\" data-validate=\"number\" class=\"mf_form__id\" value=\"344241\" \/>\n\t\t\t\t<input type=\"hidden\" name=\"form_title\" class=\"mf_form__title\" value=\"revamp-new-expert-form\" \/>\n\t\t\t\t<input type=\"hidden\" name=\"wp_rest_nonce\" class=\"mf_form__wp_rest_nonce\" value=\"3fb441f171\" \/>\n\n\t\t\t\t<input type=\"hidden\" name=\"mf_form_conditional_logic\" class=\"mf_form__title conditional_logic\" value=\"\" \/>\n\t\t\t\t\n\t\t\t\t<input type=\"hidden\" name=\"mf_form_fields_country_dpo_field\" class=\"mf_form__title conditional_logic mf_form_fields_country_dpo_field\" value=\"\" \/>\n\n\t\t\t\t<!-- Anti-spam field -->\n\t\t\t\t<input type=\"text\" \n\t\t\t\t\tname=\"website_url\" \n\t\t\t\t\tclass=\"mf_field__url\" \n\t\t\t\t\tautocomplete=\"off\"\n\t\t\t\t\ttabindex=\"-1\"\n\t\t\t\t\taria-hidden=\"true\"\n\t\t\t\t\tstyle=\"position:absolute;left:-9999px;width:1px;height:1px;opacity:0;pointer-events:none;\" \n\t\t\t\t\/>\n\t\t\t<\/form>\n\n\t\t\t<div class=\"mf_form__success\" tabindex=\"0\" role=\"alert\">\n\t\t\t\tThank you for your submission. We will be in touch with you soon!<\/p>\n\t\t\t<\/div>\n\t\t\t<div class=\"mf_form__errors\">\n\t\t\t\t<p>We are sorry, the form submission failed. Please try again.<\/p>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t<script>\n\t\t\twindow.MF_CONFIG344241 = {\"344241\":{\"errors\":[],\"redirect\":\"\"}};\n\t\t<\/script>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\n\n\t\t<div class=\"slide\">\n\t\t\t<div class=\"box\">\n\t\t\t\t<div class=\"row\">\n\t\t\t\t\t<div class=\"col-md-6 col-lg-4 box-img-wrapper\">\n\t\t\t\t\t\t<img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.capgemini.com\/no-no\/wp-content\/uploads\/sites\/23\/2022\/12\/Marianne-Moe-Helgesen.jpg\" alt=\"Marianne Moe-Helgesen\"\/>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"col-md-6 col-lg-8 box-inner\">\n\t\t\t\t\t\t<div class=\"row title-social-media-header\">\n\t\t\t\t\t\t\t<div class=\"col-md-12 col-lg-6 mbl-social-icon\">\n\t\t\t\t\t\t\t\t<ul class=\"social-nav\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t\t\t\t\t\t<a class=\"subnav-button--form\" href=\"javascript:void(0)\" aria-label=\"contact us\" data-bs-toggle=\"modal\" data-bs-target=\"#WPB5d3b91d9_e7fb_4c8c_b70c_bc9f5bc53d25\" data-bs-expert-title=\"1\">\n\t\t\t\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"ico-form\"><\/i>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"col-md-12 col-lg-6 box-container\">\n\t\t\t\t\t\t\t\t<div class=\"box-title\">\n\t\t\t\t\t\t\t\t\t<h3 class=\"people-profile-title\">Marianne Moe-Helgesen<\/h3>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span>Director, Banking &amp; Insurance, Digital transfomation, agile<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"col-md-12 col-lg-6 social-box-container dkt-social-icon\">\n\t\t\t\t\t\t\t\t<ul class=\"social-nav\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t\t\t\t\t\t<a class=\"subnav-button--form\" href=\"javascript:void(0)\" aria-label=\"contact us\" data-bs-toggle=\"modal\" data-bs-target=\"#WPB5d3b91d9_e7fb_4c8c_b70c_bc9f5bc53d25\" data-bs-expert-title=\"Marianne Moe-Helgesen\">\n\t\t\t\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"ico-form\"><\/i>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"people-info\">Marianne has more than 15 years of experience from the insurance industry. Passionate about digital business transformation and agile ways of working. Experienced leader with strong technical background and understanding.<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"modal\" id=\"WPB5d3b91d9_e7fb_4c8c_b70c_bc9f5bc53d25\">\n\t\t\t\t\t<div class=\"modal-dialog modal-dialog-centered modal-lg modal-dialog-scrollable landing-page-modals\">\n\t\t\t\t\t\t<div class=\"modal-content\">\n\t\t\t\t\t\t\t<div class=\"modal-header\">\n\t\t\t\t\t\t\t\t<button type=\"button\" class=\"btn-close\" aria-label=\"close\" data-bs-dismiss=\"modal\"><\/button>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"modal-body\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"logo-wrapper\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.capgemini.com\/no-no\/wp-content\/themes\/capgemini2025\/assets\/images\/logo.svg\"\n\t\t\t\t\t\t\t\t\t\talt=\"Connect with us\" class=\"light\" \/>\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.capgemini.com\/no-no\/wp-content\/themes\/capgemini2025\/assets\/images\/logo-white.svg\"\n\t\t\t\t\t\t\t\t\t\talt=\"Connect with us\" class=\"dark\" \/>\n\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"form-title\">Connect with us<\/h4>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"mf_forms__container \">\n\t\t\t\t\t\t\t\t<form id=\"mf_form_344241_2639829058\" class=\"mf_form__form row needs-validation\" action=\"\" method=\"post\" enctype=\"multipart\/form-data\" data-nosnippet>\n\t\t\t<div class=\"col-12\">\n\t\t\t\t<div class=\"asterisk_title\">\n\t\t\t\t\t<p><span class=\"star-required\">*<\/span> Mandatory field<\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"col-12\">\n\t\t\t\t<div class=\"mf_form__errors mf_form__errors--top\" role=\"alert\" aria-live=\"polite\">\n\t\t\t\t\t<ul class=\"mf_form__errors__list\"><\/ul>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t<div class=\"mf-field-wrapper form-floating col-sm-12\"><input type=\"text\" class=\"form-control\" id=\"_mf_344241_8430_2460698672\" name=\"_mf_344241_8430\" placeholder=\"First Name\" required \/><label for=\"_mf_344241_8430_2460698672\" class=\"form-label\">First Name <span class=\"star-required\">*<\/span><\/label><div class=\"invalid-feedback-frm\">First Name is not valid.<\/div><\/div><div class=\"mf-field-wrapper form-floating col-sm-12\"><input type=\"text\" class=\"form-control\" id=\"_mf_344241_7950_3499539663\" name=\"_mf_344241_7950\" placeholder=\"Last Name\" required \/><label for=\"_mf_344241_7950_3499539663\" class=\"form-label\">Last Name <span class=\"star-required\">*<\/span><\/label><div class=\"invalid-feedback-frm\">Last Name is not valid.<\/div><\/div><div class=\"mf-field-wrapper form-floating col-sm-12\"><input type=\"email\" class=\"form-control\" id=\"_mf_344241_6828_2019715163\" name=\"_mf_344241_6828\" placeholder=\"Email\" required \/><label for=\"_mf_344241_6828_2019715163\" class=\"form-label\">Email <span class=\"star-required\">*<\/span><\/label><div class=\"invalid-feedback-frm\">Email is not valid.<\/div><\/div><div class=\"mf-field-wrapper form-floating col-sm-12\"><input type=\"text\" class=\"form-control\" id=\"_mf_344241_448_3395985783\" name=\"_mf_344241_448\" placeholder=\"Company\" required \/><label for=\"_mf_344241_448_3395985783\" class=\"form-label\">Company <span class=\"star-required\">*<\/span><\/label><div class=\"invalid-feedback-frm\">Company is not valid.<\/div><\/div>\t\t<div class=\"mf_field mf_field--country mf_field--select floating form-country-select-parent mf-required\">\n\n\t\t\t<label for=\"_mf_344241_7028_2563278449\" class=\"floating__label form-country-select-label\" data-content=\"Country\">\n\t\t\t\t<span class=\"floating-label-content\">Country<\/span>\n\t\t\t<\/label>\n\n\t\t\t<div class=\"select-wrap\">\n<i class=\"icon icon-zodiak-chevron-down\"><\/i>\n\t\t\t\t<select id=\"_mf_344241_7028_2563278449\" class=\"mf_field__input empty mf-country-selectbox form_country_select\" name=\"_mf_344241_7028\" data-validate=\"select\" required>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"\"  selected='selected'>Country<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"AF\" >Afghanistan<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"AX\" >Aland Islands<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"AL\" >Albania<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"DZ\" >Algeria<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"AS\" >American Samoa<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"AD\" >Andorra<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"AO\" >Angola<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"AI\" >Anguilla<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"AQ\" >Antarctica<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"AG\" >Antigua And Barbuda<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"AR\" >Argentina<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"AM\" >Armenia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"AW\" >Aruba<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"AU\" >Australia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"AT\" >Austria<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"AZ\" >Azerbaijan<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"BS\" >Bahamas<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"BH\" >Bahrain<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"BD\" >Bangladesh<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"BB\" >Barbados<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"BY\" >Belarus<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"BE\" >Belgium<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"BZ\" >Belize<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"BJ\" >Benin<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"BM\" >Bermuda<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"BT\" >Bhutan<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"BO\" >Bolivia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"BA\" >Bosnia And Herzegovina<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"BW\" >Botswana<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"BV\" >Bouvet Island<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"BR\" >Brazil<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"IO\" >British Indian Ocean Territory<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"BN\" >Brunei Darussalam<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"BG\" >Bulgaria<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"BF\" >Burkina Faso<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"BI\" >Burundi<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"KH\" >Cambodia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"CM\" >Cameroon<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"CA\" >Canada<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"CV\" >Cape Verde<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"KY\" >Cayman Islands<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"CF\" >Central African Republic<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"TD\" >Chad<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"CL\" >Chile<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"CN\" >China<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"CX\" >Christmas Island<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"CC\" >Cocos (Keeling) Islands<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"CO\" >Colombia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"KM\" >Comoros<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"CG\" >Congo<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"CD\" >Congo, Democratic Republic<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"CK\" >Cook Islands<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"CR\" >Costa Rica<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"CI\" >Cote D&#039;Ivoire<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"HR\" >Croatia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"CU\" >Cuba<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"CY\" >Cyprus<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"CZ\" >Czech Republic<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"DK\" >Denmark<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"DJ\" >Djibouti<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"DM\" >Dominica<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"DO\" >Dominican Republic<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"EC\" >Ecuador<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"EG\" >Egypt<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"SV\" >El Salvador<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"GQ\" >Equatorial Guinea<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"ER\" >Eritrea<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"EE\" >Estonia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"ET\" >Ethiopia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"FK\" >Falkland Islands (Malvinas)<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"FO\" >Faroe Islands<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"FJ\" >Fiji<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"FI\" >Finland<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"FR\" >France<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"GF\" >French Guiana<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"PF\" >French Polynesia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"TF\" >French Southern Territories<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"GA\" >Gabon<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"GM\" >Gambia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"GE\" >Georgia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"DE\" >Germany<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"GH\" >Ghana<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"GI\" >Gibraltar<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"GR\" >Greece<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"GL\" >Greenland<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"GD\" >Grenada<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"GP\" >Guadeloupe<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"GU\" >Guam<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"GT\" >Guatemala<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"GG\" >Guernsey<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"GN\" >Guinea<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"GW\" >Guinea-Bissau<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"GY\" >Guyana<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"HT\" >Haiti<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"HM\" >Heard Island &amp; Mcdonald Islands<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"VA\" >Holy See (Vatican City State)<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"HN\" >Honduras<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"HK\" >Hong Kong<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"HU\" >Hungary<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"IS\" >Iceland<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"IN\" >India<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"ID\" >Indonesia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"IR\" >Iran, Islamic Republic Of<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"IQ\" >Iraq<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"IE\" >Ireland<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"IM\" >Isle Of Man<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"IL\" >Israel<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"IT\" >Italy<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"JM\" >Jamaica<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"JP\" >Japan<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"JE\" >Jersey<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"JO\" >Jordan<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"KZ\" >Kazakhstan<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"KE\" >Kenya<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"KI\" >Kiribati<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"KR\" >Korea<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"KW\" >Kuwait<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"KG\" >Kyrgyzstan<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"LA\" >Lao People&#039;s Democratic Republic<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"LV\" >Latvia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"LB\" >Lebanon<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"LS\" >Lesotho<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"LR\" >Liberia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"LY\" >Libyan Arab Jamahiriya<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"LI\" >Liechtenstein<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"LT\" >Lithuania<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"LU\" >Luxembourg<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"MO\" >Macao<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"MK\" >Macedonia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"MG\" >Madagascar<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"MW\" >Malawi<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"MY\" >Malaysia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"MV\" >Maldives<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"ML\" >Mali<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"MT\" >Malta<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"MH\" >Marshall Islands<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"MQ\" >Martinique<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"MR\" >Mauritania<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"MU\" >Mauritius<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"YT\" >Mayotte<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"MX\" >Mexico<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"FM\" >Micronesia, Federated States Of<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"MD\" >Moldova<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"MC\" >Monaco<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"MN\" >Mongolia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"ME\" >Montenegro<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"MS\" >Montserrat<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"MA\" >Morocco<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"MZ\" >Mozambique<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"MM\" >Myanmar<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"NA\" >Namibia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"NR\" >Nauru<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"NP\" >Nepal<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"NL\" >Netherlands<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"AN\" >Netherlands Antilles<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"NC\" >New Caledonia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"NZ\" >New Zealand<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"NI\" >Nicaragua<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"NE\" >Niger<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"NG\" >Nigeria<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"NU\" >Niue<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"NF\" >Norfolk Island<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"MP\" >Northern Mariana Islands<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"NO\" >Norway<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"OM\" >Oman<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"PK\" >Pakistan<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"PW\" >Palau<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"PS\" >Palestinian Territory, Occupied<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"PA\" >Panama<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"PG\" >Papua New Guinea<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"PY\" >Paraguay<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"PE\" >Peru<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"PH\" >Philippines<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"PN\" >Pitcairn<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"PL\" >Poland<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"PT\" >Portugal<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"PR\" >Puerto Rico<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"QA\" >Qatar<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"RE\" >Reunion<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"RO\" >Romania<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"RU\" >Russian Federation<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"RW\" >Rwanda<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"BL\" >Saint Barthelemy<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"SH\" >Saint Helena<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"KN\" >Saint Kitts And Nevis<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"LC\" >Saint Lucia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"MF\" >Saint Martin<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"PM\" >Saint Pierre And Miquelon<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"VC\" >Saint Vincent And Grenadines<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"WS\" >Samoa<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"SM\" >San Marino<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"ST\" >Sao Tome And Principe<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"SA\" >Saudi Arabia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"SN\" >Senegal<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"RS\" >Serbia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"SC\" >Seychelles<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"SL\" >Sierra Leone<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"SG\" >Singapore<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"SK\" >Slovakia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"SI\" >Slovenia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"SB\" >Solomon Islands<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"SO\" >Somalia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"ZA\" >South Africa<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"GS\" >South Georgia And Sandwich Isl.<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"ES\" >Spain<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"LK\" >Sri Lanka<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"SD\" >Sudan<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"SR\" >Suriname<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"SJ\" >Svalbard And Jan Mayen<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"SZ\" >Swaziland<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"SE\" >Sweden<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"CH\" >Switzerland<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"SY\" >Syrian Arab Republic<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"TW\" >Taiwan<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"TJ\" >Tajikistan<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"TZ\" >Tanzania<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"TH\" >Thailand<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"TL\" >Timor-Leste<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"TG\" >Togo<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"TK\" >Tokelau<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"TO\" >Tonga<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"TT\" >Trinidad And Tobago<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"TN\" >Tunisia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"TR\" >Turkey<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"TM\" >Turkmenistan<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"TC\" >Turks And Caicos Islands<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"TV\" >Tuvalu<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"UG\" >Uganda<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"UA\" >Ukraine<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"AE\" >United Arab Emirates<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"GB\" >United Kingdom<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"US\" >United States<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"UM\" >United States Outlying Islands<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"UY\" >Uruguay<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"UZ\" >Uzbekistan<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"VU\" >Vanuatu<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"VE\" >Venezuela<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"VN\" >Viet Nam<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"VG\" >Virgin Islands, British<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"VI\" >Virgin Islands, U.S.<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"WF\" >Wallis And Futuna<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"EH\" >Western Sahara<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"YE\" >Yemen<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"ZM\" >Zambia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"ZW\" >Zimbabwe<\/option>\n\t\t\t\t\t\t\t\t\t<\/select>\n\n\t\t\t\t<div class=\"invalid-feedback-frm\">Country is not valid.<\/div>\n\t\t\t<\/div>\n\n\t\t<\/div>\n\n\t\t<script type=\"text\/javascript\">\n            jQuery(document).ready(function($) {\n                $('.mf_form__form').each(function() {\n                    var $form = $(this); \/\/ This specific form instance\n\n                    \/\/ Find the country select in this form\n                    $form.find('.form_country_select').each(function() {\n                        var $select = $(this);\n\t\t\t\t\t\tvar clickCount = 0;\n                        \/\/ On change\n                        $select.on('click', function() {\n\t\t\t\t\t\t\tclickCount++;\n\t\t\t\t\t\t\tif (clickCount === 1) {\n\t\t\t\t\t\t\t\t$(this).parent().find('.icon-zodiak-chevron-down').addClass('active');\n\t\t\t\t\t\t\t} else {\n\t\t\t\t\t\t\t\tclickCount = 0;\n\t\t\t\t\t\t\t\t$(this).parent().find('.icon-zodiak-chevron-down').removeClass('active');\n\t\t\t\t\t\t\t}\n\t\t\t\t\t\t});\n\t\t\t\t\t\t$select.on('blur', function() {\n\t\t\t\t\t\t\tclickCount = 0;\n\t\t\t\t\t\t\t$(this).parent().find('.icon-zodiak-chevron-down').removeClass('active');\n\t\t\t\t\t\t});\n                    });\n                });\n            });\n        <\/script>\n\n\t\t<div class=\"mf-field-wrapper form-floating col-sm-12\"><input type=\"text\" pattern=\"^[0-9\\-\\+\\s]+$\"  class=\"form-control\" id=\"_mf_344241_4361_647914686\" name=\"_mf_344241_4361\" oninput=\"validateInput(this)\" maxlength=\"14\" placeholder=\"Phone\"  \/><label for=\"_mf_344241_4361_647914686\" class=\"form-label\">Phone (optional)<\/label><\/div><div class=\"mf-field-wrapper form-floating col-sm-12\"><textarea type=\"text\" class=\"form-control\" id=\"_mf_344241_6784_672768401\" name=\"_mf_344241_6784\" placeholder=\"Your Message\" required><\/textarea><label for=\"_mf_344241_6784_672768401\" class=\"form-label\">Your Message <span class=\"star-required\">*<\/span><\/label><div class=\"invalid-feedback-frm\">Your Message is not valid.<\/div><\/div><div class=\"mf-field-wrapper  col-sm-12\">\n\t\t<div class=\"form-check checkbox-controls\">\n\n\t\t\t<input type=\"checkbox\" id=\"_mf_344241_781_3198375213\" class=\"form-check-input\"\n\t\t\t\tname=\"_mf_344241_781[]\"\n\t\t\t\tvalue=\"1\"\n\t\t\t\trequired\n\t\t\t>\n\n\t\t\t<label for=\"_mf_344241_781_3198375213\" class=\"form-check-label consent-text\">\n\t\t\t\tI agree to Capgemini collecting and processing my personal data to allow me to receive information on Capgemini services. For further information, please see <a href=\"https:\/\/www.capgemini.com\/no-no\/privacy-notice\/\" target=\"_blank\">our Privacy Notice<\/a>.  &nbsp;\t\t\t<\/label>\n\n\t\t<\/div>\n\t\t<\/div>\t\t\t<div class=\"mf_field mf_field--hidden \">\n\t\t\t\t<label for=\"_mf_344241_1688_3465527245\">Expert title\t\t\t\t\t<\/label>\n\t\t\t\t<input type=\"hidden\" id=\"_mf_344241_1688_3465527245\" class=\"mf_field__input empty\" name=\"_mf_344241_1688\" data-validate=\"text\" data-hidden-field-tag=\"expert_title\" value=\"\"  \/>\n\t\t\t<\/div>\n\t\t\t\t\t<div class=\"mf_field mf_field--hidden \">\n\t\t\t\t<label for=\"_mf_344241_7135_2698162714\">Page URL\t\t\t\t\t<\/label>\n\t\t\t\t<input\n\t\t\t\t\ttype=\"hidden\"\n\t\t\t\t\tid=\"_mf_344241_7135_2698162714\"\n\t\t\t\t\tclass=\"mf_field__input empty\"\n\t\t\t\t\tname=\"_mf_344241_7135\"\n\t\t\t\t\tdata-validate=\"text\"\n\t\t\t\t\tvalue=\"https:\/\/www.capgemini.com\/no-no\/industries\/banking-and-capital-markets\/retail-and-commercial-banking\/\"\n\t\t\t\t\t\t\t\t\t\/>\n\t\t\t<\/div>\n\t\t\t\t\t<div class=\"mf_field mf_field--recaptcha\">\n\t\t\t\t<div class=\"g-recaptcha\" data-sitekey=\"6Lc3OpIUAAAAADY4ErEHF0HF6Tr7vuknduDU-fbl\"><\/div>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t<div class=\"mf_field mf_field--submit\" >\n\t\t\t\t<div class=\"slide-button-background button-background\">\n\t\t\t\t\t<label for=\"slider-submit-_mf_344241_1145\" class=\"slide-text\">\n\t\t\t\t\t\tSlide to submit\t\t\t\t\t<\/label>\n\t\t\t\t\t<input\n\t\t\t\t\t\tid=\"slider-submit-_mf_344241_1145\"\n\t\t\t\t\t\ttype=\"range\"\n\t\t\t\t\t\tclass=\"mf_field__input slider-frm-btn\"\n\t\t\t\t\t\trel=\"_mf_344241_1145\"\n\t\t\t\t\t\tmin=\"0\"\n\t\t\t\t\t\tmax=\"100\"\n\t\t\t\t\t\tvalue=\"0\"\n\t\t\t\t\t\taria-label=\"Slide to submit\"\n\t\t\t\t\t\taria-describedby=\"slide-instruction-_mf_344241_1145\"\n\t\t\t\t\t\taria-valuenow=\"0\"\n\t\t\t\t\t\taria-valuemin=\"0\"\n\t\t\t\t\t\taria-valuemax=\"100\"\n\t\t\t\t\t\taria-orientation=\"horizontal\"\n\t\t\t\t\t\trole=\"slider\"\n\t\t\t\t\t\ttabindex=\"0\"\n\t\t\t\t\t\/>\n\t\t\t\t\t<!-- Icon element for Firefox (doesn't support ::before\/::after on inputs) -->\n\t\t\t\t\t<span class=\"slider-icon\" aria-hidden=\"true\"><\/span>\n\t\t\t\t\t<span id=\"slide-instruction-_mf_344241_1145\" class=\"sr-only\">\n\t\t\t\t\t\tUse right arrow keys to slide, or drag right with your finger. When you reach 100 percent, the form is submitted.\t\t\t\t\t<\/span>\n\t\t\t\t\t<!-- Mobile-only submit button fallback -->\n\t\t\t\t\t<button type=\"submit\" class=\"mf-mobile-submit-btn\" disabled>\n\t\t\t\t\t\t<span class=\"sr-only\">If you use a screen reader or VoiceOver, double-tap this button to submit the form.<\/span>\n\t\t\t\t\t\tSlide to submit\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t\t<input type=\"hidden\" name=\"submit_btn_txt\" class=\"submit_btn_txt\" value=\"Slide to submit\"\/>\n\t\t\t\t<input type=\"hidden\" name=\"submitted_state_txt\" class=\"submitted_state_txt\" value=\"Submitted\"\/>\n\t\t\t<\/div>\n\t\t\t\t\t\t<input type=\"hidden\" name=\"form_id\" data-validate=\"number\" class=\"mf_form__id\" value=\"344241\" \/>\n\t\t\t\t<input type=\"hidden\" name=\"form_title\" class=\"mf_form__title\" value=\"revamp-new-expert-form\" \/>\n\t\t\t\t<input type=\"hidden\" name=\"wp_rest_nonce\" class=\"mf_form__wp_rest_nonce\" value=\"3fb441f171\" \/>\n\n\t\t\t\t<input type=\"hidden\" name=\"mf_form_conditional_logic\" class=\"mf_form__title conditional_logic\" value=\"\" \/>\n\t\t\t\t\n\t\t\t\t<input type=\"hidden\" name=\"mf_form_fields_country_dpo_field\" class=\"mf_form__title conditional_logic mf_form_fields_country_dpo_field\" value=\"\" \/>\n\n\t\t\t\t<!-- Anti-spam field -->\n\t\t\t\t<input type=\"text\" \n\t\t\t\t\tname=\"website_url\" \n\t\t\t\t\tclass=\"mf_field__url\" \n\t\t\t\t\tautocomplete=\"off\"\n\t\t\t\t\ttabindex=\"-1\"\n\t\t\t\t\taria-hidden=\"true\"\n\t\t\t\t\tstyle=\"position:absolute;left:-9999px;width:1px;height:1px;opacity:0;pointer-events:none;\" \n\t\t\t\t\/>\n\t\t\t<\/form>\n\n\t\t\t<div class=\"mf_form__success\" tabindex=\"0\" role=\"alert\">\n\t\t\t\tThank you for your submission. We will be in touch with you soon!<\/p>\n\t\t\t<\/div>\n\t\t\t<div class=\"mf_form__errors\">\n\t\t\t\t<p>We are sorry, the form submission failed. Please try again.<\/p>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t<script>\n\t\t\twindow.MF_CONFIG344241 = {\"344241\":{\"errors\":[],\"redirect\":\"\"}};\n\t\t<\/script>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div><\/div><\/div><div class=\"slider-nav\"><button class=\"slider-prev inactive\" aria-label=\"Slider-previous\" tabindex=\"-1\"><\/button><ul class=\"slider-paginator\"><\/ul><button class=\"slider-next\" aria-label=\"Slider-next\"><\/button><\/div><\/div><\/section>\n\n\n\n<section class=\"wp-block-cg-blocks-intro-para undefined section section--intro\"><div class=\"intro-para\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-md-8 offset-md-2\"><h2 class=\"intro-para-title\">Awards and recognition<\/h2><\/div><\/div><\/div><\/div><\/section>\n\n\n\t<section class=\"wp-block-cg-blocks-wrapper-learning-slider section learning-slider\">\n\t\t<div class=\"container\">\n\t\t\t<div class=\"learning-header\">\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<div class=\"slider slider-fader\">\n\t\t\t\t<div class=\"slider-list\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"slide active card-learning-slide right-card short-copy\" data-align-right=\"false\" data-long-copy=\"false\">\n\t\t\t\t\t\t\t\t<div>\n\t\t\t\t\t\t\t\t\t<div class=\"slide-bg-wrapper\">\n\n                                        \n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n                                            \n                                            \n                                            \n                                            <img decoding=\"async\" loading=\"lazy\" class=\"slide-bg d-md-block\" src=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2025\/02\/Award-4.jpg\" alt=\"\" style=\"object-position: 50% 50%;object-fit: cover\" \/>\n                                        \n\n                  \t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"slide-reveal\"><\/div>\n\n\t\t\t\t\t\t\t\t\t\t<div class=\"container slide-info-wrapper card-learning-slider\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-12 col-lg-10 col-xl-6 col-xxl-6 right-card\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"slide-info short-copy\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"box\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"title-link\" href=\"https:\/\/www.temenos.com\/news\/2024\/01\/23\/temenos-impact-awards-celebrate-success-of-partners\/\" target=\"_blank\" rel=\"noopener noreferrer\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"title-text\" data-maxlength=\"88\">Temenos delivery partner of the year<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p data-maxlength=\"330\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tRecognition for our investment in technology and complex projects delivery with enhanced client impact\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"box-bottom\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-12 col-md-6\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"slide-info-footer\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"brand-logo-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-12 col-md-6\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"btnDiv\">\t<a class=\"more2\" aria-label=\"Read more about Temenos delivery partner of the year\" href=\"https:\/\/www.temenos.com\/news\/2024\/01\/23\/temenos-impact-awards-celebrate-success-of-partners\/\" target=\"_blank\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tRead more\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t         \t\t\t<\/div>\n\n\n\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"slider-nav-wrapper container\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"row\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"slider-nav-content col-12 col-lg-10 col-xl-6 col-xxl-6\" data-nav-content>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"slide-nav-container\">\n                                                                                                            <\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t<\/section>\n\n\t\n\n\n<section class=\"wp-block-cg-blocks-wrapper-partners section--partners-core undefined section section--partners-small\"><div class=\"container\"><div class=\"row\"><div class=\"content-title col-12 col-md-8\"><h2 class=\"partner-heading\">Partners<\/h2><\/div><\/div><div class=\"row\">\n<div class=\"col-6 col-md-4 col-lg-2 small\">\n            <a href=\"https:\/\/www.capgemini.com\/no-no\/about-us\/partnerships\/adobe\/\" class=\"partner-box-title\" aria-label=\"Achieve hyper-personalized customer experience using the power of data.\">\n        <div class=\"partner-box\">\n                                                     <div class=\"partner-box-bottom\">\n                        <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2024\/07\/adobe.png?w=350&#038;quality=70\" alt=\"\" class=\"partner-box-logo light\">\n\n                                                    <img decoding=\"async\" loading=\"lazy\" src=\"\/no-no\/wp-json\/wp\/v2\/pages\/849286?w=350&#038;quality=70\" alt=\"\" class=\"partner-box-logo dark\">\n\n                            \n                    <\/div>\n                                                    <\/div>\n            <\/a>\n    <\/div>\n\n\n\n\n<div class=\"col-6 col-md-4 col-lg-2 small\">\n            <a href=\"https:\/\/www.capgemini.com\/no-no\/about-us\/partnerships\/amazon-web-services\/\" class=\"partner-box-title\" aria-label=\"Unlock sustainable growth and competitive advantage through scalable, cloud-powered innovation.\">\n        <div class=\"partner-box\">\n                                                     <div class=\"partner-box-bottom\">\n                        <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2024\/07\/aws.png?w=350&#038;quality=70\" alt=\"\" class=\"partner-box-logo light\">\n\n                                                    <img decoding=\"async\" loading=\"lazy\" src=\"\/no-no\/wp-json\/wp\/v2\/pages\/849286?w=350&#038;quality=70\" alt=\"\" class=\"partner-box-logo dark\">\n\n                            \n                    <\/div>\n                                                    <\/div>\n            <\/a>\n    <\/div>\n\n\n\n\n<div class=\"col-6 col-md-4 col-lg-2 small\">\n            <a href=\"https:\/\/www.capgemini.com\/no-no\/about-us\/technology-partners\/google-cloud\/\" class=\"partner-box-title\" aria-label=\"Unleash what&#039;s possible. Innovate for growth and re-invent your business models.\">\n        <div class=\"partner-box\">\n                                                     <div class=\"partner-box-bottom\">\n                        <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.capgemini.com\/no-no\/wp-content\/uploads\/sites\/23\/2021\/04\/lockup_GoogleCloud_FullColor.png?w=350&#038;quality=70\" alt=\"\" class=\"partner-box-logo light\">\n\n                                                    <img decoding=\"async\" loading=\"lazy\" src=\"\/no-no\/wp-json\/wp\/v2\/pages\/849286?w=350&#038;quality=70\" alt=\"\" class=\"partner-box-logo dark\">\n\n                            \n                    <\/div>\n                                                    <\/div>\n            <\/a>\n    <\/div>\n\n\n\n\n<div class=\"col-6 col-md-4 col-lg-2 small\">\n            <a href=\"https:\/\/www.capgemini.com\/no-no\/about-us\/partnerships\/microsoft\/\" class=\"partner-box-title\" aria-label=\"Working together to help companies boost business value with cloud-powered solutions.\">\n        <div class=\"partner-box\">\n                                                     <div class=\"partner-box-bottom\">\n                        <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.capgemini.com\/no-no\/wp-content\/uploads\/sites\/23\/2025\/10\/microsoft.png?w=350&#038;quality=70\" alt=\"\" class=\"partner-box-logo light\">\n\n                                                    <img decoding=\"async\" loading=\"lazy\" src=\"\/no-no\/wp-json\/wp\/v2\/pages\/849286?w=350&#038;quality=70\" alt=\"\" class=\"partner-box-logo dark\">\n\n                            \n                    <\/div>\n                                                    <\/div>\n            <\/a>\n    <\/div>\n\n\n\n\n<div class=\"col-6 col-md-4 col-lg-2 small\">\n            <a href=\"https:\/\/www.capgemini.com\/no-no\/about-us\/partnerships\/salesforce\/\" class=\"partner-box-title\" aria-label=\"Helping brands deliver personalized, engaging, relevant and memorable customer experiences.\">\n        <div class=\"partner-box\">\n                                                     <div class=\"partner-box-bottom\">\n                        <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2024\/07\/salesforce.png?w=350&#038;quality=70\" alt=\"\" class=\"partner-box-logo light\">\n\n                                                    <img decoding=\"async\" loading=\"lazy\" src=\"\/no-no\/wp-json\/wp\/v2\/pages\/849286?w=350&#038;quality=70\" alt=\"\" class=\"partner-box-logo dark\">\n\n                            \n                    <\/div>\n                                                    <\/div>\n            <\/a>\n    <\/div>\n\n\n\n\n<div class=\"col-6 col-md-4 col-lg-2 small\">\n            <a href=\"https:\/\/www.capgemini.com\/no-no\/about-us\/partnerships\/temenos\/\" class=\"partner-box-title\" aria-label=\"Helping banks become digital-first enterprises across the entire banking value chain.\">\n        <div class=\"partner-box\">\n                                                     <div class=\"partner-box-bottom\">\n                        <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2024\/07\/temenos.png?w=350&#038;quality=70\" alt=\"\" class=\"partner-box-logo light\">\n\n                                                    <img decoding=\"async\" loading=\"lazy\" src=\"\/no-no\/wp-json\/wp\/v2\/pages\/849286?w=350&#038;quality=70\" alt=\"\" class=\"partner-box-logo dark\">\n\n                            \n                    <\/div>\n                                                    <\/div>\n            <\/a>\n    <\/div>\n\n<\/div><\/div><\/section>\n\n\n\n<section class=\"wp-block-cg-blocks-call-to-action undefined is-style-cg-secondary-3 call-to-action-block\"><div class=\"container\"><div class=\"call-to-action-block-content-wrapper has-description\"><div class=\"text-wrapper has-description\"><h3 class=\"title\" data-maxlength=\"144\">Join the conversation on LinkedIn<\/h3><p class=\"description\" data-maxlength=\"210\">Connect with our experts and read the latest industry insights on our dedicated LinkedIn page<\/p><\/div><div class=\"button-wrapper has-description\"><a class=\"cta-btn action-valid\" href=\"https:\/\/www.linkedin.com\/company\/capgemini\" target=\"_blank\" rel=\"noopener noreferrer\" aria-label=\"Follow our page about Join the conversation on LinkedIn\" title=\"Opens in a new window\" data-maxlength=\"24\" tabindex=\"0\"> Follow our page <\/a><\/div><\/div><\/div><\/section>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":118,"featured_media":849287,"parent":637937,"menu_order":4,"comment_status":"closed","ping_status":"closed","template":"","meta":{"cg_dt_proposed_to":[],"cg_seo_hreflang_relations":"[{\"uuid\":\"95da5a6a-0ac3-4d4f-aded-5467833b4875\",\"blogId\":\"1\",\"domain\":\"www.capgemini.com\",\"sitePath\":\"\/\",\"postLink\":\"https:\/\/www.capgemini.com\/industries\/banking-and-capital-markets\/retail-and-commercial-banking\/\",\"postId\":628650,\"isSaved\":true,\"isCrossLink\":true,\"hasCrossLink\":false},{\"uuid\":\"7da2739a-982e-45c3-a90d-d2e74bf15489\",\"blogId\":\"30\",\"domain\":\"www.capgemini.com\",\"sitePath\":\"\/us-en\/\",\"postLink\":\"https:\/\/www.capgemini.com\/us-en\/industries\/banking-and-capital-markets\/retail-and-commercial-banking\/\",\"postId\":567047,\"isSaved\":true,\"isCrossLink\":true,\"hasCrossLink\":false},{\"uuid\":\"2bbd04cf-648c-4a38-983d-790c6d9d6a40\",\"blogId\":\"5\",\"domain\":\"www.capgemini.com\",\"sitePath\":\"\/gb-en\/\",\"postLink\":\"https:\/\/www.capgemini.com\/gb-en\/industries\/banking-and-capital-markets\/retail-and-commercial-banking\/\",\"postId\":558961,\"isSaved\":true,\"isCrossLink\":true,\"hasCrossLink\":false},{\"uuid\":\"d6513bda-46af-4f24-9ebc-b5ec0babdc9e\",\"blogId\":\"18\",\"domain\":\"www.capgemini.com\",\"sitePath\":\"\/in-en\/\",\"postLink\":\"https:\/\/www.capgemini.com\/in-en\/industries\/banking-and-capital-markets\/retail-and-commercial-banking\/\",\"postId\":986874,\"isSaved\":true,\"isCrossLink\":true,\"hasCrossLink\":false},{\"uuid\":\"abe7f355-8b20-41fe-88c0-eefa3fe75a30\",\"blogId\":\"28\",\"domain\":\"www.capgemini.com\",\"sitePath\":\"\/mx-es\/\",\"postLink\":\"https:\/\/www.capgemini.com\/mx-es\/sectores\/banca-y-mercados-de-capital\/banca-comercial-y-retail\/\",\"postId\":5649,\"isSaved\":true,\"isCrossLink\":true,\"hasCrossLink\":false},{\"uuid\":\"db9d6415-f75a-4bb1-8d4b-92491ada2770\",\"blogId\":\"20\",\"domain\":\"www.capgemini.com\",\"sitePath\":\"\/se-en\/\",\"postLink\":\"https:\/\/www.capgemini.com\/se-en\/industries\/banking-and-capital-markets\/retail-and-commercial-banking\/\",\"postId\":129104,\"isSaved\":true,\"isCrossLink\":true,\"hasCrossLink\":false},{\"uuid\":\"a5a76e5b-3a48-4218-af7f-ba3cd60b36a5\",\"blogId\":\"26\",\"domain\":\"www.capgemini.com\",\"sitePath\":\"\/fi-en\/\",\"postLink\":\"https:\/\/www.capgemini.com\/fi-en\/industries\/banking-and-capital-markets\/retail-and-commercial-banking\/\",\"postId\":503438,\"isSaved\":true,\"isCrossLink\":true,\"hasCrossLink\":false},{\"uuid\":\"c8a6de0c-51d9-439f-bedc-e0d291a3388b\",\"blogId\":\"12\",\"domain\":\"www.capgemini.com\",\"sitePath\":\"\/br-pt\/\",\"postLink\":\"https:\/\/www.capgemini.com\/br-pt\/industrias\/banco-comercial-e-de-varejo\/\",\"postId\":628578,\"isSaved\":true,\"isCrossLink\":true,\"hasCrossLink\":false},{\"uuid\":\"c0af8486-fe74-4939-99db-2c4bfbb72dae\",\"blogId\":\"25\",\"domain\":\"www.capgemini.com\",\"sitePath\":\"\/co-es\/\",\"postLink\":\"https:\/\/www.capgemini.com\/co-es\/?page_id=522769&preview_id=522769\",\"postId\":522769,\"isSaved\":true,\"isCrossLink\":true,\"hasCrossLink\":false},{\"uuid\":\"48293e63-7fe0-4d52-b964-e1b2e6bb6cd5\",\"blogId\":\"23\",\"domain\":\"www.capgemini.com\",\"sitePath\":\"\/no-no\/\",\"postLink\":\"https:\/\/www.capgemini.com\/no-no\/industries\/banking-and-capital-markets\/retail-and-commercial-banking\/\",\"postId\":849286,\"isSaved\":true,\"isCrossLink\":true,\"hasCrossLink\":false},{\"uuid\":\"a9f02327-4ceb-4ad5-9da2-33cd05302918\",\"blogId\":\"7\",\"domain\":\"www.capgemini.com\",\"sitePath\":\"\/dk-en\/\",\"postLink\":\"https:\/\/www.capgemini.com\/dk-en\/industries\/banking-and-capital-markets\/retail-and-commercial-banking\/\",\"postId\":855851,\"isSaved\":true,\"isCrossLink\":true,\"hasCrossLink\":false}]","cg_seo_canonical_relation":"","cg_seo_hreflang_x_default_relation":"{\"uuid\":\"b4192ecd-f580-4994-89d5-93c04587e071\",\"blogId\":\"\",\"domain\":\"\",\"sitePath\":\"\",\"postLink\":\"\",\"postId\":null,\"isSaved\":true,\"isCrossLink\":false,\"hasCrossLink\":false}","cg_dt_approved_content":true,"cg_dt_mandatory_content":false,"cg_dt_notes":"","cg_dg_source_changed":true,"cg_dt_link_disabled":false,"_yoast_wpseo_primary_brand":"","footnotes":"","featured_focal_points":"","partner_card_description":"","gsap_animation":0},"brand":[],"partner_type":[],"service":[],"industry":[],"partners":[],"page-type":[163],"content-group":[],"class_list":["post-849286","page","type-page","status-publish","has-post-thumbnail","hentry","page-type-industry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.8 (Yoast SEO v22.8) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Retail and Commercial Banking Transformation Solutions | Capgemini<\/title>\n<meta name=\"description\" content=\"Capgemini offers transformative retail and commercial banking solutions, enabling banks to deliver personalized customer experiences and adopt platform-based models.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.capgemini.com\/no-no\/industries\/banking-and-capital-markets\/retail-and-commercial-banking\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Retail and commercial banking\" \/>\n<meta property=\"og:description\" content=\"Capgemini offers transformative retail and commercial banking solutions, enabling banks to deliver personalized customer experiences and adopt platform-based models.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.capgemini.com\/no-no\/industries\/banking-and-capital-markets\/retail-and-commercial-banking\/\" \/>\n<meta property=\"og:site_name\" content=\"Capgemini Norway\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-16T09:46:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.capgemini.com\/no-no\/wp-content\/uploads\/sites\/23\/2024\/11\/Capgemini_Industries_Capital-Markets_Retail-banking-e1638447185800.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2879\" \/>\n\t<meta property=\"og:image:height\" content=\"899\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.capgemini.com\/no-no\/industries\/banking-and-capital-markets\/retail-and-commercial-banking\/\",\"url\":\"https:\/\/www.capgemini.com\/no-no\/industries\/banking-and-capital-markets\/retail-and-commercial-banking\/\",\"name\":\"Retail and Commercial Banking Transformation Solutions | Capgemini\",\"isPartOf\":{\"@id\":\"https:\/\/www.capgemini.com\/no-no\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.capgemini.com\/no-no\/industries\/banking-and-capital-markets\/retail-and-commercial-banking\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.capgemini.com\/no-no\/industries\/banking-and-capital-markets\/retail-and-commercial-banking\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.capgemini.com\/no-no\/wp-content\/uploads\/sites\/23\/2024\/11\/Capgemini_Industries_Capital-Markets_Retail-banking-e1638447185800.jpg\",\"datePublished\":\"2021-09-28T06:49:00+00:00\",\"dateModified\":\"2026-04-16T09:46:17+00:00\",\"description\":\"Capgemini offers transformative retail and commercial banking solutions, enabling banks to deliver personalized customer experiences and adopt platform-based models.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.capgemini.com\/no-no\/industries\/banking-and-capital-markets\/retail-and-commercial-banking\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.capgemini.com\/no-no\/industries\/banking-and-capital-markets\/retail-and-commercial-banking\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.capgemini.com\/no-no\/industries\/banking-and-capital-markets\/retail-and-commercial-banking\/#primaryimage\",\"url\":\"https:\/\/www.capgemini.com\/no-no\/wp-content\/uploads\/sites\/23\/2024\/11\/Capgemini_Industries_Capital-Markets_Retail-banking-e1638447185800.jpg\",\"contentUrl\":\"https:\/\/www.capgemini.com\/no-no\/wp-content\/uploads\/sites\/23\/2024\/11\/Capgemini_Industries_Capital-Markets_Retail-banking-e1638447185800.jpg\",\"width\":2879,\"height\":899},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.capgemini.com\/no-no\/industries\/banking-and-capital-markets\/retail-and-commercial-banking\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.capgemini.com\/no-no\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Industries\",\"item\":\"https:\/\/www.capgemini.com\/no-no\/industries\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Banking and capital markets\",\"item\":\"https:\/\/www.capgemini.com\/no-no\/industries\/banking-and-capital-markets\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Retail and commercial banking\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.capgemini.com\/no-no\/#website\",\"url\":\"https:\/\/www.capgemini.com\/no-no\/\",\"name\":\"Capgemini Norway\",\"description\":\"Capgemini\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.capgemini.com\/no-no\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Retail and Commercial Banking Transformation Solutions | Capgemini","description":"Capgemini offers transformative retail and commercial banking solutions, enabling banks to deliver personalized customer experiences and adopt platform-based models.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.capgemini.com\/no-no\/industries\/banking-and-capital-markets\/retail-and-commercial-banking\/","og_locale":"en_US","og_type":"article","og_title":"Retail and commercial banking","og_description":"Capgemini offers transformative retail and commercial banking solutions, enabling banks to deliver personalized customer experiences and adopt platform-based models.","og_url":"https:\/\/www.capgemini.com\/no-no\/industries\/banking-and-capital-markets\/retail-and-commercial-banking\/","og_site_name":"Capgemini Norway","article_modified_time":"2026-04-16T09:46:17+00:00","og_image":[{"width":2879,"height":899,"url":"https:\/\/www.capgemini.com\/no-no\/wp-content\/uploads\/sites\/23\/2024\/11\/Capgemini_Industries_Capital-Markets_Retail-banking-e1638447185800.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.capgemini.com\/no-no\/industries\/banking-and-capital-markets\/retail-and-commercial-banking\/","url":"https:\/\/www.capgemini.com\/no-no\/industries\/banking-and-capital-markets\/retail-and-commercial-banking\/","name":"Retail and Commercial Banking Transformation Solutions | Capgemini","isPartOf":{"@id":"https:\/\/www.capgemini.com\/no-no\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.capgemini.com\/no-no\/industries\/banking-and-capital-markets\/retail-and-commercial-banking\/#primaryimage"},"image":{"@id":"https:\/\/www.capgemini.com\/no-no\/industries\/banking-and-capital-markets\/retail-and-commercial-banking\/#primaryimage"},"thumbnailUrl":"https:\/\/www.capgemini.com\/no-no\/wp-content\/uploads\/sites\/23\/2024\/11\/Capgemini_Industries_Capital-Markets_Retail-banking-e1638447185800.jpg","datePublished":"2021-09-28T06:49:00+00:00","dateModified":"2026-04-16T09:46:17+00:00","description":"Capgemini offers transformative retail and commercial banking solutions, enabling banks to deliver personalized customer experiences and adopt platform-based models.","breadcrumb":{"@id":"https:\/\/www.capgemini.com\/no-no\/industries\/banking-and-capital-markets\/retail-and-commercial-banking\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.capgemini.com\/no-no\/industries\/banking-and-capital-markets\/retail-and-commercial-banking\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.capgemini.com\/no-no\/industries\/banking-and-capital-markets\/retail-and-commercial-banking\/#primaryimage","url":"https:\/\/www.capgemini.com\/no-no\/wp-content\/uploads\/sites\/23\/2024\/11\/Capgemini_Industries_Capital-Markets_Retail-banking-e1638447185800.jpg","contentUrl":"https:\/\/www.capgemini.com\/no-no\/wp-content\/uploads\/sites\/23\/2024\/11\/Capgemini_Industries_Capital-Markets_Retail-banking-e1638447185800.jpg","width":2879,"height":899},{"@type":"BreadcrumbList","@id":"https:\/\/www.capgemini.com\/no-no\/industries\/banking-and-capital-markets\/retail-and-commercial-banking\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.capgemini.com\/no-no\/"},{"@type":"ListItem","position":2,"name":"Industries","item":"https:\/\/www.capgemini.com\/no-no\/industries\/"},{"@type":"ListItem","position":3,"name":"Banking and capital markets","item":"https:\/\/www.capgemini.com\/no-no\/industries\/banking-and-capital-markets\/"},{"@type":"ListItem","position":4,"name":"Retail and commercial banking"}]},{"@type":"WebSite","@id":"https:\/\/www.capgemini.com\/no-no\/#website","url":"https:\/\/www.capgemini.com\/no-no\/","name":"Capgemini Norway","description":"Capgemini","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.capgemini.com\/no-no\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"}]}},"brand_term":[],"parsely":{"version":"1.1.0","canonical_url":"https:\/\/capgemini.com\/no-no\/industries\/banking-and-capital-markets\/retail-and-commercial-banking\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"WebPage","headline":"Retail and commercial banking","url":"https:\/\/www.capgemini.com\/no-no\/industries\/banking-and-capital-markets\/retail-and-commercial-banking\/","mainEntityOfPage":{"@type":"WebPage","@id":"https:\/\/www.capgemini.com\/no-no\/industries\/banking-and-capital-markets\/retail-and-commercial-banking\/"},"thumbnailUrl":"https:\/\/www.capgemini.com\/no-no\/wp-content\/uploads\/sites\/23\/2024\/11\/Capgemini_Industries_Capital-Markets_Retail-banking-e1638447185800.jpg?w=150&h=150&crop=1","image":{"@type":"ImageObject","url":"https:\/\/www.capgemini.com\/no-no\/wp-content\/uploads\/sites\/23\/2024\/11\/Capgemini_Industries_Capital-Markets_Retail-banking-e1638447185800.jpg"},"articleSection":"Uncategorized","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Capgemini Norway","logo":""},"keywords":[],"dateCreated":"2021-09-28T06:49:00Z","datePublished":"2021-09-28T06:49:00Z","dateModified":"2026-04-16T09:46:17Z"},"rendered":"<meta name=\"parsely-title\" content=\"Retail and commercial banking\" \/>\n<meta name=\"parsely-link\" content=\"https:\/\/www.capgemini.com\/no-no\/industries\/banking-and-capital-markets\/retail-and-commercial-banking\/\" \/>\n<meta name=\"parsely-type\" content=\"index\" \/>\n<meta name=\"parsely-image-url\" content=\"https:\/\/www.capgemini.com\/no-no\/wp-content\/uploads\/sites\/23\/2024\/11\/Capgemini_Industries_Capital-Markets_Retail-banking-e1638447185800.jpg?w=150&amp;h=150&amp;crop=1\" \/>\n<meta name=\"parsely-pub-date\" content=\"2021-09-28T06:49:00Z\" \/>\n<meta name=\"parsely-section\" content=\"Uncategorized\" \/>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/capgemini.com\/p.js"},"archive_status":false,"featured_image_src":"https:\/\/www.capgemini.com\/no-no\/wp-content\/uploads\/sites\/23\/2024\/11\/Capgemini_Industries_Capital-Markets_Retail-banking-e1638447185800.jpg","featured_image_alt":"","jetpack_sharing_enabled":true,"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"Capgemini Norway","distributor_original_site_url":"https:\/\/www.capgemini.com\/no-no","push-errors":false,"_links":{"self":[{"href":"https:\/\/www.capgemini.com\/no-no\/wp-json\/wp\/v2\/pages\/849286","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.capgemini.com\/no-no\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.capgemini.com\/no-no\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.capgemini.com\/no-no\/wp-json\/wp\/v2\/users\/118"}],"replies":[{"embeddable":true,"href":"https:\/\/www.capgemini.com\/no-no\/wp-json\/wp\/v2\/comments?post=849286"}],"version-history":[{"count":14,"href":"https:\/\/www.capgemini.com\/no-no\/wp-json\/wp\/v2\/pages\/849286\/revisions"}],"predecessor-version":[{"id":866951,"href":"https:\/\/www.capgemini.com\/no-no\/wp-json\/wp\/v2\/pages\/849286\/revisions\/866951"}],"up":[{"embeddable":true,"href":"https:\/\/www.capgemini.com\/no-no\/wp-json\/wp\/v2\/pages\/637937"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.capgemini.com\/no-no\/wp-json\/wp\/v2\/media\/849287"}],"wp:attachment":[{"href":"https:\/\/www.capgemini.com\/no-no\/wp-json\/wp\/v2\/media?parent=849286"}],"wp:term":[{"taxonomy":"brand","embeddable":true,"href":"https:\/\/www.capgemini.com\/no-no\/wp-json\/wp\/v2\/brand?post=849286"},{"taxonomy":"partner_type","embeddable":true,"href":"https:\/\/www.capgemini.com\/no-no\/wp-json\/wp\/v2\/partner_type?post=849286"},{"taxonomy":"service","embeddable":true,"href":"https:\/\/www.capgemini.com\/no-no\/wp-json\/wp\/v2\/service?post=849286"},{"taxonomy":"industry","embeddable":true,"href":"https:\/\/www.capgemini.com\/no-no\/wp-json\/wp\/v2\/industry?post=849286"},{"taxonomy":"partners","embeddable":true,"href":"https:\/\/www.capgemini.com\/no-no\/wp-json\/wp\/v2\/partners?post=849286"},{"taxonomy":"page-type","embeddable":true,"href":"https:\/\/www.capgemini.com\/no-no\/wp-json\/wp\/v2\/page-type?post=849286"},{"taxonomy":"content-group","embeddable":true,"href":"https:\/\/www.capgemini.com\/no-no\/wp-json\/wp\/v2\/content-group?post=849286"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}