{"id":561656,"date":"2026-03-17T15:48:48","date_gmt":"2026-03-17T15:48:48","guid":{"rendered":"https:\/\/www.capgemini.com\/mx-es\/?post_type=research-and-insight&#038;p=561656"},"modified":"2026-07-03T16:24:49","modified_gmt":"2026-07-03T16:24:49","slug":"una-conversacion-con-anu-bradford","status":"publish","type":"research-and-insight","link":"https:\/\/www.capgemini.com\/mx-es\/insights\/biblioteca-de-investigacion\/una-conversacion-con-anu-bradford\/","title":{"rendered":"Navegando la soberan\u00eda tecnol\u00f3gica en un mundo fracturado: una conversaci\u00f3n con Anu Bradford"},"content":{"rendered":"\n<header class=\"wp-block-cg-blocks-hero-reusable header heroReusable  \"><div class=\"header-bgs\"><picture><source srcset=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2026\/06\/CFT-11_CommskitDotcom-banner.jpg?w=2880&amp;quality=70 1x, https:\/\/www.capgemini.com\/wp-content\/uploads\/2026\/06\/CFT-11_CommskitDotcom-banner.jpg?w=2880&amp;quality=70 2x\" media=\"(min-width: 1500px)\"\/><source srcset=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2026\/06\/CFT-11_CommskitDotcom-banner.jpg?w=1440&amp;quality=70 1x, https:\/\/www.capgemini.com\/wp-content\/uploads\/2026\/06\/CFT-11_CommskitDotcom-banner.jpg?w=2880&amp;quality=70 2x\" media=\"(min-width: 992px)\"\/><source srcset=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2026\/06\/CFT-11_CommskitDotcom-banner.jpg?w=1024&amp;quality=70 1x, https:\/\/www.capgemini.com\/wp-content\/uploads\/2026\/06\/CFT-11_CommskitDotcom-banner.jpg?w=1024&amp;quality=70 2x\" media=\"(min-width: 768px)\"\/><source srcset=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2026\/06\/CFT-11_CommskitDotcom-banner.jpg?w=768&amp;quality=70 1x, https:\/\/www.capgemini.com\/wp-content\/uploads\/2026\/06\/CFT-11_CommskitDotcom-banner.jpg?w=768&amp;quality=70 2x\" media=\"(min-width: 0)\"\/><img decoding=\"async\" src=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2026\/06\/CFT-11_CommskitDotcom-banner.jpg\" class=\"header-img header-img-d\" alt=\"\" style=\"object-fit:cover;object-position:50% 50%\" loading=\"eager\"\/><\/picture><\/div><div class=\"heroPictureCardHeaderShape\"><\/div><div class=\"container\"><div class=\"row\"><div class=\"col-md-12\"><div class=\"box\"><div class=\"boxTagWrapper\"><div class=\"tagInfo\"><div><span class=\"box-tag\">Innovation<\/span><\/div><\/div><div class=\"brandInfo\"><div class=\"brandLogo\"><img decoding=\"async\" loading=\"lazy\" src=\"\/wp-content\/themes\/capgemini2025\/assets\/images\/capgemini-research-institute-white.svg\" alt=\"capgemini-research-institute\" class=\"dark\"\/><img decoding=\"async\" loading=\"lazy\" src=\"\/wp-content\/themes\/capgemini2025\/assets\/images\/capgemini-research-institute.svg\" alt=\"capgemini-research-institute\" class=\"light\"\/><\/div><\/div><\/div><div class=\"box-title\"><h1 data-maxlength=\"34\">Una conversaci\u00f3n con Anu Bradford<\/h1><\/div><div class=\"inner-row-insight download-btn\"><div class=\"col-md-4 downloadFiles addPadding\"><a class=\"button-download--small\" type=\"download\" href=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2026\/03\/04-03-2026-CFT11_Anu-Bradford_Interview-v1.pdf\" target=\"_blank\" rel=\"noopener noreferrer\" title=\"Abrir en una nueva ventana\"><span>Descargar la entrevista<\/span><span class=\"type\">2 MB pdf<\/span><\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/header>\n\n\n\n<section class=\"wp-block-cg-blocks-group undefined section section--article-content\"><div class=\"article-main-content\"><div class=\"container\"><div class=\"grid-container\"><div class=\"col-12 col-md-2\"><nav class=\"article-social\"><ul class=\"social-nav\"><li class=\"ip-order-fb\"><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https:\/\/www.capgemini.com\/?post_type=research-and-insight&amp;p=1142578\" target=\"_blank\" rel=\"noopener noreferrer\" title=\"Abrir en una nueva ventana\"><i aria-hidden=\"true\" class=\"icon-fb\"><\/i><span class=\"sr-only\">Facebook<\/span><\/a><\/li><li class=\"ip-order-li\"><a href=\"https:\/\/www.linkedin.com\/shareArticle?url=https:\/\/www.capgemini.com\/?post_type=research-and-insight&amp;p=1142578\" target=\"_blank\" rel=\"noopener noreferrer\" title=\"Abrir en una nueva ventana\"><i aria-hidden=\"true\" class=\"icon-li\"><\/i><span class=\"sr-only\">Linkedin<\/span><\/a><\/li><\/ul><\/nav><\/div><div><div class=\"article-text article-quote-text\">\n<h2 class=\"wp-block-heading\" id=\"h-navegando-la-soberania-tecnologica-en-un-mundo-fracturado\">Navegando la soberan\u00eda tecnol\u00f3gica en un mundo fracturado<\/h2>\n\n\n\n<figure class=\"wp-block-image alignright size-full is-resized\"><img decoding=\"async\" src=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2026\/02\/Anu-Bradford-pic2.jpg\" alt=\"\" class=\"wp-image-1201271\" style=\"width:400px\"\/><\/figure>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-anu-bradford-profesora-henry-l-moses-de-derecho-y-organizacion-internacional-universidad-de-columbia\">Anu Bradford, Profesora Henry L. Moses de Derecho y Organizaci\u00f3n Internacional | Universidad de Columbia<\/h4>\n\n\n\n<p>Anu Bradford es una experta destacada en la forma en que la regulaci\u00f3n y el poder estatal moldean la econom\u00eda digital. Actualmente, se desempe\u00f1a como asesora especial en soberan\u00eda tecnol\u00f3gica para los l\u00edderes europeos. Es autora de <em>The Brussels Effect: How the European Union Rules the World<\/em> (2020), obra que fue nombrada uno de los mejores libros de 2020 por <em>Foreign Affairs<\/em>. Su libro m\u00e1s reciente, <em>Digital Empires: The Global Battle to Regulate Technology<\/em>, se public\u00f3 en septiembre de 2023; fue reconocido como uno de los mejores libros de 2023 por el <em>Financial Times<\/em> y galardonado con el Premio Stein Rokkan 2024 a la Investigaci\u00f3n Comparada en Ciencias Sociales. En la Facultad de Derecho de Columbia, Bradford dirige el Centro de Estudios Jur\u00eddicos Europeos. Antes de incorporarse al cuerpo docente de la Facultad de Derecho de Columbia en 2012, Bradford fue profesora asistente en la Facultad de Derecho de la Universidad de Chicago. Asimismo, ejerci\u00f3 la abogac\u00eda en los \u00e1mbitos del derecho de la Uni\u00f3n Europea y el derecho de la competencia en Bruselas, y ha prestado servicios como asesora en pol\u00edtica econ\u00f3mica en el Parlamento de Finlandia y como asistente experta en el Parlamento Europeo. El Foro Econ\u00f3mico Mundial la design\u00f3 \u00abJoven L\u00edder Global\u00bb en 2010.<\/p>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p><\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-usted-acuno-el-termino-efecto-bruselas-para-describir-como-las-regulaciones-de-la-ue-moldean-las-practicas-tecnologicas-a-nivel-global-en-que-punto-nos-encontramos-hoy-en-dia-respecto-a-la-influencia-regulatoria-digital-de-europa\">Usted acu\u00f1\u00f3 el t\u00e9rmino \u00abEfecto Bruselas\u00bb para describir c\u00f3mo las regulaciones de la UE moldean las pr\u00e1cticas tecnol\u00f3gicas a nivel global. \u00bfEn qu\u00e9 punto nos encontramos hoy en d\u00eda respecto a la influencia regulatoria digital de Europa?<\/h4>\n\n\n\n<p>Creo que el punto \u00e1lgido del liderazgo regulatorio de Europa ha quedado atr\u00e1s. Hace unos a\u00f1os, durante el apogeo de la \u00abreacci\u00f3n contra las tecnol\u00f3gicas\u00bb (<em>techlash<\/em>), parec\u00eda que el mundo avanzaba hacia normas digitales m\u00e1s estrictas y que la UE marcaba la pauta. Incluso Estados Unidos, bajo la presidencia de Biden, se inclin\u00f3 inicialmente hacia una regulaci\u00f3n tecnol\u00f3gica m\u00e1s rigurosa. Pero desde entonces, hemos sido testigos de una fuerte reacci\u00f3n adversa. En el plano exterior, Washington se ha vuelto m\u00e1s hostil hacia cualquier potencia extranjera \u2014incluida la UE\u2014 que intente poner coto a las empresas tecnol\u00f3gicas estadounidenses. Los responsables pol\u00edticos de EE. UU. ven con desagrado los intentos de Europa de establecer normas para Silicon Valley; de hecho, hemos presenciado incluso audiencias en el Congreso en las que se criticaba el \u00abefecto Bruselas\u00bb. Al mismo tiempo, dentro de Europa ha cobrado fuerza la idea de que, tal vez, el exceso de regulaci\u00f3n est\u00e9 perjudicando nuestra competitividad. Un informe de gran repercusi\u00f3n, dirigido por Mario Draghi, sosten\u00eda, por ejemplo, que el d\u00e9ficit de innovaci\u00f3n de Europa se debe en parte a una regulaci\u00f3n excesivamente gravosa. Esto ha modificado el rumbo del debate en Bruselas. Los l\u00edderes de la UE han pasado de defender con firmeza los derechos digitales y una supervisi\u00f3n rigurosa a plantearse: \u00ab\u00bfEstamos actuando con excesiva mano dura? \u00bfNecesitamos rebajar el nivel de regulaci\u00f3n y centrarnos m\u00e1s en la innovaci\u00f3n?\u00bb. Como consecuencia, la Comisi\u00f3n Europea ha propuesto flexibilizar o revisar algunas pol\u00edticas, incluida la iniciativa \u00abDigital Omnibus\u00bb, con el fin de simplificar las normas y replantearse ciertos aspectos de la Ley de Inteligencia Artificial y del RGPD. En definitiva, la determinaci\u00f3n de Europa de erigirse como el regulador digital del mundo ha flaqueado ante la presi\u00f3n de Estados Unidos y las dudas surgidas en el \u00e1mbito interno.<a id=\"_msocom_1\"><\/a><a id=\"_msocom_1\"><\/a><\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p><\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-en-un-reciente-articulo-de-foreign-affairs-usted-advirtio-que-europa-podria-perder-aquello-que-la-hace-grande-contra-que-estaba-advirtiendo\">En un reciente art\u00edculo de <em>Foreign Affairs<\/em>, usted advirti\u00f3 que Europa podr\u00eda \u00abperder aquello que la hace grande\u00bb. \u00bfContra qu\u00e9 estaba advirtiendo?<\/h4>\n\n\n\n<p>Europa posee muchas fortalezas y algunas debilidades profundas. Mi advertencia fue que la UE no debe desperdiciar su mayor fortaleza en la era digital: su compromiso con la protecci\u00f3n de los derechos de los usuarios y con un mercado digital equitativo. Europa ha liderado al mundo en la defensa de la privacidad, la seguridad en l\u00ednea y la competencia. Y seamos claros: no podemos confiar en que los directivos de las empresas tecnol\u00f3gicas protejan voluntariamente los valores sociales. Se requiere una supervisi\u00f3n democr\u00e1tica para establecer salvaguardas en la econom\u00eda digital, y Europa ha sido ese estandarte a nivel mundial. Europa no deber\u00eda librar la batalla equivocada. El exceso de regulaci\u00f3n no es la raz\u00f3n fundamental por la que Europa se queda atr\u00e1s en el \u00e1mbito tecnol\u00f3gico; la falta de un mercado digital unificado, unos mercados de capitales subdesarrollados, una aversi\u00f3n cultural al riesgo y las brechas de talento son factores de mucha mayor envergadura. En lugar de desmantelar el RGPD o debilitar las futuras normativas sobre inteligencia artificial, Europa deber\u00eda abordar esos fundamentos. Hay que completar el mercado \u00fanico digital para que las empresas emergentes puedan expandirse por toda la UE; construir una uni\u00f3n de mercados de capitales s\u00f3lida para que los innovadores tengan acceso a financiaci\u00f3n para el crecimiento; reformar las leyes de insolvencia y la cultura en torno al fracaso para que los emprendedores puedan asumir riesgos y volver a intentarlo; y trabajar en materia de inmigraci\u00f3n para atraer y retener talento tecnol\u00f3gico de todo el mundo. Estas medidas contribuir\u00edan mucho m\u00e1s a la competitividad que desmantelar las regulaciones digitales de la UE.<\/p>\n\n\n\n<section class=\"wp-block-cg-blocks-custom-quote undefined section-quote-layout\"><div class=\"quote-layout\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-md-8 offset-md-2\"><p class=\"quote-title\"><strong>&#8220;El exceso de regulaci\u00f3n no es la raz\u00f3n fundamental por la que Europa se queda atr\u00e1s en tecnolog\u00eda; la falta de un mercado digital unificado, unos mercados de capitales subdesarrollados, una aversi\u00f3n cultural al riesgo y las brechas de talento son factores mucho m\u00e1s importantes.&#8221;<\/strong><\/p><\/div><\/div><\/div><\/div><\/section>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p><\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-en-su-nuevo-libro-digital-empires-usted-describe-tres-modelos-tecnologicos-en-competencia-el-enfoque-estadounidense-impulsado-por-el-mercado-el-enfoque-europeo-impulsado-por-los-derechos-y-el-modelo-chino-impulsado-por-el-estado-como-estan-evolucionando-esos-modelos-en-la-actualidad\">En su nuevo libro, <em>Digital Empires<\/em>, usted describe tres modelos tecnol\u00f3gicos en competencia: el enfoque estadounidense impulsado por el mercado, el enfoque europeo impulsado por los derechos y el modelo chino impulsado por el Estado. \u00bfC\u00f3mo est\u00e1n evolucionando esos modelos en la actualidad?<\/h4>\n\n\n\n<figure class=\"wp-block-image alignleft size-full is-resized\"><img decoding=\"async\" src=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2026\/02\/Anu-Bradford-pic4.jpg\" alt=\"\" class=\"wp-image-1201277\" style=\"width:400px\"\/><\/figure>\n\n\n\n<p>Estamos presenciando una verdadera convergencia hacia el modelo dirigido por el Estado en muchos aspectos. Ahora, todos est\u00e1n siguiendo el juego de Pek\u00edn. Las tensiones geopol\u00edticas han impulsado a los gobiernos a asumir un papel mucho m\u00e1s destacado en el \u00e1mbito tecnol\u00f3gico. Estados Unidos \u2014tradicionalmente muy partidario de la no intervenci\u00f3n y guiado por el mercado\u2014 est\u00e1 ahora interviniendo de manera contundente en el sector tecnol\u00f3gico cuando la seguridad nacional o la ventaja estrat\u00e9gica est\u00e1n en juego. El pa\u00eds est\u00e1 subvencionando la fabricaci\u00f3n nacional de semiconductores, restringiendo las exportaciones de chips avanzados e incluso adquiriendo participaciones accionariales o imponiendo prohibiciones de inversi\u00f3n; acciones que, en ocasiones, hacen que Estados Unidos parezca m\u00e1s Pek\u00edn que el propio Pek\u00edn. Europa, por su parte, ha puesto en marcha sus propias pol\u00edticas industriales para el sector tecnol\u00f3gico, en su empe\u00f1o por lograr una mayor soberan\u00eda tecnol\u00f3gica. Los europeos dependen en exceso de las tecnolog\u00edas estadounidenses y chinas. Sol\u00eda \u200b\u200bpreocuparme la necesidad de Europa de reducir su exposici\u00f3n a los riesgos derivados de China, pero ahora los europeos deben reducir esos riesgos tambi\u00e9n con respecto a Estados Unidos. As\u00ed pues, la brecha entre el enfoque de libre mercado y el enfoque controlado por el Estado se est\u00e1 estrechando. Cada uno de los tres grandes actores est\u00e1 haciendo hincapi\u00e9 en la soberan\u00eda y el control sobre las tecnolog\u00edas clave.<\/p>\n\n\n\n<p>Dicho esto, persisten distinciones importantes. En el plano cultural, Estados Unidos sigue siendo m\u00e1s tecnolibertario: empodera a las grandes tecnol\u00f3gicas para impulsar la innovaci\u00f3n y se muestra bastante reacio a regular la privacidad de los datos, la inteligencia artificial o el contenido de las redes sociales. La opini\u00f3n predominante tanto en Silicon Valley como en Washington es que la regulaci\u00f3n podr\u00eda socavar el liderazgo tecnol\u00f3gico estadounidense, por lo que se muestran recelosos ante el tipo de normas estrictas que favorece Europa. Europa, por su parte, atraviesa una suerte de crisis de identidad: si bien ha abanderado un modelo centrado en los derechos (privacidad, seguridad, competencia), ahora se cuestiona a s\u00ed misma y se inclina gradualmente hacia la postura estadounidense de flexibilizar la normativa. Y China, naturalmente, contin\u00faa con su modelo autoritario y dirigido por el Estado: un f\u00e9rreo control estatal sobre los datos y las plataformas, una censura estricta y una inversi\u00f3n p\u00fablica masiva en los sectores tecnol\u00f3gicos.<\/p>\n\n\n\n<p>Es importante destacar que el enfoque basado en valores y orientado a los derechos no ha desaparecido. Sigue existiendo una demanda p\u00fablica significativa de protecci\u00f3n de la privacidad, rendici\u00f3n de cuentas y freno a los excesos corporativos. Incluso en Estados Unidos, a pesar de la ret\u00f3rica desreguladora, existe una preocupaci\u00f3n bipartidista respecto al poder de las grandes tecnol\u00f3gicas; los casos antimonopolio contra los gigantes tecnol\u00f3gicos siguen su curso y muchos estados est\u00e1n implementando sus propias normativas sobre privacidad e inteligencia artificial. En Europa, se observa una resistencia a una desregulaci\u00f3n excesiva. Por tanto, nos encontramos en un momento de cambio. En t\u00e9rminos generales, observamos una mayor influencia estatal y una inclinaci\u00f3n hacia el proteccionismo en todas partes, pero tambi\u00e9n existe un reconocimiento subyacente de que unos mercados tecnol\u00f3gicos totalmente desbocados pueden poner en peligro valores sociales fundamentales. Los tres \u00abimperios digitales\u00bb siguen siendo distintos, pero sus fronteras se est\u00e1n difuminando a medida que cada uno intenta asegurar su futuro tecnol\u00f3gico en un mundo vol\u00e1til.<a id=\"_msocom_1\"><\/a><a id=\"_msocom_1\"><\/a><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p><\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-es-realmente-alcanzable-la-verdadera-soberania-tecnologica\">\u00bfEs realmente alcanzable la verdadera soberan\u00eda tecnol\u00f3gica?<\/h4>\n\n\n\n<p>Muchas naciones est\u00e1n, de hecho, intentando cubrirse las espaldas y desarrollar capacidades tecnol\u00f3gicas internas. India, por ejemplo, habla de soberan\u00eda digital y ha adoptado medidas como la localizaci\u00f3n de datos y el fomento de <em>startups<\/em> de origen nacional. Pa\u00edses como Rusia, Brasil y otros han manifestado su deseo de controlar en mayor medida su destino digital. El impulso por depender menos de la tecnolog\u00eda extranjera se ha vuelto pr\u00e1cticamente universal. Sin embargo, una aut\u00e9ntica soberan\u00eda tecnol\u00f3gica integral resulta extraordinariamente dif\u00edcil \u2014si no imposible\u2014 para casi cualquier pa\u00eds. El ecosistema tecnol\u00f3gico moderno est\u00e1 profundamente globalizado y es interdependiente. Tomemos el caso de los semiconductores: ninguna naci\u00f3n por s\u00ed sola controla la totalidad de la cadena de suministro. Estados Unidos puede dise\u00f1ar chips de vanguardia, pero depende de m\u00e1quinas de litograf\u00eda neerlandesas, productos qu\u00edmicos japoneses, procesos de fabricaci\u00f3n taiwaneses o coreanos, y minerales de tierras raras procesados \u200b\u200ben gran medida en China. La propia China, a pesar de destinar ingentes recursos al desarrollo de chips, sigue dependiendo de equipos extranjeros para su fabricaci\u00f3n, as\u00ed como de propiedad intelectual for\u00e1nea. Europa posee fortalezas en \u00e1reas como los equipos para semiconductores (ASML en los Pa\u00edses Bajos, por ejemplo), pero tampoco abarca la totalidad del proceso. Ning\u00fan pa\u00eds puede actuar en solitario; ni siquiera una superpotencia.<\/p>\n\n\n\n<section class=\"wp-block-cg-blocks-custom-quote undefined section-quote-layout\"><div class=\"quote-layout\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-md-8 offset-md-2\"><p class=\"quote-title\"><strong>&#8220;Una aut\u00e9ntica soberan\u00eda tecnol\u00f3gica de extremo a extremo es extraordinariamente dif\u00edcil \u2014si no imposible\u2014 para casi cualquier pa\u00eds.&#8221;<\/strong><\/p><\/div><\/div><\/div><\/div><\/section>\n\n\n\n<p><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p><\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-que-significan-estos-cambios-geopoliticos-para-las-empresas-globales-como-deberian-las-empresas-desenvolverse-en-un-mundo-en-el-que-los-mercados-tecnologicos-se-estan-fragmentando-segun-lineas-nacionales\">\u00bfQu\u00e9 significan estos cambios geopol\u00edticos para las empresas globales? \u00bfC\u00f3mo deber\u00edan las empresas desenvolverse en un mundo en el que los mercados tecnol\u00f3gicos se est\u00e1n fragmentando seg\u00fan l\u00edneas nacionales?<\/h4>\n\n\n\n<figure class=\"wp-block-image alignright size-large is-resized\"><img decoding=\"async\" src=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2026\/02\/Anu-Bradford-pic1.jpg?w=960\" alt=\"\" class=\"wp-image-1201275\" style=\"width:500px\"\/><\/figure>\n\n\n\n<p>Se est\u00e1 convirtiendo en un enorme desaf\u00edo para las empresas tecnol\u00f3gicas multinacionales \u2014y, en realidad, para cualquier empresa afectada por la normativa digital (lo cual, hoy en d\u00eda, abarca a casi todas). Durante la \u00faltima d\u00e9cada, muchas firmas se beneficiaron de est\u00e1ndares relativamente armonizados o, al menos, de la capacidad de operar a nivel global con un conjunto \u00fanico de pr\u00e1cticas; a menudo, optaban por adoptar por defecto el r\u00e9gimen m\u00e1s estricto \u2014como las normas de la UE\u2014 y lo aplicaban en todo el mundo. Ese era el cl\u00e1sico \u00abefecto Bruselas\u00bb. Ahora, las empresas se ven cada vez m\u00e1s atrapadas entre gobiernos y regulaciones contrapuestos. Estados Unidos y la UE, por ejemplo, discrepan en cuestiones como la moderaci\u00f3n de contenidos, los flujos de datos y la supervisi\u00f3n de la inteligencia artificial. Es posible que la legislaci\u00f3n europea exija a una plataforma retirar contenidos que inciten al odio o constituyan desinformaci\u00f3n; sin embargo, en algunos casos, hacer lo mismo en Estados Unidos podr\u00eda provocar una reacci\u00f3n pol\u00edtica adversa o incluso contravenir las normas estadounidenses sobre la libertad de expresi\u00f3n, que son m\u00e1s permisivas. La perspectiva, a la larga, de tener que enfrentarse a normativas irreconciliables es una realidad.<\/p>\n\n\n\n<p>Para las empresas, esto supone mayores costes y decisiones dif\u00edciles. Es posible que deban mantener sistemas, pol\u00edticas o incluso versiones de productos distintos para las diferentes regiones. Ya observamos una versi\u00f3n leve de este fen\u00f3meno: pensemos en las empresas de redes sociales que desactivan ciertas funcionalidades en Europa para cumplir con el RGPD o la Ley de Servicios Digitales, o en los proveedores de servicios en la nube que ofrecen particiones especiales de \u00abnube soberana\u00bb para sus clientes europeos. En el pasado, las empresas sol\u00edan optar por cumplir a nivel global con el est\u00e1ndar m\u00e1s estricto para simplificar los procesos; sin embargo, hoy en d\u00eda, ese mismo est\u00e1ndar podr\u00eda acarrearles sanciones en otras jurisdicciones. Si la fragmentaci\u00f3n se intensifica, algunas empresas podr\u00edan verse obligadas a implementar configuraciones espec\u00edficas para cada regi\u00f3n a fin de satisfacer requisitos contradictorios. Si bien esto resulta costoso y operativamente complejo, en algunos casos podr\u00eda ser indispensable.<\/p>\n\n\n\n<p>Tambi\u00e9n existe un verdadero problema de confianza en juego. Los clientes y gobiernos internacionales est\u00e1n empezando a cuestionarse si los proveedores tecnol\u00f3gicos extranjeros acatar\u00e1n las leyes locales o los dictados de su propio gobierno de origen. Por ejemplo, a los funcionarios europeos les preocupa lo siguiente: llegado el momento decisivo, \u00bfse pondr\u00e1 una empresa estadounidense del lado de Washington o de Bruselas? Vimos el caso inverso en Estados Unidos con TikTok: \u00bfpuede una plataforma de propiedad china aislar verdaderamente, mediante un \u00abcortafuegos\u00bb, los datos de sus usuarios estadounidenses del gobierno de Pek\u00edn? Muchos en Estados Unidos lo dudan; de ah\u00ed la presi\u00f3n ejercida sobre TikTok. Del mismo modo, los clientes europeos est\u00e1n empezando a preguntarse si el uso de un servicio de computaci\u00f3n en la nube estadounidense podr\u00eda dejarlos expuestos en caso de que una futura administraci\u00f3n de EE. UU. adopte un rumbo hostil. Esta situaci\u00f3n est\u00e1 obligando a las empresas a prometer soluciones de \u00absoberan\u00eda digital\u00bb \u2014como almacenar y procesar los datos de la UE exclusivamente en Europa y bajo jurisdicci\u00f3n europea\u2014 con el fin de tranquilizar a sus clientes.<\/p>\n\n\n\n<p>Las empresas se encuentran entre la espada y la pared. Consideremos un escenario concreto: si una administraci\u00f3n estadounidense exigiera a una empresa tecnol\u00f3gica de su pa\u00eds que interrumpiera sus servicios a Europa o que entregara los datos de los usuarios europeos, dicha empresa se ver\u00eda en una posici\u00f3n imposible: infringir la legislaci\u00f3n estadounidense o la de la UE; en cualquier caso, se enfrentar\u00eda a enormes responsabilidades legales y a un grave da\u00f1o reputacional. A\u00fan no hemos presenciado una situaci\u00f3n tan extrema entre Estados Unidos y Europa (dado que son aliados), pero s\u00ed la hemos visto en otros contextos \u2014como en el cumplimiento de sanciones\u2014, y podr\u00eda ocurrir tambi\u00e9n en el \u00e1mbito tecnol\u00f3gico. Hasta la fecha, este tipo de conflictos transatl\u00e1nticos han sido poco frecuentes y se han gestionado como excepciones, en lugar de como problemas sist\u00e9micos. No obstante, las empresas deben actuar con astucia. Necesitan contar con planes de contingencia ante posibles fracturas geopol\u00edticas: desde la diversificaci\u00f3n de sus cadenas de suministro hasta estar preparadas para localizar sus operaciones si fuera necesario. En algunos casos, las empresas podr\u00edan concluir que un mercado resulta demasiado arriesgado y optar por abandonarlo si los requisitos legales divergen de manera dr\u00e1stica. Hemos visto a empresas enfrentarse en China a disyuntivas que desencadenaron una fuerte reacci\u00f3n adversa por parte de la opini\u00f3n p\u00fablica, lo cual hizo que continuar operando resultara dif\u00edcil, e incluso imposible. No es descabellado pensar que podr\u00edan surgir dilemas similares en otros lugares.<\/p>\n\n\n\n<p>Las empresas tendr\u00e1n que ser m\u00e1s \u00e1giles y adaptarse a las especificidades de cada jurisdicci\u00f3n. Necesitar\u00e1n interactuar con los responsables pol\u00edticos en todos los mercados principales para hallar soluciones de compromiso viables; en esencia, se convertir\u00e1n tanto en diplom\u00e1ticos como en empresas.<\/p>\n\n\n\n<section class=\"wp-block-cg-blocks-custom-quote undefined section-quote-layout\"><div class=\"quote-layout\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-md-8 offset-md-2\"><p class=\"quote-title\"><strong>&#8220;Los clientes internacionales y los gobiernos est\u00e1n empezando a cuestionar si los proveedores tecnol\u00f3gicos extranjeros acatar\u00e1n las leyes locales o los dictados de su gobierno de origen.&#8221;<\/strong><\/p><\/div><\/div><\/div><\/div><\/section>\n\n\n\n<p><a id=\"_msocom_1\"><\/a><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p><\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-cree-que-las-empresas-deben-elevar-la-gestion-del-riesgo-geopolitico-al-nivel-de-la-alta-direccion-es-hora-de-contar-con-un-director-geopolitico\">\u00bfCree que las empresas deben elevar la gesti\u00f3n del riesgo geopol\u00edtico al nivel de la alta direcci\u00f3n? \u00bfEs hora de contar con un director geopol\u00edtico?<\/h4>\n\n\n\n<p>Por supuesto. El riesgo geopol\u00edtico ha pasado de ser una preocupaci\u00f3n perif\u00e9rica a convertirse en un asunto central de la alta direcci\u00f3n para las empresas globales. Del mismo modo que las compa\u00f1\u00edas cuentan con directores financieros para gestionar su salud econ\u00f3mica y con directores de seguridad para administrar la ciberseguridad, ahora necesitan un estratega principal de alto nivel para los riesgos pol\u00edticos y geopol\u00edticos. Ya sea que se le denomine director geopol\u00edtico o se le asigne un t\u00edtulo similar, su funci\u00f3n consistir\u00eda en anticipar y gestionar el tipo de desaf\u00edos que hemos estado analizando: la fragmentaci\u00f3n regulatoria, las sanciones, las guerras comerciales e incluso los conflictos que podr\u00edan perturbar las operaciones.<\/p>\n\n\n\n<p>En t\u00e9rminos pr\u00e1cticos, esto implica conformar un equipo dedicado a monitorear el horizonte en busca de acontecimientos geopol\u00edticos y a analizar c\u00f3mo estos podr\u00edan repercutir en el negocio. Este equipo debe colaborar estrechamente con todas las \u00e1reas de la empresa \u2014producto, cadena de suministro, cumplimiento normativo, ventas\u2014, dado que las cuestiones geopol\u00edticas afectan a todos los aspectos de la actividad empresarial. El equipo de riesgo geopol\u00edtico debe estar plenamente integrado en el proceso de toma de decisiones corporativas, en lugar de limitarse a elaborar informes puntuales de manera espor\u00e1dica. Cabr\u00eda esperar que este equipo realice ejercicios de planificaci\u00f3n de escenarios (\u00ab\u00bfQu\u00e9 suceder\u00eda si las relaciones entre X e Y se deterioraran el pr\u00f3ximo a\u00f1o? \u00bfC\u00f3mo responder\u00edamos?\u00bb), asesore en las decisiones relativas a la entrada o salida de mercados, y mantenga una coordinaci\u00f3n con los equipos de asuntos gubernamentales en lo referente a las tendencias pol\u00edticas.<\/p>\n\n\n\n<p>En la actualidad, muchas empresas abordan estos riesgos de manera fragmentada: un equipo legal se encarga del cumplimiento de las sanciones, un equipo de operaciones gestiona la diversificaci\u00f3n de la cadena de suministro y, tal vez, se recurre a un consultor externo cuando surge una crisis. Esto ya no es suficiente.<\/p>\n\n\n\n<section class=\"wp-block-cg-blocks-custom-quote undefined section-quote-layout\"><div class=\"quote-layout\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-md-8 offset-md-2\"><p class=\"quote-title\"><strong>&#8220;El riesgo geopol\u00edtico ha pasado de ser una preocupaci\u00f3n perif\u00e9rica a convertirse en un asunto central de los consejos de administraci\u00f3n para las empresas globales.&#8221;<\/strong><\/p><\/div><\/div><\/div><\/div><\/section>\n\n\n\n<p><a id=\"_msocom_1\"><\/a><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p><\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-como-deberia-ser-un-equipo-de-riesgos-geopoliticos-de-este-tipo-que-habilidades-o-enfoques-resultan-cruciales-para-gestionar-estos-riesgos-de-manera-eficaz\">\u00bfC\u00f3mo deber\u00eda ser un equipo de riesgos geopol\u00edticos de este tipo? \u00bfQu\u00e9 habilidades o enfoques resultan cruciales para gestionar estos riesgos de manera eficaz?<\/h4>\n\n\n\n<p>La clave reside en la diversidad de perspectivas y conocimientos especializados. La geopol\u00edtica es multifac\u00e9tica \u2014abarca la econom\u00eda, el derecho, la seguridad y la cultura\u2014 y se manifiesta de manera distinta en cada regi\u00f3n. Por ello, no cabe esperar que un solo analista o un \u00fanico modelo de datos logre abarcarlo todo. Se requiere un equipo integrado por personas que comprendan diversos \u00e1mbitos y geograf\u00edas. Estos expertos deben colaborar e intercambiar ideas y conocimientos de forma rec\u00edproca. Han de ser capaces de vincular la estrategia de la empresa y sus oportunidades de negocio con una s\u00f3lida comprensi\u00f3n de la tecnolog\u00eda, todo ello enmarcado en una conciencia clara de la pol\u00edtica tanto interna como exterior. Deben mostrarse proactivos en la evaluaci\u00f3n de riesgos, sin dejar de reconocer, al mismo tiempo, que existe una gran cantidad de \u00abruido\u00bb informativo. Si no se cuenta con un equipo experimentado en riesgos geopol\u00edticos, es muy probable que se termine reaccionando de forma desmedida ante cualquier acontecimiento. Asimismo, las empresas necesitan contar con conocimientos especializados a nivel regional. Por ejemplo, resulta dif\u00edcil encontrar a alguien que sepa prever la reacci\u00f3n de Bruselas y que, simult\u00e1neamente, comprenda la din\u00e1mica de Pek\u00edn.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p><\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-en-el-caso-de-tecnologias-emergentes-como-la-ia-como-pueden-los-paises-equilibrar-la-presion-por-regular-con-el-impulso-a-la-innovacion\">En el caso de tecnolog\u00edas emergentes como la IA, \u00bfc\u00f3mo pueden los pa\u00edses equilibrar la presi\u00f3n por regular con el impulso a la innovaci\u00f3n?<\/h4>\n\n\n\n<p>La IA es multifac\u00e9tica y evoluciona con rapidez, con un alto grado de trascendencia tanto en lo que respecta a los riesgos como a las oportunidades. Los gobiernos no deben limitarse a ser espectadores que permitan que sean las empresas, por s\u00ed solas, quienes moldeen la pr\u00f3xima d\u00e9cada. Necesitamos un enfoque regulatorio \u00e1gil, con normas vigentes desde ahora y la disposici\u00f3n a revisarlas a medida que la tecnolog\u00eda evolucione.<\/p>\n\n\n\n<p>En Europa, revisar el marco regulatorio de la IA tan poco tiempo despu\u00e9s de su promulgaci\u00f3n corre el riesgo de socavar la credibilidad y generar una mayor incertidumbre, justo en el momento en que las empresas se est\u00e1n adaptando. Algunos de los cambios propuestos consisten en aplazamientos; por ejemplo, extender el plazo para finalizar los est\u00e1ndares en \u00e1reas de alto riesgo. Otros podr\u00edan tener un alcance m\u00e1s profundo, como las propuestas relativas al uso de datos personales para el entrenamiento de grandes modelos ling\u00fc\u00edsticos. Me preocupa que las reformas se vean a\u00fan m\u00e1s condicionadas por las presiones corporativas, as\u00ed como una aplicaci\u00f3n menos firme de la normativa en un momento en que la carrera por la IA se est\u00e1 intensificando y las tensiones geopol\u00edticas son elevadas. Esta combinaci\u00f3n incrementa el riesgo de que se tomen decisiones irresponsables que podr\u00edan perjudicar a la sociedad.<\/p>\n\n\n\n<p>No se trata de elegir entre innovaci\u00f3n y seguridad. Necesitamos ambas, a partir de ahora, y debemos perfeccionar las normas a medida que adquirimos conocimientos. Me preocupa que las medidas iniciales para simplificar puedan ir demasiado lejos, generar incertidumbre y enviar se\u00f1ales contradictorias, justo cuando muchos gobiernos est\u00e1n elaborando sus propios marcos normativos y buscando orientaci\u00f3n en Europa. Mientras tanto, Estados Unidos avanza con rapidez \u2014a menudo centrado en la IGA (Inteligencia General Artificial)\u2014, y China est\u00e1 logrando avances pragm\u00e1ticos, incluso a escala global, en el \u00e1mbito de la IA de c\u00f3digo abierto. Europa debe aprovechar sus propias fortalezas, las cuales \u2014para la mayor\u00eda de las empresas\u2014 dif\u00edcilmente residir\u00e1n en los modelos fundacionales. Sin embargo, Europa no tiene ninguna desventaja inherente a la hora de desarrollar aplicaciones de IA y acelerar su adopci\u00f3n en todos los sectores industriales. La cuesti\u00f3n reside en determinar qu\u00e9 carrera es la que realmente importa y c\u00f3mo garantizar que la IA sea segura a medida que avanza.<\/p>\n\n\n\n<section class=\"wp-block-cg-blocks-custom-quote undefined section-quote-layout\"><div class=\"quote-layout\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-md-8 offset-md-2\"><p class=\"quote-title\"><strong>&#8220;En Europa, revisar el marco de la IA tan poco tiempo despu\u00e9s de su promulgaci\u00f3n corre el riesgo de erosionar la credibilidad y generar mayor incertidumbre, justo cuando las empresas se est\u00e1n adaptando.&#8221;<\/strong><\/p><\/div><\/div><\/div><\/div><\/section>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p><\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-es-la-soberania-de-la-ia-un-objetivo-realista\">\u00bfEs la soberan\u00eda de la IA un objetivo realista?<\/h4>\n\n\n\n<p>Una verdadera soberan\u00eda en IA implicar\u00eda que un pa\u00eds mantenga sus vulnerabilidades bajo control. Nadie llegar\u00e1 a controlar la totalidad de la pila tecnol\u00f3gica de la IA \u2014desde las materias primas y los servicios en la nube hasta la soberan\u00eda de los datos, los modelos desarrollados localmente y, muy especialmente, la capa de hardware\u2014; \u00e1mbito este \u00faltimo en el que los semiconductores constituyen un claro ejemplo de una industria profundamente interconectada a nivel global. Por consiguiente, no creo que exista tal cosa como una soberan\u00eda absoluta en materia de IA. El objetivo realista es de car\u00e1cter relativo: avanzar hacia una mayor soberan\u00eda mediante la reducci\u00f3n de las vulnerabilidades. Para algunos pa\u00edses, esto se traduce en establecer m\u00e1s alianzas y estrategias de cobertura; para otros, implica potenciar la inversi\u00f3n interna con el fin de realizar m\u00e1s actividades dentro de sus propias fronteras y desarrollar capacidades propias.<\/p>\n\n\n\n<p>Para Estados Unidos, el objetivo tambi\u00e9n ha sido restringir el acceso de sus rivales a capacidades clave; por ejemplo, limitando el acceso de China a puntos de estrangulamiento \u2014como los chips m\u00e1s avanzados\u2014 con el fin de mantener su liderazgo en la carrera de la IA. Esto tambi\u00e9n puede incentivar a China a innovar sorteando dichas restricciones, y lo cierto es que el pa\u00eds asi\u00e1tico ha demostrado gran destreza para hacer que el desarrollo de la IA sea m\u00e1s eficiente en t\u00e9rminos de capital y energ\u00eda. No obstante, Estados Unidos tambi\u00e9n presenta vulnerabilidades. Los costos energ\u00e9ticos son elevados y la red el\u00e9ctrica es limitada, mientras que los centros de datos requieren un enorme suministro de energ\u00eda. Esta situaci\u00f3n puede disparar las facturas de electricidad y acarrear un costo pol\u00edtico en un pa\u00eds que ya se enfrenta a una crisis del costo de la vida. Estados Unidos no controla la totalidad de la cadena de valor, y aumentar la producci\u00f3n nacional de chips con rapidez resulta inviable, dado que carece de la totalidad de los equipos y las materias primas necesarios. Incluso en los casos en que se dispone de capital, las inversiones suelen financiarse mediante deuda, lo cual puede generar una fragilidad sist\u00e9mica. Existe la posibilidad de que se agote el suministro el\u00e9ctrico necesario para abastecer a los centros de datos que se est\u00e1n construyendo. Incluso el l\u00edder mundial en el \u00e1mbito de la IA se enfrenta a limitaciones en esa escurridiza b\u00fasqueda de la soberan\u00eda en inteligencia artificial.<\/p>\n\n\n\n<p>En Europa, los pa\u00edses tambi\u00e9n deben considerar c\u00f3mo sus vulnerabilidades geopol\u00edticas y sus costos ambientales influyen en estas decisiones.<\/p>\n\n\n\n<section class=\"wp-block-cg-blocks-custom-quote undefined section-quote-layout\"><div class=\"quote-layout\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-md-8 offset-md-2\"><p class=\"quote-title\">&#8220;No creo que exista tal cosa como una soberan\u00eda total en IA.<br>Incluso el l\u00edder mundial en IA enfrenta l\u00edmites en esa elusiva b\u00fasqueda de la soberan\u00eda en IA.&#8221;<\/p><\/div><\/div><\/div><\/div><\/section>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p><\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-cual-considera-que-es-el-papel-de-iniciativas-como-euro-stack-o-gaia-x-para-el-desarrollo-de-una-infraestructura-digital-comun\">\u00bfCu\u00e1l considera que es el papel de iniciativas como Euro Stack o Gaia-X para el desarrollo de una infraestructura digital com\u00fan?<\/h4>\n\n\n\n<figure class=\"wp-block-image alignleft size-full is-resized\"><img decoding=\"async\" src=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2026\/02\/Anu-Bradford-pic3.jpg\" alt=\"\" class=\"wp-image-1201276\" style=\"width:400px\"\/><\/figure>\n\n\n\n<p id=\"h-what-do-you-see-as-the-role-of-initiatives-such-as-the-euro-stack-or-gaia-x-for-developing-common-digital-infrastructure\">Los europeos necesitan un plan de pol\u00edtica industrial genuino. Mi preocupaci\u00f3n es que esto pueda derivar en una gran cantidad de inversiones ineficientes. Los gobiernos europeos no disponen de recursos ilimitados. Gaia-X no ha resultado ser particularmente exitoso. Se han producido intentos \u2014por ejemplo, por parte del gobierno franc\u00e9s\u2014 de desarrollar un motor de b\u00fasqueda nacional e, incluso, de hacer que los gobiernos recurran por defecto a tecnolog\u00edas sub\u00f3ptimas. Eso no funciona. La pol\u00edtica industrial es, probablemente, necesaria en los tiempos que corren, pero sigue siendo susceptible de caer en el despilfarro.<\/p>\n\n\n\n<p>Necesitamos una combinaci\u00f3n de capital p\u00fablico y privado para financiar el Euro Stack. El Euro Stack no puede constituir una alternativa total a las tecnolog\u00edas estadounidenses. Algunas tecnolog\u00edas resultan m\u00e1s sencillas de desarrollar a nivel interno, mientras que otras son m\u00e1s complejas. Los europeos deben analizar con realismo sus fortalezas y vulnerabilidades, los costes relativos, aquello que puede acometerse de inmediato, lo que puede realizarse a medio plazo, lo que corresponde al largo plazo y cu\u00e1les son las prioridades. No todo puede llevarse a cabo de forma inmediata, y los recursos financieros son limitados.<\/p>\n\n\n\n<p>Por eso estoy deseoso de movilizar m\u00e1s capital privado en Europa. La Uni\u00f3n de los Mercados de Capitales deber\u00eda ser una obviedad, y lleva mucho tiempo gest\u00e1ndose. Existe una gran cantidad de capital en los fondos de pensiones y en las inversiones institucionales que no se canaliza hacia el sistema. Existen muchas restricciones sobre d\u00f3nde pueden invertir, y la tecnolog\u00eda de gesti\u00f3n de riesgos no est\u00e1 disponible para los fondos de pensiones en muchos pa\u00edses europeos. Europa tiene dinero, pero este debe canalizarse de manera mucho m\u00e1s eficaz.<\/p>\n\n\n\n<p>No podemos permitirnos depender \u00fanicamente de los programas de desarrollo impulsados \u200b\u200bpor el gobierno. Gran parte de esos recursos se destinar\u00e1 a tecnolog\u00edas militares, y muchas de estas tecnolog\u00edas son de doble uso. En los Estados Unidos, no es el Pent\u00e1gono quien desarrolla la IA para fines militares; esta proviene de Silicon Valley y es de doble uso, sirviendo tanto a aplicaciones comerciales como militares. Es necesaria una colaboraci\u00f3n eficiente \u2014que incluya la contrataci\u00f3n conjunta cuando intervengan fondos p\u00fablicos\u2014; asimismo, debemos dar rienda suelta plenamente al esp\u00edritu emprendedor y a los mercados de capitales para contribuir a la construcci\u00f3n de capacidades europeas.<\/p>\n\n\n\n<section class=\"wp-block-cg-blocks-custom-quote undefined section-quote-layout\"><div class=\"quote-layout\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-md-8 offset-md-2\"><p class=\"quote-title\"><strong>&#8220;<\/strong>Una verdadera soberan\u00eda en IA significar\u00eda que un pa\u00eds mantenga sus vulnerabilidades bajo control.&#8221;<\/p><\/div><\/div><\/div><\/div><\/section>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p><\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-cuales-son-sus-opiniones-sobre-el-tema-emergente-de-la-soberania-de-los-datos\">\u00bfCu\u00e1les son sus opiniones sobre el tema emergente de la soberan\u00eda de los datos?<\/h4>\n\n\n\n<p id=\"h-what-are-your-views-on-the-emerging-topic-of-data-sovereignty\">La cuesti\u00f3n de la soberan\u00eda de los datos es de suma importancia. China lleva mucho tiempo restringiendo el movimiento de datos fuera del pa\u00eds. Estados Unidos \u2014incluso en el seno de la OMC\u2014 ha promovido durante largo tiempo la idea de que los flujos de datos no deber\u00edan restringirse; sin embargo, incluso el propio Estados Unidos est\u00e1 modificando ahora su postura. Los europeos, a trav\u00e9s del RGPD y de decisiones conexas, han procurado restringir los flujos de datos hacia Estados Unidos en aquellos casos en que estos pudieran comprometer los derechos a la privacidad de los datos. As\u00ed pues, nos enfrentamos ahora a inquietudes tanto en materia de privacidad como de seguridad nacional: dos razones de peso para abogar por una mayor soberan\u00eda de los datos.<\/p>\n\n\n\n<p>Hemos observado una creciente exigencia de almacenar datos localmente. Sin embargo, los mandatos de localizaci\u00f3n de datos resultan costosos para las empresas. A mi juicio, los pa\u00edses deber\u00edan, como m\u00ednimo, prepararse para afrontar obligaciones que impulsen la adopci\u00f3n de soluciones de datos localizadas, o bien exigir pruebas de que es posible salvaguardar el control soberano sobre los datos, incluso cuando estos se encuentran en manos de empresas extranjeras. La cuesti\u00f3n radica en c\u00f3mo deben actuar las empresas en el marco de la Ley CLOUD de los Estados Unidos. Los europeos son conscientes de que las autoridades estadounidenses pueden obligar a las empresas tecnol\u00f3gicas de su pa\u00eds a entregar datos al gobierno de los Estados Unidos; una situaci\u00f3n que suscita una inquietud cada vez mayor a medida que se profundiza la brecha transatl\u00e1ntica.<\/p>\n\n\n\n<p>Para los europeos, la soberan\u00eda de los datos se ha concebido, en gran medida, a trav\u00e9s del prisma de la protecci\u00f3n de los mismos. Si bien este enfoque es importante, ha supuesto renunciar a numerosas oportunidades para comercializar dichos datos. En Europa existe un vasto acervo de datos a\u00fan inexplorados que, si bien deben ser protegidos, tambi\u00e9n han de utilizarse para la innovaci\u00f3n, la inversi\u00f3n y la comercializaci\u00f3n, siempre de manera compatible con la protecci\u00f3n de datos. Lamento la idea de que esta situaci\u00f3n se perciba a menudo como una disyuntiva tajante entre los derechos y las oportunidades comerciales. Las empresas pueden ofrecer soluciones que satisfagan ambos objetivos. Debemos demostrar c\u00f3mo liberar el potencial de estos acervos de datos, insistiendo al mismo tiempo en que ello se realice sin comprometer la privacidad de los mismos. Es posible tener ambas cosas.<\/p>\n\n\n\n<section class=\"wp-block-cg-blocks-custom-quote undefined section-quote-layout\"><div class=\"quote-layout\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-md-8 offset-md-2\"><p class=\"quote-title\"><strong>&#8220;Existe en Europa un vasto conjunto de datos sin explotar que debe ser protegido, pero tambi\u00e9n utilizado para la innovaci\u00f3n, la inversi\u00f3n y la comercializaci\u00f3n, de manera compatible con la protecci\u00f3n de datos.&#8221;<\/strong><\/p><\/div><\/div><\/div><\/div><\/section>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p><\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-si-estuviera-asesorando-al-consejo-de-administracion-de-una-empresa-del-global-500-sobre-los-riesgos-geopoliticos-en-el-ambito-tecnologico-cuales-serian-las-dos-o-tres-acciones-principales-que-les-recomendaria-emprender-este-ano\">Si estuviera asesorando al consejo de administraci\u00f3n de una empresa del Global 500 sobre los riesgos geopol\u00edticos en el \u00e1mbito tecnol\u00f3gico, \u00bfcu\u00e1les ser\u00edan las dos o tres acciones principales que les recomendar\u00eda emprender este a\u00f1o?<\/h4>\n\n\n\n<p id=\"h-if-you-were-advising-the-board-of-a-global-500-company-on-geopolitical-risks-in-technology-what-are-the-top-two-or-three-actions-you-would-recommend-they-take-this-year\">Me centrar\u00eda en tres \u00e1reas.<\/p>\n\n\n\n<p><strong>El desacoplamiento entre EE. UU. y China y el riesgo de Taiw\u00e1n<br><\/strong>Todav\u00eda se observa un desacoplamiento entre Estados Unidos y China, dada la magnitud de la rivalidad tecnol\u00f3gica y el tama\u00f1o de esos dos mercados. Los consejos de administraci\u00f3n deben gestionar una brecha que podr\u00eda profundizarse entre ambas naciones. Si bien existen se\u00f1ales m\u00e1s conciliadoras respecto al mantenimiento de relaciones comerciales funcionales, persiste un c\u00e1lculo geopol\u00edtico en torno a Taiw\u00e1n. Si la actividad de TSMC se viera interrumpida, la econom\u00eda global se paralizar\u00eda. No estoy prediciendo que China vaya a tomar posesi\u00f3n de Taiw\u00e1n; no obstante, todo consejo de administraci\u00f3n deber\u00eda contemplar escenarios que involucren a Taiw\u00e1n, Estados Unidos y China, as\u00ed como la magnitud y las manifestaciones del desacoplamiento tecnol\u00f3gico. Si se sobreestima el riesgo, se corre el riesgo de desaprovechar oportunidades; si se subestima, las disrupciones pueden resultar severas.<\/p>\n\n\n\n<p><strong>El papel regulador de Europa y las din\u00e1micas transatl\u00e1nticas<\/strong><br>Europa genera gran parte de la regulaci\u00f3n tecnol\u00f3gica y ejerce liderazgo para el resto del mundo. Si Europa retrocediera, ello alterar\u00eda significativamente el entorno regulatorio. Dudo que Europa se retire por completo; no obstante, las empresas deben sortear las tensiones transatl\u00e1nticas, as\u00ed como los esfuerzos europeos por lograr una mayor soberan\u00eda tecnol\u00f3gica mediante la reducci\u00f3n de riesgos tanto frente a China como frente a Estados Unidos. Esto reviste importancia, dado el valor del mercado europeo, la presencia de empresas tecnol\u00f3gicas en la regi\u00f3n y la posible ruptura de un frente unido entre Estados Unidos y la UE.<\/p>\n\n\n\n<p><strong>Gestionar una burbuja de IA y los riesgos de concentraci\u00f3n<br><\/strong>Los consejos de administraci\u00f3n deben contemplar la posibilidad de que estalle una burbuja de la IA, afectando as\u00ed a los flujos de inversi\u00f3n y a la industria. Al mismo tiempo, deben acelerar la adopci\u00f3n e invertir en los actores y niveles adecuados. Existe un riesgo si no se invierte en IA; no obstante, tambi\u00e9n es necesario seleccionar a los proveedores con cautela y protegerse frente a posibles fallos. Diversifique sus inversiones en un mercado de la IA cada vez m\u00e1s concentrado, a fin de no depender de un \u00fanico pa\u00eds, de un solo actor o de un \u00fanico modelo de lenguaje grande. Aseg\u00farese de contar con alternativas. Proteja la integridad de los datos de su empresa que puedan utilizarse para entrenar modelos de lenguaje grandes. Siempre que sea posible, considere la posibilidad de recurrir a modelos a medida que le otorguen un mayor control. Piense en soluciones no solo a nivel nacional, sino tambi\u00e9n a nivel de su propia empresa: sus datos, sus modelos, sus vulnerabilidades y qu\u00e9 suceder\u00eda si algunos proveedores dejaran de existir dentro de unos a\u00f1os.<\/p>\n\n\n\n<section class=\"wp-block-cg-blocks-custom-quote undefined section-quote-layout\"><div class=\"quote-layout\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-md-8 offset-md-2\"><p class=\"quote-title\"><strong>&#8220;Si TSMC se viera interrumpida, la econom\u00eda global se detendr\u00eda.&#8221;<\/strong><\/p><\/div><\/div><\/div><\/div><\/section>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p><\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-si-tuvieras-una-varita-magica-cual-seria-la-unica-cosa-que-cambiarias-sobre-la-forma-en-que-las-empresas-gestionan-el-riesgo-geopolitico-o-sobre-como-la-ue-y-otros-paises-lo-abordan\">Si tuvieras una varita m\u00e1gica, \u00bfcu\u00e1l ser\u00eda la \u00fanica cosa que cambiar\u00edas sobre la forma en que las empresas gestionan el riesgo geopol\u00edtico, o sobre c\u00f3mo la UE y otros pa\u00edses lo abordan?<\/h4>\n\n\n\n<p>Me gustar\u00eda que las empresas abordaran el riesgo geopol\u00edtico \u2014y el riesgo en general\u2014 como una oportunidad para clarificar su prop\u00f3sito y sus valores. Utilicen la volatilidad para replantearse la forma en que gestionan sus operaciones, los criterios en los que fundamentan sus decisiones y cu\u00e1les son sus valores, de modo que no se limiten a seguir la direcci\u00f3n de los vientos pol\u00edticos. No act\u00faen al estilo de Mark Zuckerberg: inclinarse hacia la moderaci\u00f3n de contenidos para luego abandonarla en cuanto cambia el panorama pol\u00edtico. Eso hace que la empresa d\u00e9 la impresi\u00f3n de carecer de principios.<\/p>\n\n\n\n<p>Las empresas de confianza proyectan seguridad en medio de la turbulencia. Piense en el esp\u00edritu de las declaraciones de Mark Carney (actual primer ministro de Canad\u00e1) en Davos: sepa qui\u00e9n es, acepte la volatilidad, tenga claros sus puntos fuertes y sus principios, y defina qu\u00e9 har\u00e1 ante los escenarios A, B o C. Est\u00e9 preparado, pues ha invertido en conocimiento, ha perfeccionado su estrategia y ha desarrollado agilidad. Combine el pragmatismo y el realismo con una base de principios, para no quedar a la deriva, cambiando de bando d\u00eda tras d\u00eda.<\/p>\n\n\n\n<p>Las empresas con valores claros se ganan la confianza del mercado. Por ejemplo, la administraci\u00f3n Trump presion\u00f3 a Microsoft para que despidiera a un responsable de pol\u00edticas p\u00fablicas que era percibido como alguien desalineado con la pol\u00edtica estadounidense; Microsoft no actu\u00f3, dej\u00f3 pasar la tormenta y la persona no fue destituida. Si una empresa comienza a despedir personal, a abandonar a sus clientes o a retirarse de ciertos mercados, proyecta una imagen de falta de rumbo y de carencia de br\u00fajula. No sea ingenuo; desarrolle habilidades diplom\u00e1ticas y pragmatismo. Sin embargo, sin un anclaje en valores y principios fundamentales, las empresas terminan perdiendo la confianza de sus clientes y empleados. Visto de este modo, toda la incertidumbre y volatilidad que se est\u00e1n desarrollando pueden convertirse tambi\u00e9n en un momento de gran claridad para aquellas empresas que act\u00faan con confianza y est\u00e1n bien gestionadas.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-container-core-column-is-layout-8a368f38 wp-block-column-is-layout-flow\" style=\"border-style:none;border-width:0px;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-left-radius:0px;border-bottom-right-radius:0px\">\n<section class=\"wp-block-cg-blocks-custom-quote undefined section-quote-layout\"><div class=\"quote-layout\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-md-8 offset-md-2\"><p class=\"quote-title\"><strong>&#8220;Utiliza la volatilidad para replantearte c\u00f3mo gestionas las cosas, c\u00f3mo fundamentas tus decisiones y cu\u00e1les son tus valores, de modo que no te limites simplemente a seguir los vientos pol\u00edticos.&#8221;<\/strong><\/p><\/div><\/div><\/div><\/div><\/section>\n<\/div>\n<\/div>\n\n\n\n<p><a id=\"_msocom_1\"><\/a><\/p>\n<\/div><\/div><\/div><\/div><\/div><\/section>\n\n\n\n<div class=\"wp-block-cg-blocks-profile-card\"><section class=\"profile-card section profile-card-slider\"><div class=\"container profileCardContainer\"><div class=\"profile-box\"><div class=\"row\"><div class=\"col-md-6 col-lg-3\"><div class=\"box\"><div class=\"box-author-img\"><img decoding=\"async\" src=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2026\/02\/Anu-Bradford-pic2.jpg?w=500&amp;quality=70\" srcset=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2026\/02\/Anu-Bradford-pic2.jpg?w=500&amp;quality=70 1x, https:\/\/www.capgemini.com\/wp-content\/uploads\/2026\/02\/Anu-Bradford-pic2.jpg?w=1000&amp;quality=70 2x\" class=\"box-img\" alt=\"\" style=\"object-fit:cover;object-position:50% 50%\" loading=\"lazy\"\/><\/div><\/div><\/div><div class=\"col-md-6 col-lg-9 right-side-box\"><div class=\"row right-box\"><div class=\"col-lg-4 profile\"><h3 class=\"profile-title\">Anu Bradford<\/h3><p class=\"box-position\">Profesor Henry L. Moses de Derecho y Organizaci\u00f3n Internacional | Universidad de Columbia<\/p><ul class=\"social-nav social-nav-icons\"><\/ul><\/div><div class=\"col-lg-8 desc\"><p class=\"authorDesr\">&#8220;No sea ingenuo; desarrolle habilidades diplom\u00e1ticas y pragmatismo. Pero, sin un anclaje en valores y principios fundamentales, las empresas terminan perdiendo la confianza de sus clientes y empleados.&#8221;<\/p><\/div><\/div><\/div><\/div><\/div><\/div><\/section><\/div>\n\n\n\n<section class=\"wp-block-cg-blocks-call-to-action undefined is-style-cg-secondary-3 call-to-action-block\"><div class=\"container\"><div class=\"call-to-action-block-content-wrapper has-description\"><div class=\"text-wrapper has-description\"><h3 class=\"title\" data-maxlength=\"144\">Stay informed<\/h3><p class=\"description\" data-maxlength=\"210\">Subscribe to have the latest reports from the Capgemini Research Institute delivered direct to your inbox.<\/p><\/div><div class=\"button-wrapper has-description\"><a class=\"cta-btn action-valid\" data-bs-toggle=\"modal\" data-bs-target=\"#CTA8a45928e_bb7f_4615_b632_ab7f778bf353\" data-maxlength=\"24\" tabindex=\"0\" href=\"#\"> Subscribe <\/a><\/div><div class=\"modal cta-frontend-modal-wrapper\" id=\"CTA8a45928e_bb7f_4615_b632_ab7f778bf353\"><div class=\"modal-dialog modal-lg modal-dialog-centered modal-dialog-scrollable cta-frontend-modal\"><div class=\"modal-content\"><div class=\"modal-header\"><button type=\"button\" class=\"btn-close\" data-bs-dismiss=\"modal\" aria-label=\"close\"> <\/button><\/div><div class=\"modal-body\"><div class=\"logo-wrapper\"><img decoding=\"async\" loading=\"lazy\" src=\"\/wp-content\/themes\/capgemini2025\/assets\/images\/logo-white.svg\" alt=\"logo\" class=\"dark\"\/><img decoding=\"async\" loading=\"lazy\" src=\"\/wp-content\/themes\/capgemini2025\/assets\/images\/logo.svg\" alt=\"logo\" class=\"light\"\/><\/div><h4 class=\"form-title\">Stay informed<\/h4>\t\t<div class=\"mf_forms__container \">\n\t\t\t\t\t\t\t\t<form id=\"mf_form_548055_436344563\" class=\"mf_form__form row needs-validation\" action=\"\" method=\"post\" enctype=\"multipart\/form-data\" data-nosnippet>\n\t\t\t<div class=\"col-12\">\n\t\t\t\t<div class=\"asterisk_title\">\n\t\t\t\t\t<p><span class=\"star-required\">*<\/span> Campo obligatorio<\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"col-12\">\n\t\t\t\t<div class=\"mf_form__errors mf_form__errors--top\" role=\"alert\" aria-live=\"polite\">\n\t\t\t\t\t<ul class=\"mf_form__errors__list\"><\/ul>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t<div class=\"mf-field-wrapper form-floating col-sm-12\"><input type=\"text\" class=\"form-control\" id=\"_mf_344265_1190_3377751006\" name=\"_mf_344265_1190\" placeholder=\"First Name\" required \/><label for=\"_mf_344265_1190_3377751006\" class=\"form-label\">First Name <span class=\"star-required\">*<\/span><\/label><div class=\"invalid-feedback-frm\">First Name no es v\u00e1lido.<\/div><\/div><div class=\"mf-field-wrapper form-floating col-sm-12\"><input type=\"text\" class=\"form-control\" id=\"_mf_344265_8465_2883809159\" name=\"_mf_344265_8465\" placeholder=\"Last Name\" required \/><label for=\"_mf_344265_8465_2883809159\" class=\"form-label\">Last Name <span class=\"star-required\">*<\/span><\/label><div class=\"invalid-feedback-frm\">Last Name no es v\u00e1lido.<\/div><\/div><div class=\"mf-field-wrapper form-floating col-sm-12\"><input type=\"email\" class=\"form-control\" id=\"_mf_344265_5480_1825720913\" name=\"_mf_344265_5480\" placeholder=\"Email\" required \/><label for=\"_mf_344265_5480_1825720913\" class=\"form-label\">Email <span class=\"star-required\">*<\/span><\/label><div class=\"invalid-feedback-frm\">Email no es v\u00e1lido.<\/div><\/div><div class=\"mf-field-wrapper form-floating col-sm-12\">\n\t\t<select tabindex=\"0\" class=\"mac-form-selects form-control empty\"\n\t\t\tid=\"_mf_344265_2919_3062489597\"\n\t\t\tname=\"_mf_344265_2919\"\n\t\t\trequired\t\t>\n\t\t\t<option value=\"\">Selecciona un valor<\/option>\n\t\t\t\t\t\t\t<option value=\"yes\">Yes<\/option>\n\t\t\t\t\t\t\t<option value=\"no\">No<\/option>\n\t\t\t\t\t<\/select>\n\n\t\t<label for=\"_mf_344265_2919_3062489597\" class=\"form-label\">Would you consider being interviewed for research? <span class=\"star-required\">*<\/span><\/label><div class=\"invalid-feedback-frm\">Would you consider being interviewed for research? no es v\u00e1lido.<\/div><\/div><div class=\"mf-field-wrapper form-floating col-sm-12\">\n\t\t<select tabindex=\"0\" class=\"mac-form-selects form-control empty\"\n\t\t\tid=\"_mf_700026_6651_832642221\"\n\t\t\tname=\"_mf_700026_6651\"\n\t\t\trequired\t\t>\n\t\t\t<option value=\"\">Selecciona un valor<\/option>\n\t\t\t\t\t\t\t<option value=\"Assistant\/secretary\">Assistant\/secretary<\/option>\n\t\t\t\t\t\t\t<option value=\"CDO\/CMO\">CDO\/CMO<\/option>\n\t\t\t\t\t\t\t<option value=\"CEO\">CEO<\/option>\n\t\t\t\t\t\t\t<option value=\"CFO\">CFO<\/option>\n\t\t\t\t\t\t\t<option value=\"Chairman\/Board of Directors\">Chairman\/Board of Directors<\/option>\n\t\t\t\t\t\t\t<option value=\"CIO\/CTO\">CIO\/CTO<\/option>\n\t\t\t\t\t\t\t<option value=\"Consultant\/Senior Consultant\">Consultant\/Senior Consultant<\/option>\n\t\t\t\t\t\t\t<option value=\"Director\/Principle Consultant\">Director\/Principle Consultant<\/option>\n\t\t\t\t\t\t\t<option value=\"EVP\">EVP<\/option>\n\t\t\t\t\t\t\t<option value=\"Manager\">Manager<\/option>\n\t\t\t\t\t\t\t<option value=\"Operational\">Operational<\/option>\n\t\t\t\t\t\t\t<option value=\"Other CXO\">Other CXO<\/option>\n\t\t\t\t\t\t\t<option value=\"Purchaser\">Purchaser<\/option>\n\t\t\t\t\t\t\t<option value=\"Senior Manager\/Managing Consultant\">Senior Manager\/Managing Consultant<\/option>\n\t\t\t\t\t\t\t<option value=\"SVP\">SVP<\/option>\n\t\t\t\t\t\t\t<option value=\"Vice President\">Vice President<\/option>\n\t\t\t\t\t<\/select>\n\n\t\t<label for=\"_mf_700026_6651_832642221\" class=\"form-label\">Position\/Level <span class=\"star-required\">*<\/span><\/label><div class=\"invalid-feedback-frm\">Position\/Level no es v\u00e1lido.<\/div><\/div>\n\t\t<div class=\"mf-field-wrapper mf_field--multiselect form-floating mf-required\"\n\t\t\tdata-validate=\"multiselect\">\n\n\t\t\t<label class=\"floating__label\" for=\"_mf_700026_4596_952610511\">\n\t\t\t\tInterests \t\t\t<\/label>\n\n\t\t\t<select multiple=\"true\" id=\"_mf_700026_4596_952610511\" class=\"mf_field__input js-with-select2 empty\"\n\t\t\t\tname=\"_mf_700026_4596[]\" required>\n\t\t\t\t<option value=\"all\">All<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Sustainability\">Sustainability <\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Innovation\">Innovation<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Talent and People\">Talent and People<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Intelligent Industry\">Intelligent Industry<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Customer first\">Customer first<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Enterprise management\">Enterprise management<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Data &amp; AI\">Data &amp; AI<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Cloud\">Cloud<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Cybersecurity\">Cybersecurity<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Lifesciences and Healthcare\">Lifesciences and Healthcare<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Financial services\">Financial services<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Public Services\">Public Services<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Automotive\">Automotive<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Energy &amp; utilities\">Energy &amp; utilities<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"CPRD\">CPRD<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"TMT\">TMT<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Manufacturing\">Manufacturing<\/option>\n\t\t\t\t\t\t\t<\/select>\n\n\t\t\t<div class=\"invalid-feedback-frm\">Interests no es v\u00e1lido.<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"mf_field mf_field--country mf_field--select floating form-country-select-parent mf-required\">\n\n\t\t\t<label for=\"_mf_344265_6540_1150525270\" class=\"floating__label form-country-select-label\" data-content=\"Country\">\n\t\t\t\t<span class=\"floating-label-content\">Country<\/span>\n\t\t\t<\/label>\n\n\t\t\t<div class=\"select-wrap\">\n<i class=\"icon icon-zodiak-chevron-down\"><\/i>\n\t\t\t\t<select id=\"_mf_344265_6540_1150525270\" class=\"mf_field__input empty mf-country-selectbox form_country_select\" name=\"_mf_344265_6540\" data-validate=\"select\" required>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"\"  selected='selected'>Pa\u00eds<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"AF\" >Afghanistan<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"AX\" >Aland Islands<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"AL\" >Albania<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"DZ\" >Algeria<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"AS\" >American Samoa<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"AD\" >Andorra<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"AO\" >Angola<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"AI\" >Anguilla<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"AQ\" >Antarctica<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"AG\" >Antigua And Barbuda<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"AR\" >Argentina<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"AM\" >Armenia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"AW\" >Aruba<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"AU\" >Australia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"AT\" >Austria<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"AZ\" >Azerbaijan<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"BS\" >Bahamas<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"BH\" >Bahrain<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"BD\" >Bangladesh<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"BB\" >Barbados<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"BY\" >Belarus<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"BE\" >Belgium<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"BZ\" >Belize<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"BJ\" >Benin<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"BM\" >Bermuda<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"BT\" >Bhutan<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"BO\" >Bolivia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"BA\" >Bosnia And Herzegovina<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"BW\" >Botswana<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"BV\" >Bouvet Island<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"BR\" >Brazil<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"IO\" >British Indian Ocean Territory<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"BN\" >Brunei Darussalam<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"BG\" >Bulgaria<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"BF\" >Burkina Faso<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"BI\" >Burundi<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"KH\" >Cambodia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"CM\" >Cameroon<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"CA\" >Canada<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"CV\" >Cape Verde<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"KY\" >Cayman Islands<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"CF\" >Central African Republic<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"TD\" >Chad<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"CL\" >Chile<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"CN\" >China<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"CX\" >Christmas Island<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"CC\" >Cocos (Keeling) Islands<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"CO\" >Colombia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"KM\" >Comoros<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"CG\" >Congo<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"CD\" >Congo, Democratic Republic<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"CK\" >Cook Islands<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"CR\" >Costa Rica<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"CI\" >Cote D&#039;Ivoire<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"HR\" >Croatia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"CU\" >Cuba<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"CY\" >Cyprus<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"CZ\" >Czech Republic<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"DK\" >Denmark<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"DJ\" >Djibouti<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"DM\" >Dominica<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"DO\" >Dominican Republic<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"EC\" >Ecuador<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"EG\" >Egypt<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"SV\" >El Salvador<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"GQ\" >Equatorial Guinea<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"ER\" >Eritrea<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"EE\" >Estonia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"ET\" >Ethiopia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"FK\" >Falkland Islands (Malvinas)<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"FO\" >Faroe Islands<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"FJ\" >Fiji<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"FI\" >Finland<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"FR\" >France<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"GF\" >French Guiana<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"PF\" >French Polynesia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"TF\" >French Southern Territories<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"GA\" >Gabon<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"GM\" >Gambia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"GE\" >Georgia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"DE\" >Germany<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"GH\" >Ghana<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"GI\" >Gibraltar<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"GR\" >Greece<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"GL\" >Greenland<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"GD\" >Grenada<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"GP\" >Guadeloupe<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"GU\" >Guam<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"GT\" >Guatemala<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"GG\" >Guernsey<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"GN\" >Guinea<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"GW\" >Guinea-Bissau<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"GY\" >Guyana<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"HT\" >Haiti<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"HM\" >Heard Island &amp; Mcdonald Islands<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"VA\" >Holy See (Vatican City State)<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"HN\" >Honduras<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"HK\" >Hong Kong<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"HU\" >Hungary<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"IS\" >Iceland<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"IN\" >India<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"ID\" >Indonesia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"IR\" >Iran, Islamic Republic Of<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"IQ\" >Iraq<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"IE\" >Ireland<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"IM\" >Isle Of Man<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"IL\" >Israel<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"IT\" >Italy<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"JM\" >Jamaica<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"JP\" >Japan<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"JE\" >Jersey<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"JO\" >Jordan<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"KZ\" >Kazakhstan<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"KE\" >Kenya<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"KI\" >Kiribati<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"KR\" >Korea<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"KW\" >Kuwait<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"KG\" >Kyrgyzstan<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"LA\" >Lao People&#039;s Democratic Republic<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"LV\" >Latvia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"LB\" >Lebanon<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"LS\" >Lesotho<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"LR\" >Liberia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"LY\" >Libyan Arab Jamahiriya<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"LI\" >Liechtenstein<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"LT\" >Lithuania<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"LU\" >Luxembourg<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"MO\" >Macao<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"MK\" >Macedonia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"MG\" >Madagascar<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"MW\" >Malawi<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"MY\" >Malaysia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"MV\" >Maldives<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"ML\" >Mali<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"MT\" >Malta<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"MH\" >Marshall Islands<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"MQ\" >Martinique<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"MR\" >Mauritania<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"MU\" >Mauritius<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"YT\" >Mayotte<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"MX\" >Mexico<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"FM\" >Micronesia, Federated States Of<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"MD\" >Moldova<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"MC\" >Monaco<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"MN\" >Mongolia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"ME\" >Montenegro<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"MS\" >Montserrat<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"MA\" >Morocco<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"MZ\" >Mozambique<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"MM\" >Myanmar<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"NA\" >Namibia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"NR\" >Nauru<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"NP\" >Nepal<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"NL\" >Netherlands<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"AN\" >Netherlands Antilles<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"NC\" >New Caledonia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"NZ\" >New Zealand<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"NI\" >Nicaragua<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"NE\" >Niger<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"NG\" >Nigeria<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"NU\" >Niue<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"NF\" >Norfolk Island<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"MP\" >Northern Mariana Islands<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"NO\" >Norway<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"OM\" >Oman<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"PK\" >Pakistan<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"PW\" >Palau<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"PS\" >Palestinian Territory, Occupied<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"PA\" >Panama<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"PG\" >Papua New Guinea<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"PY\" >Paraguay<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"PE\" >Peru<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"PH\" >Philippines<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"PN\" >Pitcairn<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"PL\" >Poland<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"PT\" >Portugal<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"PR\" >Puerto Rico<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"QA\" >Qatar<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"RE\" >Reunion<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"RO\" >Romania<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"RU\" >Russian Federation<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"RW\" >Rwanda<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"BL\" >Saint Barthelemy<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"SH\" >Saint Helena<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"KN\" >Saint Kitts And Nevis<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"LC\" >Saint Lucia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"MF\" >Saint Martin<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"PM\" >Saint Pierre And Miquelon<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"VC\" >Saint Vincent And Grenadines<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"WS\" >Samoa<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"SM\" >San Marino<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"ST\" >Sao Tome And Principe<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"SA\" >Saudi Arabia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"SN\" >Senegal<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"RS\" >Serbia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"SC\" >Seychelles<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"SL\" >Sierra Leone<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"SG\" >Singapore<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"SK\" >Slovakia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"SI\" >Slovenia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"SB\" >Solomon Islands<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"SO\" >Somalia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"ZA\" >South Africa<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"GS\" >South Georgia And Sandwich Isl.<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"ES\" >Spain<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"LK\" >Sri Lanka<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"SD\" >Sudan<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"SR\" >Suriname<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"SJ\" >Svalbard And Jan Mayen<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"SZ\" >Swaziland<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"SE\" >Sweden<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"CH\" >Switzerland<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"SY\" >Syrian Arab Republic<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"TW\" >Taiwan<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"TJ\" >Tajikistan<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"TZ\" >Tanzania<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"TH\" >Thailand<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"TL\" >Timor-Leste<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"TG\" >Togo<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"TK\" >Tokelau<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"TO\" >Tonga<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"TT\" >Trinidad And Tobago<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"TN\" >Tunisia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"TR\" >Turkey<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"TM\" >Turkmenistan<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"TC\" >Turks And Caicos Islands<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"TV\" >Tuvalu<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"UG\" >Uganda<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"UA\" >Ukraine<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"AE\" >United Arab Emirates<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"GB\" >United Kingdom<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"US\" >United States<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"UM\" >United States Outlying Islands<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"UY\" >Uruguay<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"UZ\" >Uzbekistan<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"VU\" >Vanuatu<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"VE\" >Venezuela<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"VN\" >Viet Nam<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"VG\" >Virgin Islands, British<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"VI\" >Virgin Islands, U.S.<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"WF\" >Wallis And Futuna<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"EH\" >Western Sahara<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"YE\" >Yemen<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"ZM\" >Zambia<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<option value=\"ZW\" >Zimbabwe<\/option>\n\t\t\t\t\t\t\t\t\t<\/select>\n\n\t\t\t\t<div class=\"invalid-feedback-frm\">Country no es v\u00e1lido.<\/div>\n\t\t\t<\/div>\n\n\t\t<\/div>\n\n\t\t<script type=\"text\/javascript\">\n            jQuery(document).ready(function($) {\n                $('.mf_form__form').each(function() {\n                    var $form = $(this); \/\/ This specific form instance\n\n                    \/\/ Find the country select in this form\n                    $form.find('.form_country_select').each(function() {\n                        var $select = $(this);\n\t\t\t\t\t\tvar clickCount = 0;\n                        \/\/ On change\n                        $select.on('click', function() {\n\t\t\t\t\t\t\tclickCount++;\n\t\t\t\t\t\t\tif (clickCount === 1) {\n\t\t\t\t\t\t\t\t$(this).parent().find('.icon-zodiak-chevron-down').addClass('active');\n\t\t\t\t\t\t\t} else {\n\t\t\t\t\t\t\t\tclickCount = 0;\n\t\t\t\t\t\t\t\t$(this).parent().find('.icon-zodiak-chevron-down').removeClass('active');\n\t\t\t\t\t\t\t}\n\t\t\t\t\t\t});\n\t\t\t\t\t\t$select.on('blur', function() {\n\t\t\t\t\t\t\tclickCount = 0;\n\t\t\t\t\t\t\t$(this).parent().find('.icon-zodiak-chevron-down').removeClass('active');\n\t\t\t\t\t\t});\n                    });\n                });\n            });\n        <\/script>\n\n\t\t<div class=\"mf-field-wrapper form-floating col-sm-12\"><input type=\"text\" class=\"form-control\" id=\"_mf_344265_8838_1176167755\" name=\"_mf_344265_8838\" placeholder=\"Company\" required \/><label for=\"_mf_344265_8838_1176167755\" class=\"form-label\">Company <span class=\"star-required\">*<\/span><\/label><div class=\"invalid-feedback-frm\">Company no es v\u00e1lido.<\/div><\/div><div class=\"mf-field-wrapper  col-sm-12\">\n\t\t<div class=\"form-check checkbox-controls\">\n\n\t\t\t<input type=\"checkbox\" id=\"_mf_344265_2520_320838118\" class=\"form-check-input\"\n\t\t\t\tname=\"_mf_344265_2520[]\"\n\t\t\t\tvalue=\"1\"\n\t\t\t\trequired\n\t\t\t>\n\n\t\t\t<label for=\"_mf_344265_2520_320838118\" class=\"form-check-label consent-text\">\n\t\t\t\tI agree to Capgemini collecting &amp; processing my personal data to allow me to receive information on Capgemini services. For further information, please see our<a href=\"https:\/\/www.capgemini.com\/privacy-notice\/\"> Privacy Notice<\/a>.  &nbsp;\t\t\t<\/label>\n\n\t\t<\/div>\n\t\t<\/div>\t\t\t<div class=\"mf_field mf_field--recaptcha\">\n\t\t\t\t<div class=\"g-recaptcha\" data-sitekey=\"6Lc3OpIUAAAAADY4ErEHF0HF6Tr7vuknduDU-fbl\"><\/div>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t<div class=\"mf_field mf_field--submit\" >\n\t\t\t\t<div class=\"slide-button-background button-background\">\n\t\t\t\t\t<label for=\"slider-submit-_mf_344265_5056\" class=\"slide-text\">\n\t\t\t\t\t\tSlide to submit\t\t\t\t\t<\/label>\n\t\t\t\t\t<input\n\t\t\t\t\t\tid=\"slider-submit-_mf_344265_5056\"\n\t\t\t\t\t\ttype=\"range\"\n\t\t\t\t\t\tclass=\"mf_field__input slider-frm-btn\"\n\t\t\t\t\t\trel=\"_mf_344265_5056\"\n\t\t\t\t\t\tmin=\"0\"\n\t\t\t\t\t\tmax=\"100\"\n\t\t\t\t\t\tvalue=\"0\"\n\t\t\t\t\t\taria-label=\"Slide to submit\"\n\t\t\t\t\t\taria-describedby=\"slide-instruction-_mf_344265_5056\"\n\t\t\t\t\t\taria-valuenow=\"0\"\n\t\t\t\t\t\taria-valuemin=\"0\"\n\t\t\t\t\t\taria-valuemax=\"100\"\n\t\t\t\t\t\taria-orientation=\"horizontal\"\n\t\t\t\t\t\trole=\"slider\"\n\t\t\t\t\t\ttabindex=\"0\"\n\t\t\t\t\t\/>\n\t\t\t\t\t<!-- Icon element for Firefox (doesn't support ::before\/::after on inputs) -->\n\t\t\t\t\t<span class=\"slider-icon\" aria-hidden=\"true\"><\/span>\n\t\t\t\t\t<span id=\"slide-instruction-_mf_344265_5056\" class=\"sr-only\">\n\t\t\t\t\t\tUse right arrow keys to slide, or drag right with your finger. When you reach 100 percent, the form is submitted.\t\t\t\t\t<\/span>\n\t\t\t\t\t<!-- Mobile-only submit button fallback -->\n\t\t\t\t\t<button type=\"submit\" class=\"mf-mobile-submit-btn\" disabled>\n\t\t\t\t\t\t<span class=\"sr-only\">If you use a screen reader or VoiceOver, double-tap this button to submit the form.<\/span>\n\t\t\t\t\t\tSlide to submit\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t\t<input type=\"hidden\" name=\"submit_btn_txt\" class=\"submit_btn_txt\" value=\"Slide to submit\"\/>\n\t\t\t\t<input type=\"hidden\" name=\"submitted_state_txt\" class=\"submitted_state_txt\" value=\"Submitted\"\/>\n\t\t\t<\/div>\n\t\t\t\t\t\t<input type=\"hidden\" name=\"form_id\" data-validate=\"number\" class=\"mf_form__id\" value=\"548055\" \/>\n\t\t\t\t<input type=\"hidden\" name=\"form_title\" class=\"mf_form__title\" value=\"revamp-new-global-cri-form\" \/>\n\t\t\t\t<input type=\"hidden\" name=\"wp_rest_nonce\" class=\"mf_form__wp_rest_nonce\" value=\"d873041170\" \/>\n\n\t\t\t\t<input type=\"hidden\" name=\"mf_form_conditional_logic\" class=\"mf_form__title conditional_logic\" value=\"\" \/>\n\t\t\t\t\n\t\t\t\t<input type=\"hidden\" name=\"mf_form_fields_country_dpo_field\" class=\"mf_form__title conditional_logic mf_form_fields_country_dpo_field\" value=\"\" \/>\n\n\t\t\t\t<!-- Anti-spam field -->\n\t\t\t\t<input type=\"text\" \n\t\t\t\t\tname=\"website_url\" \n\t\t\t\t\tclass=\"mf_field__url\" \n\t\t\t\t\tautocomplete=\"off\"\n\t\t\t\t\ttabindex=\"-1\"\n\t\t\t\t\taria-hidden=\"true\"\n\t\t\t\t\tstyle=\"position:absolute;left:-9999px;width:1px;height:1px;opacity:0;pointer-events:none;\" \n\t\t\t\t\/>\n\t\t\t<\/form>\n\n\t\t\t<div class=\"mf_form__success\" tabindex=\"0\" role=\"alert\">\n\t\t\t\tThankyou for your submission. You will be contacted shortly.<\/p>\n\t\t\t<\/div>\n\t\t\t<div class=\"mf_form__errors\">\n\t\t\t\t<p>Lo sentimos, el env\u00edo del formulario fall\u00f3. Int\u00e9ntalo de nuevo.<\/p>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t<script>\n\t\t\twindow.MF_CONFIG548055 = {\"548055\":{\"errors\":[],\"redirect\":\"\"}};\n\t\t<\/script>\n\t<\/div><\/div><\/div><\/div><\/div><\/div><\/section>\n\n\n\n<section class=\"wp-block-cg-blocks-learn-more updated-new-sample-amal learnMoreBlock\"><div class=\"container\"><div class=\"row\"><div class=\"content-title col-12 col-md-8\"><h2 class=\"learnmore-heading\">Lecturas adicionales<\/h2><\/div><\/div><div class=\"row\"><div class=\"col-md-4\"><div class=\"box\"><div class=\"box-wrapper\"><a class=\"box-title\" href=\"\/mx-es\/insights\/biblioteca-de-investigacion\/principales-tendencias-tecnologicas-de-2026\/\" target=\"\" aria-label=\"Las principales tendencias tecnol\u00f3gicas de 2026\" rel=\"noopener noreferrer\"><div class=\"box-img-wrapper\"><img decoding=\"async\" src=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2025\/12\/TTT2026_herobanner_Top-Tech-Trends-2026.jpg?w=500&amp;quality=70\" srcset=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2025\/12\/TTT2026_herobanner_Top-Tech-Trends-2026.jpg?w=500&amp;quality=70 1x, https:\/\/www.capgemini.com\/wp-content\/uploads\/2025\/12\/TTT2026_herobanner_Top-Tech-Trends-2026.jpg?w=1000&amp;quality=70 2x\" class=\"box-img\" alt=\"\" style=\"object-fit:cover;object-position:50% 50%\" loading=\"lazy\"\/><\/div><h3 class=\"titleWithoutLink_learnMore\">Las principales tendencias tecnol\u00f3gicas de 2026<\/h3><\/a><\/div><\/div><div class=\"box-inner\"><p class=\"box-desc\">Reconstruyendo cimientos s\u00f3lidos para el crecimiento futuro<\/p><\/div><\/div><div class=\"col-md-4\"><div class=\"box\"><div class=\"box-wrapper\"><a class=\"box-title\" href=\"\/mx-es\/insights\/biblioteca-de-investigacion\/technovision-2026\/\" target=\"\" aria-label=\"TechnoVision 2026\" rel=\"noopener noreferrer\"><div class=\"box-img-wrapper\"><img decoding=\"async\" src=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2025\/12\/TechnoVision26-Web-banner.jpg?w=500&amp;quality=70\" srcset=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2025\/12\/TechnoVision26-Web-banner.jpg?w=500&amp;quality=70 1x, https:\/\/www.capgemini.com\/wp-content\/uploads\/2025\/12\/TechnoVision26-Web-banner.jpg?w=1000&amp;quality=70 2x\" class=\"box-img\" alt=\"TechnoVision26- Web banner\" style=\"object-fit:cover;object-position:50% 50%\" loading=\"lazy\"\/><\/div><h3 class=\"titleWithoutLink_learnMore\">TechnoVision 2026<\/h3><\/a><\/div><\/div><div class=\"box-inner\"><p class=\"box-desc\">Su puerta de entrada para aplicar tecnolog\u00edas emergentes<\/p><\/div><\/div><div class=\"col-md-4\"><div class=\"box\"><div class=\"box-wrapper\"><a class=\"box-title\" href=\"\/mx-es\/insights\/biblioteca-de-investigacion\/conversaciones-para-el-manana-11\/\" target=\"\" aria-label=\"Conversaciones para el ma\u00f1ana n.\u00ba 11: Soberan\u00eda digital\" rel=\"noopener noreferrer\"><div class=\"box-img-wrapper\"><img decoding=\"async\" src=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2026\/06\/CFT-11_CommskitDotcom-banner.jpg?w=500&amp;quality=70\" srcset=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2026\/06\/CFT-11_CommskitDotcom-banner.jpg?w=500&amp;quality=70 1x, https:\/\/www.capgemini.com\/wp-content\/uploads\/2026\/06\/CFT-11_CommskitDotcom-banner.jpg?w=1000&amp;quality=70 2x\" class=\"box-img\" alt=\"\" style=\"object-fit:cover;object-position:50% 50%\" loading=\"lazy\"\/><\/div><h3 class=\"titleWithoutLink_learnMore\">Conversaciones para el ma\u00f1ana n.\u00ba 11: Soberan\u00eda digital<\/h3><\/a><\/div><\/div><div class=\"box-inner\"><p class=\"box-desc\">Perspectivas de los l\u00edderes sobre la tecnolog\u00eda<\/p><\/div><\/div><\/div><\/div><\/section>\n","protected":false},"excerpt":{"rendered":"<p>Navegando la soberan\u00eda tecnol\u00f3gica en un mundo fracturado<\/p>\n","protected":false},"author":33,"featured_media":1000001219468,"template":"","meta":{"cg_dt_proposed_to":[25],"cg_seo_hreflang_relations":"[]","cg_seo_canonical_relation":"","cg_seo_hreflang_x_default_relation":"","cg_dt_approved_content":true,"cg_dt_mandatory_content":false,"cg_dt_notes":"","cg_dg_source_changed":true,"cg_dt_link_disabled":true,"footnotes":"","related_resource_url":"","related_resource_id":0,"related_resource_size":"","related_resource_type":"","cg_author":0,"_yoast_wpseo_primary_theme":231,"primary_term":"Innovation","featured_focal_points":""},"tags":[],"research-and-insight-type":[234,238],"theme":[231],"brand":[350],"service":[],"industry":[],"partners":[],"content-group":[],"class_list":["post-561656","research-and-insight","type-research-and-insight","status-publish","has-post-thumbnail","hentry","research-and-insight-type-capgemini-research-institute","research-and-insight-type-conversations-for-tomorrow","theme-innovation","brand-capgemini-research-institute"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.8 (Yoast SEO v22.8) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Anu Bradford: Soberan\u00eda Tecnol\u00f3gica | Capgemini<\/title>\n<meta name=\"description\" content=\"Explora c\u00f3mo Anu Bradford analiza la soberan\u00eda tecnol\u00f3gica y el impacto global de la regulaci\u00f3n digital en un mundo cada vez m\u00e1s fragmentado.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.capgemini.com\/mx-es\/insights\/biblioteca-de-investigacion\/una-conversacion-con-anu-bradford\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Navegando la soberan\u00eda tecnol\u00f3gica en un mundo fracturado: una conversaci\u00f3n con Anu Bradford\" \/>\n<meta property=\"og:description\" content=\"Explora c\u00f3mo Anu Bradford analiza la soberan\u00eda tecnol\u00f3gica y el impacto global de la regulaci\u00f3n digital en un mundo cada vez m\u00e1s fragmentado.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.capgemini.com\/mx-es\/insights\/biblioteca-de-investigacion\/una-conversacion-con-anu-bradford\/\" \/>\n<meta property=\"og:site_name\" content=\"Capgemini Mexico\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-03T16:24:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.capgemini.com\/mx-es\/wp-json\/wp\/v2\/research-and-insight\/561656\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"627\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"30 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.capgemini.com\/mx-es\/insights\/biblioteca-de-investigacion\/una-conversacion-con-anu-bradford\/\",\"url\":\"https:\/\/www.capgemini.com\/mx-es\/insights\/biblioteca-de-investigacion\/una-conversacion-con-anu-bradford\/\",\"name\":\"Anu Bradford: Soberan\u00eda Tecnol\u00f3gica | Capgemini\",\"isPartOf\":{\"@id\":\"https:\/\/www.capgemini.com\/mx-es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.capgemini.com\/mx-es\/insights\/biblioteca-de-investigacion\/una-conversacion-con-anu-bradford\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.capgemini.com\/mx-es\/insights\/biblioteca-de-investigacion\/una-conversacion-con-anu-bradford\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2026\/05\/Headshots_Anu-Bradford_-CFT11.jpg\",\"datePublished\":\"2026-03-17T15:48:48+00:00\",\"dateModified\":\"2026-07-03T16:24:49+00:00\",\"description\":\"Explora c\u00f3mo Anu Bradford analiza la soberan\u00eda tecnol\u00f3gica y el impacto global de la regulaci\u00f3n digital en un mundo cada vez m\u00e1s fragmentado.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.capgemini.com\/mx-es\/insights\/biblioteca-de-investigacion\/una-conversacion-con-anu-bradford\/#breadcrumb\"},\"inLanguage\":\"es-MX\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.capgemini.com\/mx-es\/insights\/biblioteca-de-investigacion\/una-conversacion-con-anu-bradford\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-MX\",\"@id\":\"https:\/\/www.capgemini.com\/mx-es\/insights\/biblioteca-de-investigacion\/una-conversacion-con-anu-bradford\/#primaryimage\",\"url\":\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2026\/05\/Headshots_Anu-Bradford_-CFT11.jpg\",\"contentUrl\":\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2026\/05\/Headshots_Anu-Bradford_-CFT11.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.capgemini.com\/mx-es\/insights\/biblioteca-de-investigacion\/una-conversacion-con-anu-bradford\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.capgemini.com\/mx-es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Navegando la soberan\u00eda tecnol\u00f3gica en un mundo fracturado: una conversaci\u00f3n con Anu Bradford\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.capgemini.com\/mx-es\/#website\",\"url\":\"https:\/\/www.capgemini.com\/mx-es\/\",\"name\":\"Capgemini Mexico\",\"description\":\"Capgemini\",\"publisher\":{\"@id\":\"https:\/\/www.capgemini.com\/mx-es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.capgemini.com\/mx-es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es-MX\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.capgemini.com\/mx-es\/#organization\",\"name\":\"Capgemini Mexico\",\"url\":\"https:\/\/www.capgemini.com\/mx-es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-MX\",\"@id\":\"https:\/\/www.capgemini.com\/mx-es\/#\/schema\/logo\/image\/\",\"url\":\"\/mx-es\/wp-json\/wp\/v2\/research-and-insight\/561656\",\"contentUrl\":\"\/mx-es\/wp-json\/wp\/v2\/research-and-insight\/561656\",\"width\":800,\"height\":800,\"caption\":\"Capgemini Mexico\"},\"image\":{\"@id\":\"https:\/\/www.capgemini.com\/mx-es\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Anu Bradford: Soberan\u00eda Tecnol\u00f3gica | Capgemini","description":"Explora c\u00f3mo Anu Bradford analiza la soberan\u00eda tecnol\u00f3gica y el impacto global de la regulaci\u00f3n digital en un mundo cada vez m\u00e1s fragmentado.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.capgemini.com\/mx-es\/insights\/biblioteca-de-investigacion\/una-conversacion-con-anu-bradford\/","og_locale":"es_MX","og_type":"article","og_title":"Navegando la soberan\u00eda tecnol\u00f3gica en un mundo fracturado: una conversaci\u00f3n con Anu Bradford","og_description":"Explora c\u00f3mo Anu Bradford analiza la soberan\u00eda tecnol\u00f3gica y el impacto global de la regulaci\u00f3n digital en un mundo cada vez m\u00e1s fragmentado.","og_url":"https:\/\/www.capgemini.com\/mx-es\/insights\/biblioteca-de-investigacion\/una-conversacion-con-anu-bradford\/","og_site_name":"Capgemini Mexico","article_modified_time":"2026-07-03T16:24:49+00:00","og_image":[{"width":1200,"height":627,"url":"https:\/\/www.capgemini.com\/mx-es\/wp-json\/wp\/v2\/research-and-insight\/561656","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"30 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.capgemini.com\/mx-es\/insights\/biblioteca-de-investigacion\/una-conversacion-con-anu-bradford\/","url":"https:\/\/www.capgemini.com\/mx-es\/insights\/biblioteca-de-investigacion\/una-conversacion-con-anu-bradford\/","name":"Anu Bradford: Soberan\u00eda Tecnol\u00f3gica | Capgemini","isPartOf":{"@id":"https:\/\/www.capgemini.com\/mx-es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.capgemini.com\/mx-es\/insights\/biblioteca-de-investigacion\/una-conversacion-con-anu-bradford\/#primaryimage"},"image":{"@id":"https:\/\/www.capgemini.com\/mx-es\/insights\/biblioteca-de-investigacion\/una-conversacion-con-anu-bradford\/#primaryimage"},"thumbnailUrl":"https:\/\/www.capgemini.com\/wp-content\/uploads\/2026\/05\/Headshots_Anu-Bradford_-CFT11.jpg","datePublished":"2026-03-17T15:48:48+00:00","dateModified":"2026-07-03T16:24:49+00:00","description":"Explora c\u00f3mo Anu Bradford analiza la soberan\u00eda tecnol\u00f3gica y el impacto global de la regulaci\u00f3n digital en un mundo cada vez m\u00e1s fragmentado.","breadcrumb":{"@id":"https:\/\/www.capgemini.com\/mx-es\/insights\/biblioteca-de-investigacion\/una-conversacion-con-anu-bradford\/#breadcrumb"},"inLanguage":"es-MX","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.capgemini.com\/mx-es\/insights\/biblioteca-de-investigacion\/una-conversacion-con-anu-bradford\/"]}]},{"@type":"ImageObject","inLanguage":"es-MX","@id":"https:\/\/www.capgemini.com\/mx-es\/insights\/biblioteca-de-investigacion\/una-conversacion-con-anu-bradford\/#primaryimage","url":"https:\/\/www.capgemini.com\/wp-content\/uploads\/2026\/05\/Headshots_Anu-Bradford_-CFT11.jpg","contentUrl":"https:\/\/www.capgemini.com\/wp-content\/uploads\/2026\/05\/Headshots_Anu-Bradford_-CFT11.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.capgemini.com\/mx-es\/insights\/biblioteca-de-investigacion\/una-conversacion-con-anu-bradford\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.capgemini.com\/mx-es\/"},{"@type":"ListItem","position":2,"name":"Navegando la soberan\u00eda tecnol\u00f3gica en un mundo fracturado: una conversaci\u00f3n con Anu Bradford"}]},{"@type":"WebSite","@id":"https:\/\/www.capgemini.com\/mx-es\/#website","url":"https:\/\/www.capgemini.com\/mx-es\/","name":"Capgemini Mexico","description":"Capgemini","publisher":{"@id":"https:\/\/www.capgemini.com\/mx-es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.capgemini.com\/mx-es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es-MX"},{"@type":"Organization","@id":"https:\/\/www.capgemini.com\/mx-es\/#organization","name":"Capgemini Mexico","url":"https:\/\/www.capgemini.com\/mx-es\/","logo":{"@type":"ImageObject","inLanguage":"es-MX","@id":"https:\/\/www.capgemini.com\/mx-es\/#\/schema\/logo\/image\/","url":"\/mx-es\/wp-json\/wp\/v2\/research-and-insight\/561656","contentUrl":"\/mx-es\/wp-json\/wp\/v2\/research-and-insight\/561656","width":800,"height":800,"caption":"Capgemini Mexico"},"image":{"@id":"https:\/\/www.capgemini.com\/mx-es\/#\/schema\/logo\/image\/"}}]}},"theme_term_info":[{"id":231,"name":"Innovation"}],"industry_term_info":[],"services_term_info":[],"partners_term_info":[],"brand_term_info":[{"id":350,"name":"Capgemini Research Institute","slug":"capgemini-research-institute"}],"brand_term":[{"id":350,"slug":"capgemini-research-institute"}],"parsely":{"version":"1.1.0","canonical_url":"https:\/\/capgemini.com\/mx-es\/insights\/biblioteca-de-investigacion\/una-conversacion-con-anu-bradford\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Navegando la soberan\u00eda tecnol\u00f3gica en un mundo fracturado: una conversaci\u00f3n con Anu Bradford","url":"https:\/\/www.capgemini.com\/mx-es\/insights\/biblioteca-de-investigacion\/una-conversacion-con-anu-bradford\/","mainEntityOfPage":{"@type":"WebPage","@id":"https:\/\/www.capgemini.com\/mx-es\/insights\/biblioteca-de-investigacion\/una-conversacion-con-anu-bradford\/"},"thumbnailUrl":"https:\/\/www.capgemini.com\/wp-content\/uploads\/2026\/05\/Headshots_Anu-Bradford_-CFT11.jpg?w=150&h=150&crop=1","image":{"@type":"ImageObject","url":"https:\/\/www.capgemini.com\/wp-content\/uploads\/2026\/05\/Headshots_Anu-Bradford_-CFT11.jpg"},"articleSection":"Uncategorized","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Capgemini Mexico","logo":""},"keywords":[],"dateCreated":"2026-03-17T15:48:48Z","datePublished":"2026-03-17T15:48:48Z","dateModified":"2026-07-03T16:24:49Z"},"rendered":"<meta name=\"parsely-title\" content=\"Navegando la soberan\u00eda tecnol\u00f3gica en un mundo fracturado: una conversaci\u00f3n con Anu Bradford\" \/>\n<meta name=\"parsely-link\" content=\"https:\/\/www.capgemini.com\/mx-es\/insights\/biblioteca-de-investigacion\/una-conversacion-con-anu-bradford\/\" \/>\n<meta name=\"parsely-type\" content=\"post\" \/>\n<meta name=\"parsely-image-url\" content=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2026\/05\/Headshots_Anu-Bradford_-CFT11.jpg?w=150&amp;h=150&amp;crop=1\" \/>\n<meta name=\"parsely-pub-date\" content=\"2026-03-17T15:48:48Z\" \/>\n<meta name=\"parsely-section\" content=\"Uncategorized\" \/>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/capgemini.com\/p.js"},"archive_status":false,"featured_image_src":"https:\/\/www.capgemini.com\/wp-content\/uploads\/2026\/05\/Headshots_Anu-Bradford_-CFT11.jpg","featured_image_alt":"","jetpack_sharing_enabled":true,"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"Capgemini Mexico","distributor_original_site_url":"https:\/\/www.capgemini.com\/mx-es","push-errors":false,"tag_names":[],"featured_image_url":"https:\/\/www.capgemini.com\/wp-content\/uploads\/2026\/05\/Headshots_Anu-Bradford_-CFT11.jpg","_links":{"self":[{"href":"https:\/\/www.capgemini.com\/mx-es\/wp-json\/wp\/v2\/research-and-insight\/561656","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.capgemini.com\/mx-es\/wp-json\/wp\/v2\/research-and-insight"}],"about":[{"href":"https:\/\/www.capgemini.com\/mx-es\/wp-json\/wp\/v2\/types\/research-and-insight"}],"author":[{"embeddable":true,"href":"https:\/\/www.capgemini.com\/mx-es\/wp-json\/wp\/v2\/users\/33"}],"version-history":[{"count":3,"href":"https:\/\/www.capgemini.com\/mx-es\/wp-json\/wp\/v2\/research-and-insight\/561656\/revisions"}],"predecessor-version":[{"id":565863,"href":"https:\/\/www.capgemini.com\/mx-es\/wp-json\/wp\/v2\/research-and-insight\/561656\/revisions\/565863"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.capgemini.com\/mx-es\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.capgemini.com\/mx-es\/wp-json\/wp\/v2\/media?parent=561656"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.capgemini.com\/mx-es\/wp-json\/wp\/v2\/tags?post=561656"},{"taxonomy":"research-and-insight-type","embeddable":true,"href":"https:\/\/www.capgemini.com\/mx-es\/wp-json\/wp\/v2\/research-and-insight-type?post=561656"},{"taxonomy":"theme","embeddable":true,"href":"https:\/\/www.capgemini.com\/mx-es\/wp-json\/wp\/v2\/theme?post=561656"},{"taxonomy":"brand","embeddable":true,"href":"https:\/\/www.capgemini.com\/mx-es\/wp-json\/wp\/v2\/brand?post=561656"},{"taxonomy":"service","embeddable":true,"href":"https:\/\/www.capgemini.com\/mx-es\/wp-json\/wp\/v2\/service?post=561656"},{"taxonomy":"industry","embeddable":true,"href":"https:\/\/www.capgemini.com\/mx-es\/wp-json\/wp\/v2\/industry?post=561656"},{"taxonomy":"partners","embeddable":true,"href":"https:\/\/www.capgemini.com\/mx-es\/wp-json\/wp\/v2\/partners?post=561656"},{"taxonomy":"content-group","embeddable":true,"href":"https:\/\/www.capgemini.com\/mx-es\/wp-json\/wp\/v2\/content-group?post=561656"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}