{"id":511893,"date":"2025-02-25T02:00:24","date_gmt":"2025-02-25T02:00:24","guid":{"rendered":"https:\/\/www.capgemini.com\/?post_type=research-and-insight&#038;p=823307"},"modified":"2026-04-27T13:19:02","modified_gmt":"2026-04-27T13:19:02","slug":"podcast-de-realidades-en-la-nube","status":"publish","type":"research-and-insight","link":"https:\/\/www.capgemini.com\/mx-es\/insights\/biblioteca-de-investigacion\/podcast-de-realidades-en-la-nube\/","title":{"rendered":"Realidades remezcladas: la serie de podcasts"},"content":{"rendered":"\n<header class=\"wp-block-cg-blocks-hero-reusable header heroReusable  \"><div class=\"header-bgs\"><picture><source srcset=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2026\/02\/Realities-Remixed_Dotcom-banner_2880x1800px.jpg?w=2880&amp;quality=70 1x, https:\/\/www.capgemini.com\/wp-content\/uploads\/2026\/02\/Realities-Remixed_Dotcom-banner_2880x1800px.jpg?w=2880&amp;quality=70 2x\" media=\"(min-width: 1500px)\"\/><source srcset=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2026\/02\/Realities-Remixed_Dotcom-banner_2880x1800px.jpg?w=1440&amp;quality=70 1x, https:\/\/www.capgemini.com\/wp-content\/uploads\/2026\/02\/Realities-Remixed_Dotcom-banner_2880x1800px.jpg?w=2880&amp;quality=70 2x\" media=\"(min-width: 992px)\"\/><source srcset=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2026\/02\/Realities-Remixed_Dotcom-banner_2880x1800px.jpg?w=1024&amp;quality=70 1x, https:\/\/www.capgemini.com\/wp-content\/uploads\/2026\/02\/Realities-Remixed_Dotcom-banner_2880x1800px.jpg?w=1024&amp;quality=70 2x\" media=\"(min-width: 768px)\"\/><source srcset=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2026\/02\/Realities-Remixed_Dotcom-banner_2880x1800px.jpg?w=768&amp;quality=70 1x, https:\/\/www.capgemini.com\/wp-content\/uploads\/2026\/02\/Realities-Remixed_Dotcom-banner_2880x1800px.jpg?w=768&amp;quality=70 2x\" media=\"(min-width: 0)\"\/><img decoding=\"async\" src=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2026\/02\/Realities-Remixed_Dotcom-banner_2880x1800px.jpg\" class=\"header-img header-img-d\" alt=\"\" style=\"object-fit:cover;object-position:49% 44%\" loading=\"eager\"\/><\/picture><\/div><div class=\"heroPictureCardHeaderShape\"><\/div><div class=\"container\"><div class=\"row\"><div class=\"col-md-12\"><div class=\"box\"><div class=\"boxTagWrapper\"><div class=\"tagInfo\"><div><span class=\"box-tag\">Cloud<\/span><\/div><\/div><\/div><div class=\"box-title\"><h1 data-maxlength=\"34\">Realidades remezcladas: la serie de podcasts<\/h1><\/div><div class=\"inner-row-insight download-btn\"><\/div><\/div><\/div><\/div><\/div><\/header>\n\n\n\n<section class=\"wp-block-cg-blocks-group undefined section section--article-content\"><div class=\"article-main-content\"><div class=\"container\"><div class=\"grid-container\"><div class=\"col-12 col-md-2\"><nav class=\"article-social\"><ul class=\"social-nav\"><li class=\"ip-order-fb\"><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https:\/\/www.capgemini.com\/insights\/research-library\/cloud-realities-podcast\/\" target=\"_blank\" rel=\"noopener noreferrer\" title=\"Abrir en una nueva ventana\"><i aria-hidden=\"true\" class=\"icon-fb\"><\/i><span class=\"sr-only\">Facebook<\/span><\/a><\/li><li class=\"ip-order-tw\"><a href=\"https:\/\/twitter.com\/intent\/tweet?url=https:\/\/www.capgemini.com\/insights\/research-library\/cloud-realities-podcast\/&amp;text=Cloud%20realities%20podcast\" target=\"_blank\" rel=\"noopener noreferrer\" title=\"Abrir en una nueva ventana\"><i aria-hidden=\"true\" class=\"icon-tw\"><\/i><span class=\"sr-only\">Twitter<\/span><\/a><\/li><li class=\"ip-order-li\"><a href=\"https:\/\/www.linkedin.com\/shareArticle?url=https:\/\/www.capgemini.com\/insights\/research-library\/cloud-realities-podcast\/&amp;text=Cloud%20realities%20podcast\" target=\"_blank\" rel=\"noopener noreferrer\" title=\"Abrir en una nueva ventana\"><i aria-hidden=\"true\" class=\"icon-li\"><\/i><span class=\"sr-only\">Linkedin<\/span><\/a><\/li><\/ul><\/nav><\/div><div><div class=\"article-text article-quote-text\">\n<h3 class=\"wp-block-heading\" id=\"h-del-galardonado-equipo-detras-de-cloud-realities-realities-remixed-explora-que-sucede-cuando-las-personas-la-cultura-la-industria-y-la-tecnologia-colisionan-ya-que-los-verdaderos-avances-rara-vez-provienen-unicamente-de-la-tecnologia\">Del galardonado equipo detr\u00e1s de Cloud Realities, Realities Remixed explora qu\u00e9 sucede cuando las personas, la cultura, la industria y la tecnolog\u00eda colisionan, ya que los verdaderos avances rara vez provienen \u00fanicamente de la tecnolog\u00eda.<\/h3>\n\n\n\n<p>En cada episodio, los presentadores Dave Chapman, Esmee van de Giessen y Rob Kernahan profundizan bajo la superficie de la innovaci\u00f3n para comprender qu\u00e9 es lo que realmente est\u00e1 cambiando. Conversan con l\u00edderes, profesionales, proveedores y pensadores de diversos sectores para explorar c\u00f3mo la tecnolog\u00eda redefine el comportamiento humano, la cultura organizacional y la sociedad; a veces para bien y, en ocasiones, para mal.<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/section>\n\n\n\n<section class=\"wp-block-cg-blocks-group undefined section section--article-content\"><div class=\"article-main-content\"><div class=\"container\"><div class=\"grid-container\"><div><div class=\"article-text article-quote-text\">\n<h2 class=\"wp-block-heading\" id=\"h-el-podcast-de-esta-semana\">El podcast de esta semana<\/h2>\n\n\n\n<iframe loading=\"lazy\" width=\"100%\" height=\"390\" frameborder=\"no\" scrolling=\"no\" seamless=\"\" src=\"https:\/\/share.transistor.fm\/e\/cloud-realities-4443ea6b-0eb6-4eeb-a19c-08980c983ba9\/playlist\/dark\"><\/iframe>\n<\/div><\/div><\/div><\/div><\/div><\/section>\n\n\n\n<section class=\"wp-block-cg-blocks-group undefined section section--article-content\"><div class=\"article-main-content\"><div class=\"container\"><div class=\"grid-container\"><div><div class=\"article-text article-quote-text\">\n<h4 class=\"wp-block-heading\" id=\"h-escucha-y-suscribete-en-los-siguientes-canales\">Escucha y suscr\u00edbete en los siguientes canales:<\/h4>\n\n\n\n<div class=\"wp-block-columns is-not-stacked-on-mobile is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image aligncenter size-full is-style-default\"><a href=\"https:\/\/music.amazon.com\/podcasts\/7dc49c3d-66b1-4a86-b4db-742ceb9e330d\" target=\"_blank\" rel=\"noreferrer noopener\"><img decoding=\"async\" src=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2023\/07\/Amazon-music.jpg\" alt=\"\" class=\"wp-image-941801\"\/><\/a><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image aligncenter size-full is-style-default\"><a href=\"https:\/\/overcast.fm\/itunes1655138563\" target=\"_blank\" rel=\"noreferrer noopener\"><img decoding=\"async\" src=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2023\/07\/Overcast.jpg\" alt=\"\" class=\"wp-image-941802\"\/><\/a><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image aligncenter size-full\"><a href=\"https:\/\/podcasts.apple.com\/us\/podcast\/cloud-realities\/id1655138563?uo=4\" target=\"_blank\" rel=\"noreferrer noopener\"><img decoding=\"async\" src=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2023\/07\/Apple-podcast.jpg\" alt=\"\" class=\"wp-image-941803\"\/><\/a><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image aligncenter size-full\"><a href=\"https:\/\/open.spotify.com\/show\/07A7ScmXRCZtSmpwrHklk6\" target=\"_blank\" rel=\"noreferrer noopener\"><img decoding=\"async\" src=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2023\/07\/Spotify.jpg\" alt=\"\" class=\"wp-image-941804\"\/><\/a><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image aligncenter size-large is-style-rectangular is-style-default\"><a href=\"https:\/\/www.youtube.com\/playlist?list=PLTMJrcAa63de2jTe1Q-tRJSYDGGV30kTy\" target=\"_blank\" rel=\"noreferrer noopener\"><img decoding=\"async\" src=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2022\/12\/Capture-decran-2024-06-10-151111.png?w=695\" alt=\"\" class=\"wp-image-1030085\"\/><\/a><\/figure>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-not-stacked-on-mobile is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image aligncenter size-full\"><a href=\"https:\/\/www.goodpods.com\/podcasts-aid\/1655138563\" target=\"_blank\" rel=\"noreferrer noopener\"><img decoding=\"async\" src=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2023\/07\/Goodpods.jpg\" alt=\"\" class=\"wp-image-941807\"\/><\/a><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image aligncenter size-full\"><a href=\"https:\/\/www.deezer.com\/show\/5393907\" target=\"_blank\" rel=\"noreferrer noopener\"><img decoding=\"async\" src=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2023\/07\/deezer.jpg\" alt=\"\" class=\"wp-image-941808\"\/><\/a><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image aligncenter size-full\"><a href=\"https:\/\/player.fm\/series\/series-3417535\" target=\"_blank\" rel=\"noreferrer noopener\"><img decoding=\"async\" src=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2023\/07\/Player-FM.jpg\" alt=\"\" class=\"wp-image-941809\"\/><\/a><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image aligncenter size-full\"><a href=\"https:\/\/pca.st\/itunes\/1655138563\" target=\"_blank\" rel=\"noreferrer noopener\"><img decoding=\"async\" src=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2023\/07\/Pocket-Casts.jpg\" alt=\"\" class=\"wp-image-941810\"\/><\/a><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image aligncenter size-full\"><a href=\"https:\/\/castbox.fm\/vic\/1655138563\" target=\"_blank\" rel=\"noreferrer noopener\"><img decoding=\"async\" src=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2023\/07\/Castbox.jpg\" alt=\"\" class=\"wp-image-941811\"\/><\/a><\/figure>\n<\/div>\n<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/section>\n\n\n\n<section class=\"wp-block-cg-blocks-how-we-do-it section section--howwedoit block-howwedoit\"><div class=\"container\"><div><div class=\"row\"><div class=\"content-title col-12 col-md-8\"><h2 data-maxlength=\"72\" class=\"expandable-heading-tag\">Estaci\u00f3n 6<\/h2><\/div><\/div><div class=\"row\"><div class=\"col-12 col-md-8\"><p><\/p><\/div><\/div><\/div><div class=\"row\"><div class=\"col-12 col-md-8\"><div class=\"section-content\">\n<div class=\"wp-block-cg-blocks-card-howwedoit expanders\"><div class=\"box card-regulated-agreements card-howwedoit\"><div class=\"expander-box filter-box tag-active opened\"><div class=\"expander-title\" tabindex=\"0\" role=\"button\" aria-expanded=\"true\"><h3 class=\"expander-heading-title\">Episodio 204 \u2013 RRLIVE06: Reflexiones del equipo sobre Google Cloud Next 2026 | Abril de 2026<\/h3><\/div><div class=\"expander-content\"><p><\/p><div class=\"bg-color video-align-right\"><div class=\"container\"><div class=\"row video-align-left\"><div class=\"col-md-12\"><div class=\"video-align-left row box box--4 box--mini\"><div class=\"col-md-3\"><\/div><div class=\"col-md-8 box-img-wrapper\"><div class=\"video-box\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n<p>Las Vegas, est\u00e1s oficialmente en el aire durante Google Cloud Next 2026.<\/p>\n\n\n\n<p>El equipo del podcast #RealitiesRemixed regresa a GCN\u201926, grabando en directo desde el Strip, donde las luces brillantes se encuentran con las grandes ideas.<\/p>\n\n\n\n<p>Esta semana, cambiamos las ruedas de la ruleta por conversaciones francas, manteniendo di\u00e1logos en vivo con l\u00edderes de Google que est\u00e1n redefiniendo el futuro en \u00e1mbitos como la transformaci\u00f3n empresarial centrada en la IA, la IA ag\u00e9ntica, los datos, la soberan\u00eda, la seguridad y m\u00e1s all\u00e1.<\/p>\n\n\n\n<p>Prep\u00e1rense para recibir perspectivas agudas, opiniones audaces y conversaciones que dar\u00e1n forma al futuro, transmitidas directamente desde Las Vegas hasta sus auriculares.<\/p>\n\n\n\n<p>\u00a1Dave, Rachel y Rob analizan los momentos m\u00e1s destacados de Google Cloud Next 2026!<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong>TLDR:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>00:24 \u2013 Introducci\u00f3n<\/li>\n\n\n\n<li>01:14 \u2013 Conversaci\u00f3n: Avances desde Google Cloud Next 2025 hasta Google Cloud Next 2026<\/li>\n\n\n\n<li>08:15 \u2013 Profundizaci\u00f3n: Resumen ejecutivo de los temas clave de este a\u00f1o<\/li>\n\n\n\n<li>31:38 \u2013 Palabras de cierre<\/li>\n<\/ul>\n\n\n\n<p><strong>Anfitriones especiales<\/strong>:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.linkedin.com\/in\/rachel-belmonte-63550358\/\" target=\"_blank\" rel=\"noreferrer noopener\">Rachel Belmonte<\/a><\/li>\n<\/ul>\n<div class=\"content-more\"><a class=\"more2\" aria-label=\"Escuchar link\" href=\"https:\/\/open.spotify.com\/episode\/0ImDOEsthh3Vkgh6DpZJ5Q\" target=\"_blank\" title=\"Opens in a new window\" rel=\"noopener noreferrer\">Escuchar<\/a><\/div><\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-cg-blocks-card-howwedoit expanders\"><div class=\"box card-regulated-agreements card-howwedoit\"><div class=\"expander-box filter-box tag-active opened\"><div class=\"expander-title\" tabindex=\"0\" role=\"button\" aria-expanded=\"true\"><h3 class=\"expander-heading-title\">Episodio 203 \u2013 RRLIVE05: Google Cloud Next 2026, Ingenier\u00eda con IA con Cliff Krimmel, Google Cloud | Abril de 2026<\/h3><\/div><div class=\"expander-content\"><p><\/p><div class=\"bg-color video-align-right\"><div class=\"container\"><div class=\"row video-align-left\"><div class=\"col-md-12\"><div class=\"video-align-left row box box--4 box--mini\"><div class=\"col-md-3\"><\/div><div class=\"col-md-8 box-img-wrapper\"><div class=\"video-box\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n<p>Las Vegas, est\u00e1s oficialmente en el aire durante el Google Cloud Next 2026.<\/p>\n\n\n\n<p>El equipo del podcast #RealitiesRemixed regresa al GCN\u201926 para grabar en directo desde el Strip, el lugar donde las luces brillantes convergen con las grandes ideas.<\/p>\n\n\n\n<p>Esta semana, cambiamos las ruedas de la ruleta por conversaciones francas, manteniendo di\u00e1logos en vivo con l\u00edderes de Google que est\u00e1n redefiniendo el futuro en \u00e1mbitos como la transformaci\u00f3n empresarial centrada en la IA, la IA ag\u00e9ntica, los datos, la soberan\u00eda, la seguridad y mucho m\u00e1s.<\/p>\n\n\n\n<p>Prep\u00e1rense para recibir an\u00e1lisis agudos, opiniones audaces y conversaciones que dar\u00e1n forma al futuro, transmitidas directamente desde Las Vegas hasta sus auriculares.<\/p>\n\n\n\n<p>Dave, Rachel y Rob cierran su conversaci\u00f3n con Cliff Krimmel, Director de Ingenier\u00eda de Clientes para el sector bancario en Google Cloud, profundizando en la evoluci\u00f3n de la pila tecnol\u00f3gica y en el auge de las plataformas de desarrollo ag\u00e9ntico.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong>TLDR:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>00:32 \u2013 Arranca el D\u00eda 3<\/li>\n\n\n\n<li>01:25 \u2013 Momento distendido: Consejos para viajar<\/li>\n\n\n\n<li>05:18 \u2013 Profundizando: La Nube de Datos Ag\u00e9ntica<\/li>\n\n\n\n<li>09:00 \u2013 Conversaci\u00f3n con Cliff Krimmel<\/li>\n\n\n\n<li>32:05 \u2013 Cierre con hamburguesas y perritos calientes<\/li>\n<\/ul>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Invitada:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.linkedin.com\/in\/ckrimmel\/\" target=\"_blank\" rel=\"noreferrer noopener\"><\/a><a href=\"https:\/\/www.linkedin.com\/in\/ckrimmel\/\" target=\"_blank\" rel=\"noreferrer noopener\">Cliff Krimmel<\/a><\/li>\n<\/ul>\n\n\n\n<p><strong>Anfitriones especiales<\/strong>:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.linkedin.com\/in\/rachel-belmonte-63550358\/\" target=\"_blank\" rel=\"noreferrer noopener\">Rachel Belmonte<\/a><\/li>\n<\/ul>\n<div class=\"content-more\"><a class=\"more2\" aria-label=\"Escuchar link\" href=\"https:\/\/open.spotify.com\/episode\/4n7bqY4SjqeOlXgKTYZqKe\" target=\"_blank\" title=\"Opens in a new window\" rel=\"noopener noreferrer\">Escuchar<\/a><\/div><\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-cg-blocks-card-howwedoit expanders\"><div class=\"box card-regulated-agreements card-howwedoit\"><div class=\"expander-box filter-box tag-active opened\"><div class=\"expander-title\" tabindex=\"0\" role=\"button\" aria-expanded=\"true\"><h3 class=\"expander-heading-title\">Episodio 202 \u2013 RRLIVE04: Google Cloud Next 2026, el auge de la IA creativa con Khulan Davaajav, Google Cloud | Abril de 2026<\/h3><\/div><div class=\"expander-content\"><p><\/p><div class=\"bg-color video-align-right\"><div class=\"container\"><div class=\"row video-align-left\"><div class=\"col-md-12\"><div class=\"video-align-left row box box--4 box--mini\"><div class=\"col-md-3\"><\/div><div class=\"col-md-8 box-img-wrapper\"><div class=\"video-box\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n<p>Las Vegas, has quedado oficialmente registrada durante el Google Cloud Next 2026.<\/p>\n\n\n\n<p>El equipo del podcast #RealitiesRemixed regresa al GCN\u201926 para grabar en directo desde el Strip, el lugar donde las luces brillantes convergen con las grandes ideas.<\/p>\n\n\n\n<p>Esta semana, cambiamos las ruedas de la ruleta por conversaciones francas, manteniendo di\u00e1logos en vivo con l\u00edderes de Google que est\u00e1n redefiniendo el futuro en \u00e1mbitos como la transformaci\u00f3n empresarial centrada en la IA, la IA ag\u00e9ntica, los datos, la soberan\u00eda, la seguridad y mucho m\u00e1s.<\/p>\n\n\n\n<p>Prep\u00e1rense para recibir an\u00e1lisis agudos, opiniones audaces y conversaciones que dar\u00e1n forma al futuro, transmitidas directamente desde Las Vegas hasta sus auriculares.<\/p>\n\n\n\n<p>Dave, Rachel y Rob contin\u00faan su conversaci\u00f3n con Khulan Davaajav, Gerente de Marketing de Producto para Modelos de Medios Generativos en Google, acerca del auge de la IA creativa y de c\u00f3mo esta est\u00e1 redefiniendo la expresi\u00f3n humana en la era de las herramientas inteligentes.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong>TLDR:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>00:24 \u2013 \u00a1El segundo d\u00eda ya est\u00e1 en marcha!<\/li>\n\n\n\n<li>00:40 \u2013 Charla: El productor, distra\u00eddo, y el ojo rojo de Rob<\/li>\n\n\n\n<li>03:31 \u2013 Momentos destacados: Anuncios sobre medios del reportero itinerante<\/li>\n\n\n\n<li>07:16 \u2013 Conversaci\u00f3n con Khulan Davaajav<\/li>\n\n\n\n<li>34:24 \u2013 Barbacoa mongola<\/li>\n<\/ul>\n\n\n\n<p><strong>Special Host<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.linkedin.com\/in\/rachel-belmonte-63550358\/\" target=\"_blank\" rel=\"noreferrer noopener\">Rachel Belmonte<\/a><\/li>\n<\/ul>\n\n\n\n<p><strong>Anfitriones especiales<\/strong>:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.linkedin.com\/in\/rachel-belmonte-63550358\/\" target=\"_blank\" rel=\"noreferrer noopener\">Rachel Belmonte<\/a><\/li>\n<\/ul>\n<div class=\"content-more\"><a class=\"more2\" aria-label=\"Escuchar link\" href=\"https:\/\/open.spotify.com\/episode\/7AAJqfY46bUMoI6T6MW5RE\" target=\"_blank\" title=\"Opens in a new window\" rel=\"noopener noreferrer\">Escuchar<\/a><\/div><\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-cg-blocks-card-howwedoit expanders\"><div class=\"box card-regulated-agreements card-howwedoit\"><div class=\"expander-box filter-box tag-active opened\"><div class=\"expander-title\" tabindex=\"0\" role=\"button\" aria-expanded=\"true\"><h3 class=\"expander-heading-title\">Episodio 201 \u2013 RRLIVE03: Google Cloud Next 2026, acelerando los recorridos ag\u00e9nticos con Gina Fratarcangeli, Google Cloud | Abril de 2026<\/h3><\/div><div class=\"expander-content\"><p><\/p><div class=\"bg-color video-align-right\"><div class=\"container\"><div class=\"row video-align-left\"><div class=\"col-md-12\"><div class=\"video-align-left row box box--4 box--mini\"><div class=\"col-md-3\"><\/div><div class=\"col-md-8 box-img-wrapper\"><div class=\"video-box\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n<p>Las Vegas, tu presencia queda oficialmente registrada durante el Google Cloud Next 2026.<\/p>\n\n\n\n<p>El equipo del podcast #RealitiesRemixed regresa al GCN\u201926 para grabar en directo desde el Strip, el lugar donde las luces brillantes convergen con las grandes ideas.<\/p>\n\n\n\n<p>Esta semana, cambiamos las ruedas de la ruleta por conversaciones francas, manteniendo di\u00e1logos en vivo con l\u00edderes de Google que est\u00e1n redefiniendo el futuro en \u00e1mbitos como la transformaci\u00f3n empresarial centrada en la IA, la IA ag\u00e9ntica, los datos, la soberan\u00eda, la seguridad y mucho m\u00e1s.<\/p>\n\n\n\n<p>Prep\u00e1rense para recibir an\u00e1lisis agudos, opiniones audaces y conversaciones que dar\u00e1n forma al futuro, transmitidas directamente desde Las Vegas hasta sus auriculares.<\/p>\n\n\n\n<p>Dave, Rachel y Rob contin\u00faan su conversaci\u00f3n con Gina Fratarcangeli, Directora General y L\u00edder de GSI para Norteam\u00e9rica, explorando c\u00f3mo los socios est\u00e1n redefiniendo su rol: desde los modelos de financiaci\u00f3n y las conversaciones a nivel de junta directiva, hasta la configuraci\u00f3n del modelo de la empresa ag\u00e9ntica.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong>TLDR:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>00:24 \u2013 \u00a1Arranca el segundo d\u00eda!<\/li>\n\n\n\n<li>00:40 \u2013 Charla: impresiones sobre la GCN \u201926 en el Centro de Convenciones Mandalay Bay y Dave abollando sus cosas<\/li>\n\n\n\n<li>05:26 \u2013 Profundizamos: qu\u00e9 anuncios capt\u00f3 nuestro reportero itinerante<\/li>\n\n\n\n<li>09:54 \u2013 Conversaci\u00f3n con Gina Fratarcangeli<\/li>\n\n\n\n<li>32:41 \u2013 Brisket estilo Texas en papel para barbacoa<\/li>\n<\/ul>\n\n\n\n<p><strong>Guest<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.linkedin.com\/in\/gina-fratarcangeli\/\" target=\"_blank\" rel=\"noreferrer noopener\">Gina Fratarcangeli<\/a><\/li>\n<\/ul>\n\n\n\n<p><strong>Anfitriones especiales<\/strong>:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.linkedin.com\/in\/rachel-belmonte-63550358\/\" target=\"_blank\" rel=\"noreferrer noopener\">Rachel Belmonte<\/a><\/li>\n<\/ul>\n<div class=\"content-more\"><a class=\"more2\" aria-label=\"Escuchar link\" href=\"https:\/\/open.spotify.com\/episode\/6bZdbW4PyU7q8m2Egw4lXM\" target=\"_blank\" title=\"Opens in a new window\" rel=\"noopener noreferrer\">Escuchar<\/a><\/div><\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-cg-blocks-card-howwedoit expanders\"><div class=\"box card-regulated-agreements card-howwedoit\"><div class=\"expander-box filter-box tag-active opened\"><div class=\"expander-title\" tabindex=\"0\" role=\"button\" aria-expanded=\"true\"><h3 class=\"expander-heading-title\">Episodio 200 \u2013 RRLIVE02: Google Cloud Next 2026, La opcionalidad es la nueva soberan\u00eda, con Dominic Cody, Google Cloud | Abril de 2026<\/h3><\/div><div class=\"expander-content\"><p><\/p><div class=\"bg-color video-align-right\"><div class=\"container\"><div class=\"row video-align-left\"><div class=\"col-md-12\"><div class=\"video-align-left row box box--4 box--mini\"><div class=\"col-md-3\"><\/div><div class=\"col-md-8 box-img-wrapper\"><div class=\"video-box\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n<p>Las Vegas, est\u00e1s oficialmente en el aire durante el Google Cloud Next 2026.<\/p>\n\n\n\n<p>El equipo del podcast #RealitiesRemixed regresa al GCN\u201926, grabando en directo desde el Strip, donde las luces brillantes convergen con las grandes ideas.<\/p>\n\n\n\n<p>Esta semana, cambiamos las ruedas de la ruleta por conversaciones francas, manteniendo di\u00e1logos en vivo con l\u00edderes de Google que est\u00e1n redefiniendo el futuro en \u00e1mbitos como la transformaci\u00f3n empresarial centrada en la IA, la IA ag\u00e9ntica, los datos, la soberan\u00eda, la seguridad y m\u00e1s all\u00e1.<\/p>\n\n\n\n<p>Prep\u00e1rense para recibir perspectivas agudas, opiniones audaces y conversaciones que dar\u00e1n forma al futuro, transmitidas directamente desde Las Vegas hasta sus auriculares.<\/p>\n\n\n\n<p>Dave, Rachel y Rob contin\u00faan la conversaci\u00f3n con Dominic Cody, Director Global de Tecnolog\u00eda de Distributed Cloud, acerca del <em>Sovereign Edge<\/em> y de c\u00f3mo recuperar el control en la era de la IA ag\u00e9ntica.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong>TLDR:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>00:24 \u2013 Presentaci\u00f3n del invitado y temas clave de esta semana<\/li>\n\n\n\n<li>00:40 \u2013 Hangout: La IA en el recinto de la Expo y la reportera itinerante Rachel Belmonte<\/li>\n\n\n\n<li>01:24 \u2013 A fondo: qu\u00e9 esperar de los anuncios de Google<\/li>\n\n\n\n<li>05:36 \u2013 Conversaci\u00f3n con Dominic Cody<\/li>\n\n\n\n<li>31:28 \u2013 Nuestras recomendaciones favoritas para la barbacoa<\/li>\n<\/ul>\n\n\n\n<p><strong>Invitada<\/strong>:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.linkedin.com\/in\/rachel-belmonte-63550358\/\" target=\"_blank\" rel=\"noreferrer noopener\"><\/a><a href=\"https:\/\/www.linkedin.com\/in\/dominiccody\/\" target=\"_blank\" rel=\"noreferrer noopener\">Dominic Cody<\/a><\/li>\n<\/ul>\n\n\n\n<p><strong>Anfitriones especiales:<\/strong><\/p>\n\n\n\n<p><a href=\"https:\/\/www.linkedin.com\/in\/rachel-belmonte-63550358\/\" target=\"_blank\" rel=\"noreferrer noopener\">Rachel Belmonte<\/a><\/p>\n<div class=\"content-more\"><a class=\"more2\" aria-label=\"Escuchar link\" href=\"https:\/\/open.spotify.com\/episode\/2JsBHM0ktcWgD2o8ZvPHZ2\" target=\"_blank\" title=\"Opens in a new window\" rel=\"noopener noreferrer\">Escuchar<\/a><\/div><\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-cg-blocks-card-howwedoit expanders\"><div class=\"box card-regulated-agreements card-howwedoit\"><div class=\"expander-box filter-box tag-active opened\"><div class=\"expander-title\" tabindex=\"0\" role=\"button\" aria-expanded=\"true\"><h3 class=\"expander-heading-title\">Episodio 199 \u2013 RRLIVE01: Google Cloud Next 2026, El auge del comercio ag\u00e9ntico con Mark Steel, Google Cloud | Abril de 2026<\/h3><\/div><div class=\"expander-content\"><p><\/p><div class=\"bg-color video-align-right\"><div class=\"container\"><div class=\"row video-align-left\"><div class=\"col-md-12\"><div class=\"video-align-left row box box--4 box--mini\"><div class=\"col-md-3\"><\/div><div class=\"col-md-8 box-img-wrapper\"><div class=\"video-box\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n<p>Las Vegas, est\u00e1s oficialmente en el aire durante el Google Cloud Next 2026.<\/p>\n\n\n\n<p>El equipo del podcast #RealitiesRemixed regresa al GCN\u201926, grabando en directo desde el Strip, donde las luces brillantes convergen con las grandes ideas.<\/p>\n\n\n\n<p>Esta semana, cambiamos las ruedas de la ruleta por conversaciones francas, manteniendo di\u00e1logos en vivo con l\u00edderes de Google que est\u00e1n redefiniendo el futuro en \u00e1mbitos como la transformaci\u00f3n empresarial centrada en la IA, la IA ag\u00e9ntica, los datos, la soberan\u00eda, la seguridad y mucho m\u00e1s.<\/p>\n\n\n\n<p>Prep\u00e1rense para recibir an\u00e1lisis agudos, opiniones audaces y conversaciones que dar\u00e1n forma al futuro, transmitidas directamente desde Las Vegas hasta sus auriculares.<\/p>\n\n\n\n<p>Dave, Rachel y Rob dan el pistoletazo de salida al evento junto a Mark Steel, Director del Sector Minorista para EMEA en Google Cloud, profundizando en el auge del Comercio Ag\u00e9ntico y en c\u00f3mo los agentes de IA est\u00e1n redefiniendo la relaci\u00f3n entre las marcas, los minoristas y los consumidores.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong>TLDR:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>00:24 \u2013 Presentaci\u00f3n del invitado y temas clave de esta semana<\/li>\n\n\n\n<li>00:52 \u2013 Hangout: nuevo equipo de podcast y la reportera itinerante Rachel Belmonte<\/li>\n\n\n\n<li>05:52 \u2013 A fondo: qu\u00e9 esperar de los anuncios de Google<\/li>\n\n\n\n<li>11:41 \u2013 Conversaci\u00f3n con Mark Steel<\/li>\n\n\n\n<li>39:10 \u2013 Favoritos para la barbacoa<\/li>\n\n\n\n<li><strong>Invitada:<\/strong><\/li>\n\n\n\n<li><a href=\"https:\/\/www.linkedin.com\/in\/marksteel220\/\" target=\"_blank\" rel=\"noreferrer noopener\"><\/a><a href=\"https:\/\/www.linkedin.com\/in\/marksteel220\/\" target=\"_blank\" rel=\"noreferrer noopener\">Mark Steel<\/a><\/li>\n<\/ul>\n\n\n\n<p><strong>Anfitriones especiales<\/strong>:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.linkedin.com\/in\/rachel-belmonte-63550358\/\" target=\"_blank\" rel=\"noreferrer noopener\">Rachel Belmonte<\/a><\/li>\n<\/ul>\n<div class=\"content-more\"><a class=\"more2\" aria-label=\"Transcripci\u00f3n del episod link\" href=\"https:\/\/open.spotify.com\/episode\/05BWEtRm8mP3gacCwCQ4KW\" target=\"_blank\" title=\"Opens in a new window\" rel=\"noopener noreferrer\">Transcripci\u00f3n del episod<\/a><\/div><\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-cg-blocks-card-howwedoit expanders\"><div class=\"box card-regulated-agreements card-howwedoit\"><div class=\"expander-box filter-box tag-active opened\"><div class=\"expander-title\" tabindex=\"0\" role=\"button\" aria-expanded=\"true\"><h3 class=\"expander-heading-title\">Episodio 198 \u2013 RR009 Liderar en la \u00abNunca Normal\u00bb con Peter Hinssen | Abril de 2026<\/h3><\/div><div class=\"expander-content\"><p><\/p><div class=\"bg-color video-align-right\"><div class=\"container\"><div class=\"row video-align-left\"><div class=\"col-md-12\"><div class=\"video-align-left row box box--4 box--mini\"><div class=\"col-md-3\"><\/div><div class=\"col-md-8 box-img-wrapper\"><div class=\"video-box\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n<p>Realities Remixed, anteriormente conocido como Cloud Realities, lanza una nueva temporada que explora la intersecci\u00f3n entre las personas, la cultura, la industria y la tecnolog\u00eda.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>A medida que la IA acelera la transici\u00f3n de las redes a los ecosistemas, las organizaciones se enfrentan a una tensi\u00f3n creciente entre una tecnolog\u00eda de ritmo vertiginoso y un cambio organizacional m\u00e1s lento, impulsado por factores sociales. El \u00e9xito en la \u00abNunca Normalidad\u00bb depender\u00e1 menos de la inteligencia en s\u00ed misma y m\u00e1s de las cualidades de liderazgo, el buen juicio, la narrativa, la confianza y la capacidad de crear un espacio para que los \u00abexploradores corporativos\u00bb construyan el \u00abpasado ma\u00f1ana\u00bb, y no solo optimicen el presente.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Esta semana, Dave, Esmee y Rob se unen a Peter Hinssen \u2014conferencista principal, autor, docente y cofundador de nexxworks\u2014 para explorar c\u00f3mo los l\u00edderes navegan a trav\u00e9s del cambio acelerado, enfoc\u00e1ndose en transformar la incertidumbre en oportunidades de crecimiento e innovaci\u00f3n.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong>TLDR:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>00:41 \u2013 Presentaci\u00f3n del invitado y resumen del tema de esta semana.<\/li>\n\n\n\n<li>01:02 \u2013 Hangout: \u00a1Episodio 200!<\/li>\n\n\n\n<li>06:25 \u2013 Ad\u00e9ntrate: Un an\u00e1lisis profundo del ritmo del cambio<\/li>\n\n\n\n<li>14:17 \u2013 Conversaci\u00f3n con Peter Hinssen sobre organizaciones adaptativas y estilos de liderazgo.<\/li>\n\n\n\n<li>55:10 \u2013 Continuando la conversaci\u00f3n sobre tecnolog\u00eda<\/li>\n\n\n\n<li>1:11:20 \u2013 Viaje a Taiw\u00e1n, Silicon Valley y China<\/li>\n<\/ul>\n\n\n\n<p><strong>Invitada:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.linkedin.com\/in\/phinssen\/\" target=\"_blank\" rel=\"noreferrer noopener\">Peter Hinssen<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.peterhinssen.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.peterhinssen.com<\/a><\/li>\n<\/ul>\n<div class=\"content-more\"><a class=\"more2\" aria-label=\"Transcripci\u00f3n del episod link\" href=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2026\/04\/RR009-Leading-in-the-Never-Normal-with-Peter-Hinssen.pdf\" target=\"_blank\" title=\"Opens in a new window\" rel=\"noopener noreferrer\">Transcripci\u00f3n del episod<\/a><a class=\"more2\" aria-label=\"Escuchar link\" href=\"https:\/\/open.spotify.com\/episode\/2MvxNuQ5endqkfP7MyM5fx\" target=\"_blank\" title=\"Opens in a new window\" rel=\"noopener noreferrer\">Escuchar<\/a><\/div><\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-cg-blocks-card-howwedoit expanders\"><div class=\"box card-regulated-agreements card-howwedoit\"><div class=\"expander-box filter-box tag-active \"><div class=\"expander-title\" tabindex=\"0\" role=\"button\" aria-expanded=\"false\"><h3 class=\"expander-heading-title\">Episodio 197 \u2013 RR008: Salto estrat\u00e9gico en un mundo convulso con Andre Loesekrug-Pietri, JEDI: la ARPA europea | Abril de 2026<\/h3><\/div><div class=\"expander-content\"><p><\/p><div class=\"bg-color video-align-right\"><div class=\"container\"><div class=\"row video-align-left\"><div class=\"col-md-12\"><div class=\"video-align-left row box box--4 box--mini\"><div class=\"col-md-3\"><\/div><div class=\"col-md-8 box-img-wrapper\"><div class=\"video-box\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n<p>En una era en la que el progreso tecnol\u00f3gico redefine el poder, la seguridad y la prosperidad a una velocidad sin precedentes, las sociedades se enfrentan a una elecci\u00f3n decisiva: adaptarse de manera incremental o reinventarse con audacia. \u00bfC\u00f3mo pueden las tecnolog\u00edas revolucionarias y disruptivas posibilitar un salto estrat\u00e9gico, transformando las ambiciones a largo plazo en un impacto tangible en el mundo real, en medio de un panorama global en r\u00e1pida transformaci\u00f3n?<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Esta semana, Dave, Esmee y Rob se re\u00fanen con Andre Loesekrug-Pietri, presidente y director cient\u00edfico de la Joint European Disruptive Initiative (JEDI, la ARPA europea), para explorar la ambici\u00f3n subyacente y lo que har\u00eda falta para que Europa deje de reaccionar ante el cambio tecnol\u00f3gico y comience a darle forma.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong>TLDR:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>00:30 \u2013 Presentaci\u00f3n del invitado y resumen de la conversaci\u00f3n de esta semana.<\/li>\n\n\n\n<li>01:35 \u2013 An\u00e1lisis a fondo del equipo: \u00bfSe est\u00e1 quedando atr\u00e1s Europa en materia de competitividad?<\/li>\n\n\n\n<li>13:52 \u2013 Conversaci\u00f3n con Andre Loesekrug-Pietri<\/li>\n\n\n\n<li>1:00:19 \u2013 Viajando a Jap\u00f3n con la presidenta francesa<\/li>\n<\/ul>\n\n\n\n<p><strong>Invitada:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.linkedin.com\/in\/andrepietri\/\" target=\"_blank\" rel=\"noreferrer noopener\">Andre Loeskrug-Petri<\/a><br>X: @eurojedi<br>www.jedi.foundation<\/li>\n<\/ul>\n<div class=\"content-more\"><a class=\"more2\" aria-label=\"Transcripci\u00f3n del episod link\" href=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2026\/04\/RR008-Strategic-leapfrogging-in-a-disturbed-world-with-Andre-Loesekrug-Pietri-Head-of-JEDI.pdf\" target=\"_blank\" title=\"Opens in a new window\" rel=\"noopener noreferrer\">Transcripci\u00f3n del episod<\/a><a class=\"more2\" aria-label=\"Escuchar link\" href=\"https:\/\/open.spotify.com\/episode\/4w1ZQWV6xCcm0poRnm2l6M\" target=\"_blank\" title=\"Opens in a new window\" rel=\"noopener noreferrer\">Escuchar<\/a><\/div><\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-cg-blocks-card-howwedoit expanders\"><div class=\"box card-regulated-agreements card-howwedoit\"><div class=\"expander-box filter-box tag-active \"><div class=\"expander-title\" tabindex=\"0\" role=\"button\" aria-expanded=\"false\"><h3 class=\"expander-heading-title\">Episodio 196 \u2013 RR007: \u00bfQu\u00e9 pasa si la Ley de Moore ha terminado? con AJ Guillon y Peter Richards, YetiWare | Abril de 2026<\/h3><\/div><div class=\"expander-content\"><p><\/p><div class=\"bg-color video-align-right\"><div class=\"container\"><div class=\"row video-align-left\"><div class=\"col-md-12\"><div class=\"video-align-left row box box--4 box--mini\"><div class=\"col-md-3\"><\/div><div class=\"col-md-8 box-img-wrapper\"><div class=\"video-box\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n<p>Realities Remixed, anteriormente conocido como Cloud Realities, lanza una nueva temporada que explora la intersecci\u00f3n entre las personas, la cultura, la industria y la tecnolog\u00eda.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Uno de los desaf\u00edos m\u00e1s fundamentales de la computaci\u00f3n moderna es la creciente disparidad entre el hardware y el software. A medida que la Ley de Moore se desacelera y las mejoras de rendimiento dejan de obtenerse \u00abde forma gratuita\u00bb, el software \u2014construido sobre supuestos secuenciales propios de la era de Turing\u2014 tiene dificultades para seguir el ritmo del hardware actual, altamente paralelo y heterog\u00e9neo. Esta desconexi\u00f3n constituye hoy en d\u00eda una limitaci\u00f3n central para la innovaci\u00f3n.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Esta semana, Dave, Esmee y Rob se unen a Peter Richards \u2014asesor\u2014 y a AJ Guillon \u2014fundador de YetiWare\u2014 para explorar por qu\u00e9 persiste este desajuste, qu\u00e9 implica para las organizaciones de hoy en d\u00eda y c\u00f3mo los enfoques emergentes podr\u00edan redefinir la relaci\u00f3n entre el software y el hardware en los a\u00f1os venideros.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong>TLDR:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>00:35 \u2013 Introducci\u00f3n<\/li>\n\n\n\n<li>01:04 \u2013 Charla: \u00bfQu\u00e9 tan profundo podemos llegar y cu\u00e1l es la historia de la era inform\u00e1tica?<\/li>\n\n\n\n<li>07:00 \u2013 Adentr\u00e9monos: Las demandas energ\u00e9ticas de los LLM, los centros de datos, la escala, el tama\u00f1o y las papas fritas.<\/li>\n\n\n\n<li>15:35 \u2013 Conversaci\u00f3n con Peter Richards y AJ Guillon<\/li>\n\n\n\n<li>55:31 \u2013 Limpieza de primavera con motosierra y ciclismo<\/li>\n<\/ul>\n\n\n\n<p><strong>Invitada:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.linkedin.com\/in\/peter-richards-3b99688\/\" target=\"_blank\" rel=\"noreferrer noopener\">Peter Richards<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.linkedin.com\/in\/ajguillon\/\" target=\"_blank\" rel=\"noreferrer noopener\">AJ Guillon<\/a><\/li>\n<\/ul>\n\n\n\n<p><\/p>\n<div class=\"content-more\"><a class=\"more2\" aria-label=\"Transcripci\u00f3n del episod link\" href=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2026\/04\/RR007-What-happens-when-Moores-law-is-over-with-AJ-Guillon-and-Peter-Richards-YetiWare.pdf\" target=\"_blank\" title=\"Opens in a new window\" rel=\"noopener noreferrer\">Transcripci\u00f3n del episod<\/a><a class=\"more2\" aria-label=\"Escuchar link\" href=\"https:\/\/open.spotify.com\/episode\/4cfDvp8pEXIortHVZcmSz3\" target=\"_blank\" title=\"Opens in a new window\" rel=\"noopener noreferrer\">Escuchar<\/a><\/div><\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-cg-blocks-card-howwedoit expanders\"><div class=\"box card-regulated-agreements card-howwedoit\"><div class=\"expander-box filter-box tag-active \"><div class=\"expander-title\" tabindex=\"0\" role=\"button\" aria-expanded=\"false\"><h3 class=\"expander-heading-title\">Episodio 195 \u2013 RR006: C\u00f3mo deben adaptarse los l\u00edderes ahora para escalar la IA con \u00e9xito, con Jana Werner y Phil Le-Brun, AWS | Marzo de 2026<\/h3><\/div><div class=\"expander-content\"><p><\/p><div class=\"bg-color video-align-right\"><div class=\"container\"><div class=\"row video-align-left\"><div class=\"col-md-12\"><div class=\"video-align-left row box box--4 box--mini\"><div class=\"col-md-3\"><\/div><div class=\"col-md-8 box-img-wrapper\"><div class=\"video-box\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n<p>Realities Remixed, anteriormente conocido como Cloud Realities, lanza una nueva temporada que explora la intersecci\u00f3n entre las personas, la cultura, la industria y la tecnolog\u00eda.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>En un mundo definido por el cambio constante, los l\u00edderes deben evolucionar desde jerarqu\u00edas r\u00edgidas hacia un liderazgo emocionalmente inteligente y empoderador. Al fomentar la adaptabilidad, el aprendizaje continuo, el liderazgo distribuido y una cultura de curiosidad, las organizaciones se equipan mejor para navegar las disrupciones tecnol\u00f3gicas \u2014como la IA\u2014 con resiliencia e innovaci\u00f3n.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Esta semana, Dave, Esmee y Rob se unen a Jana Werner y Phil Le-Brun \u2014Ejecutivos en Residencia en AWS\u2014 para explorar qu\u00e9 se necesita realmente para que las organizaciones prosperen en un mundo de transformaci\u00f3n continua, y por qu\u00e9 las jerarqu\u00edas r\u00edgidas, el control y los programas de cambio excesivamente elaborados suelen interponerse en el camino.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong>TLDR:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>00:42 \u2013 Presentaci\u00f3n del invitado y resumen del tema de esta semana.<\/li>\n\n\n\n<li>01:26 \u2013 El equipo se pone manos a la obra: se avecina un nuevo ciclo de cambio.<\/li>\n\n\n\n<li>19:27 \u2013 Conversaci\u00f3n en profundidad con Jana y Phil<\/li>\n\n\n\n<li>57:37 \u2013 Lista de reproducci\u00f3n y aspectos destacados del caso de estudio de Octopus<\/li>\n<\/ul>\n\n\n\n<p><strong>Invitada:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.linkedin.com\/in\/janawerner1\/\" target=\"_blank\" rel=\"noreferrer noopener\">Jana Werner<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.linkedin.com\/in\/phillebrun\/\" target=\"_blank\" rel=\"noreferrer noopener\">Phil Le-Brun<\/a><\/li>\n<\/ul>\n\n\n\n<p><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.theoctopusorganization.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">A Guide to Thriving in a World of Continuous Transformation<\/a><\/li>\n<\/ul>\n\n\n\n<p><\/p>\n<div class=\"content-more\"><a class=\"more2\" aria-label=\"Transcripci\u00f3n del episod link\" href=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2026\/03\/RR006-How-leaders-must-adapt-now-to-successfully-scale-AI-with-Jana-Werner-and-Phil-Le-Brun-AWS.pdf\" target=\"_blank\" title=\"Opens in a new window\" rel=\"noopener noreferrer\">Transcripci\u00f3n del episod<\/a><a class=\"more2\" aria-label=\"Escuchar link\" href=\"https:\/\/open.spotify.com\/episode\/0KgOdezWoPpD7iVKjeKKnG\" target=\"_blank\" title=\"Opens in a new window\" rel=\"noopener noreferrer\">Escuchar<\/a><\/div><\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-cg-blocks-card-howwedoit expanders\"><div class=\"box card-regulated-agreements card-howwedoit\"><div class=\"expander-box filter-box tag-active \"><div class=\"expander-title\" tabindex=\"0\" role=\"button\" aria-expanded=\"false\"><h3 class=\"expander-heading-title\">Episodio 194 \u2013 RR005: M\u00e9tricas de valor vs. m\u00e9tricas de vanidad con Carlos Corredor, Condor | Marzo de 2026<\/h3><\/div><div class=\"expander-content\"><p><\/p><div class=\"bg-color video-align-right\"><div class=\"container\"><div class=\"row video-align-left\"><div class=\"col-md-12\"><div class=\"video-align-left row box box--4 box--mini\"><div class=\"col-md-3\"><\/div><div class=\"col-md-8 box-img-wrapper\"><div class=\"video-box\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n<p><em>Realities Remixed<\/em>, anteriormente conocido como Cloud Realities, lanza una nueva temporada que explora la intersecci\u00f3n entre las personas, la cultura, la industria y la tecnolog\u00eda.<\/p>\n\n\n\n<div style=\"height:18px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>La tecnolog\u00eda y la IA est\u00e1n transformando r\u00e1pidamente el marketing, desafiando viejos supuestos y desplazando el enfoque hacia una precisi\u00f3n impulsada por el an\u00e1lisis de datos, una segmentaci\u00f3n m\u00e1s inteligente y el contenido multimodal. A medida que resulta cada vez m\u00e1s dif\u00edcil captar la atenci\u00f3n y los flujos de trabajo creativos evolucionan, la verdadera ventaja reside en adaptarse a un entorno que prioriza la IA; en particular, replanteando segmentos a menudo pasados \u200b\u200bpor alto \u2014como el mercado medio\u2014 y siendo mucho m\u00e1s espec\u00edficos tanto en la estrategia como en la ejecuci\u00f3n.<\/p>\n\n\n\n<div style=\"height:18px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Esta semana, Dave, Esmee y Rob reciben a Carlos Corredor, fundador y CEO de Condor, para analizar la diferencia entre las m\u00e9tricas de valor y las m\u00e9tricas de vanidad en el marketing moderno, y por qu\u00e9 muchas organizaciones siguen teniendo dificultades para vincular las actividades de marketing con los resultados empresariales reales.<\/p>\n\n\n\n<div style=\"height:18px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong>TLDR:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>00:32 \u2013 Introducci\u00f3n<\/li>\n\n\n\n<li>00:59 \u2013 Pasar el rato: Mantenerse saludable<\/li>\n\n\n\n<li>06:10 \u2013 Profundicemos: Lo valioso de medir mediante m\u00e9tricas.<\/li>\n\n\n\n<li>17:52 \u2013 Conversaci\u00f3n con Carlos Corredor<\/li>\n\n\n\n<li>47:15 \u2013 De cara a la Copa Mundial de F\u00fatbol<\/li>\n<\/ul>\n\n\n\n<p><strong>Invitada:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.linkedin.com\/in\/carlos-corredor-condor\/\" target=\"_blank\" rel=\"noreferrer noopener\">Carlos Corredor<\/a><\/li>\n<\/ul>\n<div class=\"content-more\"><a class=\"more2\" aria-label=\"Transcripci\u00f3n del episod link\" href=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2026\/03\/RR005-Value-metrics-vs-vanity-metrics-with-Carlos-Corredor-Condor.pdf\" target=\"\" title=\"\" rel=\"noopener noreferrer\">Transcripci\u00f3n del episod<\/a><a class=\"more2\" aria-label=\"Escuchar link\" href=\"https:\/\/open.spotify.com\/episode\/4aLzoZ64ogU542FdVzTNZa\" target=\"\" title=\"\" rel=\"noopener noreferrer\">Escuchar<\/a><\/div><\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-cg-blocks-card-howwedoit expanders\"><div class=\"box card-regulated-agreements card-howwedoit\"><div class=\"expander-box filter-box tag-active \"><div class=\"expander-title\" tabindex=\"0\" role=\"button\" aria-expanded=\"false\"><h3 class=\"expander-heading-title\">Episodio 193 \u2013 RR004: La brecha de confianza con el Dr. Tim Currie, autor | Marzo de 2026<\/h3><\/div><div class=\"expander-content\"><p><\/p><div class=\"bg-color video-align-right\"><div class=\"container\"><div class=\"row video-align-left\"><div class=\"col-md-12\"><div class=\"video-align-left row box box--4 box--mini\"><div class=\"col-md-3\"><\/div><div class=\"col-md-8 box-img-wrapper\"><div class=\"video-box\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n<p><em>Realities Remixed<\/em>, anteriormente conocido como Cloud Realities, lanza una nueva temporada que explora la intersecci\u00f3n entre las personas, la cultura, la industria y la tecnolog\u00eda.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Tras a\u00f1os de trabajo con prioridad remota, cimentado en una confianza r\u00e1pida, las empresas se plantean una pregunta m\u00e1s compleja: \u00bfqu\u00e9 representa realmente una organizaci\u00f3n cuando las personas rara vez coinciden en persona? A medida que la IA acelera el cambio, los l\u00edderes est\u00e1n replanteando la presencia, el dise\u00f1o de equipos y la colaboraci\u00f3n para impulsar la confianza, la innovaci\u00f3n y el crecimiento.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Esta semana, Dave, Esmee y Rob se unen al Dr. Tim Currie \u2014disruptor, autor, innovador y asesor\u2014 para examinar la transformaci\u00f3n frente a la confianza, el papel de la IA y si las organizaciones pueden realmente construir una cultura sin una conexi\u00f3n humana m\u00e1s profunda.<\/p>\n\n\n\n<div style=\"height:18px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong>TLDR:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>00:42\u2013 Introducci\u00f3n<\/li>\n\n\n\n<li>01:10 \u2013&nbsp; Para pasar el rato: Nuevos estrenos de cine<\/li>\n\n\n\n<li>07:17 \u2013 Profundicemos: La brecha de confianza en el trabajo remoto<\/li>\n\n\n\n<li>17:57 \u2013 Conversaci\u00f3n con el Dr. Tim Currie<\/li>\n\n\n\n<li>54:07 \u2013&nbsp;El <em>Mago de Oz en la<\/em> Sphere de Las Vegas y mantenerse conectado<\/li>\n<\/ul>\n\n\n\n<p><strong>Invitada:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.linkedin.com\/in\/dr-tim-currie-37756a\/\" target=\"_blank\" rel=\"noreferrer noopener\">Dr. Tim Currie<\/a><\/li>\n<\/ul>\n\n\n\n<p><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/swifttrustbook.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">Book Swift Trust<\/a><\/li>\n<\/ul>\n<div class=\"content-more\"><a class=\"more2\" aria-label=\"Transcripci\u00f3n del episod link\" href=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2026\/03\/RR004-cloud-podcast-The-trust-gap-with-Dr-Tim-Currie.pdf\" target=\"_blank\" title=\"Opens in a new window\" rel=\"noopener noreferrer\">Transcripci\u00f3n del episod<\/a><a class=\"more2\" aria-label=\"Listado en link\" href=\"https:\/\/open.spotify.com\/episode\/7xLasCfm2R9YLP4OOlwUR3\" target=\"_blank\" title=\"Opens in a new window\" rel=\"noopener noreferrer\">Listado en<\/a><\/div><\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-cg-blocks-card-howwedoit expanders\"><div class=\"box card-regulated-agreements card-howwedoit\"><div class=\"expander-box filter-box tag-active \"><div class=\"expander-title\" tabindex=\"0\" role=\"button\" aria-expanded=\"false\"><h3 class=\"expander-heading-title\">Episodio 192 \u2013 RR003: Comunicando el futuro con Kathleen Tandy, Meta | Marzo de 2026<\/h3><\/div><div class=\"expander-content\"><p><\/p><div class=\"bg-color video-align-right\"><div class=\"container\"><div class=\"row video-align-left\"><div class=\"col-md-12\"><div class=\"video-align-left row box box--4 box--mini\"><div class=\"col-md-3\"><\/div><div class=\"col-md-8 box-img-wrapper\"><div class=\"video-box\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n<p><em>Realities Remixed, anteriormente conocido como Cloud Realities<\/em>, lanza una nueva temporada que explora la intersecci\u00f3n entre las personas, la cultura, la industria y la tecnolog\u00eda.<\/p>\n\n\n\n<p><br>La mensajer\u00eda empresarial est\u00e1 transformando la interacci\u00f3n con los clientes al permitir que las marcas trasladen las conversaciones a plataformas de mensajer\u00eda familiares y siempre activas. El resultado para los clientes es una mayor comodidad, resoluciones m\u00e1s r\u00e1pidas e interacciones m\u00e1s significativas y personalizadas.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Esta semana, Dave, Esmee y Rob se re\u00fanen con Kathleen Tandy, directora global y responsable de Marketing de Mensajer\u00eda Empresarial y WhatsApp for Business en Meta, para explorar c\u00f3mo las empresas utilizan las plataformas de mensajer\u00eda para interactuar con los clientes, qu\u00e9 esperan estos de dichas experiencias y los desaf\u00edos que conlleva escalar la mensajer\u00eda en el sector tecnol\u00f3gico.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong>TLDR:<\/strong><\/p>\n\n\n\n<p><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>00:35 \u2013 Introducci\u00f3n<\/li>\n\n\n\n<li>01:00 \u2013&nbsp; Para pasar el rato: La nueva Remarkable<\/li>\n\n\n\n<li>05:25 \u2013 Profundicemos: el uso de la mensajer\u00eda para mejorar la experiencia del cliente.<\/li>\n\n\n\n<li>20:49 \u2013 Conversaci\u00f3n con Kathleen Tandy<\/li>\n\n\n\n<li>55:26 \u2013 \u00a1La pasi\u00f3n por el f\u00fatbol americano universitario y el fin de semana de campeonatos!<\/li>\n<\/ul>\n\n\n\n<p><strong>Guest:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.linkedin.com\/in\/kptandy\/\" target=\"_blank\" rel=\"noreferrer noopener\">Kathleen Tandy<\/a><\/li>\n<\/ul>\n<div class=\"content-more\"><a class=\"more2\" aria-label=\"Transcripci\u00f3n del episod link\" href=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2026\/03\/RR003-Messaging-the-future-with-Kathleen-Tandy-Meta.pdf\" target=\"_blank\" title=\"Opens in a new window\" rel=\"noopener noreferrer\">Transcripci\u00f3n del episod<\/a><a class=\"more2\" aria-label=\"Escuchar link\" href=\"https:\/\/open.spotify.com\/episode\/1u5nr82CHvUchJTOrMRicE\" target=\"_blank\" title=\"Opens in a new window\" rel=\"noopener noreferrer\">Escuchar<\/a><\/div><\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-cg-blocks-card-howwedoit expanders\"><div class=\"box card-regulated-agreements card-howwedoit\"><div class=\"expander-box filter-box tag-active \"><div class=\"expander-title\" tabindex=\"0\" role=\"button\" aria-expanded=\"false\"><h3 class=\"expander-heading-title\">Episodio 191 \u2013 RR002: La brecha entre negocios y tecnolog\u00eda con John Koerwer, UGI Corporation | Febrero de 2026<\/h3><\/div><div class=\"expander-content\"><p><\/p><div class=\"bg-color video-align-right\"><div class=\"container\"><div class=\"row video-align-left\"><div class=\"col-md-12\"><div class=\"video-align-left row box box--4 box--mini\"><div class=\"col-md-3\"><\/div><div class=\"col-md-8 box-img-wrapper\"><div class=\"video-box\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n<p><em>Realities Remixed, anteriormente conocido como Cloud Realities<\/em>, lanza una nueva temporada que explora la intersecci\u00f3n entre las personas, la cultura, la industria y la tecnolog\u00eda.<\/p>\n\n\n\n<div style=\"height:18px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>El transporte de energ\u00eda es un negocio profundamente local que suministra gas y electricidad de manera segura \u2014cada vez m\u00e1s, provenientes de fuentes renovables\u2014 directamente a las comunidades a las que sirve. La tecnolog\u00eda y la inteligencia artificial contribuyen a hacerlo posible al reforzar la seguridad, acercar a las empresas a sus clientes y permitir que los equipos construyan el futuro juntos.<\/p>\n\n\n\n<div style=\"height:18px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Esta semana, Dave, Esmee y Rob se re\u00fanen con John Koerwer, CIO de UGI Corporation, para explorar por qu\u00e9 \u00abel negocio\u00bb y la tecnolog\u00eda siguen teniendo dificultades para hablar el mismo idioma, y \u200b\u200bqu\u00e9 ayuda a cerrar esa brecha.<\/p>\n\n\n\n<div style=\"height:18px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong>TLDR:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>00:35 \u2013 Introducci\u00f3n<\/li>\n\n\n\n<li>01:17 \u2013 Pasar el rato: juguetes nuevos y caf\u00e9<\/li>\n\n\n\n<li>07:55 \u2013 Profundicemos: la brecha entre negocios y tecnolog\u00eda<\/li>\n\n\n\n<li>21:07 \u2013 Conversaci\u00f3n con John Koerwer<\/li>\n\n\n\n<li>59:40 \u2013 La asombrosa tecnolog\u00eda de IA en la versi\u00f3n de <em>El mago de Oz<\/em> de The Sphere.<\/li>\n<\/ul>\n\n\n\n<div style=\"height:18px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong>Invitada:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.linkedin.com\/in\/john-koerwer-46102127\/\" target=\"_blank\" rel=\"noreferrer noopener\">John Koerwer<\/a><\/li>\n<\/ul>\n<div class=\"content-more\"><a class=\"more2\" aria-label=\"Transcripci\u00f3n del episod link\" href=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2026\/03\/RR002-The-business-tech-divide-with-John-Koerwer-UGI-Corporation.pdf\" target=\"_blank\" title=\"Opens in a new window\" rel=\"noopener noreferrer\">Transcripci\u00f3n del episod<\/a><a class=\"more2\" aria-label=\"Escuchar link\" href=\"https:\/\/open.spotify.com\/episode\/7Kq9W3R3rBwLaGkmkxtX8v\" target=\"_blank\" title=\"Opens in a new window\" rel=\"noopener noreferrer\">Escuchar<\/a><\/div><\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-cg-blocks-card-howwedoit expanders\"><div class=\"box card-regulated-agreements card-howwedoit\"><div class=\"expander-box filter-box tag-active \"><div class=\"expander-title\" tabindex=\"0\" role=\"button\" aria-expanded=\"false\"><h3 class=\"expander-heading-title\">Episodio 190 \u2013 RR001: Esto es Realities Remixed y las grandes tendencias para 2026 | Febrero de 2026<\/h3><\/div><div class=\"expander-content\"><p><\/p><div class=\"bg-color video-align-right\"><div class=\"container\"><div class=\"row video-align-left\"><div class=\"col-md-12\"><div class=\"video-align-left row box box--4 box--mini\"><div class=\"col-md-3\"><\/div><div class=\"col-md-8 box-img-wrapper\"><div class=\"video-box\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n<p>Realities Remixed, anteriormente conocido como Cloud Realities, estrena una nueva temporada que explora la intersecci\u00f3n entre las personas, la cultura, la tecnolog\u00eda y la sociedad. Los presentadores Dave Chapman, Esmee van de Giessen y Rob Kernahan analizan las tendencias que definir\u00e1n el a\u00f1o 2026 \u2014desde la IA y la soberan\u00eda hasta la adaptabilidad y la automatizaci\u00f3n\u2014, ofreciendo nuevas perspectivas, reflexiones francas y conversaciones con visi\u00f3n de futuro que dar\u00e1n forma al a\u00f1o venidero.<\/p>\n\n\n\n<div style=\"height:18px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong>TLDR:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>00:20 \u2013 Introducci\u00f3n a Realities Remixed<\/li>\n\n\n\n<li>02:30 \u2013 \u00bfPor qu\u00e9 evolucion\u00f3 el programa?<\/li>\n\n\n\n<li>04:50 \u2013 Ad\u00e9ntrate con el equipo: Predicciones para 2026<\/li>\n\n\n\n<li>06:40 \u2013 Macrotendencias<\/li>\n\n\n\n<li>13:00 \u2013 Sovereignty&nbsp;<\/li>\n\n\n\n<li>17:40 \u2013 IA ag\u00e9ntica<\/li>\n\n\n\n<li>22:17 \u2013 Human\u2013AI interaction<\/li>\n\n\n\n<li>26:06 \u2013 Cloud trends<\/li>\n\n\n\n<li>30:42 \u2013 AI scaling, domain\u2011specific models<\/li>\n\n\n\n<li>35:03 \u2013 Adoption lag<\/li>\n\n\n\n<li>39:34 \u2013 IA f\u00edsica<\/li>\n\n\n\n<li>43:47 \u2013 Computaci\u00f3n cu\u00e1ntica<\/li>\n\n\n\n<li>48:21 \u2013 Aceleraci\u00f3n por hardware<\/li>\n\n\n\n<li>50:30 \u2013 Ciberseguridad<\/li>\n\n\n\n<li>52:38 \u2013 Perspectivas de la temporada<\/li>\n<\/ul>\n<div class=\"content-more\"><a class=\"more2\" aria-label=\"Transcripci\u00f3n del episod link\" href=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2026\/02\/RR001-This-is-Realities-Remixed-big-trends-for-2026.pdf\" target=\"_blank\" title=\"Opens in a new window\" rel=\"noopener noreferrer\">Transcripci\u00f3n del episod<\/a><a class=\"more2\" aria-label=\"Escuchar link\" href=\"https:\/\/open.spotify.com\/episode\/66tBFhNIFuWPQLZPpWalYp\" target=\"_blank\" title=\"Opens in a new window\" rel=\"noopener noreferrer\">Escuchar<\/a><\/div><\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-cg-blocks-card-howwedoit expanders\"><div class=\"box card-regulated-agreements card-howwedoit\"><div class=\"expander-box filter-box tag-active \"><div class=\"expander-title\" tabindex=\"0\" role=\"button\" aria-expanded=\"false\"><h3 class=\"expander-heading-title\">Episodio 189 \u2013 RR000: \u00a1Pr\u00f3ximamente! | Febrero de 2026<\/h3><\/div><div class=\"expander-content\"><p><\/p><div class=\"bg-color video-align-right\"><div class=\"container\"><div class=\"row video-align-left\"><div class=\"col-md-12\"><div class=\"video-align-left row box box--4 box--mini\"><div class=\"col-md-3\"><\/div><div class=\"col-md-8 box-img-wrapper\"><div class=\"video-box\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n<p>En <em>Cloud Realities<\/em>, las verdaderas revelaciones rara vez proven\u00edan \u00fanicamente de la tecnolog\u00eda; surg\u00edan en la intersecci\u00f3n entre las personas, la cultura, la industria y la tecnolog\u00eda. En esta nueva versi\u00f3n, recuperamos voces y temas familiares, al tiempo que profundizamos en los impactos m\u00e1s amplios, la influencia y el potencial de la tecnolog\u00eda actual en toda la sociedad.<\/p>\n\n\n\n<div style=\"height:18px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>El tr\u00e1iler de la temporada 2026 \u2014que llega un poco m\u00e1s tarde de lo previsto\u2014 arranca con este enfoque renovado y prepara el terreno para el Episodio 1, que se estrenar\u00e1 el 19 de febrero. \u00a1Aqu\u00ed tienen un breve tr\u00e1iler para ir calentando motores!<\/p>\n\n\n\n<div style=\"height:18px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong>TLDR:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>00:11 El surgimiento de la perspectiva a partir de las realidades de la nube<\/li>\n\n\n\n<li>01:00 Donde ocurre la magia<\/li>\n\n\n\n<li>01:42 El impacto real en las personas, la cultura, la industria y la tecnolog\u00eda.<\/li>\n<\/ul>\n<div class=\"content-more\"><a class=\"more2\" aria-label=\"Escuchar link\" href=\"https:\/\/open.spotify.com\/episode\/5fqPZqZoQM8YcGRkkSM994\" target=\"_blank\" title=\"Opens in a new window\" rel=\"noopener noreferrer\">Escuchar<\/a><\/div><\/div><\/div><\/div><\/div>\n<\/div><\/div><\/div><\/div><\/section>\n\n\n\n<section class=\"wp-block-cg-blocks-group undefined section section--article-content\"><div class=\"article-main-content\"><div class=\"container\"><div class=\"grid-container\"><div><div class=\"article-text article-quote-text\">\n<h2 class=\"wp-block-heading\" id=\"h-explorar-temporadas-anteriores\">Explorar temporadas anteriores<\/h2>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading\" id=\"h-estacion-5\">Estaci\u00f3n 5<\/h3>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-septiembre-diciembre-2025\">Septiembre &#8211; Diciembre 2025<\/h4>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-outline is-style-outline--1\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/www.capgemini.com\/insights\/research-library\/cloud-realities-season-5\/\">Escucha aqu\u00ed<\/a><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading\" id=\"h-estacion-4\">Estaci\u00f3n 4<\/h3>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-septiembre-2024-agosto-2025\">Septiembre 2024 &#8211; Agosto 2025<\/h4>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-outline is-style-outline--2\"><a class=\"wp-block-button__link wp-element-button\" href=\"\/mx-es\/insights\/biblioteca-de-investigacion\/realidades-en-las-nubes-temporada-4\/\">Escucha aqu\u00ed<\/a><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading\" id=\"h-estacion-3-part-2\">Estaci\u00f3n 3 (part 2)<\/h3>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-enero-agosto-2024\">Enero &#8211; Agosto 2024<\/h4>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-outline is-style-outline--3\"><a class=\"wp-block-button__link wp-element-button\" href=\"\/mx-es\/insights\/biblioteca-de-investigacion\/realidades-en-las-nubes-temporada-3-2\/\">Escucha aqu\u00ed<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading\" id=\"h-estacion-3-part-1\">Estaci\u00f3n 3 (part 1)<\/h3>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-septiembre-diciembre-2023\">Septiembre &#8211; Diciembre 2023<\/h4>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-outline is-style-outline--4\"><a class=\"wp-block-button__link wp-element-button\" href=\"\/mx-es\/insights\/biblioteca-de-investigacion\/realidades-en-las-nubes-temporada-3\/\">Escucha aqu\u00ed<\/a><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading\" id=\"h-estacion-2\">Estaci\u00f3n 2<\/h3>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-enero-agosto-2023\">Enero &#8211; Agosto 2023<\/h4>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-outline is-style-outline--5\"><a class=\"wp-block-button__link wp-element-button\" href=\"\/mx-es\/insights\/biblioteca-de-investigacion\/cloud-realities-season-2\/\">Escucha aqu\u00ed<\/a><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading\" id=\"h-estacion-1\">Estaci\u00f3n 1<\/h3>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-noviembre-diciembre-2022\">Noviembre &#8211; Diciembre 2022<\/h4>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-outline is-style-outline--6\"><a class=\"wp-block-button__link wp-element-button\" href=\"\/mx-es\/insights\/biblioteca-de-investigacion\/realidades-en-las-nubes-temporada-1\/\">Escucha aqu\u00ed<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/section>\n\n\n\n<section class=\"wp-block-cg-blocks-group undefined section section--article-content\"><div class=\"article-main-content\"><div class=\"container\"><div class=\"grid-container\"><div><div class=\"article-text article-quote-text\">\n<h2 class=\"wp-block-heading\" id=\"h-creditos\">Cr\u00e9ditos<\/h2>\n\n\n\n<p>Adem\u00e1s de a los anfitriones, el agradecimiento se extiende tambi\u00e9n a <a href=\"https:\/\/www.linkedin.com\/in\/marcel-van-der-burg-99a655\/\" target=\"_blank\" rel=\"noreferrer noopener\">Marcel Van Der Burg <\/a>y <a href=\"https:\/\/www.linkedin.com\/in\/chapmandr\/\" target=\"_blank\" rel=\"noreferrer noopener\">Dave Chapman<\/a> por la producci\u00f3n, y a <a href=\"https:\/\/www.linkedin.com\/in\/ben-corbett-3b6a11135\/\" target=\"_blank\" rel=\"noreferrer noopener\">Ben Corbett<\/a> y <a href=\"https:\/\/www.linkedin.com\/in\/louis-corbett-087250264\/\" target=\"_blank\" rel=\"noreferrer noopener\">Louis Corbett<\/a> por el sonido.<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/section>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Podcast de realidades en la nube<\/p>\n","protected":false},"author":33,"featured_media":1000001198642,"template":"","meta":{"cg_dt_proposed_to":[9,25],"cg_seo_hreflang_relations":"[]","cg_seo_canonical_relation":"","cg_seo_hreflang_x_default_relation":"{\"uuid\":\"8d0bf31e-4f05-4f23-9758-505ac4fc9f9c\",\"blogId\":\"\",\"domain\":\"\",\"sitePath\":\"\",\"postLink\":\"\",\"postId\":null,\"isSaved\":true,\"isCrossLink\":false,\"hasCrossLink\":false}","cg_dt_approved_content":true,"cg_dt_mandatory_content":false,"cg_dt_notes":"","cg_dg_source_changed":true,"cg_dt_link_disabled":true,"footnotes":"","related_resource_url":"","related_resource_id":0,"related_resource_size":"","related_resource_type":"","cg_author":0,"_yoast_wpseo_primary_theme":61,"primary_term":"Cloud","featured_focal_points":""},"tags":[],"research-and-insight-type":[262,280],"theme":[61],"brand":[],"service":[197],"industry":[],"partners":[],"content-group":[],"class_list":["post-511893","research-and-insight","type-research-and-insight","status-publish","has-post-thumbnail","hentry","research-and-insight-type-podcast-episode","research-and-insight-type-podcast-series","theme-cloud","service-cloud"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.8 (Yoast SEO v22.8) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Podcast Realidades en la Nube: Perspectivas Cloud | Capgemini<\/title>\n<meta name=\"description\" content=\"Escucha el podcast Realidades en la Nube de Capgemini y explora tendencias, experiencias y aprendizajes clave sobre cloud y tecnolog\u00eda.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.capgemini.com\/mx-es\/insights\/biblioteca-de-investigacion\/podcast-de-realidades-en-la-nube\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Realidades remezcladas: la serie de podcasts\" \/>\n<meta property=\"og:description\" content=\"Escucha el podcast Realidades en la Nube de Capgemini y explora tendencias, experiencias y aprendizajes clave sobre cloud y tecnolog\u00eda.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.capgemini.com\/mx-es\/insights\/biblioteca-de-investigacion\/podcast-de-realidades-en-la-nube\/\" \/>\n<meta property=\"og:site_name\" content=\"Capgemini Mexico\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-27T13:19:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.capgemini.com\/mx-es\/wp-content\/uploads\/sites\/28\/2025\/10\/New-Web-preview-global.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"627\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"19 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.capgemini.com\/mx-es\/insights\/biblioteca-de-investigacion\/podcast-de-realidades-en-la-nube\/\",\"url\":\"https:\/\/www.capgemini.com\/mx-es\/insights\/biblioteca-de-investigacion\/podcast-de-realidades-en-la-nube\/\",\"name\":\"Podcast Realidades en la Nube: Perspectivas Cloud | Capgemini\",\"isPartOf\":{\"@id\":\"https:\/\/www.capgemini.com\/mx-es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.capgemini.com\/mx-es\/insights\/biblioteca-de-investigacion\/podcast-de-realidades-en-la-nube\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.capgemini.com\/mx-es\/insights\/biblioteca-de-investigacion\/podcast-de-realidades-en-la-nube\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2026\/02\/Realities-Remixed_Dotcom-banner_2880x1800px.jpg\",\"datePublished\":\"2025-02-25T02:00:24+00:00\",\"dateModified\":\"2026-04-27T13:19:02+00:00\",\"description\":\"Escucha el podcast Realidades en la Nube de Capgemini y explora tendencias, experiencias y aprendizajes clave sobre cloud y tecnolog\u00eda.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.capgemini.com\/mx-es\/insights\/biblioteca-de-investigacion\/podcast-de-realidades-en-la-nube\/#breadcrumb\"},\"inLanguage\":\"es-MX\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.capgemini.com\/mx-es\/insights\/biblioteca-de-investigacion\/podcast-de-realidades-en-la-nube\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-MX\",\"@id\":\"https:\/\/www.capgemini.com\/mx-es\/insights\/biblioteca-de-investigacion\/podcast-de-realidades-en-la-nube\/#primaryimage\",\"url\":\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2026\/02\/Realities-Remixed_Dotcom-banner_2880x1800px.jpg\",\"contentUrl\":\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2026\/02\/Realities-Remixed_Dotcom-banner_2880x1800px.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.capgemini.com\/mx-es\/insights\/biblioteca-de-investigacion\/podcast-de-realidades-en-la-nube\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.capgemini.com\/mx-es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Research &amp; insights\",\"item\":\"https:\/\/www.capgemini.com\/mx-es\/research-and-insight\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Realidades remezcladas: la serie de podcasts\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.capgemini.com\/mx-es\/#website\",\"url\":\"https:\/\/www.capgemini.com\/mx-es\/\",\"name\":\"Capgemini Mexico\",\"description\":\"Capgemini\",\"publisher\":{\"@id\":\"https:\/\/www.capgemini.com\/mx-es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.capgemini.com\/mx-es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es-MX\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.capgemini.com\/mx-es\/#organization\",\"name\":\"Capgemini Mexico\",\"url\":\"https:\/\/www.capgemini.com\/mx-es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-MX\",\"@id\":\"https:\/\/www.capgemini.com\/mx-es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.capgemini.com\/mx-es\/wp-content\/uploads\/sites\/28\/2025\/07\/linkedin_mwo0q6.png\",\"contentUrl\":\"https:\/\/www.capgemini.com\/mx-es\/wp-content\/uploads\/sites\/28\/2025\/07\/linkedin_mwo0q6.png\",\"width\":800,\"height\":800,\"caption\":\"Capgemini Mexico\"},\"image\":{\"@id\":\"https:\/\/www.capgemini.com\/mx-es\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Podcast Realidades en la Nube: Perspectivas Cloud | Capgemini","description":"Escucha el podcast Realidades en la Nube de Capgemini y explora tendencias, experiencias y aprendizajes clave sobre cloud y tecnolog\u00eda.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.capgemini.com\/mx-es\/insights\/biblioteca-de-investigacion\/podcast-de-realidades-en-la-nube\/","og_locale":"es_MX","og_type":"article","og_title":"Realidades remezcladas: la serie de podcasts","og_description":"Escucha el podcast Realidades en la Nube de Capgemini y explora tendencias, experiencias y aprendizajes clave sobre cloud y tecnolog\u00eda.","og_url":"https:\/\/www.capgemini.com\/mx-es\/insights\/biblioteca-de-investigacion\/podcast-de-realidades-en-la-nube\/","og_site_name":"Capgemini Mexico","article_modified_time":"2026-04-27T13:19:02+00:00","og_image":[{"width":1200,"height":627,"url":"https:\/\/www.capgemini.com\/mx-es\/wp-content\/uploads\/sites\/28\/2025\/10\/New-Web-preview-global.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"19 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.capgemini.com\/mx-es\/insights\/biblioteca-de-investigacion\/podcast-de-realidades-en-la-nube\/","url":"https:\/\/www.capgemini.com\/mx-es\/insights\/biblioteca-de-investigacion\/podcast-de-realidades-en-la-nube\/","name":"Podcast Realidades en la Nube: Perspectivas Cloud | Capgemini","isPartOf":{"@id":"https:\/\/www.capgemini.com\/mx-es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.capgemini.com\/mx-es\/insights\/biblioteca-de-investigacion\/podcast-de-realidades-en-la-nube\/#primaryimage"},"image":{"@id":"https:\/\/www.capgemini.com\/mx-es\/insights\/biblioteca-de-investigacion\/podcast-de-realidades-en-la-nube\/#primaryimage"},"thumbnailUrl":"https:\/\/www.capgemini.com\/wp-content\/uploads\/2026\/02\/Realities-Remixed_Dotcom-banner_2880x1800px.jpg","datePublished":"2025-02-25T02:00:24+00:00","dateModified":"2026-04-27T13:19:02+00:00","description":"Escucha el podcast Realidades en la Nube de Capgemini y explora tendencias, experiencias y aprendizajes clave sobre cloud y tecnolog\u00eda.","breadcrumb":{"@id":"https:\/\/www.capgemini.com\/mx-es\/insights\/biblioteca-de-investigacion\/podcast-de-realidades-en-la-nube\/#breadcrumb"},"inLanguage":"es-MX","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.capgemini.com\/mx-es\/insights\/biblioteca-de-investigacion\/podcast-de-realidades-en-la-nube\/"]}]},{"@type":"ImageObject","inLanguage":"es-MX","@id":"https:\/\/www.capgemini.com\/mx-es\/insights\/biblioteca-de-investigacion\/podcast-de-realidades-en-la-nube\/#primaryimage","url":"https:\/\/www.capgemini.com\/wp-content\/uploads\/2026\/02\/Realities-Remixed_Dotcom-banner_2880x1800px.jpg","contentUrl":"https:\/\/www.capgemini.com\/wp-content\/uploads\/2026\/02\/Realities-Remixed_Dotcom-banner_2880x1800px.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.capgemini.com\/mx-es\/insights\/biblioteca-de-investigacion\/podcast-de-realidades-en-la-nube\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.capgemini.com\/mx-es\/"},{"@type":"ListItem","position":2,"name":"Research &amp; insights","item":"https:\/\/www.capgemini.com\/mx-es\/research-and-insight\/"},{"@type":"ListItem","position":3,"name":"Realidades remezcladas: la serie de podcasts"}]},{"@type":"WebSite","@id":"https:\/\/www.capgemini.com\/mx-es\/#website","url":"https:\/\/www.capgemini.com\/mx-es\/","name":"Capgemini Mexico","description":"Capgemini","publisher":{"@id":"https:\/\/www.capgemini.com\/mx-es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.capgemini.com\/mx-es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es-MX"},{"@type":"Organization","@id":"https:\/\/www.capgemini.com\/mx-es\/#organization","name":"Capgemini Mexico","url":"https:\/\/www.capgemini.com\/mx-es\/","logo":{"@type":"ImageObject","inLanguage":"es-MX","@id":"https:\/\/www.capgemini.com\/mx-es\/#\/schema\/logo\/image\/","url":"https:\/\/www.capgemini.com\/mx-es\/wp-content\/uploads\/sites\/28\/2025\/07\/linkedin_mwo0q6.png","contentUrl":"https:\/\/www.capgemini.com\/mx-es\/wp-content\/uploads\/sites\/28\/2025\/07\/linkedin_mwo0q6.png","width":800,"height":800,"caption":"Capgemini Mexico"},"image":{"@id":"https:\/\/www.capgemini.com\/mx-es\/#\/schema\/logo\/image\/"}}]}},"theme_term_info":[{"id":61,"name":"Cloud"}],"industry_term_info":[],"services_term_info":[{"id":197,"name":"Cloud"}],"partners_term_info":[],"brand_term_info":[],"brand_term":[],"parsely":{"version":"1.1.0","canonical_url":"https:\/\/capgemini.com\/mx-es\/insights\/biblioteca-de-investigacion\/podcast-de-realidades-en-la-nube\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Realidades remezcladas: la serie de podcasts","url":"https:\/\/www.capgemini.com\/mx-es\/insights\/biblioteca-de-investigacion\/podcast-de-realidades-en-la-nube\/","mainEntityOfPage":{"@type":"WebPage","@id":"https:\/\/www.capgemini.com\/mx-es\/insights\/biblioteca-de-investigacion\/podcast-de-realidades-en-la-nube\/"},"thumbnailUrl":"https:\/\/www.capgemini.com\/wp-content\/uploads\/2026\/02\/Realities-Remixed_Dotcom-banner_2880x1800px.jpg?w=150&h=150&crop=1","image":{"@type":"ImageObject","url":"https:\/\/www.capgemini.com\/wp-content\/uploads\/2026\/02\/Realities-Remixed_Dotcom-banner_2880x1800px.jpg"},"articleSection":"Uncategorized","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Capgemini Mexico","logo":""},"keywords":[],"dateCreated":"2025-02-25T02:00:24Z","datePublished":"2025-02-25T02:00:24Z","dateModified":"2026-04-27T13:19:02Z"},"rendered":"<meta name=\"parsely-title\" content=\"Realidades remezcladas: la serie de podcasts\" \/>\n<meta name=\"parsely-link\" content=\"https:\/\/www.capgemini.com\/mx-es\/insights\/biblioteca-de-investigacion\/podcast-de-realidades-en-la-nube\/\" \/>\n<meta name=\"parsely-type\" content=\"post\" \/>\n<meta name=\"parsely-image-url\" content=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2026\/02\/Realities-Remixed_Dotcom-banner_2880x1800px.jpg?w=150&amp;h=150&amp;crop=1\" \/>\n<meta name=\"parsely-pub-date\" content=\"2025-02-25T02:00:24Z\" \/>\n<meta name=\"parsely-section\" content=\"Uncategorized\" \/>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/capgemini.com\/p.js"},"archive_status":false,"featured_image_src":"https:\/\/www.capgemini.com\/wp-content\/uploads\/2026\/02\/Realities-Remixed_Dotcom-banner_2880x1800px.jpg","featured_image_alt":"","jetpack_sharing_enabled":true,"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"Capgemini Mexico","distributor_original_site_url":"https:\/\/www.capgemini.com\/mx-es","push-errors":false,"tag_names":[],"featured_image_url":"https:\/\/www.capgemini.com\/wp-content\/uploads\/2026\/02\/Realities-Remixed_Dotcom-banner_2880x1800px.jpg","_links":{"self":[{"href":"https:\/\/www.capgemini.com\/mx-es\/wp-json\/wp\/v2\/research-and-insight\/511893","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.capgemini.com\/mx-es\/wp-json\/wp\/v2\/research-and-insight"}],"about":[{"href":"https:\/\/www.capgemini.com\/mx-es\/wp-json\/wp\/v2\/types\/research-and-insight"}],"author":[{"embeddable":true,"href":"https:\/\/www.capgemini.com\/mx-es\/wp-json\/wp\/v2\/users\/33"}],"version-history":[{"count":19,"href":"https:\/\/www.capgemini.com\/mx-es\/wp-json\/wp\/v2\/research-and-insight\/511893\/revisions"}],"predecessor-version":[{"id":563493,"href":"https:\/\/www.capgemini.com\/mx-es\/wp-json\/wp\/v2\/research-and-insight\/511893\/revisions\/563493"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.capgemini.com\/mx-es\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.capgemini.com\/mx-es\/wp-json\/wp\/v2\/media?parent=511893"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.capgemini.com\/mx-es\/wp-json\/wp\/v2\/tags?post=511893"},{"taxonomy":"research-and-insight-type","embeddable":true,"href":"https:\/\/www.capgemini.com\/mx-es\/wp-json\/wp\/v2\/research-and-insight-type?post=511893"},{"taxonomy":"theme","embeddable":true,"href":"https:\/\/www.capgemini.com\/mx-es\/wp-json\/wp\/v2\/theme?post=511893"},{"taxonomy":"brand","embeddable":true,"href":"https:\/\/www.capgemini.com\/mx-es\/wp-json\/wp\/v2\/brand?post=511893"},{"taxonomy":"service","embeddable":true,"href":"https:\/\/www.capgemini.com\/mx-es\/wp-json\/wp\/v2\/service?post=511893"},{"taxonomy":"industry","embeddable":true,"href":"https:\/\/www.capgemini.com\/mx-es\/wp-json\/wp\/v2\/industry?post=511893"},{"taxonomy":"partners","embeddable":true,"href":"https:\/\/www.capgemini.com\/mx-es\/wp-json\/wp\/v2\/partners?post=511893"},{"taxonomy":"content-group","embeddable":true,"href":"https:\/\/www.capgemini.com\/mx-es\/wp-json\/wp\/v2\/content-group?post=511893"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}