{"id":567356,"date":"2026-09-01T15:33:10","date_gmt":"2026-09-01T15:33:10","guid":{"rendered":"https:\/\/www.capgemini.com\/mx-es\/?post_type=analyst-report&#038;p=567356"},"modified":"2026-09-01T15:41:54","modified_gmt":"2026-09-01T15:41:54","slug":"capgemini-lider-en-idc-marketscape-2025-para-servicios-de-ia-en-defensa-e-inteligencia-de-ee-uu","status":"publish","type":"analyst-report","link":"https:\/\/www.capgemini.com\/mx-es\/news\/reconocimiento-analistas\/capgemini-lider-en-idc-marketscape-2025-para-servicios-de-ia-en-defensa-e-inteligencia-de-ee-uu\/","title":{"rendered":"Capgemini, reconocida como l\u00edder en el informe de evaluaci\u00f3n de proveedores IDC MarketScape: Servicios de IA para agencias de defensa e inteligencia de EE. UU. (2025)"},"content":{"rendered":"\t\t<div class=\"wp-block-cg-blocks-hero-press-release\">\n\t\t\t<header class=\"header-hero-press-release\" role=\"main\" id=\"main-content-press-release\">\n\t\t\t\t<div class=\"container\">\n\t\t\t\t\t<div class=\"hero-press-release\">\n\t\t\t\t\t\t<div class=\"hero-press-release-content-wrapper\">\n\t\t\t\t\t\t\t<div class=\"row\">\n\t\t\t\t\t\t\t\t<div class=\"col-12\">\n\t\t\t\t\t\t\t\t\t<div class=\"header-title\">\n\t\t\t\t\t\t\t\t\t\t<h1>\n\t\t\t\t\t\t\t\t\t\t\tCapgemini, reconocida como l\u00edder en el informe de evaluaci\u00f3n de proveedores IDC MarketScape: Servicios de IA para agencias de defensa e inteligencia de EE. UU. (2025)\t\t\t\t\t\t\t\t\t\t<\/h1>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"header-description\">\n\t\t\t\t\t\t\t\t\t\t<p><\/p>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"header-date\">\n\t\t\t\t\t\t\t\t\t\t<span>sep. 1, 2026<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/header>\n\t\t<\/div>\n\t\t\n\n\n<section class=\"wp-block-cg-blocks-group undefined section section--article-content\"><div class=\"article-main-content\"><div class=\"container\"><div class=\"grid-container\"><div class=\"col-12 col-md-2\"><nav class=\"article-social\"><ul class=\"social-nav\"><li class=\"ip-order-fb\"><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https:\/\/www.capgemini.com\/?post_type=analyst-report&amp;p=994076\" target=\"_blank\" rel=\"noopener noreferrer\" title=\"Abrir en una nueva ventana\"><i aria-hidden=\"true\" class=\"icon-fb\"><\/i><span class=\"sr-only\">Facebook<\/span><\/a><\/li><li class=\"ip-order-tw\"><a href=\"https:\/\/twitter.com\/intent\/tweet?url=https:\/\/www.capgemini.com\/?post_type=analyst-report&amp;p=994076&amp;text=Capgemini%20named%20a%20%E2%80%98LEADER%E2%80%99%20in%20Worldwide%20ESG%20Program%20Management%20Services\" target=\"_blank\" rel=\"noopener noreferrer\" title=\"Abrir en una nueva ventana\"><i aria-hidden=\"true\" class=\"icon-tw\"><\/i><span class=\"sr-only\">Twitter<\/span><\/a><\/li><li class=\"ip-order-li\"><a href=\"https:\/\/www.linkedin.com\/shareArticle?url=https:\/\/www.capgemini.com\/?post_type=analyst-report&amp;p=994076&amp;text=Capgemini%20named%20a%20%E2%80%98LEADER%E2%80%99%20in%20Worldwide%20ESG%20Program%20Management%20Services\" target=\"_blank\" rel=\"noopener noreferrer\" title=\"Abrir en una nueva ventana\"><i aria-hidden=\"true\" class=\"icon-li\"><\/i><span class=\"sr-only\">Linkedin<\/span><\/a><\/li><\/ul><\/nav><\/div><div><div class=\"article-text article-quote-text\">\n<h2 id=\"h-idc-marketscape-ha-posicionado-a-capgemini-como-lider-en-este-informe-inaugural-de-evaluacion-de-proveedores-de-servicios-de-ia-para-agencias-de-defensa-e-inteligencia-de-ee-uu-2025\" class=\"wp-block-heading\">IDC MarketScape ha posicionado a Capgemini como l\u00edder en este informe inaugural de evaluaci\u00f3n de proveedores de servicios de IA para agencias de defensa e inteligencia de EE. UU. (2025).<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La inteligencia artificial (IA) est\u00e1 transformando la forma en que se realiza el trabajo, la naturaleza y estructura de las organizaciones militares y de seguridad nacional, as\u00ed como el campo de batalla. Para obtener valor organizacional de la IA, las empresas deben comprender tanto la tecnolog\u00eda como la misi\u00f3n. Este estudio IDC MarketScape eval\u00faa a los proveedores del mercado de servicios de IA para la defensa y la inteligencia de EE. UU. en 2025, utilizando el modelo IDC MarketScape; su objetivo es ayudar a los funcionarios de contrataci\u00f3n, a los representantes t\u00e9cnicos de la autoridad contratante (COTR) y a los profesionales de adquisiciones a identificar las empresas de servicios capaces de comprender tanto la tecnolog\u00eda como la misi\u00f3n.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan el informe: \u00abLa base de ingresos y la plantilla global de 341.100 empleados de Capgemini brindan acceso a investigaciones de vanguardia en IA a trav\u00e9s de centros de innovaci\u00f3n especializados, asociaciones de computaci\u00f3n cu\u00e1ntica con DARPA y el desarrollo de soluciones 5G avanzadas, lo que permite a las agencias federales aprovechar la innovaci\u00f3n comercial a gran escala para aplicaciones de defensa\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Consideramos que Capgemini Government Solutions ha demostrado su solidez en la modernizaci\u00f3n de entornos en la nube y la integraci\u00f3n de IA. Capgemini cuenta con la capacidad de modernizar entornos militares en la nube mediante la integraci\u00f3n de IA y aprendizaje autom\u00e1tico (ML); asimismo, el Acuerdo Marco de Compra (BPA) para Pruebas y Evaluaci\u00f3n del Centro Conjunto de Inteligencia Artificial (JAIC) posiciona a la empresa para desarrollar prototipos y probar soluciones de IA en diversas misiones del Departamento de Defensa, aplicando marcos de seguridad en la nube.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Capgemini Government Solutions mantiene un s\u00f3lido ecosistema de alianzas tecnol\u00f3gicas estrat\u00e9gicas con l\u00edderes clave del sector, como Google, Microsoft, Amazon Web Services y Salesforce. Esto, sumado a las capacidades mejoradas de ciberseguridad federal y servicios en la nube adquiridas a trav\u00e9s de VariQ, garantiza el acceso a soluciones de IA de vanguardia para iniciativas de modernizaci\u00f3n de la defensa, al tiempo que mitiga estrat\u00e9gicamente los riesgos asociados a la dependencia de un \u00fanico proveedor (<em>vendor lock-in<\/em>).<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Desde el aprovechamiento de su escala global y de los esfuerzos de I+D en computaci\u00f3n cu\u00e1ntica junto a DARPA, hasta la integraci\u00f3n de un ecosistema flexible de socios comerciales de primer nivel, Capgemini est\u00e1 bien posicionada para apoyar la modernizaci\u00f3n de la defensa. Su capacidad para integrar de forma segura entornos en la nube y desarrollar prototipos de soluciones de IA garantiza que las agencias de defensa e inteligencia puedan aprovechar la innovaci\u00f3n comercial de manera eficiente.<\/p>\n<cite>Alan Webber, vicepresidente de programas de Seguridad Nacional, Defensa e Inteligencia (D&amp;I), IDC Research<\/cite><\/blockquote>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">La fortaleza de Capgemini se fundamenta en nuestro s\u00f3lido y estrat\u00e9gico ecosistema de alianzas tecnol\u00f3gicas. Al mantener relaciones estrechas con gigantes del sector como Google, Microsoft, AWS y Salesforce, e integrar la experiencia especializada en el \u00e1mbito federal derivada de la adquisici\u00f3n de VariQ, garantizamos a nuestros clientes el acceso a una selecci\u00f3n de tecnolog\u00edas de IA l\u00edderes en su clase; esto aporta la flexibilidad necesaria para las iniciativas de modernizaci\u00f3n de la defensa, al tiempo que mitiga estrat\u00e9gicamente la dependencia de un \u00fanico proveedor.<\/p>\n<cite><em>Daniel Ford, director ejecutivo de Capgemini Government Solutions<\/em><\/cite><\/blockquote>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-d9a36c2f wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button has-custom-width wp-block-button__width-50\"><a class=\"wp-block-button__link has-text-align-center wp-element-button\" href=\"https:\/\/idcdocserv.com\/US53685225e_Capgemini\" target=\"_blank\" rel=\"noreferrer noopener\">Haz clic aqu\u00ed para leer el fragmento.<\/a><\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Acerca de IDC MarketScape<br><\/strong>El modelo de evaluaci\u00f3n de proveedores IDC MarketScape est\u00e1 dise\u00f1ado para ofrecer una visi\u00f3n general de la competitividad de los proveedores de tecnolog\u00eda y servicios en un mercado determinado. El estudio emplea una metodolog\u00eda de puntuaci\u00f3n rigurosa, basada en criterios tanto cualitativos como cuantitativos, que da lugar a una representaci\u00f3n gr\u00e1fica \u00fanica de la posici\u00f3n de cada proveedor en dicho mercado. IDC MarketScape proporciona un marco claro que permite comparar de manera significativa la oferta de productos y servicios, las capacidades y estrategias, as\u00ed como los factores de \u00e9xito actuales y futuros en el mercado de los proveedores de tecnolog\u00eda. Asimismo, este marco ofrece a los compradores de tecnolog\u00eda una evaluaci\u00f3n integral (de 360 \u200b\u200bgrados) de las fortalezas y debilidades de los proveedores actuales y potenciales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Sobre Capgemini<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Capgemini es un socio global de transformaci\u00f3n empresarial y tecnol\u00f3gica impulsado por la IA, que aporta un valor empresarial tangible. Imaginamos el futuro de las organizaciones y lo hacemos realidad gracias a la IA, la tecnolog\u00eda y las personas. Con una s\u00f3lida trayectoria de casi 60 a\u00f1os, somos un grupo responsable y diverso de 420.000 profesionales en m\u00e1s de 50 pa\u00edses. Ofrecemos servicios y soluciones integrales respaldados por nuestra profunda experiencia sectorial y un s\u00f3lido ecosistema de socios, aprovechando nuestras capacidades en estrategia, tecnolog\u00eda, dise\u00f1o, ingenier\u00eda y operaciones empresariales. El Grupo registr\u00f3 unos ingresos globales de 22.100 millones de euros en 2024.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Make it real |&nbsp;<a href=\"http:\/\/www.capgemini.com\/#_blank\"><\/a><a href=\"https:\/\/www.capgemini-gs.com\/\">www.capgemini-gs.com<\/a><\/p>\n<\/div><\/div><\/div><\/div><\/div><\/section>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":291,"featured_media":0,"template":"","meta":{"cg_dt_proposed_to":[25],"cg_seo_hreflang_relations":"[]","cg_seo_canonical_relation":"","cg_seo_hreflang_x_default_relation":"","cg_dt_approved_content":true,"cg_dt_mandatory_content":false,"cg_dt_notes":"","cg_dg_source_changed":false,"cg_dt_link_disabled":true,"footnotes":"","featured_focal_points":""},"brand":[],"service":[],"industry":[],"partners":[],"analyst":[24],"content-group":[],"class_list":["post-567356","analyst-report","type-analyst-report","status-publish","hentry","analyst-idc"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.7 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>L\u00edder en IA para Defensa e Inteligencia | Capgemini<\/title>\n<meta name=\"description\" content=\"Descubra por qu\u00e9 Capgemini fue reconocida como l\u00edder por IDC MarketScape en servicios de IA para defensa e inteligencia de EE. UU.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.capgemini.com\/mx-es\/news\/reconocimiento-analistas\/capgemini-lider-en-idc-marketscape-2025-para-servicios-de-ia-en-defensa-e-inteligencia-de-ee-uu\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Capgemini, reconocida como l\u00edder en el informe de evaluaci\u00f3n de proveedores IDC MarketScape: Servicios de IA para agencias de defensa e inteligencia de EE. UU. (2025)\" \/>\n<meta property=\"og:description\" content=\"Descubra por qu\u00e9 Capgemini fue reconocida como l\u00edder por IDC MarketScape en servicios de IA para defensa e inteligencia de EE. UU.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.capgemini.com\/mx-es\/news\/reconocimiento-analistas\/capgemini-lider-en-idc-marketscape-2025-para-servicios-de-ia-en-defensa-e-inteligencia-de-ee-uu\/\" \/>\n<meta property=\"og:site_name\" content=\"Capgemini Mexico\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-01T15:41:54+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.capgemini.com\\\/mx-es\\\/news\\\/reconocimiento-analistas\\\/capgemini-lider-en-idc-marketscape-2025-para-servicios-de-ia-en-defensa-e-inteligencia-de-ee-uu\\\/\",\"url\":\"https:\\\/\\\/www.capgemini.com\\\/mx-es\\\/news\\\/reconocimiento-analistas\\\/capgemini-lider-en-idc-marketscape-2025-para-servicios-de-ia-en-defensa-e-inteligencia-de-ee-uu\\\/\",\"name\":\"L\u00edder en IA para Defensa e Inteligencia | Capgemini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.capgemini.com\\\/mx-es\\\/#website\"},\"datePublished\":\"2026-09-01T15:33:10+00:00\",\"dateModified\":\"2026-09-01T15:41:54+00:00\",\"description\":\"Descubra por qu\u00e9 Capgemini fue reconocida como l\u00edder por IDC MarketScape en servicios de IA para defensa e inteligencia de EE. UU.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.capgemini.com\\\/mx-es\\\/news\\\/reconocimiento-analistas\\\/capgemini-lider-en-idc-marketscape-2025-para-servicios-de-ia-en-defensa-e-inteligencia-de-ee-uu\\\/#breadcrumb\"},\"inLanguage\":\"es-MX\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.capgemini.com\\\/mx-es\\\/news\\\/reconocimiento-analistas\\\/capgemini-lider-en-idc-marketscape-2025-para-servicios-de-ia-en-defensa-e-inteligencia-de-ee-uu\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.capgemini.com\\\/mx-es\\\/news\\\/reconocimiento-analistas\\\/capgemini-lider-en-idc-marketscape-2025-para-servicios-de-ia-en-defensa-e-inteligencia-de-ee-uu\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.capgemini.com\\\/mx-es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Capgemini, reconocida como l\u00edder en el informe de evaluaci\u00f3n de proveedores IDC MarketScape: Servicios de IA para agencias de defensa e inteligencia de EE. UU. (2025)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.capgemini.com\\\/mx-es\\\/#website\",\"url\":\"https:\\\/\\\/www.capgemini.com\\\/mx-es\\\/\",\"name\":\"Capgemini Mexico\",\"description\":\"Capgemini\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.capgemini.com\\\/mx-es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-MX\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"L\u00edder en IA para Defensa e Inteligencia | Capgemini","description":"Descubra por qu\u00e9 Capgemini fue reconocida como l\u00edder por IDC MarketScape en servicios de IA para defensa e inteligencia de EE. UU.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.capgemini.com\/mx-es\/news\/reconocimiento-analistas\/capgemini-lider-en-idc-marketscape-2025-para-servicios-de-ia-en-defensa-e-inteligencia-de-ee-uu\/","og_locale":"es_MX","og_type":"article","og_title":"Capgemini, reconocida como l\u00edder en el informe de evaluaci\u00f3n de proveedores IDC MarketScape: Servicios de IA para agencias de defensa e inteligencia de EE. UU. (2025)","og_description":"Descubra por qu\u00e9 Capgemini fue reconocida como l\u00edder por IDC MarketScape en servicios de IA para defensa e inteligencia de EE. UU.","og_url":"https:\/\/www.capgemini.com\/mx-es\/news\/reconocimiento-analistas\/capgemini-lider-en-idc-marketscape-2025-para-servicios-de-ia-en-defensa-e-inteligencia-de-ee-uu\/","og_site_name":"Capgemini Mexico","article_modified_time":"2026-09-01T15:41:54+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.capgemini.com\/mx-es\/news\/reconocimiento-analistas\/capgemini-lider-en-idc-marketscape-2025-para-servicios-de-ia-en-defensa-e-inteligencia-de-ee-uu\/","url":"https:\/\/www.capgemini.com\/mx-es\/news\/reconocimiento-analistas\/capgemini-lider-en-idc-marketscape-2025-para-servicios-de-ia-en-defensa-e-inteligencia-de-ee-uu\/","name":"L\u00edder en IA para Defensa e Inteligencia | Capgemini","isPartOf":{"@id":"https:\/\/www.capgemini.com\/mx-es\/#website"},"datePublished":"2026-09-01T15:33:10+00:00","dateModified":"2026-09-01T15:41:54+00:00","description":"Descubra por qu\u00e9 Capgemini fue reconocida como l\u00edder por IDC MarketScape en servicios de IA para defensa e inteligencia de EE. UU.","breadcrumb":{"@id":"https:\/\/www.capgemini.com\/mx-es\/news\/reconocimiento-analistas\/capgemini-lider-en-idc-marketscape-2025-para-servicios-de-ia-en-defensa-e-inteligencia-de-ee-uu\/#breadcrumb"},"inLanguage":"es-MX","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.capgemini.com\/mx-es\/news\/reconocimiento-analistas\/capgemini-lider-en-idc-marketscape-2025-para-servicios-de-ia-en-defensa-e-inteligencia-de-ee-uu\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.capgemini.com\/mx-es\/news\/reconocimiento-analistas\/capgemini-lider-en-idc-marketscape-2025-para-servicios-de-ia-en-defensa-e-inteligencia-de-ee-uu\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.capgemini.com\/mx-es\/"},{"@type":"ListItem","position":2,"name":"Capgemini, reconocida como l\u00edder en el informe de evaluaci\u00f3n de proveedores IDC MarketScape: Servicios de IA para agencias de defensa e inteligencia de EE. UU. (2025)"}]},{"@type":"WebSite","@id":"https:\/\/www.capgemini.com\/mx-es\/#website","url":"https:\/\/www.capgemini.com\/mx-es\/","name":"Capgemini Mexico","description":"Capgemini","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.capgemini.com\/mx-es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-MX"}]}},"archive_status":false,"featured_image_src":"https:\/\/www.capgemini.com\/mx-es\/wp-content\/themes\/capgemini2025\/assets\/images\/mockup.png","featured_image_alt":false,"jetpack_sharing_enabled":true,"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"Capgemini Mexico","distributor_original_site_url":"https:\/\/www.capgemini.com\/mx-es","push-errors":false,"_links":{"self":[{"href":"https:\/\/www.capgemini.com\/mx-es\/wp-json\/wp\/v2\/analyst-report\/567356","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.capgemini.com\/mx-es\/wp-json\/wp\/v2\/analyst-report"}],"about":[{"href":"https:\/\/www.capgemini.com\/mx-es\/wp-json\/wp\/v2\/types\/analyst-report"}],"author":[{"embeddable":true,"href":"https:\/\/www.capgemini.com\/mx-es\/wp-json\/wp\/v2\/users\/291"}],"version-history":[{"count":1,"href":"https:\/\/www.capgemini.com\/mx-es\/wp-json\/wp\/v2\/analyst-report\/567356\/revisions"}],"predecessor-version":[{"id":567358,"href":"https:\/\/www.capgemini.com\/mx-es\/wp-json\/wp\/v2\/analyst-report\/567356\/revisions\/567358"}],"wp:attachment":[{"href":"https:\/\/www.capgemini.com\/mx-es\/wp-json\/wp\/v2\/media?parent=567356"}],"wp:term":[{"taxonomy":"brand","embeddable":true,"href":"https:\/\/www.capgemini.com\/mx-es\/wp-json\/wp\/v2\/brand?post=567356"},{"taxonomy":"service","embeddable":true,"href":"https:\/\/www.capgemini.com\/mx-es\/wp-json\/wp\/v2\/service?post=567356"},{"taxonomy":"industry","embeddable":true,"href":"https:\/\/www.capgemini.com\/mx-es\/wp-json\/wp\/v2\/industry?post=567356"},{"taxonomy":"partners","embeddable":true,"href":"https:\/\/www.capgemini.com\/mx-es\/wp-json\/wp\/v2\/partners?post=567356"},{"taxonomy":"analyst","embeddable":true,"href":"https:\/\/www.capgemini.com\/mx-es\/wp-json\/wp\/v2\/analyst?post=567356"},{"taxonomy":"content-group","embeddable":true,"href":"https:\/\/www.capgemini.com\/mx-es\/wp-json\/wp\/v2\/content-group?post=567356"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}