{"id":67,"date":"2022-10-27T06:49:00","date_gmt":"2022-10-27T06:49:00","guid":{"rendered":"https:\/\/www.capgemini.com\/it-it\/?post_type=press-release&#038;p=67"},"modified":"2026-01-20T15:41:50","modified_gmt":"2026-01-20T15:41:50","slug":"il-settore-automotive-riuscira-a-raggiungere-gli-obiettivi-di-sostenibilita-prefissati","status":"publish","type":"press-release","link":"https:\/\/www.capgemini.com\/it-it\/news\/comunicati-stampa\/il-settore-automotive-riuscira-a-raggiungere-gli-obiettivi-di-sostenibilita-prefissati\/","title":{"rendered":"Il settore automotive riuscir\u00e0 a raggiungere gli obiettivi di sostenibilit\u00e0 prefissati?"},"content":{"rendered":"\n<p><\/p>\n\n\n\t\t<div class=\"wp-block-cg-blocks-hero-press-release\">\n\t\t\t<header class=\"header-hero-press-release\" role=\"main\" id=\"main-content-press-release\">\n\t\t\t\t<div class=\"container\">\n\t\t\t\t\t<div class=\"hero-press-release\">\n\t\t\t\t\t\t<div class=\"hero-press-release-content-wrapper\">\n\t\t\t\t\t\t\t<div class=\"row\">\n\t\t\t\t\t\t\t\t<div class=\"col-12\">\n\t\t\t\t\t\t\t\t\t<div class=\"header-title\">\n\t\t\t\t\t\t\t\t\t\t<h1>\n\t\t\t\t\t\t\t\t\t\t\tIl settore automotive riuscir\u00e0 a raggiungere gli obiettivi di sostenibilit\u00e0 prefissati?\t\t\t\t\t\t\t\t\t\t<\/h1>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"header-description\">\n\t\t\t\t\t\t\t\t\t\t<p><\/p>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"header-date\">\n\t\t\t\t\t\t\t\t\t\t<span>ott 27, 2022<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"hero-press-release-downloads\">\n\t\t\t\t\t\t\t\t<div class=\"row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-12 col-md-6 col-lg-3\">\n\t\t\t\t\t\t\t\t\t\t\t<a class=\"download-item\" type=\"download\" href=\"https:\/\/www.capgemini.com\/it-it\/wp-content\/uploads\/sites\/15\/2023\/01\/2022_10_27_Capgemini_Sustainability-in-Automotive_Report_ITA.pdf\" target=\"_blank\" rel=\"noopener noreferrer\" title=\"Si apre in una nuova finestra\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"download-icon\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"download-details\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"download-title\">Download press release<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"download-props\">227 KB  pdf<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-12 col-md-6 col-lg-3\">\n\t\t\t\t\t\t\t\t\t\t\t<a class=\"download-item\" type=\"download\" href=\"https:\/\/www.capgemini.com\/it-it\/wp-content\/uploads\/sites\/15\/2023\/01\/Final-Infographic.pdf\" target=\"_blank\" rel=\"noopener noreferrer\" title=\"Si apre in una nuova finestra\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"download-icon\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"download-details\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"download-title\">Download press release<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"download-props\">713 KB  pdf<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/header>\n\t\t<\/div>\n\t\t\n\n\n<section class=\"wp-block-cg-blocks-group undefined section section--article-content\"><div class=\"article-main-content\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-md-1\"><nav class=\"article-social\"><ul class=\"social-nav\"><li class=\"ip-order-fb\"><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https:\/\/www.capgemini.com\/it-it\/?post_type=press-release&amp;p=67\" target=\"_blank\" rel=\"noopener noreferrer\" title=\"si apre in una nuova finestra\"><i aria-hidden=\"true\" class=\"icon-fb\"><\/i><span class=\"sr-only\">Facebook<\/span><\/a><\/li><li class=\"ip-order-tw\"><a href=\"https:\/\/twitter.com\/intent\/tweet?url=https:\/\/www.capgemini.com\/it-it\/?post_type=press-release&amp;p=67&amp;text=\" target=\"_blank\" rel=\"noopener noreferrer\" title=\"si apre in una nuova finestra\"><i aria-hidden=\"true\" class=\"icon-tw\"><\/i><span class=\"sr-only\">Twitter<\/span><\/a><\/li><li class=\"ip-order-li\"><a href=\"https:\/\/www.linkedin.com\/sharing\/share-offsite\/?url=https:\/\/www.capgemini.com\/it-it\/?post_type=press-release&amp;p=67&amp;text=\" target=\"_blank\" rel=\"noopener noreferrer\" title=\"si apre in una nuova finestra\"><i aria-hidden=\"true\" class=\"icon-li\"><\/i><span class=\"sr-only\">Linkedin<\/span><\/a><\/li><\/ul><\/nav><\/div><div class=\"col-12 col-md-11 col-lg-10\"><div class=\"article-text article-quote-text\">\n<p><em>Un nuovo report di Capgemini rileva che:<\/em><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><em>L\u2019attuale livello di maturit\u00e0 delle iniziative in tutto il settore non \u00e8 sufficiente a ridurre le emissioni in maniera significativa e raggiungere gli obiettivi dell\u2019Accordo di Parigi.<\/em><\/li>\n\n\n\n<li><em>Gli investimenti<a href=\"#_ftn1\" id=\"_ftnref1\"><strong>[1]<\/strong><\/a> in iniziative sostenibili sono in calo \u2013 da una media dell\u20191,22% dei ricavi annuali del 2019 allo 0,85% nel 2022 \u2013 e si stima che entro il 2026 il livello rimarr\u00e0 sempre intorno allo 0,86%.<\/em><\/li>\n\n\n\n<li><em>I supplier stanno investendo una quota maggiore dei ricavi (0,93%) in iniziative annuali di sostenibilit\u00e0 rispetto alle controparti OEM (0,79%).<\/em><\/li>\n\n\n\n<li><em>Un piccolo gruppo di organizzazioni con alti livelli di implementazione delle principali iniziative di sostenibilit\u00e0 ha gi\u00e0 ottenuto un miglioramento medio del 9% delle proprie emissioni a partire dal 2018, rispetto al 5% dell\u2019intero settore.<\/em><\/li>\n<\/ul>\n\n\n\n<p><strong>Milano, 27 ottobre 2022 \u2013 I livelli di attuazione delle principali iniziative di sostenibilit\u00e0<\/strong><a href=\"#_ftn2\" id=\"_ftnref2\"><strong>[2]<\/strong><\/a> <strong>sono cresciuti solo marginalmente, e in alcune aree sono addirittura diminuiti <\/strong><a href=\"https:\/\/www.capgemini.com\/insights\/research-library\/sustainability-in-automotive\/\"><strong>rispetto al 2019<\/strong><\/a><strong>. \u00c8 quanto emerge dall\u2019ultimo report del Capgemini Research Institute, dal titolo \u201c<\/strong><a href=\"https:\/\/bit.ly\/3yz8KUL\"><strong><em>Sustainability in Automotive: From Ambition to Action<\/em><\/strong><\/a><strong>\u201d<\/strong><strong>. Le sfide recenti, come la scarsit\u00e0 di chip e i colli di bottiglia della catena di approvvigionamento, hanno costretto le organizzazioni del settore automotive a ridefinire le proprie priorit\u00e0.<\/strong><\/p>\n\n\n\n<p>Secondo la ricerca, alcune direttive come il <a href=\"https:\/\/ec.europa.eu\/info\/strategy\/priorities-2019-2024\/european-green-deal_en\">Green Deal europeo<\/a> e l\u2019<a href=\"https:\/\/www.un.org\/en\/climatechange\/paris-agreement\">Accordo di Parigi<\/a> incoraggiano l\u2019industria automobilistica ad adottare soluzioni pi\u00f9 sostenibili per raggiungere i target di riduzione delle emissioni. La stragrande maggioranza (70%) del settore automotive si sta dedicando alla riduzione delle emissioni complessive lungo tutta la catena del valore, comprese le emissioni Scope 1, 2 e 3,<a href=\"#_ftn3\" id=\"_ftnref3\">[3]<\/a> dalla fornitura ai processi end-of-life. Due terzi (64%) delle organizzazioni del settore prevedono di ridurre le emissioni di anidride carbonica entro il 2040 e il 57% si spinge oltre la conformit\u00e0 ai fattori ESG al fine di rendere la sostenibilit\u00e0 uno dei principali driver aziendali. Tuttavia, dal 2018, l\u2019industria automobilistica ha ridotto le emissioni complessive di gas serra (GHG) solo del 5%, con un\u2019ulteriore riduzione del 19% prevista entro il 2030. Di questo passo, le aziende del comparto automotive non appaiono ben posizionate per raggiungere il target generale di emissioni nette zero entro il 2050 previsto dall\u2019Accordo di Parigi.<\/p>\n\n\n\n<p>Il report rileva che solo un piccolo gruppo di organizzazioni (meno del 10%) si sta impegnando per rendere il settore automobilistico davvero sostenibile, affermando di voler ridurre le emissioni di gas serra del 35% entro il 2030 (rispetto a una riduzione media prevista del 19% per l\u2019intero settore). Al contempo, si stima che la loro efficienza operativa migliorer\u00e0 del 22% entro il 2026 come conseguenza diretta delle iniziative di sostenibilit\u00e0, che aumentano la trasparenza lungo tutta la catena del valore (rispetto al 16% per il resto delle organizzazioni nello stesso periodo). Inoltre, grazie alle recenti iniziative di sostenibilit\u00e0, queste aziende risultano pi\u00f9 interessanti per i nuovi talenti (18% rispetto al 10%).<\/p>\n\n\n\n<p><strong>L\u2019implementazione delle iniziative \u00e8 cresciuta solo in alcune aree strategiche<\/strong><\/p>\n\n\n\n<p>Le organizzazioni del settore automotive si focalizzano sulla riduzione delle emissioni e danno priorit\u00e0 alle iniziative sulle quali hanno un controllo e un\u2019influenza diretti, come ad esempio la produzione e la decarbonizzazione del parco veicoli. Il report rileva che l\u2019implementazione di iniziative sostenibili nella catena di fornitura \u00e8 salita al 57% nel 2022 rispetto al 42% del 2019, e l\u2019approvvigionamento di metalli in modo responsabile \u00e8 passato dal 33% al 44% nello stesso periodo.<\/p>\n\n\n\n<p>Tuttavia, dal report risulta un calo nell\u2019implementazione di iniziative di economia circolare. Sebbene il 73% delle organizzazioni sia concorde nel ritenere che il contributo all\u2019economia circolare rappresenti un imperativo per raggiungere i propri obiettivi finanziari e di competitivit\u00e0 a lungo periodo, solo il 53% dispone di una strategia in questo senso e attualmente meno della met\u00e0 (45%) ne rispetta i principi<a href=\"#_ftn4\" id=\"_ftnref4\">[4]<\/a> lungo tutta la catena del valore.<\/p>\n\n\n\n<p><strong>Il passaggio ai veicoli elettrici \u00e8 complesso e costituisce solamente una parte della soluzione<\/strong><\/p>\n\n\n\n<p>La necessit\u00e0 di ridurre le emissioni di gas serra ha ulteriormente incentivato le organizzazioni del settore automobilistico a focalizzarsi sui veicoli elettrici (EV). Al fine di ottenere un impatto significativo lungo tutto il ciclo di vita di un veicolo elettrico, \u00e8 indispensabile che gli OEM (Original Equipment Manufacturer) garantiscano la circolarit\u00e0 della produzione e considerino il processo di fine vita delle batterie dei veicoli elettrici lungo tutta la catena del valore. Meno della met\u00e0 (41%) dei manager intervistati afferma che la propria organizzazione dispone di iniziative di sostenibilit\u00e0 dedicate, percentuale che scende al 28% per le batterie second life. Nonostante l\u2019aumento delle vendite, i consumatori sono ancora restii verso i veicoli elettrici a causa dei timori relativi all\u2019autonomia e ai costi per la ricarica, ritenendo i pezzi di ricambio e le opzioni di assistenza per i veicoli a combustione interna (ICE) pi\u00f9 facilmente reperibili. L\u2019adozione dei veicoli elettrici \u00e8 inoltre frenata dall\u2019aumento dei costi dell\u2019energia e dalle complesse modalit\u00e0 di ricarica.<\/p>\n\n\n\n<p><strong>La mancanza di KPI porta a una stagnazione in termini di implementazione<\/strong><\/p>\n\n\n\n<p>Il report evidenzia che la scarsa integrazione dei KPI legati alla sostenibilit\u00e0 nelle attivit\u00e0 quotidiane e nella gestione delle performance sta provocando una stagnazione del processo di implementazione: il 73% dei dirigenti concorda sul fatto che l\u2019adozione di misure di sostenibilit\u00e0 nelle attivit\u00e0 e nei processi quotidiani sia cresciuta solo marginalmente o sia rimasta invariata negli ultimi 2-3 anni. Soltanto il 10% delle organizzazioni ha provveduto ad allineare gli obiettivi di performance con i principali target di sostenibilit\u00e0 per i dipendenti di livello non manageriale e anche la difficolt\u00e0 di raccolta, gestione e analisi dei dati sulla sostenibilit\u00e0 costituisce una delle sfide pi\u00f9 impegnative, tanto che solo il 12% dei dirigenti dichiara che la propria organizzazione abbia implementato su larga scala una piattaforma per misurare, monitorare e rendicontare le iniziative di sostenibilit\u00e0.<\/p>\n\n\n\n<p>Il report rileva che, in ogni caso, la responsabilit\u00e0 all\u2019interno dell\u2019organizzazione \u00e8 fondamentale per definire gli obiettivi e condividere i progressi delle iniziative di sostenibilit\u00e0. Dal momento che gli stakeholder puntano i riflettori sulla conformit\u00e0 ai temi ESG, \u00e8 necessario raccogliere i dati dell\u2019intera catena di fornitura per offrire trasparenza e stabilire una base di partenza per la definizione dei KPI dell\u2019azienda.<\/p>\n\n\n\n<p><strong>Incorporare la sostenibilit\u00e0 nel business model<\/strong><\/p>\n\n\n\n<p>Con l\u2019inasprimento delle normative e l\u2019aumento delle aspettative da parte dei consumatori e della societ\u00e0 in generale, le organizzazioni del settore automobilistico devono considerare in modo realistico i livelli di investimento attuali e futuri. Il settore automotive sta per intraprendere un decennio decisivo, con il passaggio dai veicoli ICE ai veicoli elettrici: nonostante le aziende leader siano ben posizionate per questo cambiamento, \u00e8 necessario adottare un approccio pi\u00f9 olistico che comprenda i nuovi processi, le persone e il pianeta.<\/p>\n\n\n\n<p><em>\u201cL\u2019industria automobilistica si appresta a entrare in un decennio decisivo, definito in gran parte dalla sua capacit\u00e0 di passare completamente all\u2019elettrico. Tuttavia, sebbene la sostenibilit\u00e0 sia considerata una priorit\u00e0 assoluta, il settore nel suo complesso \u00e8 in grave ritardo: le organizzazioni devono riflettere concretamente sul loro approccio per raggiungere gli obiettivi fissati nell\u2019Accordo di Parigi per il 2050. Questo comporta un impegno notevole e rinnovato verso l\u2019economia circolare che abbracci l\u2019intero ciclo di vita del veicolo, cos\u00ec come la considerazione delle emissioni Scope 3\u201d,<\/em> ha dichiarato <strong>Eraldo Federici<\/strong>, <strong>Manufacturing, Automotive, Life Sciences, Aerospace &amp; Defence Director di Capgemini in Italia<\/strong>. <em>\u201cLa responsabilit\u00e0 \u00e8 fondamentale per definire obiettivi e KPI a tutti i livelli dell\u2019organizzazione e per fare progressi nella giusta direzione\u201d.<\/em><\/p>\n\n\n\n<p>Per ulteriori informazioni e per scaricare una copia del report, visitare <a href=\"https:\/\/www.capgemini.com\/insights\/research-library\/sustainability-in-automotive?utm_source=pr&amp;utm_medium=referral&amp;utm_content=automotive_none_link_pressrelease_none&amp;utm_campaign=Auto_cri_sustainability_automotive\">questo link<\/a>.<\/p>\n\n\n\n<p><strong>Metodologia di ricerca<\/strong><\/p>\n\n\n\n<p>Il Capgemini Research Institute ha intervistato 1.080 dirigenti di grandi organizzazioni, tra cui OEM del settore automobilistico con un fatturato annuo superiore a 1 miliardo di dollari, supplier del settore automobilistico e produttori di veicoli elettrici pure-play, in 9 paesi, nel periodo compreso tra luglio e agosto 2022. Le aree di competenza dei dirigenti riguardavano strategia aziendale e di prodotto, pianificazione, finanza, catena di approvvigionamento, sostenibilit\u00e0, post-vendita, servizi di mobilit\u00e0, vendite e marketing, fabbricazione e produzione, operation, IT, ingegneria, R&amp;D e design. Hanno risposto soggetti con un ruolo di Director o superiore, responsabili della strategia di sostenibilit\u00e0 delle aziende automobilistiche, delle iniziative, della governance, degli investimenti e di tutti i benefici e i vantaggi che ne derivano. Sono state inoltre condotte 20 interviste approfondite con dirigenti ed esperti del settore.<\/p>\n\n\n\n<p><a href=\"#_ftnref1\" id=\"_ftn1\">[1]<\/a> Per gli investimenti in iniziative di sostenibilit\u00e0 si intendono gli investimenti in tecnologie, processi e competenze per raggiungere gli obiettivi di sostenibilit\u00e0 dell\u2019organizzazione, esclusi i grandi investimenti Capex che le aziende automobilistiche effettuano, tra l\u2019altro, nella ricerca e produzione di veicoli elettrici.<\/p>\n\n\n\n<p><a href=\"#_ftnref2\" id=\"_ftn2\">[2]<\/a> La sostenibilit\u00e0 nell\u2019industria automobilistica coinvolge una visione globale delle attivit\u00e0, dei processi, dei prodotti e dei servizi che rispettano il pianeta e l\u2019umanit\u00e0. Ci\u00f2 comprende una serie di elementi che vanno da \u201cR&amp;D e sviluppo di prodotti sostenibili\u201d a \u201cIT sostenibile\u201d e che abbracciano la catena del valore dell\u2019industria automotive, dalla R&amp;D ai servizi di mobilit\u00e0. All\u2019interno dei tre fattori ESG, per questa ricerca il Capgemini Research Institute si \u00e8 concentrato sull\u2019aspetto della sostenibilit\u00e0 ambientale.<\/p>\n\n\n\n<p><a href=\"#_ftnref3\" id=\"_ftn3\">[3]<\/a> Le emissioni di gas a effetto serra Scope 1 sono emissioni dirette rilasciate nell\u2019atmosfera da fonti dirette o controllate. Le emissioni Scope 3 sono emissioni indirette di gas a serra diverse da quelle Scope 2, che vengono generate nell\u2019economia in generale. Sono il risultato delle attivit\u00e0 di una societ\u00e0, ma non provenienti da fonti controllate o di propriet\u00e0 della societ\u00e0 stessa. Alcuni esempi sono l\u2019estrazione e la produzione di materiali acquistati, il trasporto di combustibili acquistati, l\u2019uso di prodotti e servizi venduti. Lo Scope 3 comprende anche le emissioni associate allo smaltimento dei rifiuti solidi e al trattamento delle acque reflue. Alcune emissioni Scope 3 possono derivare anche dalle perdite di trasporto e distribuzione (T&amp;D) associate all\u2019elettricit\u00e0 acquistata.<\/p>\n\n\n\n<p><a href=\"#_ftnref4\" id=\"_ftn4\">[4]<\/a> L\u2019economia circolare \u00e8 un concetto rigenerativo che punta a separare gradualmente la crescita dal consumo di risorse limitate, distanziandosi dal modello lineare del \u201ctake-make-waste\u201d. I modelli circolari aiutano a fare \u201cun uso ottimale delle risorse, evitando sprechi durante il ciclo di vita di un prodotto, utilizzandolo il pi\u00f9 a lungo possibile e rigenerandone le materie prime, riportandole al loro stato iniziale\u201d. Fonte: <a href=\"https:\/\/ec.europa.eu\/eurostat\/web\/circular-economy\">https:\/\/ec.europa.eu\/eurostat\/web\/circular-economy<\/a><\/p>\n\n\n<div class=\"wp-block-cg-blocks-cg-block-related-content\"><section class=\"relatedContentBlock\"><div class=\"container\"><div class=\"row\"><div class=\"content-title col-12 col-md-8\"><h2 class=\"related-content-heading\">Contenuti correlati<\/h2><\/div><\/div><div class=\"row relatedContent\"><div class=\"col-lg-4 col-md-6 col-xs-12\">\n\t\t\t\t\t\t\t<div class=\"box\">\n\t\t\t\t\t\t\t\t<a aria-label=\"Leggi di pi\u00f9 su Due terzi delle aziende considerano la physical AI una priorit\u00e0 assoluta per i prossimi tre-cinque anni\" href=\"https:\/\/www.capgemini.com\/it-it\/news\/comunicati-stampa\/due-terzi-delle-aziende-considerano-la-physical-ai-una-priorita-assoluta-per-i-prossimi-tre-cinque-anni\/\" class=\"anchorWrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"box-tag\"><span>Report<\/span><\/span>\n\t\t\t\t\t\t\t\t\t<div class=\"box-title\"><h3 class=\"box-subtitle\">Due terzi delle aziende considerano la physical AI una priorit\u00e0 assoluta per i prossimi tre-cinque anni<\/h3><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"box-date\">\n\t\t\t\t\t\t\t\t\t\t<span>May 7, 2026<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"box-bottom\">\n\t\t\t\t\t\t\t\t\t\t&lt;a class=&quot;link-download&quot; href=&quot;https:\/\/www.capgemini.com\/it-it\/wp-content\/uploads\/sites\/15\/2026\/05\/05_07-Robotics-in-the-age-of-physical-AI-CRI_PR_ITA.pdf&quot; aria-label=&quot;Download Press Release&quot; target=&quot;_blank&quot;  type=&quot;download&quot; title=&quot;Opens in a new window&quot;&gt;\n\t\t\t\t\t\t\t&lt;span&gt;Scarica il comunicato stampa&lt;\/span&gt;\n\t\t\t\t\t\t\t&lt;span&gt;149 KB PDF&lt;\/span&gt;\n\t\t\t\t\t\t&lt;\/a&gt;\n\t\t\t\t\t\t\t\t\t\t<a class=\"more\" aria-label=\"Leggi di pi\u00f9 su Due terzi delle aziende considerano la physical AI una priorit\u00e0 assoluta per i prossimi tre-cinque anni\" href=\"https:\/\/www.capgemini.com\/it-it\/news\/comunicati-stampa\/due-terzi-delle-aziende-considerano-la-physical-ai-una-priorita-assoluta-per-i-prossimi-tre-cinque-anni\/\">Leggi di pi\u00f9 su<\/a>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div><div class=\"col-lg-4 col-md-6 col-xs-12\">\n\t\t\t\t\t\t\t<div class=\"box\">\n\t\t\t\t\t\t\t\t<a aria-label=\"Leggi di pi\u00f9 su La reindustrializzazione entra in una fase pi\u00f9 selettiva e strategica in Europa e negli Stati Uniti\" href=\"https:\/\/www.capgemini.com\/it-it\/news\/comunicati-stampa\/la-reindustrializzazione-entra-in-una-fase-piu-selettiva-e-strategica-in-europa-e-negli-stati-uniti\/\" class=\"anchorWrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"box-tag\"><span>Report<\/span><\/span>\n\t\t\t\t\t\t\t\t\t<div class=\"box-title\"><h3 class=\"box-subtitle\">La reindustrializzazione entra in una fase pi\u00f9 selettiva e strategica in Europa e negli Stati Uniti<\/h3><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"box-date\">\n\t\t\t\t\t\t\t\t\t\t<span>Apr 29, 2026<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"box-bottom\">\n\t\t\t\t\t\t\t\t\t\t&lt;a class=&quot;link-download&quot; href=&quot;https:\/\/www.capgemini.com\/it-it\/wp-content\/uploads\/sites\/15\/2026\/04\/2026_04_29_Capgemini_Reindustrialization-of-Europe-and-US_ITA.pdf&quot; aria-label=&quot;Download Press Release&quot; target=&quot;_blank&quot;  type=&quot;download&quot; title=&quot;Opens in a new window&quot;&gt;\n\t\t\t\t\t\t\t&lt;span&gt;Scarica il comunicato stampa&lt;\/span&gt;\n\t\t\t\t\t\t\t&lt;span&gt;161 KB PDF&lt;\/span&gt;\n\t\t\t\t\t\t&lt;\/a&gt;\n\t\t\t\t\t\t\t\t\t\t<a class=\"more\" aria-label=\"Leggi di pi\u00f9 su La reindustrializzazione entra in una fase pi\u00f9 selettiva e strategica in Europa e negli Stati Uniti\" href=\"https:\/\/www.capgemini.com\/it-it\/news\/comunicati-stampa\/la-reindustrializzazione-entra-in-una-fase-piu-selettiva-e-strategica-in-europa-e-negli-stati-uniti\/\">Leggi di pi\u00f9 su<\/a>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div><div class=\"col-lg-4 col-md-6 col-xs-12\">\n\t\t\t\t\t\t\t<div class=\"box\">\n\t\t\t\t\t\t\t\t<a aria-label=\"Leggi di pi\u00f9 su L\u201985% dei clienti corporate delle banche intende rivolgersi a istituzioni finanziarie non bancarie entro un anno, in seguito all&#8217;intensificarsi della concorrenza con il capitale privato\" href=\"https:\/\/www.capgemini.com\/it-it\/news\/comunicati-stampa\/l85-dei-clienti-corporate-delle-banche-intende-rivolgersi-a-istituzioni-finanziarie-non-bancarie-entro-un-anno-in-seguito-allintensificarsi-della-concorrenza-con-il-capitale-privato\/\" class=\"anchorWrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"box-tag\"><span>Report<\/span><\/span>\n\t\t\t\t\t\t\t\t\t<div class=\"box-title\"><h3 class=\"box-subtitle\">L\u201985% dei clienti corporate delle banche intende rivolgersi a istituzioni finanziarie non bancarie entro un anno, in seguito all&#8217;intensificarsi della concorrenza con il capitale privato<\/h3><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"box-date\">\n\t\t\t\t\t\t\t\t\t\t<span>Mar 30, 2026<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"box-bottom\">\n\t\t\t\t\t\t\t\t\t\t&lt;a class=&quot;link-download&quot; href=&quot;https:\/\/www.capgemini.com\/it-it\/wp-content\/uploads\/sites\/15\/2026\/03\/03_30_WCIBR-Press-Release_ITA.pdf&quot; aria-label=&quot;Download Press Release&quot; target=&quot;_blank&quot;  type=&quot;download&quot; title=&quot;Opens in a new window&quot;&gt;\n\t\t\t\t\t\t\t&lt;span&gt;Scarica il comunicato stampa&lt;\/span&gt;\n\t\t\t\t\t\t\t&lt;span&gt;150 KB PDF&lt;\/span&gt;\n\t\t\t\t\t\t&lt;\/a&gt;\n\t\t\t\t\t\t\t\t\t\t<a class=\"more\" aria-label=\"Leggi di pi\u00f9 su L\u201985% dei clienti corporate delle banche intende rivolgersi a istituzioni finanziarie non bancarie entro un anno, in seguito all&#8217;intensificarsi della concorrenza con il capitale privato\" href=\"https:\/\/www.capgemini.com\/it-it\/news\/comunicati-stampa\/l85-dei-clienti-corporate-delle-banche-intende-rivolgersi-a-istituzioni-finanziarie-non-bancarie-entro-un-anno-in-seguito-allintensificarsi-della-concorrenza-con-il-capitale-privato\/\">Leggi di pi\u00f9 su<\/a>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div><\/div><\/div><\/section><\/div><\/div><\/div><\/div><\/div><\/div><\/section>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":336,"featured_media":0,"template":"","meta":{"cg_dt_proposed_to":[],"cg_seo_hreflang_relations":"[]","cg_seo_canonical_relation":"","cg_seo_hreflang_x_default_relation":"{\"uuid\":\"f89b17ec-b7c4-4d76-8440-0d1e9a87e052\",\"blogId\":\"\",\"domain\":\"\",\"sitePath\":\"\",\"postLink\":\"\",\"postId\":null,\"isSaved\":true,\"isCrossLink\":false,\"hasCrossLink\":false}","cg_dt_approved_content":true,"cg_dt_mandatory_content":false,"cg_dt_notes":"","cg_dg_source_changed":false,"cg_dt_link_disabled":false,"footnotes":"","related_resource_url":"https:\/\/www.capgemini.com\/it-it\/wp-content\/uploads\/sites\/15\/2023\/01\/2022_10_27_Capgemini_Sustainability-in-Automotive_Report_ITA.pdf","related_resource_id":70,"related_resource_size":"227 KB","related_resource_type":"pdf","cg_author":0,"featured_focal_points":""},"tags":[],"press-release-type":[220],"brand":[],"class_list":["post-67","press-release","type-press-release","status-publish","hentry","press-release-type-report"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.8 (Yoast SEO v22.8) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Il settore automotive riuscir\u00e0 a raggiungere gli obiettivi di sostenibilit\u00e0 prefissati? - Capgemini Italia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.capgemini.com\/it-it\/news\/comunicati-stampa\/il-settore-automotive-riuscira-a-raggiungere-gli-obiettivi-di-sostenibilita-prefissati\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il settore automotive riuscir\u00e0 a raggiungere gli obiettivi di sostenibilit\u00e0 prefissati?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.capgemini.com\/it-it\/news\/comunicati-stampa\/il-settore-automotive-riuscira-a-raggiungere-gli-obiettivi-di-sostenibilita-prefissati\/\" \/>\n<meta property=\"og:site_name\" content=\"Capgemini Italia\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-20T15:41:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.capgemini.com\/it-it\/wp-content\/uploads\/sites\/15\/2025\/10\/New-Web-preview-global.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"627\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.capgemini.com\/it-it\/news\/comunicati-stampa\/il-settore-automotive-riuscira-a-raggiungere-gli-obiettivi-di-sostenibilita-prefissati\/\",\"url\":\"https:\/\/www.capgemini.com\/it-it\/news\/comunicati-stampa\/il-settore-automotive-riuscira-a-raggiungere-gli-obiettivi-di-sostenibilita-prefissati\/\",\"name\":\"Il settore automotive riuscir\u00e0 a raggiungere gli obiettivi di sostenibilit\u00e0 prefissati? - Capgemini Italia\",\"isPartOf\":{\"@id\":\"https:\/\/www.capgemini.com\/it-it\/#website\"},\"datePublished\":\"2022-10-27T06:49:00+00:00\",\"dateModified\":\"2026-01-20T15:41:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.capgemini.com\/it-it\/news\/comunicati-stampa\/il-settore-automotive-riuscira-a-raggiungere-gli-obiettivi-di-sostenibilita-prefissati\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.capgemini.com\/it-it\/news\/comunicati-stampa\/il-settore-automotive-riuscira-a-raggiungere-gli-obiettivi-di-sostenibilita-prefissati\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.capgemini.com\/it-it\/news\/comunicati-stampa\/il-settore-automotive-riuscira-a-raggiungere-gli-obiettivi-di-sostenibilita-prefissati\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.capgemini.com\/it-it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Press Releases\",\"item\":\"https:\/\/www.capgemini.com\/it-it\/news\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Il settore automotive riuscir\u00e0 a raggiungere gli obiettivi di sostenibilit\u00e0 prefissati?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.capgemini.com\/it-it\/#website\",\"url\":\"https:\/\/www.capgemini.com\/it-it\/\",\"name\":\"Capgemini Italia\",\"description\":\"Get The Future You Want\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.capgemini.com\/it-it\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Il settore automotive riuscir\u00e0 a raggiungere gli obiettivi di sostenibilit\u00e0 prefissati? - Capgemini Italia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.capgemini.com\/it-it\/news\/comunicati-stampa\/il-settore-automotive-riuscira-a-raggiungere-gli-obiettivi-di-sostenibilita-prefissati\/","og_locale":"it_IT","og_type":"article","og_title":"Il settore automotive riuscir\u00e0 a raggiungere gli obiettivi di sostenibilit\u00e0 prefissati?","og_url":"https:\/\/www.capgemini.com\/it-it\/news\/comunicati-stampa\/il-settore-automotive-riuscira-a-raggiungere-gli-obiettivi-di-sostenibilita-prefissati\/","og_site_name":"Capgemini Italia","article_modified_time":"2026-01-20T15:41:50+00:00","og_image":[{"width":1200,"height":627,"url":"https:\/\/www.capgemini.com\/it-it\/wp-content\/uploads\/sites\/15\/2025\/10\/New-Web-preview-global.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.capgemini.com\/it-it\/news\/comunicati-stampa\/il-settore-automotive-riuscira-a-raggiungere-gli-obiettivi-di-sostenibilita-prefissati\/","url":"https:\/\/www.capgemini.com\/it-it\/news\/comunicati-stampa\/il-settore-automotive-riuscira-a-raggiungere-gli-obiettivi-di-sostenibilita-prefissati\/","name":"Il settore automotive riuscir\u00e0 a raggiungere gli obiettivi di sostenibilit\u00e0 prefissati? - Capgemini Italia","isPartOf":{"@id":"https:\/\/www.capgemini.com\/it-it\/#website"},"datePublished":"2022-10-27T06:49:00+00:00","dateModified":"2026-01-20T15:41:50+00:00","breadcrumb":{"@id":"https:\/\/www.capgemini.com\/it-it\/news\/comunicati-stampa\/il-settore-automotive-riuscira-a-raggiungere-gli-obiettivi-di-sostenibilita-prefissati\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.capgemini.com\/it-it\/news\/comunicati-stampa\/il-settore-automotive-riuscira-a-raggiungere-gli-obiettivi-di-sostenibilita-prefissati\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.capgemini.com\/it-it\/news\/comunicati-stampa\/il-settore-automotive-riuscira-a-raggiungere-gli-obiettivi-di-sostenibilita-prefissati\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.capgemini.com\/it-it\/"},{"@type":"ListItem","position":2,"name":"Press Releases","item":"https:\/\/www.capgemini.com\/it-it\/news\/"},{"@type":"ListItem","position":3,"name":"Il settore automotive riuscir\u00e0 a raggiungere gli obiettivi di sostenibilit\u00e0 prefissati?"}]},{"@type":"WebSite","@id":"https:\/\/www.capgemini.com\/it-it\/#website","url":"https:\/\/www.capgemini.com\/it-it\/","name":"Capgemini Italia","description":"Get The Future You Want","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.capgemini.com\/it-it\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/capgemini.com\/it-it\/news\/comunicati-stampa\/il-settore-automotive-riuscira-a-raggiungere-gli-obiettivi-di-sostenibilita-prefissati\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Il settore automotive riuscir\u00e0 a raggiungere gli obiettivi di sostenibilit\u00e0 prefissati?","url":"https:\/\/www.capgemini.com\/it-it\/news\/comunicati-stampa\/il-settore-automotive-riuscira-a-raggiungere-gli-obiettivi-di-sostenibilita-prefissati\/","mainEntityOfPage":{"@type":"WebPage","@id":"https:\/\/www.capgemini.com\/it-it\/news\/comunicati-stampa\/il-settore-automotive-riuscira-a-raggiungere-gli-obiettivi-di-sostenibilita-prefissati\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Uncategorized","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Capgemini Italia","logo":""},"keywords":[],"dateCreated":"2022-10-27T06:49:00Z","datePublished":"2022-10-27T06:49:00Z","dateModified":"2026-01-20T15:41:50Z"},"rendered":"<meta name=\"parsely-title\" content=\"Il settore automotive riuscir\u00e0 a raggiungere gli obiettivi di sostenibilit\u00e0 prefissati?\" \/>\n<meta name=\"parsely-link\" content=\"https:\/\/www.capgemini.com\/it-it\/news\/comunicati-stampa\/il-settore-automotive-riuscira-a-raggiungere-gli-obiettivi-di-sostenibilita-prefissati\/\" \/>\n<meta name=\"parsely-type\" content=\"post\" \/>\n<meta name=\"parsely-pub-date\" content=\"2022-10-27T06:49:00Z\" \/>\n<meta name=\"parsely-section\" content=\"Uncategorized\" \/>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/capgemini.com\/p.js"},"archive_status":false,"featured_image_src":"https:\/\/www.capgemini.com\/it-it\/wp-content\/themes\/capgemini2025\/assets\/images\/mockup.png","featured_image_alt":false,"jetpack_sharing_enabled":true,"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"Capgemini Italia","distributor_original_site_url":"https:\/\/www.capgemini.com\/it-it","push-errors":false,"tag_names":[],"_links":{"self":[{"href":"https:\/\/www.capgemini.com\/it-it\/wp-json\/wp\/v2\/press-release\/67","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.capgemini.com\/it-it\/wp-json\/wp\/v2\/press-release"}],"about":[{"href":"https:\/\/www.capgemini.com\/it-it\/wp-json\/wp\/v2\/types\/press-release"}],"author":[{"embeddable":true,"href":"https:\/\/www.capgemini.com\/it-it\/wp-json\/wp\/v2\/users\/336"}],"version-history":[{"count":4,"href":"https:\/\/www.capgemini.com\/it-it\/wp-json\/wp\/v2\/press-release\/67\/revisions"}],"predecessor-version":[{"id":851565,"href":"https:\/\/www.capgemini.com\/it-it\/wp-json\/wp\/v2\/press-release\/67\/revisions\/851565"}],"wp:attachment":[{"href":"https:\/\/www.capgemini.com\/it-it\/wp-json\/wp\/v2\/media?parent=67"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.capgemini.com\/it-it\/wp-json\/wp\/v2\/tags?post=67"},{"taxonomy":"press-release-type","embeddable":true,"href":"https:\/\/www.capgemini.com\/it-it\/wp-json\/wp\/v2\/press-release-type?post=67"},{"taxonomy":"brand","embeddable":true,"href":"https:\/\/www.capgemini.com\/it-it\/wp-json\/wp\/v2\/brand?post=67"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}