{"id":667516,"date":"2019-03-28T15:32:00","date_gmt":"2019-03-28T15:32:00","guid":{"rendered":"https:\/\/www.capgemini.com\/fr-fr\/?post_type=press-release&#038;p=667516"},"modified":"2025-03-05T04:29:26","modified_gmt":"2025-03-05T03:29:26","slug":"capgemini-invent-en-partenariat-avec-ecap-partner-devoile-les-resultats-du-nouveau-barometre-des-startups-du-numerique-focus-sur-les-pepites-de-lia","status":"publish","type":"press-release","link":"https:\/\/www.capgemini.com\/fr-fr\/actualites\/communiques-de-presse\/capgemini-invent-en-partenariat-avec-ecap-partner-devoile-les-resultats-du-nouveau-barometre-des-startups-du-numerique-focus-sur-les-pepites-de-lia\/","title":{"rendered":"Capgemini Invent, en partenariat avec eCap Partner, d\u00e9voile les r\u00e9sultats du nouveau barom\u00e8tre des startups du num\u00e9rique : focus sur les p\u00e9pites de l\u2019IA !"},"content":{"rendered":"\t\t<div class=\"wp-block-cg-blocks-hero-press-release\">\n\t\t\t<header class=\"header-hero-press-release\" role=\"main\" id=\"main-content-press-release\">\n\t\t\t\t<div class=\"container\">\n\t\t\t\t\t<div class=\"hero-press-release\">\n\t\t\t\t\t\t<div class=\"hero-press-release-content-wrapper\">\n\t\t\t\t\t\t\t<div class=\"row\">\n\t\t\t\t\t\t\t\t<div class=\"col-12\">\n\t\t\t\t\t\t\t\t\t<div class=\"header-title\">\n\t\t\t\t\t\t\t\t\t\t<h1>\n\t\t\t\t\t\t\t\t\t\t\tCapgemini Invent, en partenariat avec eCap Partner, d\u00e9voile les r\u00e9sultats du nouveau barom\u00e8tre des startups du num\u00e9rique : focus sur les p\u00e9pites de l\u2019IA !\t\t\t\t\t\t\t\t\t\t<\/h1>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"header-description\">\n\t\t\t\t\t\t\t\t\t\t<p><\/p>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"header-date\">\n\t\t\t\t\t\t\t\t\t\t<span>mars 28, 2019<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"hero-press-release-downloads\">\n\t\t\t\t\t\t\t\t<div class=\"row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-12 col-md-6 col-lg-3\">\n\t\t\t\t\t\t\t\t\t\t\t<a class=\"download-item\" type=\"download\" href=\"https:\/\/www.capgemini.com\/fr-fr\/wp-content\/uploads\/sites\/6\/2022\/04\/CP-Invent_Barometre-startups_IA_V9.pdf\" target=\"_blank\" rel=\"noopener noreferrer\" title=\"Ouvrir dans une nouvelle fen\u00eatre\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"download-icon\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"download-details\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"download-title\">Download press release<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"download-props\">396 KB  pdf<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/header>\n\t\t<\/div>\n\t\t\n\n\n<section class=\"wp-block-cg-blocks-intro-para undefined section section--intro\"><div class=\"intro-para\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-md-1\"><nav class=\"article-social\"><ul class=\"social-nav\"><li class=\"ip-order-fb\"><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https:\/\/www.capgemini.com\/fr-fr\/actualites\/communiques-de-presse\/capgemini-invent-en-partenariat-avec-ecap-partner-devoile-les-resultats-du-nouveau-barometre-des-startups-du-numerique-focus-sur-les-pepites-de-lia\/\" target=\"_blank\" rel=\"noopener noreferrer\" title=\"Ouvrir dans une nouvelle fen\u00eatre\"><i aria-hidden=\"true\" class=\"icon-fb\"><\/i><span class=\"sr-only\">Facebook<\/span><\/a><\/li><li class=\"ip-order-li\"><a href=\"https:\/\/www.linkedin.com\/sharing\/share-offsite\/?url=https:\/\/www.capgemini.com\/fr-fr\/actualites\/communiques-de-presse\/capgemini-invent-en-partenariat-avec-ecap-partner-devoile-les-resultats-du-nouveau-barometre-des-startups-du-numerique-focus-sur-les-pepites-de-lia\/\" target=\"_blank\" rel=\"noopener noreferrer\" title=\"Ouvrir dans une nouvelle fen\u00eatre\"><i aria-hidden=\"true\" class=\"icon-li\"><\/i><span class=\"sr-only\">Linkedin<\/span><\/a><\/li><\/ul><\/nav><\/div><div class=\"col-12 col-md-11 col-lg-10\"><h2 class=\"intro-para-title\"><em>Depuis 2015, plus de 845 M\u20ac ont \u00e9t\u00e9 lev\u00e9s en France dans l\u2019Intelligence Artificielle<\/em><\/h2><\/div><\/div><\/div><\/div><\/section>\n\n\n\n<section class=\"wp-block-cg-blocks-group undefined section section--article-content\"><div class=\"article-main-content\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-md-11 col-lg-10 offset-md-1 offset-lg-1\"><div class=\"article-text article-quote-text\">\n<p><strong>Paris, le 28 mars<\/strong> <strong>2019 \u2013 Pour cette \u00e9dition du barom\u00e8tre des startups du num\u00e9rique, <\/strong><a href=\"https:\/\/www.capgemini.com\/fr-fr\/\"><strong>Capgemini Invent<\/strong><\/a> <strong>et eCap Partner auscultent de pr\u00e8s les investissements effectu\u00e9s depuis quatre ans dans les startups de l\u2019intelligence artificielle.<\/strong><\/p>\n\n\n\n<p>Sur la p\u00e9riode allant de 2015 \u00e0 2018, <strong>845 M\u20ac <\/strong>(r\u00e9partis sur 173 lev\u00e9es)<strong> ont \u00e9t\u00e9 investis&nbsp;: &nbsp;<\/strong>soit une croissance des montants investis 4 fois sup\u00e9rieure au reste de l\u2019\u00e9conomie num\u00e9rique. Cette forte dynamique s\u2019observe \u00e9galement au niveau du ticket moyen d\u2019investissement&nbsp;: il a en effet presque tripl\u00e9 durant cette p\u00e9riode. Les acteurs ayant lev\u00e9 plusieurs dizaines de millions pr\u00e9parent le terrain pour de futures licornes.<\/p>\n\n\n\n<p>Tableau 1. Croissance des montants des lev\u00e9es 2015-2018<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td><\/td><td>&nbsp; Volume total en M\u20ac lev\u00e9es &nbsp;<\/td><td>Montant ticket moyen en M\u20ac<\/td><\/tr><tr><td><\/td><td><strong>2015<\/strong><\/td><td><strong>2016<\/strong><\/td><td><strong>2017<\/strong><\/td><td><strong>2018<\/strong><\/td><td><strong>2015<\/strong><\/td><td><strong>2016<\/strong><\/td><td><strong>2017<\/strong><\/td><td><strong>2018<\/strong><\/td><\/tr><tr><td>IA<\/td><td>62<\/td><td>138<\/td><td>268<\/td><td>376<\/td><td>2,4<\/td><td>4,5<\/td><td>5,5<\/td><td>6,0<\/td><\/tr><tr><td>Autres startups<\/td><td>1 312<\/td><td>1 541<\/td><td>1 855<\/td><td>2 421<\/td><td>3,1<\/td><td>3,0<\/td><td>3,9<\/td><td>5,6<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p>Les startups sp\u00e9cialis\u00e9es dans l\u2019intelligence artificielle ont le vent en poupe&nbsp;: elles b\u00e9n\u00e9ficient non seulement d\u2019<strong>une croissance de presque 30% en termes de nombre de lev\u00e9es<\/strong> (contre une stagnation pour les autres jeunes pousses), mais aussi d\u2019un grand nombre de lev\u00e9es dont le montant exc\u00e8de 10 M\u20ac&nbsp;: celui-ci est trois fois sup\u00e9rieur \u00e0 celui des autres startups.<\/p>\n\n\n\n<p>Tableau 2. Croissance du nombre de lev\u00e9es, focus sur les lev\u00e9es de &gt; 10 M\u20ac<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td><\/td><td>&nbsp; Nombre de lev\u00e9es &nbsp;<\/td><td>Nombre de lev\u00e9es &gt; 10 M\u20ac<\/td><\/tr><tr><td><\/td><td><strong>2015<\/strong><\/td><td><strong>2016<\/strong><\/td><td><strong>2017<\/strong><\/td><td><strong>2018<\/strong><\/td><td><strong>2015<\/strong><\/td><td><strong>2016<\/strong><\/td><td><strong>2017<\/strong><\/td><td><strong>2018<\/strong><\/td><\/tr><tr><td>IA<\/td><td>26<\/td><td>31<\/td><td>49<\/td><td>67<\/td><td>1<\/td><td>5<\/td><td>9<\/td><td>16<\/td><\/tr><tr><td>Autres startups<\/td><td>423<\/td><td>514<\/td><td>480<\/td><td>438<\/td><td>25<\/td><td>33<\/td><td>42<\/td><td>69<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p>.<\/p>\n\n\n\n<p>Parmi toutes les technologies analys\u00e9es, ce sont le <em>machine learning<\/em> et le <em>deep learning<\/em> qui dominent le paysage&nbsp;<strong>: plus de 75% des startups int\u00e8grent ces technologies<\/strong>, ce qui en font des briques incontournables de l\u2019IA.<\/p>\n\n\n\n<p>On note qu\u2019une tendance \u00e0 la verticalisation sectorielle des startup IA \u00e9merge&nbsp;: en effet, 60% d\u2019entre elles en 2015 commercialisent des technologies, pour seulement 46% en 2018. C\u2019est par ailleurs plus de la <strong>moiti\u00e9 des startups IA qui trouvent d\u00e9j\u00e0 leurs&nbsp;applications dans des cas d\u2019usages<\/strong> sectoriels.<\/p>\n\n\n\n<p>A l\u2019instar de ce que nous pouvons observer dans l\u2019industrie du num\u00e9rique, les secteurs les plus dynamiques sont la finance, la sant\u00e9, les transports et l\u2019\u00e9ducation. Le volume des nouveaux usages IA se concentre dans ce nombre r\u00e9duit de secteurs, qui repr\u00e9sentent d\u00e9j\u00e0 plus d\u20191\/4 des startups de l\u2019intelligence artificielle en France.<\/p>\n\n\n\n<p><strong>METHODOLOGIE<\/strong><\/p>\n\n\n\n<p>Comme en atteste le nombre \u2013 <em>et parfois la dissonance<\/em> \u2013 des analyses qui visent \u00e0 l\u2019appr\u00e9hender, l\u2019\u00e9cosyst\u00e8me des startups est un objet complexe, mouvant et difficile \u00e0 saisir dans son int\u00e9gralit\u00e9. Afin de d\u00e9limiter un p\u00e9rim\u00e8tre d\u2019\u00e9tude le plus objectif possible, cette analyse se focalise sur les entreprises r\u00e9pondant aux crit\u00e8res suivants:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>disposer d\u2019une activit\u00e9 li\u00e9e au d\u00e9veloppement de technologies ou d\u2019usage de l\u2019IA<\/li>\n\n\n\n<li>avoir r\u00e9ussi au moins une lev\u00e9e de fonds aupr\u00e8s d\u2019un investisseur du capital risque<\/li>\n\n\n\n<li>\u00eatre \u00e2g\u00e9e de moins de 10 ans au moment de la lev\u00e9e<\/li>\n\n\n\n<li>\u00eatre ind\u00e9pendante et non cot\u00e9e en bourse<\/li>\n<\/ul>\n\n\n\n<p>Pour \u00e9tablir cette base, l\u2019inventaire complet des lev\u00e9es de fonds r\u00e9centes (2015-2018) r\u00e9alis\u00e9es dans le num\u00e9rique en France (plus de 2 000 lev\u00e9es de fonds identifi\u00e9es au total) a \u00e9t\u00e9 effectu\u00e9 sur la base d\u2019une veille sur les lev\u00e9es (50 m\u00e9dias sources, annuaire de lev\u00e9es, etc.) et d\u2019une validation de ces informations aupr\u00e8s des investisseurs (screening des sites, validation des portefeuilles).<\/p>\n\n\n\n<p>Pour chacune des entreprises ayant fait l\u2019objet d\u2019une de ces lev\u00e9es de fonds, ont \u00e9t\u00e9 r\u00e9cup\u00e9r\u00e9s, sur la base de sources d\u2019informations publiques, les informations relatives aux noms, date de cr\u00e9ation, adresse, nombre d\u2019effectifs, site web et description de l\u2019activit\u00e9.<\/p>\n\n\n\n<p>Le barom\u00e8tre s\u2019appuie ainsi sur un \u00e9chantillon de plus de 1800 entreprises r\u00e9pondant \u00e0 ces crit\u00e8res. Celle-ci ont \u00e9t\u00e9 parcourues une \u00e0 une et ont \u00e9t\u00e9 affect\u00e9es manuellement \u00e0 un secteur d\u2019activit\u00e9 et \u00e0 un business model. Enfin, afin d\u2019ajouter une dimension Intelligence Artificielle, une annotation des startups IA ainsi qu\u2019une cat\u00e9gorisation des technologies utilis\u00e9es (chatbot \/ voicebot, Machine Learning \/ Deep Learning, Robotique \/ RPA, Analyse Audio\/Vid\u00e9o\/Son) ont \u00e9t\u00e9 r\u00e9alis\u00e9es.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Pour acc\u00e9der au Barom\u00e8tre&nbsp;: <a href=\"http:\/\/www.barometre-startups.org\">BAROMETRE-STARTUPS.ORG<\/a><\/li>\n<\/ul>\n\n\n\n<p><strong>A propos d\u2019eCap Partner<\/strong><\/p>\n\n\n\n<p>eCap Partner est la banque d\u2019affaires sp\u00e9cialiste de l\u2019industrie num\u00e9rique. Fond\u00e9e en 2011 la soci\u00e9t\u00e9 accompagne ses clients sur leurs op\u00e9rations de cession, de lev\u00e9e de fonds et de croissance externe.<\/p>\n\n\n\n<p>Plus d\u2019informations&nbsp;sur&nbsp;: <a href=\"http:\/\/www.ecap-partner.com\"><em>eCap-partner.com<\/em><\/a><em> @eCapPartner<\/em><\/p>\n\n\n\n<p><strong>\u00c0 propos de Capgemini Invent<\/strong><\/p>\n\n\n\n<p>Capgemini Invent est la marque d\u2019innovation digitale, de conseil et de transformation du groupe Capgemini qui aide les d\u00e9cideurs \u00e0 concevoir et construire le futur de leurs organisations. Forte de plus de 6 000 collaborateurs, bas\u00e9s dans plus de 30 bureaux et 22 studios de cr\u00e9ation \u00e0 travers le monde, Capgemini Invent conjugue une expertise en strat\u00e9gie, technologies, data science et creative design, avec des connaissances sectorielles approfondies pour b\u00e2tir les solutions digitales et business models de demain.<\/p>\n\n\n\n<p>Capgemini Invent fait partie du groupe Capgemini, un leader mondial du conseil, des services informatiques et de la transformation num\u00e9rique. A la pointe de l\u2019innovation, le Groupe aide ses clients \u00e0 saisir l\u2019ensemble des opportunit\u00e9s que pr\u00e9sentent le cloud, le digital et les plateformes. Fort de 50 ans d\u2019exp\u00e9rience et d\u2019une grande expertise des diff\u00e9rents secteurs d\u2019activit\u00e9, il accompagne les entreprises et organisations dans la r\u00e9alisation de leurs ambitions, de la d\u00e9finition de leur strat\u00e9gie \u00e0 la mise en \u0153uvre de leurs op\u00e9rations. Pour Capgemini, ce sont les hommes et les femmes qui donnent toute sa valeur \u00e0 la technologie. R\u00e9solument multiculturel, le Groupe compte 200 000 collaborateurs pr\u00e9sents dans plus de 40 pays. Il a r\u00e9alis\u00e9 un chiffre d\u2019affaires de 12,8 milliards d\u2019euros en 2017. <em>People matter, results count<\/em>.<\/p>\n\n\n\n<p>Plus d\u2019informations sur <a href=\"http:\/\/www.capgemini.com\/invent\">www.capgemini.com\/invent<\/a> <em>@CapgeminiInvent<\/em><\/p>\n\n\n\n<p><strong><em>Perform AI, le portefeuille de solutions de Capgemini d\u00e9di\u00e9 \u00e0 l\u2019intelligence artificielle, int\u00e8gre les services de strat\u00e9gie et d\u2019innovation IA d\u00e9velopp\u00e9s par Capgemini Invent&nbsp;: voir le communiqu\u00e9 <\/em><\/strong><a href=\"https:\/\/www.capgemini.com\/fr-fr\/news\/capgemini-lance-son-offre-perform-ai\/\"><strong><em>ici<\/em><\/strong><\/a><strong><em>.<\/em><\/strong><\/p>\n<\/div><\/div><\/div><\/div><\/div><\/section>\n\n\n<div class=\"wp-block-cg-blocks-cg-block-related-content\"><section class=\"relatedContentBlock\"><div class=\"container\"><div class=\"row\"><div class=\"content-title col-12 col-md-8\"><h2 class=\"related-content-heading\">Related News<\/h2><\/div><\/div><div class=\"row relatedContent\"><div class=\"col-lg-4 col-md-6 col-xs-12\">\n\t\t\t\t\t\t\t<div class=\"box\">\n\t\t\t\t\t\t\t\t<a aria-label=\"Lire la suite Capgemini consolide sa position dans l\u2019IA d\u2019entreprise avec un investissement dans l\u2019OpenAI Deployment Company\" href=\"https:\/\/www.capgemini.com\/fr-fr\/actualites\/communiques-de-presse\/capgemini-consolide-sa-position-dans-lia-dentreprise-avec-un-investissement-dans-openai-deployment-company\/\" class=\"anchorWrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"box-tag\"><span>Actualit\u00e9s du Groupe<\/span><\/span>\n\t\t\t\t\t\t\t\t\t<div class=\"box-title\"><h3 class=\"box-subtitle\">Capgemini consolide sa position dans l\u2019IA d\u2019entreprise avec un investissement dans l\u2019OpenAI Deployment Company<\/h3><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"box-date\">\n\t\t\t\t\t\t\t\t\t\t<span>May 12, 2026<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"box-bottom\">\n\t\t\t\t\t\t\t\t\t\t&lt;a class=&quot;link-download&quot; href=&quot;https:\/\/www.capgemini.com\/wp-content\/uploads\/2026\/05\/05_12_Capgemini-invests-in-the-OpenAI-Deployment-Co.pdf&quot; aria-label=&quot;T\u00e9l\u00e9charger le communiqu\u00e9 de presse&quot; target=&quot;_blank&quot;  type=&quot;download&quot; title=&quot;Opens in a new window&quot;&gt;\n\t\t\t\t\t\t\t&lt;span&gt;T\u00e9l\u00e9charger le communiqu\u00e9 de presse&lt;\/span&gt;\n\t\t\t\t\t\t\t&lt;span&gt;111 KB PDF&lt;\/span&gt;\n\t\t\t\t\t\t&lt;\/a&gt;\n\t\t\t\t\t\t\t\t\t\t<a class=\"more\" aria-label=\"Lire la suite Capgemini consolide sa position dans l\u2019IA d\u2019entreprise avec un investissement dans l\u2019OpenAI Deployment Company\" href=\"https:\/\/www.capgemini.com\/fr-fr\/actualites\/communiques-de-presse\/capgemini-consolide-sa-position-dans-lia-dentreprise-avec-un-investissement-dans-openai-deployment-company\/\">Lire la suite<\/a>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div><div class=\"col-lg-4 col-md-6 col-xs-12\">\n\t\t\t\t\t\t\t<div class=\"box\">\n\t\t\t\t\t\t\t\t<a aria-label=\"Lire la suite Le moment de v\u00e9rit\u00e9 de l\u2019IA pour l\u2019Assurance dommages : les pionniers affichent une croissance de revenus sup\u00e9rieure de 21 %, tandis que le reste du secteur peine \u00e0 suivre\" href=\"https:\/\/www.capgemini.com\/fr-fr\/actualites\/communiques-de-presse\/le-moment-de-verite-de-lia-pour-lassurance-dommages-les-pionniers-affichent-une-croissance-de-revenus-superieure-de-21-tandis-que-le-reste-du-secteur-peine-a-suivre\/\" class=\"anchorWrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"box-tag\"><span>Publications<\/span><\/span>\n\t\t\t\t\t\t\t\t\t<div class=\"box-title\"><h3 class=\"box-subtitle\">Le moment de v\u00e9rit\u00e9 de l\u2019IA pour l\u2019Assurance dommages : les pionniers affichent une croissance de revenus sup\u00e9rieure de 21 %, tandis que le reste du secteur peine \u00e0 suivre<\/h3><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"box-date\">\n\t\t\t\t\t\t\t\t\t\t<span>May 5, 2026<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"box-bottom\">\n\t\t\t\t\t\t\t\t\t\t&lt;a class=&quot;link-download&quot; href=&quot;https:\/\/www.capgemini.com\/fr-fr\/wp-content\/uploads\/sites\/6\/2026\/05\/2026_05_05_FR_Capgemini-Press-Release_WPCIR.pdf&quot; aria-label=&quot;T\u00e9l\u00e9charger le communiqu\u00e9 de presse&quot; target=&quot;_blank&quot;  type=&quot;download&quot; title=&quot;Opens in a new window&quot;&gt;\n\t\t\t\t\t\t\t&lt;span&gt;T\u00e9l\u00e9charger le communiqu\u00e9 de presse&lt;\/span&gt;\n\t\t\t\t\t\t\t&lt;span&gt;166 KB PDF&lt;\/span&gt;\n\t\t\t\t\t\t&lt;\/a&gt;\n\t\t\t\t\t\t\t\t\t\t<a class=\"more\" aria-label=\"Lire la suite Le moment de v\u00e9rit\u00e9 de l\u2019IA pour l\u2019Assurance dommages : les pionniers affichent une croissance de revenus sup\u00e9rieure de 21 %, tandis que le reste du secteur peine \u00e0 suivre\" href=\"https:\/\/www.capgemini.com\/fr-fr\/actualites\/communiques-de-presse\/le-moment-de-verite-de-lia-pour-lassurance-dommages-les-pionniers-affichent-une-croissance-de-revenus-superieure-de-21-tandis-que-le-reste-du-secteur-peine-a-suivre\/\">Lire la suite<\/a>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div><div class=\"col-lg-4 col-md-6 col-xs-12\">\n\t\t\t\t\t\t\t<div class=\"box\">\n\t\t\t\t\t\t\t\t<a aria-label=\"Lire la suite Chiffre d\u2019affaires du 1er trimestre 2026\" href=\"https:\/\/www.capgemini.com\/fr-fr\/actualites\/communiques-de-presse\/chiffre-daffaires-du-1er-trimestre-2026\/\" class=\"anchorWrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"box-tag\"><span>Actualit\u00e9s financi\u00e8res<\/span><\/span>\n\t\t\t\t\t\t\t\t\t<div class=\"box-title\"><h3 class=\"box-subtitle\">Chiffre d\u2019affaires du 1er trimestre 2026<\/h3><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"box-date\">\n\t\t\t\t\t\t\t\t\t\t<span>Apr 30, 2026<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"box-bottom\">\n\t\t\t\t\t\t\t\t\t\t&lt;a class=&quot;link-download&quot; href=&quot;https:\/\/www.capgemini.com\/fr-fr\/wp-content\/uploads\/sites\/6\/2026\/04\/Capgemini_-_2026-04-30_-_Chiffre_d_affaires_du_1er_trimestre_2026.pdf&quot; aria-label=&quot;T\u00e9l\u00e9charger le communiqu\u00e9 de presse&quot; target=&quot;_blank&quot;  type=&quot;download&quot; title=&quot;Opens in a new window&quot;&gt;\n\t\t\t\t\t\t\t&lt;span&gt;T\u00e9l\u00e9charger le communiqu\u00e9 de presse&lt;\/span&gt;\n\t\t\t\t\t\t\t&lt;span&gt;237 KB PDF&lt;\/span&gt;\n\t\t\t\t\t\t&lt;\/a&gt;\n\t\t\t\t\t\t\t\t\t\t<a class=\"more\" aria-label=\"Lire la suite Chiffre d\u2019affaires du 1er trimestre 2026\" href=\"https:\/\/www.capgemini.com\/fr-fr\/actualites\/communiques-de-presse\/chiffre-daffaires-du-1er-trimestre-2026\/\">Lire la suite<\/a>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div><\/div><\/div><\/section><\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":103,"featured_media":0,"template":"","meta":{"cg_dt_proposed_to":[],"cg_seo_hreflang_relations":"[]","cg_seo_canonical_relation":"{\"uuid\":\"a74d7ffe-b08d-4145-8f81-33554dae0bc4\",\"blogId\":\"\",\"domain\":\"\",\"sitePath\":\"\",\"postLink\":\"\",\"postId\":null,\"isSaved\":true,\"isCrossLink\":false,\"hasCrossLink\":false}","cg_seo_hreflang_x_default_relation":"{\"uuid\":\"c3d174eb-e50a-46d2-831c-61babe2edc2b\",\"blogId\":\"\",\"domain\":\"\",\"sitePath\":\"\",\"postLink\":\"\",\"postId\":null,\"isSaved\":true,\"isCrossLink\":false,\"hasCrossLink\":false}","cg_dt_approved_content":true,"cg_dt_mandatory_content":false,"cg_dt_notes":"","cg_dg_source_changed":false,"cg_dt_link_disabled":false,"footnotes":"","related_resource_url":"https:\/\/www.capgemini.com\/fr-fr\/wp-content\/uploads\/sites\/6\/2022\/04\/CP-Invent_Barometre-startups_IA_V9.pdf","related_resource_id":667517,"related_resource_size":"396 KB","related_resource_type":"pdf","cg_author":0,"featured_focal_points":""},"tags":[],"press-release-type":[],"brand":[],"class_list":["post-667516","press-release","type-press-release","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.8 (Yoast SEO v22.8) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Capgemini Invent, en partenariat avec eCap Partner, d\u00e9voile les r\u00e9sultats du nouveau barom\u00e8tre des startups du num\u00e9rique : focus sur les p\u00e9pites de l\u2019IA ! - Capgemini France<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.capgemini.com\/fr-fr\/actualites\/communiques-de-presse\/capgemini-invent-en-partenariat-avec-ecap-partner-devoile-les-resultats-du-nouveau-barometre-des-startups-du-numerique-focus-sur-les-pepites-de-lia\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Capgemini Invent, en partenariat avec eCap Partner, d\u00e9voile les r\u00e9sultats du nouveau barom\u00e8tre des startups du num\u00e9rique : focus sur les p\u00e9pites de l\u2019IA !\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.capgemini.com\/fr-fr\/actualites\/communiques-de-presse\/capgemini-invent-en-partenariat-avec-ecap-partner-devoile-les-resultats-du-nouveau-barometre-des-startups-du-numerique-focus-sur-les-pepites-de-lia\/\" \/>\n<meta property=\"og:site_name\" content=\"Capgemini France\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-05T03:29:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.capgemini.com\/fr-fr\/wp-content\/uploads\/sites\/6\/2025\/10\/image-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"627\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.capgemini.com\/fr-fr\/actualites\/communiques-de-presse\/capgemini-invent-en-partenariat-avec-ecap-partner-devoile-les-resultats-du-nouveau-barometre-des-startups-du-numerique-focus-sur-les-pepites-de-lia\/\",\"url\":\"https:\/\/www.capgemini.com\/fr-fr\/actualites\/communiques-de-presse\/capgemini-invent-en-partenariat-avec-ecap-partner-devoile-les-resultats-du-nouveau-barometre-des-startups-du-numerique-focus-sur-les-pepites-de-lia\/\",\"name\":\"Capgemini Invent, en partenariat avec eCap Partner, d\u00e9voile les r\u00e9sultats du nouveau barom\u00e8tre des startups du num\u00e9rique : focus sur les p\u00e9pites de l\u2019IA ! - Capgemini France\",\"isPartOf\":{\"@id\":\"https:\/\/www.capgemini.com\/fr-fr\/#website\"},\"datePublished\":\"2019-03-28T15:32:00+00:00\",\"dateModified\":\"2025-03-05T03:29:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.capgemini.com\/fr-fr\/actualites\/communiques-de-presse\/capgemini-invent-en-partenariat-avec-ecap-partner-devoile-les-resultats-du-nouveau-barometre-des-startups-du-numerique-focus-sur-les-pepites-de-lia\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.capgemini.com\/fr-fr\/actualites\/communiques-de-presse\/capgemini-invent-en-partenariat-avec-ecap-partner-devoile-les-resultats-du-nouveau-barometre-des-startups-du-numerique-focus-sur-les-pepites-de-lia\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.capgemini.com\/fr-fr\/actualites\/communiques-de-presse\/capgemini-invent-en-partenariat-avec-ecap-partner-devoile-les-resultats-du-nouveau-barometre-des-startups-du-numerique-focus-sur-les-pepites-de-lia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Press Releases\",\"item\":\"https:\/\/www.capgemini.com\/fr-fr\/news\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Capgemini Invent, en partenariat avec eCap Partner, d\u00e9voile les r\u00e9sultats du nouveau barom\u00e8tre des startups du num\u00e9rique : focus sur les p\u00e9pites de l\u2019IA !\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.capgemini.com\/fr-fr\/#website\",\"url\":\"https:\/\/www.capgemini.com\/fr-fr\/\",\"name\":\"Capgemini France\",\"description\":\"Just another www.capgemini.com site\",\"publisher\":{\"@id\":\"https:\/\/www.capgemini.com\/fr-fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.capgemini.com\/fr-fr\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.capgemini.com\/fr-fr\/#organization\",\"name\":\"Capgemini France\",\"url\":\"https:\/\/www.capgemini.com\/fr-fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.capgemini.com\/fr-fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.capgemini.com\/fr-fr\/wp-content\/uploads\/sites\/6\/2022\/08\/Logo-Capgemini.png\",\"contentUrl\":\"https:\/\/www.capgemini.com\/fr-fr\/wp-content\/uploads\/sites\/6\/2022\/08\/Logo-Capgemini.png\",\"width\":202,\"height\":60,\"caption\":\"Capgemini France\"},\"image\":{\"@id\":\"https:\/\/www.capgemini.com\/fr-fr\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Capgemini Invent, en partenariat avec eCap Partner, d\u00e9voile les r\u00e9sultats du nouveau barom\u00e8tre des startups du num\u00e9rique : focus sur les p\u00e9pites de l\u2019IA ! - Capgemini France","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.capgemini.com\/fr-fr\/actualites\/communiques-de-presse\/capgemini-invent-en-partenariat-avec-ecap-partner-devoile-les-resultats-du-nouveau-barometre-des-startups-du-numerique-focus-sur-les-pepites-de-lia\/","og_locale":"fr_FR","og_type":"article","og_title":"Capgemini Invent, en partenariat avec eCap Partner, d\u00e9voile les r\u00e9sultats du nouveau barom\u00e8tre des startups du num\u00e9rique : focus sur les p\u00e9pites de l\u2019IA !","og_url":"https:\/\/www.capgemini.com\/fr-fr\/actualites\/communiques-de-presse\/capgemini-invent-en-partenariat-avec-ecap-partner-devoile-les-resultats-du-nouveau-barometre-des-startups-du-numerique-focus-sur-les-pepites-de-lia\/","og_site_name":"Capgemini France","article_modified_time":"2025-03-05T03:29:26+00:00","og_image":[{"width":1200,"height":627,"url":"https:\/\/www.capgemini.com\/fr-fr\/wp-content\/uploads\/sites\/6\/2025\/10\/image-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.capgemini.com\/fr-fr\/actualites\/communiques-de-presse\/capgemini-invent-en-partenariat-avec-ecap-partner-devoile-les-resultats-du-nouveau-barometre-des-startups-du-numerique-focus-sur-les-pepites-de-lia\/","url":"https:\/\/www.capgemini.com\/fr-fr\/actualites\/communiques-de-presse\/capgemini-invent-en-partenariat-avec-ecap-partner-devoile-les-resultats-du-nouveau-barometre-des-startups-du-numerique-focus-sur-les-pepites-de-lia\/","name":"Capgemini Invent, en partenariat avec eCap Partner, d\u00e9voile les r\u00e9sultats du nouveau barom\u00e8tre des startups du num\u00e9rique : focus sur les p\u00e9pites de l\u2019IA ! - Capgemini France","isPartOf":{"@id":"https:\/\/www.capgemini.com\/fr-fr\/#website"},"datePublished":"2019-03-28T15:32:00+00:00","dateModified":"2025-03-05T03:29:26+00:00","breadcrumb":{"@id":"https:\/\/www.capgemini.com\/fr-fr\/actualites\/communiques-de-presse\/capgemini-invent-en-partenariat-avec-ecap-partner-devoile-les-resultats-du-nouveau-barometre-des-startups-du-numerique-focus-sur-les-pepites-de-lia\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.capgemini.com\/fr-fr\/actualites\/communiques-de-presse\/capgemini-invent-en-partenariat-avec-ecap-partner-devoile-les-resultats-du-nouveau-barometre-des-startups-du-numerique-focus-sur-les-pepites-de-lia\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.capgemini.com\/fr-fr\/actualites\/communiques-de-presse\/capgemini-invent-en-partenariat-avec-ecap-partner-devoile-les-resultats-du-nouveau-barometre-des-startups-du-numerique-focus-sur-les-pepites-de-lia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Press Releases","item":"https:\/\/www.capgemini.com\/fr-fr\/news\/"},{"@type":"ListItem","position":2,"name":"Capgemini Invent, en partenariat avec eCap Partner, d\u00e9voile les r\u00e9sultats du nouveau barom\u00e8tre des startups du num\u00e9rique : focus sur les p\u00e9pites de l\u2019IA !"}]},{"@type":"WebSite","@id":"https:\/\/www.capgemini.com\/fr-fr\/#website","url":"https:\/\/www.capgemini.com\/fr-fr\/","name":"Capgemini France","description":"Just another www.capgemini.com site","publisher":{"@id":"https:\/\/www.capgemini.com\/fr-fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.capgemini.com\/fr-fr\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.capgemini.com\/fr-fr\/#organization","name":"Capgemini France","url":"https:\/\/www.capgemini.com\/fr-fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.capgemini.com\/fr-fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.capgemini.com\/fr-fr\/wp-content\/uploads\/sites\/6\/2022\/08\/Logo-Capgemini.png","contentUrl":"https:\/\/www.capgemini.com\/fr-fr\/wp-content\/uploads\/sites\/6\/2022\/08\/Logo-Capgemini.png","width":202,"height":60,"caption":"Capgemini France"},"image":{"@id":"https:\/\/www.capgemini.com\/fr-fr\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/capgemini.com\/fr-fr\/actualites\/communiques-de-presse\/capgemini-invent-en-partenariat-avec-ecap-partner-devoile-les-resultats-du-nouveau-barometre-des-startups-du-numerique-focus-sur-les-pepites-de-lia\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Capgemini Invent, en partenariat avec eCap Partner, d\u00e9voile les r\u00e9sultats du nouveau barom\u00e8tre des startups du num\u00e9rique : focus sur les p\u00e9pites de l\u2019IA !","url":"https:\/\/www.capgemini.com\/fr-fr\/actualites\/communiques-de-presse\/capgemini-invent-en-partenariat-avec-ecap-partner-devoile-les-resultats-du-nouveau-barometre-des-startups-du-numerique-focus-sur-les-pepites-de-lia\/","mainEntityOfPage":{"@type":"WebPage","@id":"https:\/\/www.capgemini.com\/fr-fr\/actualites\/communiques-de-presse\/capgemini-invent-en-partenariat-avec-ecap-partner-devoile-les-resultats-du-nouveau-barometre-des-startups-du-numerique-focus-sur-les-pepites-de-lia\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Uncategorized","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Capgemini France","logo":""},"keywords":[],"dateCreated":"2019-03-28T15:32:00Z","datePublished":"2019-03-28T15:32:00Z","dateModified":"2025-03-05T03:29:26Z"},"rendered":"<meta name=\"parsely-title\" content=\"Capgemini Invent, en partenariat avec eCap Partner, d\u00e9voile les r\u00e9sultats du nouveau barom\u00e8tre des startups du num\u00e9rique : focus sur les p\u00e9pites de l\u2019IA !\" \/>\n<meta name=\"parsely-link\" content=\"https:\/\/www.capgemini.com\/fr-fr\/actualites\/communiques-de-presse\/capgemini-invent-en-partenariat-avec-ecap-partner-devoile-les-resultats-du-nouveau-barometre-des-startups-du-numerique-focus-sur-les-pepites-de-lia\/\" \/>\n<meta name=\"parsely-type\" content=\"post\" \/>\n<meta name=\"parsely-pub-date\" content=\"2019-03-28T15:32:00Z\" \/>\n<meta name=\"parsely-section\" content=\"Uncategorized\" \/>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/capgemini.com\/p.js"},"archive_status":false,"featured_image_src":"https:\/\/www.capgemini.com\/fr-fr\/wp-content\/themes\/capgemini2025\/assets\/images\/mockup.png","featured_image_alt":false,"jetpack_sharing_enabled":true,"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"Capgemini France","distributor_original_site_url":"https:\/\/www.capgemini.com\/fr-fr","push-errors":false,"tag_names":[],"_links":{"self":[{"href":"https:\/\/www.capgemini.com\/fr-fr\/wp-json\/wp\/v2\/press-release\/667516","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.capgemini.com\/fr-fr\/wp-json\/wp\/v2\/press-release"}],"about":[{"href":"https:\/\/www.capgemini.com\/fr-fr\/wp-json\/wp\/v2\/types\/press-release"}],"author":[{"embeddable":true,"href":"https:\/\/www.capgemini.com\/fr-fr\/wp-json\/wp\/v2\/users\/103"}],"version-history":[{"count":6,"href":"https:\/\/www.capgemini.com\/fr-fr\/wp-json\/wp\/v2\/press-release\/667516\/revisions"}],"predecessor-version":[{"id":778287,"href":"https:\/\/www.capgemini.com\/fr-fr\/wp-json\/wp\/v2\/press-release\/667516\/revisions\/778287"}],"wp:attachment":[{"href":"https:\/\/www.capgemini.com\/fr-fr\/wp-json\/wp\/v2\/media?parent=667516"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.capgemini.com\/fr-fr\/wp-json\/wp\/v2\/tags?post=667516"},{"taxonomy":"press-release-type","embeddable":true,"href":"https:\/\/www.capgemini.com\/fr-fr\/wp-json\/wp\/v2\/press-release-type?post=667516"},{"taxonomy":"brand","embeddable":true,"href":"https:\/\/www.capgemini.com\/fr-fr\/wp-json\/wp\/v2\/brand?post=667516"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}