{"id":531645,"date":"2021-09-16T10:42:00","date_gmt":"2021-09-16T10:42:00","guid":{"rendered":"https:\/\/www.capgemini.com\/es-es\/?post_type=press-release&#038;p=531645"},"modified":"2025-03-12T09:17:40","modified_gmt":"2025-03-12T08:17:40","slug":"world-insurtech-report-2021","status":"publish","type":"press-release","link":"https:\/\/www.capgemini.com\/es-es\/noticias\/notas-de-prensa\/world-insurtech-report-2021\/","title":{"rendered":"World InsurTech Report 2021"},"content":{"rendered":"\n<p><\/p>\n\n\n\t\t<div class=\"wp-block-cg-blocks-hero-press-release\">\n\t\t\t<header class=\"header-hero-press-release\" role=\"main\" id=\"main-content-press-release\">\n\t\t\t\t<div class=\"container\">\n\t\t\t\t\t<div class=\"hero-press-release\">\n\t\t\t\t\t\t<div class=\"hero-press-release-content-wrapper\">\n\t\t\t\t\t\t\t<div class=\"row\">\n\t\t\t\t\t\t\t\t<div class=\"col-12\">\n\t\t\t\t\t\t\t\t\t<div class=\"header-title\">\n\t\t\t\t\t\t\t\t\t\t<h1>\n\t\t\t\t\t\t\t\t\t\t\tWorld InsurTech Report 2021\t\t\t\t\t\t\t\t\t\t<\/h1>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"header-description\">\n\t\t\t\t\t\t\t\t\t\t<p><\/p>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"header-date\">\n\t\t\t\t\t\t\t\t\t\t<span>sept. 16, 2021<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"hero-press-release-downloads\">\n\t\t\t\t\t\t\t\t<div class=\"row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-12 col-md-6 col-lg-3\">\n\t\t\t\t\t\t\t\t\t\t\t<a class=\"download-item\" type=\"download\" href=\"https:\/\/www.capgemini.com\/es-es\/wp-content\/uploads\/sites\/16\/2022\/12\/NP-Informe-Mundial-de-InsurTech-2021-El-acceso-preferencial-a-la-inversion-de-capital-impulsa-la-madurez-de-InsurTech-y-BigTech.pdf\" target=\"_blank\" rel=\"noopener noreferrer\" title=\"Abrir en una nueva ventana\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"download-icon\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"download-details\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"download-title\">Download press release<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"download-props\">124 KB  pdf<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"hero-press-release-brand-image\">\n\t\t\t\t\t\t\t\t<img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.capgemini.com\/es-es\/wp-content\/themes\/capgemini2025\/assets\/images\/capgemini-white.svg\" alt=\"Logo\" \/>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/header>\n\t\t<\/div>\n\t\t\n\n\n<section class=\"wp-block-cg-blocks-group undefined section section--article-content\"><div class=\"article-main-content\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-md-1\"><nav class=\"article-social\"><ul class=\"social-nav\"><li class=\"ip-order-fb\"><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https:\/\/www.capgemini.com\/es-es\/?post_type=press-release&amp;p=531645\" target=\"_blank\" rel=\"noopener noreferrer\" title=\"abrir en una nueva ventana\"><i aria-hidden=\"true\" class=\"icon-fb\"><\/i><span class=\"sr-only\">Facebook<\/span><\/a><\/li><li class=\"ip-order-tw\"><a href=\"https:\/\/twitter.com\/intent\/tweet?url=https:\/\/www.capgemini.com\/es-es\/?post_type=press-release&amp;p=531645&amp;text=\" target=\"_blank\" rel=\"noopener noreferrer\" title=\"abrir en una nueva ventana\"><i aria-hidden=\"true\" class=\"icon-tw\"><\/i><span class=\"sr-only\">Twitter<\/span><\/a><\/li><li class=\"ip-order-li\"><a href=\"https:\/\/www.linkedin.com\/sharing\/share-offsite\/?url=https:\/\/www.capgemini.com\/es-es\/?post_type=press-release&amp;p=531645&amp;text=\" target=\"_blank\" rel=\"noopener noreferrer\" title=\"abrir en una nueva ventana\"><i aria-hidden=\"true\" class=\"icon-li\"><\/i><span class=\"sr-only\">Linkedin<\/span><\/a><\/li><\/ul><\/nav><\/div><div class=\"col-12 col-md-11 col-lg-10\"><div class=\"article-text article-quote-text\">\n<p><em>Por primera vez, el 50% de los clientes de seguros est\u00e1 dispuesto a considerar la cobertura de los nuevos actores digitales, mientras los operadores tradicionales buscan asociaciones estrat\u00e9gicas para seguir siendo competitivos.<\/em><\/p>\n\n\n\n<p><strong>Madrid, 16 de septiembre de 2021-<\/strong> El <a href=\"http:\/\/www.worldinsurtechreport.com\/\">Informe Mundial de InsurTech 2021<\/a> de <a href=\"https:\/\/www.capgemini.com\/es-es\/\">Capgemini<\/a> y <a href=\"https:\/\/www.efma.com\/\">Efma<\/a>, publicado hoy, revela que las InsurTechs y los actores de BigTech est\u00e1n aprovechando importantes entradas de capital para impulsar el desarrollo tecnol\u00f3gico y alimentar la innovaci\u00f3n, aumentando la presi\u00f3n sobre las aseguradoras tradicionales. Los actores digitales de la nueva era est\u00e1n ofreciendo una mayor personalizaci\u00f3n y haciendo hincapi\u00e9 en la experiencia del cliente, logrando as\u00ed la madurez y la adopci\u00f3n por parte de los clientes. En respuesta, las aseguradoras tradicionales intentan reforzar sus capacidades tecnol\u00f3gicas asoci\u00e1ndose o adquiriendo InsurTechs y pasando de \u201chacer digital\u201d a \u201cser digital\u201d.<\/p>\n\n\n\n<p>Seg\u00fan el informe, las grandes compa\u00f1\u00edas tecnol\u00f3gicas y las InsurTechs se han asegurado un acceso preferencial a la asignaci\u00f3n de capital por parte de los inversores y est\u00e1n reforzando sus capacidades digitales, aumentando su posici\u00f3n como l\u00edderes en innovaci\u00f3n. Entre 2018-2020, las 5 mayores empresas tecnol\u00f3gicas y un famoso fabricante de autom\u00f3viles que ofrece servicios de seguros sumaron casi 2,5 veces la capitalizaci\u00f3n total del mercado de las 30 mayores aseguradoras a nivel mundial en 2020<a href=\"#_ftn1\" id=\"_ftnref1\"><sup>[1]<\/sup><\/a>. A finales de 2020, la capitalizaci\u00f3n de mercado total de las InsurTechs cotizadas super\u00f3 los 22.000 millones de d\u00f3lares<a href=\"#_ftn2\" id=\"_ftnref2\"><sup>[2]<\/sup><\/a>. Las InsurTechs se est\u00e1n convirtiendo r\u00e1pidamente en el objeto de deseo de muchos inversores, cuyo apoyo favorece y posibilita la circulaci\u00f3n del capital de una manera fluida y constante. Los inversores de capital riesgo oportunistas y los socios de capital privado est\u00e1n desplegando el capital de la fase inicial. Por su parte, las reaseguradoras desempe\u00f1an activamente dos funciones fundamentales: capacitar a las Insurtechs mediante inversiones y proporcionar capacidades de suscripci\u00f3n esenciales.<\/p>\n\n\n\n<p><strong><em>\u201cCARE\u201d<\/em><\/strong><strong> se convierte en el ingrediente secreto del sector<\/strong><\/p>\n\n\n\n<p>La pandemia de COVID-19 cataliz\u00f3 la intenci\u00f3n de los clientes de comprar un seguro (aument\u00f3 un 7%) y cada vez m\u00e1s, los asegurados gravitan hacia las aseguradoras que ofrecen un mejor \u201cCARE\u201d<a href=\"#_ftn3\" id=\"_ftnref3\"><sup>[3]<\/sup><\/a>, donde la conveniencia, el asesoramiento y el alcance son el centro del dise\u00f1o y la evaluaci\u00f3n de la eficacia de su viaje del cliente. Hoy en d\u00eda, los asegurados ya no dudan a la hora de abandonar un proveedor en busca de soluciones CARE m\u00e1s relevantes. Por primera vez, el 50% de los clientes est\u00e1 dispuesto a considerar la cobertura de un actor de la nueva era.<\/p>\n\n\n\n<p><strong>Las tecnolog\u00edas digitales marcan la diferencia para los actores de la nueva era con abundante capital de inversi\u00f3n<\/strong><\/p>\n\n\n\n<p>Las InsurTechs est\u00e1n aprovechando la afluencia de capital de los inversores para mejorar a\u00fan m\u00e1s sus ofertas de CARE a trav\u00e9s de tecnolog\u00edas digitales, incluyendo la IA\/modelo predictivo, an\u00e1lisis de datos avanzados, API\/seguro abierto e IoT\/dispositivos conectados. Las InsurTechs son conscientes de las expectativas de los clientes y, aunque la comodidad ha estado en el centro de las propuestas InsurTech durante alg\u00fan tiempo, las prioridades est\u00e1n cambiando ahora hacia el alcance. Aunque los operadores tradicionales est\u00e1n experimentando claros desaf\u00edos en materia de datos y an\u00e1lisis (s\u00f3lo una cuarta parte de las aseguradoras conf\u00eda en sus capacidades de manejo de datos), no est\u00e1n de brazos cruzados. Para sortear y superar estas limitaciones, muchas aseguradoras tradicionales est\u00e1n comprando y asoci\u00e1ndose con actores digitales de la nueva era para mejorar sus capacidades y su propuesta de valor como parte de la ecuaci\u00f3n CARE, con un enfoque especial en el alcance.<\/p>\n\n\n\n<p><em>\u201cEl sector de los seguros est\u00e1 evolucionando, la palabra clave para su futuro es la modularidad. Las aseguradoras deben estar preparadas para afrontar una amplia gama de escenarios futuros. Las ofertas, los sistemas y las estructuras organizativas modulares ser\u00e1n indispensables para crear un cambio de valor s\u00f3lido y con capacidad de respuesta. En los pr\u00f3ximos a\u00f1os, los actores del sector se definir\u00e1n por su fuerza dentro de una cadena de valor hiperespecializada, y las aseguradoras se convertir\u00e1n cada vez m\u00e1s en orquestadoras\u201d,<\/em> explica Anirban Bose, Director General de Servicios Financieros de Capgemini y miembro del Consejo Ejecutivo del Grupo.<\/p>\n\n\n\n<p>Los seguros est\u00e1n pasando de la venta de productos a la atenci\u00f3n y protecci\u00f3n de los clientes, y a medida que se desdibujan las l\u00edneas entre los participantes en el sector de los seguros, el informe predice la aparici\u00f3n de dos escenarios posibilitados por el acceso continuo al capital:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li><strong>El seguro integrado como valor a\u00f1adido en los ecosistemas de terceros<\/strong>: La cobertura se integra en el punto de venta o en el punto de servicio, haci\u00e9ndose pr\u00e1cticamente invisible. El modelo de negocio evoluciona hacia una propuesta B2B2C, en la que los socios del ecosistema controlan las relaciones con los clientes.<\/li>\n\n\n\n<li><strong>Valor a\u00f1adido en el centro de las ofertas complejas<\/strong>: Las aseguradoras pasan de vender productos a cuidar a los clientes mediante propuestas de predicci\u00f3n y prevenci\u00f3n habilitadas por la IA y la anal\u00edtica.<\/li>\n<\/ol>\n\n\n\n<p>Seg\u00fan John Berry, Director General de Efma: <em>\u201cA medida que las aseguradoras tradicionales ampl\u00edan sus ecosistemas para seguir siendo competitivas, deben considerar cada vez m\u00e1s el valor que se puede conseguir a trav\u00e9s de socios de confianza, incluyendo BigTechs, InsurTechs y actores no tradicionales como los fabricantes de equipos originales (OEMs). Las cifras sugieren claramente que el crecimiento exponencial de las InsurTech ha llegado para quedarse, por lo que ofrecer una atenci\u00f3n superior al cliente es esencial. El \u00e9xito futuro del sector depender\u00e1 de las capacidades existentes de los actores en toda la cadena de valor, de su voluntad de invertir y de su deseo de apropiarse de la relaci\u00f3n con el cliente\u201d<\/em>.<\/p>\n\n\n\n<p><strong>Metodolog\u00eda del informe<\/strong><\/p>\n\n\n\n<p>El Informe Mundial de InsurTech (WITR) 2021 se basa en los conocimientos de investigaci\u00f3n de numerals encuestas, mesas redondas y entrevistas: <em>World InsurTech Report 2021 Roundtable Discussions<\/em>, <em>World InsurTech Report 2020-2021 Executive Interviews<\/em>, <em>2020 Global Insurance Executive Interviews<\/em>, <em>2020-2021 Global Insurance Voice of the Customer Survey<\/em>, <em>Capgemini COVID-19 Consumer Survey 2021<\/em>, C<em>apgemini InsurTech Landscape Study 2020-2021<\/em>, <em>2021 InsurTech partnership and analytics analysis<\/em>. El informe incluye un an\u00e1lisis de m\u00e1s de 900 <em>InsurTechs<\/em> centradas en Estados Unidos y Europa, divididas en tres grandes categor\u00edas como portadores completos, distribuidores y facilitadores. El an\u00e1lisis extrae informaci\u00f3n sobre la tasa de crecimiento de <em>InsurTech<\/em> entre 2020-2021 y la financiaci\u00f3n obtenida para el periodo 2020-2021.<\/p>\n\n\n\n<p><strong>Acerca de Capgemini<\/strong><\/p>\n\n\n\n<p>Capgemini es un l\u00edder mundial que acompa\u00f1a a las empresas para transformar y gestionar su negocio aprovechando el poder de la tecnolog\u00eda. El Grupo se gu\u00eda cada d\u00eda por su prop\u00f3sito de liberar la energ\u00eda humana a trav\u00e9s de la tecnolog\u00eda para construir un futuro inclusivo y sostenible. Es una organizaci\u00f3n responsable y diversa que cuenta con 290.000 profesionales en cerca de 50 pa\u00edses. Con una s\u00f3lida trayectoria de 50 a\u00f1os y su gran conocimiento sectorial, Capgemini es reconocida por sus clientes por la capacidad de respuesta a las necesidades de su negocio, desde la estrategia y el dise\u00f1o hasta la gesti\u00f3n de operaciones, todo ello impulsado por la innovaci\u00f3n en \u00e1reas como el Cloud, los datos, la IA, la conectividad, el software y las plataformas y entornos digitales. En 2020, el Grupo registr\u00f3 unos ingresos globales de 16.000 millones de euros.<\/p>\n\n\n\n<p>GET THE FUTURE YOU WANT \u2013&nbsp; <a href=\"http:\/\/www.capgemini.com\/es-es\">www.capgemini.com\/es-es<\/a><\/p>\n\n\n\n<p><strong>Acerca de la Efma<\/strong><\/p>\n\n\n\n<p>Organizaci\u00f3n mundial sin \u00e1nimo de lucro creada en 1971 por bancos y compa\u00f1\u00edas de seguros, Efma facilita la creaci\u00f3n de redes entre los responsables de la toma de decisiones. Proporciona informaci\u00f3n de calidad para ayudar a los bancos y compa\u00f1\u00edas de seguros a tomar las decisiones correctas para fomentar la innovaci\u00f3n e impulsar su transformaci\u00f3n. 120 grupos financieros de 133 pa\u00edses son miembros de Efma. Con sede en Par\u00eds. Oficinas en Londres, Bruselas, Andorra, Mil\u00e1n, Estocolmo, Bratislava, Varsovia, Mosc\u00fa, Estambul, Beirut, Dubai, Tokio, Singapur, Sidney y Montreal.<\/p>\n\n\n\n<p>Para saber m\u00e1s: <a href=\"https:\/\/www.efma.com\/\">https:\/\/www.efma.com\/<\/a><\/p>\n\n\n\n<p><a href=\"#_ftnref1\" id=\"_ftn1\">[1]<\/a> An\u00e1lisis financiero de Capgemini basado en datos de <a href=\"https:\/\/finance.yahoo.com\/\">Yahoo Finance<\/a> y <a href=\"https:\/\/companiesmarketcap.com\/\">CompaniesMarketCap<\/a>.<\/p>\n\n\n\n<p><a href=\"#_ftnref2\" id=\"_ftn2\">[2]<\/a> An\u00e1lisis financiero de Capgemini basado en datos de <a href=\"https:\/\/companiesmarketcap.com\/\">CompaniesMarketCap<\/a>.<\/p>\n\n\n\n<p><a href=\"#_ftnref3\" id=\"_ftn3\">[3]<\/a> C: Los clientes quieren una <strong>conveniencia <\/strong>24 horas al d\u00eda, 7 d\u00edas a la semana \u2013 tiempo de respuesta r\u00e1pido y acceso multicanal a la informaci\u00f3n de la p\u00f3liza y a la gesti\u00f3n de la cuenta. A: Los clientes quieren un <strong>asesoramiento <\/strong>personalizado: productos adaptados a sus necesidades, as\u00ed como la posibilidad de gestionar su perfil de riesgo a lo largo del ciclo de vida de su p\u00f3liza. RE: Los clientes esperan que las aseguradoras se pongan en <strong>contacto<\/strong> con ellos y se comprometan de forma significativa seg\u00fan sus preferencias, por ejemplo, mediante propuestas de prevenci\u00f3n de riesgos o la capacidad de ofrecer una asistencia no intrusiva en momentos de necesidad.<\/p>\n\n\n<div class=\"wp-block-cg-blocks-cg-block-related-content\"><section class=\"relatedContentBlock\"><div class=\"container\"><div class=\"row\"><div class=\"content-title col-12 col-md-8\"><h2 class=\"related-content-heading\">Related News<\/h2><\/div><\/div><div class=\"row relatedContent\"><div class=\"col-lg-4 col-md-6 col-xs-12\">\n\t\t\t\t\t\t\t<div class=\"box\">\n\t\t\t\t\t\t\t\t<a aria-label=\"Saber m\u00e1s sobre La IA acelera la demanda de electricidad e impulsa una nueva ola de adaptaci\u00f3n e inversi\u00f3n en las redes el\u00e9ctricas\" href=\"https:\/\/www.capgemini.com\/es-es\/noticias\/notas-de-prensa\/la-ia-acelera-la-demanda-de-electricidad-e-impulsa-una-nueva-ola-de-adaptacion-e-inversion-en-las-redes-electricas\/\" class=\"anchorWrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"box-tag\"><span>Reports<\/span><\/span>\n\t\t\t\t\t\t\t\t\t<div class=\"box-title\"><h3 class=\"box-subtitle\">La IA acelera la demanda de electricidad e impulsa una nueva ola de adaptaci\u00f3n e inversi\u00f3n en las redes el\u00e9ctricas<\/h3><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"box-date\">\n\t\t\t\t\t\t\t\t\t\t<span>Jun 30, 2026<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"box-bottom\">\n\t\t\t\t\t\t\t\t\t\t&lt;a class=&quot;link-download&quot; href=&quot;https:\/\/www.capgemini.com\/es-es\/wp-content\/uploads\/sites\/16\/2026\/06\/NP-La-IA-acelera-la-demanda-de-electricidad.pdf&quot; aria-label=&quot;Download Press Release&quot; target=&quot;_blank&quot;  type=&quot;download&quot; title=&quot;Opens in a new window&quot;&gt;\n\t\t\t\t\t\t\t&lt;span&gt;Descargar nota de prensa&lt;\/span&gt;\n\t\t\t\t\t\t\t&lt;span&gt;157 KB PDF&lt;\/span&gt;\n\t\t\t\t\t\t&lt;\/a&gt;\n\t\t\t\t\t\t\t\t\t\t<a class=\"more\" aria-label=\"Saber m\u00e1s sobre La IA acelera la demanda de electricidad e impulsa una nueva ola de adaptaci\u00f3n e inversi\u00f3n en las redes el\u00e9ctricas\" href=\"https:\/\/www.capgemini.com\/es-es\/noticias\/notas-de-prensa\/la-ia-acelera-la-demanda-de-electricidad-e-impulsa-una-nueva-ola-de-adaptacion-e-inversion-en-las-redes-electricas\/\">Saber m\u00e1s sobre<\/a>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div><div class=\"col-lg-4 col-md-6 col-xs-12\">\n\t\t\t\t\t\t\t<div class=\"box\">\n\t\t\t\t\t\t\t\t<a aria-label=\"Saber m\u00e1s sobre La poblaci\u00f3n mundial de millonarios aumenta en casi 2 millones en 2025, impulsada por el s\u00f3lido desempe\u00f1o de los mercados burs\u00e1tiles en todo el mundo\" href=\"https:\/\/www.capgemini.com\/es-es\/noticias\/notas-de-prensa\/poblacion-mundial-millonarios-aumenta-casi-2-millones-en-2025\/\" class=\"anchorWrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"box-tag\"><span>Reports<\/span><\/span>\n\t\t\t\t\t\t\t\t\t<div class=\"box-title\"><h3 class=\"box-subtitle\">La poblaci\u00f3n mundial de millonarios aumenta en casi 2 millones en 2025, impulsada por el s\u00f3lido desempe\u00f1o de los mercados burs\u00e1tiles en todo el mundo<\/h3><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"box-date\">\n\t\t\t\t\t\t\t\t\t\t<span>Jun 4, 2026<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"box-bottom\">\n\t\t\t\t\t\t\t\t\t\t&lt;a class=&quot;link-download&quot; href=&quot;https:\/\/www.capgemini.com\/es-es\/wp-content\/uploads\/sites\/16\/2026\/06\/NP_WWR22026.pdf&quot; aria-label=&quot;Download Press Release&quot; target=&quot;_blank&quot;  type=&quot;download&quot; title=&quot;Opens in a new window&quot;&gt;\n\t\t\t\t\t\t\t&lt;span&gt;Descargar nota de prensa&lt;\/span&gt;\n\t\t\t\t\t\t\t&lt;span&gt;154 KB PDF&lt;\/span&gt;\n\t\t\t\t\t\t&lt;\/a&gt;\n\t\t\t\t\t\t\t\t\t\t<a class=\"more\" aria-label=\"Saber m\u00e1s sobre La poblaci\u00f3n mundial de millonarios aumenta en casi 2 millones en 2025, impulsada por el s\u00f3lido desempe\u00f1o de los mercados burs\u00e1tiles en todo el mundo\" href=\"https:\/\/www.capgemini.com\/es-es\/noticias\/notas-de-prensa\/poblacion-mundial-millonarios-aumenta-casi-2-millones-en-2025\/\">Saber m\u00e1s sobre<\/a>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div><div class=\"col-lg-4 col-md-6 col-xs-12\">\n\t\t\t\t\t\t\t<div class=\"box\">\n\t\t\t\t\t\t\t\t<a aria-label=\"Saber m\u00e1s sobre El momento de la verdad de la IA en seguros No-Vida: los pioneros ven un crecimiento de ingresos un 21% mayor mientras el resto de la industria se queda atr\u00e1s\" href=\"https:\/\/www.capgemini.com\/es-es\/noticias\/notas-de-prensa\/el-momento-de-la-verdad-de-la-ia-en-seguros-no-vida-2026\/\" class=\"anchorWrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"box-tag\"><span>Reports<\/span><\/span>\n\t\t\t\t\t\t\t\t\t<div class=\"box-title\"><h3 class=\"box-subtitle\">El momento de la verdad de la IA en seguros No-Vida: los pioneros ven un crecimiento de ingresos un 21% mayor mientras el resto de la industria se queda atr\u00e1s<\/h3><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"box-date\">\n\t\t\t\t\t\t\t\t\t\t<span>May 19, 2026<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"box-bottom\">\n\t\t\t\t\t\t\t\t\t\t&lt;a class=&quot;link-download&quot; href=&quot;https:\/\/www.capgemini.com\/es-es\/wp-content\/uploads\/sites\/16\/2026\/05\/NP-El-momento-de-la-verdad-de-la-IA-en-seguros-No-Vida.pdf&quot; aria-label=&quot;Download Press Release&quot; target=&quot;_blank&quot;  type=&quot;download&quot; title=&quot;Opens in a new window&quot;&gt;\n\t\t\t\t\t\t\t&lt;span&gt;Descargar nota de prensa&lt;\/span&gt;\n\t\t\t\t\t\t\t&lt;span&gt;175 KB PDF&lt;\/span&gt;\n\t\t\t\t\t\t&lt;\/a&gt;\n\t\t\t\t\t\t\t\t\t\t<a class=\"more\" aria-label=\"Saber m\u00e1s sobre El momento de la verdad de la IA en seguros No-Vida: los pioneros ven un crecimiento de ingresos un 21% mayor mientras el resto de la industria se queda atr\u00e1s\" href=\"https:\/\/www.capgemini.com\/es-es\/noticias\/notas-de-prensa\/el-momento-de-la-verdad-de-la-ia-en-seguros-no-vida-2026\/\">Saber m\u00e1s sobre<\/a>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div><\/div><\/div><\/section><\/div><\/div><\/div><\/div><\/div><\/div><\/section>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":336,"featured_media":0,"template":"","meta":{"cg_dt_proposed_to":[],"cg_seo_hreflang_relations":"[]","cg_seo_canonical_relation":"","cg_seo_hreflang_x_default_relation":"","cg_dt_approved_content":true,"cg_dt_mandatory_content":false,"cg_dt_notes":"","cg_dg_source_changed":false,"cg_dt_link_disabled":false,"footnotes":"","related_resource_url":"https:\/\/www.capgemini.com\/es-es\/wp-content\/uploads\/sites\/16\/2022\/12\/NP-Informe-Mundial-de-InsurTech-2021-El-acceso-preferencial-a-la-inversion-de-capital-impulsa-la-madurez-de-InsurTech-y-BigTech.pdf","related_resource_id":531646,"related_resource_size":"124 KB","related_resource_type":"pdf","cg_author":0,"featured_focal_points":""},"tags":[],"press-release-type":[58,87],"brand":[30],"class_list":["post-531645","press-release","type-press-release","status-publish","hentry","press-release-type-financial-report","press-release-type-reports","brand-capgemini"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.8 (Yoast SEO v22.8) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>World InsurTech Report 2021 - Capgemini Spain<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.capgemini.com\/es-es\/noticias\/notas-de-prensa\/world-insurtech-report-2021\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"World InsurTech Report 2021\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.capgemini.com\/es-es\/noticias\/notas-de-prensa\/world-insurtech-report-2021\/\" \/>\n<meta property=\"og:site_name\" content=\"Capgemini Spain\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-12T08:17:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.capgemini.com\/es-es\/wp-json\/wp\/v2\/press-release\/531645\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"627\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.capgemini.com\/es-es\/noticias\/notas-de-prensa\/world-insurtech-report-2021\/\",\"url\":\"https:\/\/www.capgemini.com\/es-es\/noticias\/notas-de-prensa\/world-insurtech-report-2021\/\",\"name\":\"World InsurTech Report 2021 - Capgemini Spain\",\"isPartOf\":{\"@id\":\"https:\/\/www.capgemini.com\/es-es\/#website\"},\"datePublished\":\"2021-09-16T10:42:00+00:00\",\"dateModified\":\"2025-03-12T08:17:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.capgemini.com\/es-es\/noticias\/notas-de-prensa\/world-insurtech-report-2021\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.capgemini.com\/es-es\/noticias\/notas-de-prensa\/world-insurtech-report-2021\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.capgemini.com\/es-es\/noticias\/notas-de-prensa\/world-insurtech-report-2021\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.capgemini.com\/es-es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"World InsurTech Report 2021\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.capgemini.com\/es-es\/#website\",\"url\":\"https:\/\/www.capgemini.com\/es-es\/\",\"name\":\"Capgemini Espa\u00f1a\",\"description\":\"Capgemini\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.capgemini.com\/es-es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es-ES\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"World InsurTech Report 2021 - Capgemini Spain","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.capgemini.com\/es-es\/noticias\/notas-de-prensa\/world-insurtech-report-2021\/","og_locale":"es_ES","og_type":"article","og_title":"World InsurTech Report 2021","og_url":"https:\/\/www.capgemini.com\/es-es\/noticias\/notas-de-prensa\/world-insurtech-report-2021\/","og_site_name":"Capgemini Spain","article_modified_time":"2025-03-12T08:17:40+00:00","og_image":[{"width":1200,"height":627,"url":"https:\/\/www.capgemini.com\/es-es\/wp-json\/wp\/v2\/press-release\/531645","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.capgemini.com\/es-es\/noticias\/notas-de-prensa\/world-insurtech-report-2021\/","url":"https:\/\/www.capgemini.com\/es-es\/noticias\/notas-de-prensa\/world-insurtech-report-2021\/","name":"World InsurTech Report 2021 - Capgemini Spain","isPartOf":{"@id":"https:\/\/www.capgemini.com\/es-es\/#website"},"datePublished":"2021-09-16T10:42:00+00:00","dateModified":"2025-03-12T08:17:40+00:00","breadcrumb":{"@id":"https:\/\/www.capgemini.com\/es-es\/noticias\/notas-de-prensa\/world-insurtech-report-2021\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.capgemini.com\/es-es\/noticias\/notas-de-prensa\/world-insurtech-report-2021\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.capgemini.com\/es-es\/noticias\/notas-de-prensa\/world-insurtech-report-2021\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.capgemini.com\/es-es\/"},{"@type":"ListItem","position":2,"name":"World InsurTech Report 2021"}]},{"@type":"WebSite","@id":"https:\/\/www.capgemini.com\/es-es\/#website","url":"https:\/\/www.capgemini.com\/es-es\/","name":"Capgemini Espa\u00f1a","description":"Capgemini","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.capgemini.com\/es-es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es-ES"}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/capgemini.com\/es-es\/noticias\/notas-de-prensa\/world-insurtech-report-2021\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"World InsurTech Report 2021","url":"https:\/\/www.capgemini.com\/es-es\/noticias\/notas-de-prensa\/world-insurtech-report-2021\/","mainEntityOfPage":{"@type":"WebPage","@id":"https:\/\/www.capgemini.com\/es-es\/noticias\/notas-de-prensa\/world-insurtech-report-2021\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Uncategorized","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Capgemini Spain","logo":""},"keywords":[],"dateCreated":"2021-09-16T10:42:00Z","datePublished":"2021-09-16T10:42:00Z","dateModified":"2025-03-12T08:17:40Z"},"rendered":"<meta name=\"parsely-title\" content=\"World InsurTech Report 2021\" \/>\n<meta name=\"parsely-link\" content=\"https:\/\/www.capgemini.com\/es-es\/noticias\/notas-de-prensa\/world-insurtech-report-2021\/\" \/>\n<meta name=\"parsely-type\" content=\"post\" \/>\n<meta name=\"parsely-pub-date\" content=\"2021-09-16T10:42:00Z\" \/>\n<meta name=\"parsely-section\" content=\"Uncategorized\" \/>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/capgemini.com\/p.js"},"archive_status":false,"featured_image_src":"https:\/\/www.capgemini.com\/es-es\/wp-content\/themes\/capgemini2025\/assets\/images\/mockup.png","featured_image_alt":false,"jetpack_sharing_enabled":true,"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"Capgemini Spain","distributor_original_site_url":"https:\/\/www.capgemini.com\/es-es","push-errors":false,"tag_names":[],"_links":{"self":[{"href":"https:\/\/www.capgemini.com\/es-es\/wp-json\/wp\/v2\/press-release\/531645","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.capgemini.com\/es-es\/wp-json\/wp\/v2\/press-release"}],"about":[{"href":"https:\/\/www.capgemini.com\/es-es\/wp-json\/wp\/v2\/types\/press-release"}],"author":[{"embeddable":true,"href":"https:\/\/www.capgemini.com\/es-es\/wp-json\/wp\/v2\/users\/336"}],"version-history":[{"count":2,"href":"https:\/\/www.capgemini.com\/es-es\/wp-json\/wp\/v2\/press-release\/531645\/revisions"}],"predecessor-version":[{"id":568369,"href":"https:\/\/www.capgemini.com\/es-es\/wp-json\/wp\/v2\/press-release\/531645\/revisions\/568369"}],"wp:attachment":[{"href":"https:\/\/www.capgemini.com\/es-es\/wp-json\/wp\/v2\/media?parent=531645"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.capgemini.com\/es-es\/wp-json\/wp\/v2\/tags?post=531645"},{"taxonomy":"press-release-type","embeddable":true,"href":"https:\/\/www.capgemini.com\/es-es\/wp-json\/wp\/v2\/press-release-type?post=531645"},{"taxonomy":"brand","embeddable":true,"href":"https:\/\/www.capgemini.com\/es-es\/wp-json\/wp\/v2\/brand?post=531645"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}