{"id":562518,"date":"2024-10-01T16:23:23","date_gmt":"2024-10-01T14:23:23","guid":{"rendered":"https:\/\/www.capgemini.com\/es-es\/?p=562518"},"modified":"2025-03-11T08:21:11","modified_gmt":"2025-03-11T07:21:11","slug":"aumentando-la-percepcion-del-vehiculo-el-proyecto-inpercept","status":"publish","type":"post","link":"https:\/\/www.capgemini.com\/es-es\/investigacion\/perspectivas-de-expertos\/aumentando-la-percepcion-del-vehiculo-el-proyecto-inpercept\/","title":{"rendered":"Aumentando la percepci\u00f3n del veh\u00edculo: el proyecto INPERCEPT"},"content":{"rendered":"\n<header class=\"wp-block-cg-blocks-hero-blogs header-hero-blogs\"><div class=\"container\"><div class=\"hero-blogs\"><div class=\"hero-blogs-content-wrapper\"><div class=\"row\"><div class=\"col-12\"><div class=\"header-title\"><h1>Aumentando la percepci\u00f3n del veh\u00edculo: el proyecto INPERCEPT<\/h1><\/div><\/div><\/div><\/div><div class=\"hero-blogs-bottom\"><div class=\"header-author\"><div class=\"author-img\"><img decoding=\"async\" src=\"https:\/\/www.capgemini.com\/es-es\/wp-content\/uploads\/sites\/16\/2021\/06\/cg-logo.png?w=200&amp;quality=10\" alt=\"\" loading=\"lazy\"\/><\/div><div class=\"author-name-date\"><h5 class=\"author-name\">Henry Portilla \/ Jaime Santiago \/ Jorge Pinazo<\/h5><h5 class=\"blog-date\">1 de octubre de 2024<\/h5><\/div><\/div><div class=\"brand-image\"><img decoding=\"async\" loading=\"lazy\" src=\"\/wp-content\/themes\/capgemini2020\/assets\/images\/capgemini-engineering-white.svg\" alt=\"capgemini-engineering\"\/><\/div><\/div><\/div><\/div><\/header>\n\n\n\n<section class=\"wp-block-cg-blocks-intro-para undefined section section--intro\"><div class=\"intro-para\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-md-1\"><nav class=\"article-social\"><ul class=\"social-nav\"><li class=\"ip-order-fb\"><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https:\/\/www.capgemini.com\/es-es\/investigacion\/perspectivas-de-expertos\/aumentando-la-percepcion-del-vehiculo-el-proyecto-inpercept\/\" target=\"_blank\" rel=\"noopener noreferrer\" title=\"abrir en una nueva ventana\"><i aria-hidden=\"true\" class=\"icon-fb\"><\/i><span class=\"sr-only\">Facebook<\/span><\/a><\/li><li class=\"ip-order-li\"><a href=\"https:\/\/www.linkedin.com\/sharing\/share-offsite\/?url=https:\/\/www.capgemini.com\/es-es\/investigacion\/perspectivas-de-expertos\/aumentando-la-percepcion-del-vehiculo-el-proyecto-inpercept\/\" target=\"_blank\" rel=\"noopener noreferrer\" title=\"abrir en una nueva ventana\"><i aria-hidden=\"true\" class=\"icon-li\"><\/i><span class=\"sr-only\">Linkedin<\/span><\/a><\/li><\/ul><\/nav><\/div><div class=\"col-12 col-md-11 col-lg-10\"><h2 class=\"intro-para-title\">Este art\u00edculo explora las relaciones entre la arquitectura tradicional prevalente en muchos fabricantes de autom\u00f3viles a nivel mundial y las nuevas tendencias basadas en software que promueven una arquitectura conectada y definida por software (<strong>Software Defined Vehicle<\/strong>, SDV). Dentro de esta \u00faltima tendencia se encuentra INPERCEPT, un proyecto que aprovecha las nuevas capacidades de esta arquitectura para incorporar sensores avanzados e inteligencia artificial distribuida al veh\u00edculo e implementar funciones de conducci\u00f3n cooperativa a trav\u00e9s de V2X.\u00a0\u00a0<\/h2><\/div><\/div><\/div><\/div><\/section>\n\n\n\n<section class=\"wp-block-cg-blocks-group undefined section section--article-content\"><div class=\"article-main-content\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-md-11 col-lg-10 offset-md-1 offset-lg-1\"><div class=\"article-text article-quote-text\">\n<h3 class=\"wp-block-heading\" id=\"h-vehiculos-definidos-por-software\">Veh\u00edculos definidos por software<\/h3>\n\n\n\n<p>Entre las medidas incluidas en la propuesta del Reglamento para <a href=\"https:\/\/digital-strategy.ec.europa.eu\/es\/policies\/european-chips-act\" target=\"_blank\" rel=\"noreferrer noopener\">Ley Europea de Chips<\/a> (Chips Act), la UE busca crear bloques de software estandarizados y establecer interfaces que permitan desacoplar las funciones del software del hardware subyacente, para reducir la dependencia de proveedores espec\u00edficos, asegurar el cumplimiento de las normativas aplicables y facilitar la integraci\u00f3n de hardware de alto rendimiento en los diferentes sectores industriales (rob\u00f3tica, automoci\u00f3n, aeroespacial, ferrocarril, manufactura, etc.).&nbsp;<\/p>\n\n\n\n<p>En este contexto, surgen diferentes iniciativas complementarias para reforzar la soberan\u00eda y el liderazgo de la UE en la cadena de valor del autom\u00f3vil, abordando, por un lado, una plataforma abierta de hardware para autom\u00f3viles y, por otro, un ecosistema abierto para desarrollar los <strong>Veh\u00edculos Definidos por Software (SDV: Software Defined Vehicle)<\/strong> [1].&nbsp;&nbsp;<\/p>\n\n\n\n<p>La industria automotriz est\u00e1 apostando decididamente por este nuevo paradigma, reconociendo el potencial transformador del SDV. Empresas l\u00edderes como <a href=\"https:\/\/www.idtechex.com\/en\/research-article\/teslas-major-recall-shows-the-benefits-of-software-defined-vehicles\/30355\" target=\"_blank\" rel=\"noreferrer noopener\">Tesla<\/a>, <a href=\"https:\/\/www.volkswagen.es\/comunicacion\/grupo-volkswagen\/volkswagen-group-taps-into-new-profit-pools-with-sustainable-mobility\/\" target=\"_blank\" rel=\"noreferrer noopener\">Volkswagen<\/a> y <a href=\"https:\/\/www.gm.com\/stories\/ultifi-talent\" target=\"_blank\" rel=\"noreferrer noopener\">General Motors<\/a> est\u00e1n invirtiendo fuertemente en plataformas y tecnolog\u00edas que permiten una mayor integraci\u00f3n de software en sus veh\u00edculos. Este cambio de enfoque promete no solo mejorar la experiencia del usuario, sino tambi\u00e9n ofrecer nuevas oportunidades de negocio y avances en la seguridad y eficiencia vehicular.&nbsp;<\/p>\n\n\n\n<p>Entre los m\u00faltiples <strong>beneficios<\/strong> de la arquitectura SDV destacan:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Las <strong>actualizaciones en el aire (Over-the-Air<\/strong> Updates; <strong>OTA<\/strong>), es decir, la capacidad del autom\u00f3vil para reconfigurarse descargando software desde la red capaz de alterar el modo de operaci\u00f3n del hardware que lleva embebido. Se aumenta as\u00ed la flexibilidad y las posibilidades de personalizaci\u00f3n del veh\u00edculo, pudiendo incluso activar nuevas funcionalidades bajo demanda (por ejemplo, mejoras en los sistemas de conducci\u00f3n asistida; ADAS), aumentar la inteligencia de los algoritmos que procesan los datos captados por los sensores del veh\u00edculo u optimizar el rendimiento gracias al an\u00e1lisis de los datos operacionales.&nbsp;<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>La <strong>conducci\u00f3n colaborativa<\/strong>, potenciando la conexi\u00f3n entre veh\u00edculos y con la infraestructura (Vehicle-to-Vehicle: V2V, Vehicle to Infrastruture: V2I, Vehicle to Everything: V2X). Disponer de una arquitectura SDV permite adaptar el funcionamiento del hardware del veh\u00edculo a las actualizaciones y mejores de los servicios de conexi\u00f3n con otros elementos del entorno.&nbsp;<\/li>\n<\/ul>\n\n\n\n<p>En definitiva, este nuevo paradigma promete no solo mejorar la experiencia del usuario, sino tambi\u00e9n ofrecer nuevas oportunidades de negocio y avances en la seguridad y eficiencia vehicular.&nbsp;<\/p>\n\n\n\n<p>Aunque la arquitectura SDV ofrece importantes beneficios, debe tambi\u00e9n afrontar m\u00faltiples <strong>desaf\u00edos<\/strong>. En primer lugar, la <strong>seguridad<\/strong> es un aspecto crucial, ya que es necesario asegurar que los sistemas de software sean robustos frente a ciberataques, protegiendo as\u00ed la integridad y funcionamiento del veh\u00edculo. Adem\u00e1s, la <strong>interoperabilidad<\/strong> se presenta como un reto clave, dado que es fundamental garantizar que los diferentes componentes de software y hardware, provenientes de diversos proveedores, funcionen de manera conjunta y sin inconvenientes. Por \u00faltimo, el <strong>cumplimiento de las regulaciones y normativas<\/strong> es otro desaf\u00edo importante, ya que estas var\u00edan considerablemente entre diferentes regiones y mercados, abarcando aspectos de seguridad y emisiones que deben ser respetados para asegurar la viabilidad y aceptaci\u00f3n de estos veh\u00edculos en el \u00e1mbito global.&nbsp;<\/p>\n\n\n\n<p>En los siguientes apartados se comparan las arquitecturas cl\u00e1sicas con las propuestas de SDV y se detalla c\u00f3mo esta arquitectura puede facilitar la conducci\u00f3n colaborativa gracias a las comunicaciones V2X para concluir detallando la forma en que se ha desplegado dicha arquitectura en el proyecto INPERCEPT y los resultados obtenidos en las simulaciones y pruebas de campo realizadas aplicando este paradigma a diferentes casos de uso de conducci\u00f3n colaborativa.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-arquitecturas-tradicionales-de-la-electronica-de-un-vehiculo-nbsp\">Arquitecturas Tradicionales de la Electr\u00f3nica de un veh\u00edculo&nbsp;<\/h3>\n\n\n\n<p>Desde el advenimiento de la primera Unidad de Control Electr\u00f3nico (ECU) en la d\u00e9cada de 1970, estas unidades han sido el pilar fundamental de la arquitectura distribuida predominante en la industria automotriz. En \u00e9sta, cada ECU realiza una funci\u00f3n espec\u00edfica dentro del veh\u00edculo, como el control de frenos, el control del motor, la elevaci\u00f3n de vidrios y las luces, entre otros (ver Figura 1).<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1014\" height=\"495\" src=\"https:\/\/www.capgemini.com\/es-es\/wp-content\/uploads\/sites\/16\/2024\/10\/arquitectura_tradicional_auto.jpg\" alt=\"\" class=\"wp-image-562527\" srcset=\"https:\/\/www.capgemini.com\/es-es\/wp-content\/uploads\/sites\/16\/2024\/10\/arquitectura_tradicional_auto.jpg 1014w, https:\/\/www.capgemini.com\/es-es\/wp-content\/uploads\/sites\/16\/2024\/10\/arquitectura_tradicional_auto.jpg?resize=300,146 300w, https:\/\/www.capgemini.com\/es-es\/wp-content\/uploads\/sites\/16\/2024\/10\/arquitectura_tradicional_auto.jpg?resize=768,375 768w\" sizes=\"auto, (max-width: 1014px) 100vw, 1014px\" \/><figcaption class=\"wp-element-caption\">Figura 1: Arquitectura tradicional automoci\u00f3n. Fuente: Intel [2]<\/figcaption><\/figure>\n\n\n\n<p>Actualmente, un veh\u00edculo puede contar con m\u00e1s de 100 ECU, reflejando la tendencia de a\u00f1adir una nueva unidad ECU por cada nueva funcionalidad requerida en el veh\u00edculo.&nbsp;<\/p>\n\n\n\n<p>Sin embargo, el aumento de la complejidad en los veh\u00edculos, con cada vez m\u00e1s avances tecnol\u00f3gicos y posibilidades en materia de seguridad, confort, entretenimiento a bordo, etc., hace que esta arquitectura tradicional presente varios desaf\u00edos para la industria automotriz:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Aumento del cableado<\/strong>: Cada nueva ECU requiere la adici\u00f3n de cableado de datos y alimentaci\u00f3n, lo que incrementa el peso y el espacio f\u00edsico necesario dentro del veh\u00edculo.&nbsp;<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Componentes electr\u00f3nicos obsoletos<\/strong>: Los microcontroladores de las ECU suelen basarse en tecnolog\u00edas m\u00e1s antiguas en la fabricaci\u00f3n del silicio, como los 90 nm.&nbsp;<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Limitaciones de velocidad<\/strong>: Se utilizan buses de datos antiguos, con velocidades limitadas (8-10 Mbps) o Ethernet con velocidades limitadas.&nbsp;<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Rigidez funcional<\/strong>: Las ECU est\u00e1n dise\u00f1adas y programadas para un \u00fanico prop\u00f3sito, sin posibilidad de reprogramaci\u00f3n o reutilizaci\u00f3n para nuevas funciones.&nbsp;<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Heterogeneidad de proveedores<\/strong>: Cada ECU suele provenir de un proveedor diferente, lo que causa una gran heterogeneidad en la integraci\u00f3n. Adem\u00e1s, estas unidades suelen ser \u201ccajas negras\u201d con una arquitectura cerrada, lo que limita la escalabilidad y evoluci\u00f3n del veh\u00edculo.&nbsp;<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Dependencia de proveedores<\/strong>: La dependencia existente con determinadas ECU pone en riesgo el tiempo de llegada al mercado debido a problemas de fabricaci\u00f3n con ciertos proveedores.&nbsp;<\/li>\n<\/ul>\n\n\n\n<p>Estas limitaciones,&nbsp; que se acent\u00faan con el aumento de la complejidad de las funcionalidades de los nuevos veh\u00edculos, hacen que la arquitectura electr\u00f3nica tradicional se vuelva menos viable tanto desde el punto de vista tecnol\u00f3gico como del econ\u00f3mico.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-arquitectura-sdv-software-defined-vehicle-nbsp\">Arquitectura SDV (Software Defined Vehicle)&nbsp;<\/h3>\n\n\n\n<p>La tecnolog\u00eda y la ciencia avanzan r\u00e1pidamente en pr\u00e1cticamente todos los \u00e1mbitos, y el mundo de la automoci\u00f3n no es la excepci\u00f3n. Nuevos enfoques han irrumpido en la arquitectura tradicional, obligando a una industria hist\u00f3ricamente centrada en la integraci\u00f3n y la ingenier\u00eda de hardware o elementos mec\u00e1nicos, a transformarse en una industria m\u00e1s alineada con el entorno tecnol\u00f3gico de IT y el uso de inteligencia artificial.&nbsp;<\/p>\n\n\n\n<p>Esta transformaci\u00f3n est\u00e1 causando una disrupci\u00f3n en el mercado automotriz y el surgimiento de nuevos actores con enfoques innovadores. Esto incluye el uso de nuevas fuentes de energ\u00eda que son m\u00e1s compatibles con una creciente conciencia ecol\u00f3gica respecto al uso de recursos y las repercusiones ambientales. Adem\u00e1s, los procesos de producci\u00f3n se est\u00e1n volviendo m\u00e1s \u00e1giles, contrastando con el enfoque automotriz tradicional que requer\u00eda a\u00f1os para lanzar nuevos productos al mercado.&nbsp;<\/p>\n\n\n\n<p>A su vez, hay una clara tendencia hacia un mundo hiperconectado, donde los veh\u00edculos se perciben como un escal\u00f3n m\u00e1s en la digitalizaci\u00f3n de nuestro entorno. Esto conlleva y requiere el uso de nuevas tecnolog\u00edas que la arquitectura tradicional no puede manejar debido a las limitaciones en capacidades de comunicaciones y procesamiento, necesarias para la digitalizaci\u00f3n del sector.&nbsp;<\/p>\n\n\n\n<p>Adicionalmente, el sector de la automoci\u00f3n est\u00e1 fuertemente comprometido con aspectos de seguridad, con el fin de proteger a conductores y usuarios, tanto activos como pasivos. Esto ha llevado a la incorporaci\u00f3n de una nueva hornada de elementos o funciones de seguridad que mejoran o incluso reemplazan las funciones de conductores y usuarios, como son los sistemas ADAS o los veh\u00edculos aut\u00f3nomos de diversos niveles.&nbsp;<\/p>\n\n\n\n<p>Los nuevos<strong> Veh\u00edculos Definidos por Software (SDV<\/strong>), vienen a paliar estas limitaciones gracias a:&nbsp;<\/p>\n\n\n\n<p>Una <strong>Arquitectura Centralizada:&nbsp;<\/strong>&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Simplificaci\u00f3n del dise\u00f1o<\/strong>: La arquitectura SDV reduce la complejidad del hardware.&nbsp;<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Unidad central potente y\/o agrupaciones zonales<\/strong>: utiliza un menor n\u00famero de unidades de procesamiento, pero m\u00e1s potentes lo que las permite controlar diversas funciones del autom\u00f3vil simult\u00e1neamente y centralizar la conectividad tanto interna como externa, reduciendo as\u00ed el n\u00famero de ECU y buses de datos instalados en el autom\u00f3vil.&nbsp;<\/li>\n<\/ul>\n\n\n\n<p>Una <strong>Arquitectura Conectada<\/strong>:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Conectividad para actualizaciones (OTA)<\/strong>: Permite actualizar funcionalidades o corregir errores r\u00e1pidamente a trav\u00e9s de actualizaciones de software mediante comunicaciones avanzadas como, por ejemplo, 5G.&nbsp;<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Ampliaci\u00f3n de la conectividad<\/strong>: Permite la comunicaci\u00f3n con otros veh\u00edculos o infraestructuras usando nuevos protocolos como V2X, incrementando la seguridad y el conocimiento del entorno.&nbsp;<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Gesti\u00f3n remota<\/strong>: Capacidad para manejar y supervisar flotas de veh\u00edculos o veh\u00edculos espec\u00edficos a distancia.&nbsp;<\/li>\n<\/ul>\n\n\n\n<p>La coexistencia de ambas aproximaciones ofrece, entre otros, los siguientes beneficios:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Ecosistema abierto<\/strong>: Soporta m\u00faltiples proveedores con sus soluciones, en lugar de arquitecturas cerradas.&nbsp;<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Alta capacidad computacional<\/strong>: puede manejar diversas cargas funcionales del sector automoci\u00f3n.&nbsp;<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Aceleraci\u00f3n IA<\/strong>: Capacidad de procesado algoritmos de inteligencia artificial embebidos o incluso distribuidos en la red (Egde o Cloud).&nbsp;<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Modificable<\/strong>: Permite agregar caracter\u00edsticas espec\u00edficas.&nbsp;<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Eficiencia y escalabilidad<\/strong>: Rompe las limitaciones de la arquitectura distribuida tradicional basada en microcontroladores, habilitando dise\u00f1os m\u00e1s eficientes, escalables e innovadores.&nbsp;<\/li>\n<\/ul>\n\n\n\n<p>En la Figura 2 se presenta un ejemplo de arquitectura SDV. En el centro, un m\u00f3dulo central (Central Compute) gestiona todas las operaciones, conectado a trav\u00e9s de un &#8220;Ethernet Switch&#8221; que distribuye datos entre los distintos sistemas del veh\u00edculo. Estos sistemas incluyen la conectividad, la autonom\u00eda de nivel 4, la bater\u00eda y el tren motriz el\u00e9ctrico. Por otro lado, etiquetados con una \u2018Z\u2019, se encuentran las zonas de control distribuidas por el veh\u00edculo.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1010\" height=\"521\" src=\"https:\/\/www.capgemini.com\/es-es\/wp-content\/uploads\/sites\/16\/2024\/10\/image.png\" alt=\"\" class=\"wp-image-562523\" srcset=\"https:\/\/www.capgemini.com\/es-es\/wp-content\/uploads\/sites\/16\/2024\/10\/image.png 1010w, https:\/\/www.capgemini.com\/es-es\/wp-content\/uploads\/sites\/16\/2024\/10\/image.png?resize=300,155 300w, https:\/\/www.capgemini.com\/es-es\/wp-content\/uploads\/sites\/16\/2024\/10\/image.png?resize=768,396 768w\" sizes=\"auto, (max-width: 1010px) 100vw, 1010px\" \/><figcaption class=\"wp-element-caption\">Figura 2: Arquitectura definida por software en automoci\u00f3n. Fuente: Intel [2]<\/figcaption><\/figure>\n\n\n\n<p>Por otro lado, en la Figura 3 se muestra una previsi\u00f3n de mercado de la transici\u00f3n de la arquitectura tradicional hacia una nueva arquitectura definida por software.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" height=\"410\" width=\"1024\" src=\"https:\/\/www.capgemini.com\/es-es\/wp-content\/uploads\/sites\/16\/2024\/10\/evolucion_arquitectura_vehiculos.jpg?w=960\" alt=\"\" class=\"wp-image-562529\" srcset=\"https:\/\/www.capgemini.com\/es-es\/wp-content\/uploads\/sites\/16\/2024\/10\/evolucion_arquitectura_vehiculos.jpg 1629w, https:\/\/www.capgemini.com\/es-es\/wp-content\/uploads\/sites\/16\/2024\/10\/evolucion_arquitectura_vehiculos.jpg?resize=300,120 300w, https:\/\/www.capgemini.com\/es-es\/wp-content\/uploads\/sites\/16\/2024\/10\/evolucion_arquitectura_vehiculos.jpg?resize=768,308 768w, https:\/\/www.capgemini.com\/es-es\/wp-content\/uploads\/sites\/16\/2024\/10\/evolucion_arquitectura_vehiculos.jpg?resize=1024,410 1024w, https:\/\/www.capgemini.com\/es-es\/wp-content\/uploads\/sites\/16\/2024\/10\/evolucion_arquitectura_vehiculos.jpg?resize=1536,616 1536w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Figura 3: Previsi\u00f3n evoluci\u00f3n introducci\u00f3n arquitectura SDV en automoci\u00f3n. Fuente: Bosch [3]&nbsp;<\/figcaption><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-v2x-y-la-conduccion-cooperativa\">V2X y la conducci\u00f3n cooperativa <\/h3>\n\n\n\n<p>La conducci\u00f3n cooperativa, habilitada por la comunicaci\u00f3n V2X, abre nuevas posibilidades para mejorar la seguridad y eficiencia en la carretera. En lugar de depender \u00fanicamente de los sensores a bordo del veh\u00edculo, como c\u00e1maras o radares, V2X permite que los veh\u00edculos intercambien informaci\u00f3n con otros veh\u00edculos cercanos y con la infraestructura inteligente, desplegada en intersecciones y otros puntos de la v\u00eda con alto riesgo de colisi\u00f3n. Este flujo de informaci\u00f3n adicional ampl\u00eda el rango de percepci\u00f3n de los veh\u00edculos, facilitando una toma de decisiones m\u00e1s segura y eficiente.&nbsp;<\/p>\n\n\n\n<p>Gracias a la conducci\u00f3n cooperativa, los veh\u00edculos pueden anticipar situaciones de riesgo que, de otro modo, quedar\u00edan fuera de su campo de visi\u00f3n. Por ejemplo, un veh\u00edculo puede recibir informaci\u00f3n sobre la presencia de peatones en una intersecci\u00f3n antes de girar, o sobre un coche que se aproxima desde una direcci\u00f3n oculta en un cruce. Tambi\u00e9n se pueden anticipar riesgos para la seguridad de la conducci\u00f3n. Por ejemplo, en <strong>Wuxi<\/strong> (China) se han hecho ensayos en el \u00e1rea metropolitana en los que si los sensores de un veh\u00edculo detectan defectos en la calzada (por ejemplo, una superficie resbaladiza) env\u00edan esta informaci\u00f3n a un servidor central, que la transmite a otros veh\u00edculos. Adem\u00e1s, la infraestructura vial conectada puede informar a los veh\u00edculos de condiciones del tr\u00e1fico, estado de los sem\u00e1foros, accidentes o peligros en la v\u00eda en tiempo real.&nbsp;&nbsp;<\/p>\n\n\n\n<p>Entre las aplicaciones pr\u00e1cticas de esta tecnolog\u00eda se incluyen la detecci\u00f3n de peatones antes de maniobras cr\u00edticas como giros o estacionamientos, lo que reduce el riesgo de accidentes en entornos urbanos. Asimismo, en intersecciones complejas, V2X permite la percepci\u00f3n anticipada del tr\u00e1fico, ayudando a evitar colisiones.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-arquitectura-inpercept-extendiendo-capacidades-del-vehiculo-nbsp\">Arquitectura InPercept: extendiendo Capacidades del veh\u00edculo&nbsp;<\/h3>\n\n\n\n<p>El proyecto INPERCEPT busca explotar las caracter\u00edsticas de una arquitectura SDV para incorporar al veh\u00edculo sensores avanzados y conectividad V2X que le permitan operar de una manera m\u00e1s segura y eficiente.&nbsp;<\/p>\n\n\n\n<p>Para ello se ha dise\u00f1ado una arquitectura SDV apoyada en una unidad central de procesamiento, una unidad de control telem\u00e1tica (TCU) para comunicaciones V2X y unidades electr\u00f3nicas m\u00e1s peque\u00f1as para el control de movimiento del veh\u00edculo, como se muestra en la Figura 4.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" height=\"542\" width=\"1024\" src=\"https:\/\/www.capgemini.com\/es-es\/wp-content\/uploads\/sites\/16\/2024\/10\/image_046eb3.png?w=960\" alt=\"\" class=\"wp-image-562524\" srcset=\"https:\/\/www.capgemini.com\/es-es\/wp-content\/uploads\/sites\/16\/2024\/10\/image_046eb3.png 1586w, https:\/\/www.capgemini.com\/es-es\/wp-content\/uploads\/sites\/16\/2024\/10\/image_046eb3.png?resize=300,159 300w, https:\/\/www.capgemini.com\/es-es\/wp-content\/uploads\/sites\/16\/2024\/10\/image_046eb3.png?resize=768,407 768w, https:\/\/www.capgemini.com\/es-es\/wp-content\/uploads\/sites\/16\/2024\/10\/image_046eb3.png?resize=1024,542 1024w, https:\/\/www.capgemini.com\/es-es\/wp-content\/uploads\/sites\/16\/2024\/10\/image_046eb3.png?resize=1536,814 1536w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Figura 4: arquitectura conectada de Inpercept.<\/figcaption><\/figure>\n\n\n\n<p>Una de las funciones de la Unidad Central es integrar, sincronizar y analizar en tiempo real los datos heterog\u00e9neos, tanto en formato como en frecuencia de publicaci\u00f3n, proporcionados por los diferentes sensores instalados en el veh\u00edculo (c\u00e1maras, LIDAR y radar) mediante algoritmos de Inteligencia Artificial capaces de fusionar estos datos para ofrecer al veh\u00edculo una percepci\u00f3n m\u00e1s precisa del entorno. De especial relevancia es la capacidad de esta arquitectura para garantizar la baja latencia en la comunicaci\u00f3n entre los sensores, la Unidad Central que los procesa, la Unidad de Control Telem\u00e1tica que ofrecen al exterior la percepci\u00f3n del veh\u00edculo y las Unidades de Control de los elementos mec\u00e1nico.&nbsp;<\/p>\n\n\n\n<p>Garantizar este trasiego de informaci\u00f3n en tiempo real permite al veh\u00edculo enviar dicha informaci\u00f3n al exterior para ser explotada por otros veh\u00edculos de su entorno, ofreciendo as\u00ed funciones avanzadas de conducci\u00f3n cooperativa.&nbsp;<\/p>\n\n\n\n<p>Estas funciones se han validado en diferentes experimentaciones, conectando veh\u00edculos comerciales modificados para incorporar capacidad V2X con REMOTIS, una plataforma para experimentar con nuevas tecnolog\u00edas del autom\u00f3vil desarrollada \u00edntegramente por Capgemini. La comunicaci\u00f3n entre estos veh\u00edculos permite aumentar el rango de percepci\u00f3n de cada uno de ellos con los datos proporcionados por el otro, mejorando la seguridad en la conducci\u00f3n.&nbsp;&nbsp;<\/p>\n\n\n\n<p>En la siguiente imagen se observa una de las pruebas de frenado de emergencia realizadas. La prueba consisti\u00f3 en hacer circular el veh\u00edculo de Capgemini (visible en el fondo de la imagen) de forma aut\u00f3noma para comprobar que se activan el frenado hasta detener el veh\u00edculo ante la proximidad de un peat\u00f3n ubicado fuera de su campo de visi\u00f3n con intenci\u00f3n de cruzar por delante. Esto fue posible debido a que la posici\u00f3n del peat\u00f3n era detectada por uno de los veh\u00edculos y transmitida mediante V2X al de Capgemini.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"967\" height=\"635\" src=\"https:\/\/www.capgemini.com\/es-es\/wp-content\/uploads\/sites\/16\/2024\/10\/prueba_frenado.jpg\" alt=\"\" class=\"wp-image-562532\" srcset=\"https:\/\/www.capgemini.com\/es-es\/wp-content\/uploads\/sites\/16\/2024\/10\/prueba_frenado.jpg 967w, https:\/\/www.capgemini.com\/es-es\/wp-content\/uploads\/sites\/16\/2024\/10\/prueba_frenado.jpg?resize=300,197 300w, https:\/\/www.capgemini.com\/es-es\/wp-content\/uploads\/sites\/16\/2024\/10\/prueba_frenado.jpg?resize=768,504 768w\" sizes=\"auto, (max-width: 967px) 100vw, 967px\" \/><figcaption class=\"wp-element-caption\">Figura 5: Frenada de emergencia por detecci\u00f3n cooperativa.<\/figcaption><\/figure>\n\n\n\n<p>En la Figura 6 se muestra otra de las pruebas de percepci\u00f3n colaborativa realizadas. Ambos veh\u00edculos, el de Capgemini (en el fondo de la imagen) y el del partner (parte frontal izquierda de la imagen), detectaron y recibieron el veh\u00edculo negro estacionado que aparece en el centro de la imagen.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"993\" height=\"558\" src=\"https:\/\/www.capgemini.com\/es-es\/wp-content\/uploads\/sites\/16\/2024\/10\/prueba_choque.jpg\" alt=\"\" class=\"wp-image-562533\" srcset=\"https:\/\/www.capgemini.com\/es-es\/wp-content\/uploads\/sites\/16\/2024\/10\/prueba_choque.jpg 993w, https:\/\/www.capgemini.com\/es-es\/wp-content\/uploads\/sites\/16\/2024\/10\/prueba_choque.jpg?resize=300,169 300w, https:\/\/www.capgemini.com\/es-es\/wp-content\/uploads\/sites\/16\/2024\/10\/prueba_choque.jpg?resize=768,432 768w\" sizes=\"auto, (max-width: 993px) 100vw, 993px\" \/><figcaption class=\"wp-element-caption\">Figura 6: Prueba de percepci\u00f3n colaborativa entre ambos veh\u00edculos.<\/figcaption><\/figure>\n\n\n\n<p>Es importante destacar que la implementaci\u00f3n de los microservicios V2X desarrollados es viable en los veh\u00edculos manuales (no aut\u00f3nomos) y conectados que est\u00e1n actualmente disponibles en el mercado, sin necesidad de esperar al despliegue generalizado de autom\u00f3viles aut\u00f3nomos. Su implementaci\u00f3n aumentar\u00eda la seguridad en la carretera, especialmente en situaciones de baja visibilidad, donde un peat\u00f3n o veh\u00edculo podr\u00eda no ser visto por el conductor o los sensores del veh\u00edculo, pero s\u00ed detectado por una RSU (Roadside Unit) instalada en la infraestructura vial o por otro veh\u00edculo.&nbsp;&nbsp;<\/p>\n\n\n\n<p>&nbsp;<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p><br>Referencias&nbsp;<\/p>\n\n\n\n<p>[1]\u202f<a href=\"https:\/\/digital-strategy.ec.europa.eu\/en\/library\/concept-paper-open-european-software-defined-vehicle-platform\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/digital-strategy.ec.europa.eu\/en\/library\/concept-paper-open-european-software-defined-vehicle-platform<\/a>&nbsp;<\/p>\n\n\n\n<p>[2] <a href=\"https:\/\/www.intel.com\/content\/dam\/www\/central-libraries\/us\/en\/documents\/2024-04\/automotive-sdv-solution-brief.pdf   \">https:\/\/www.intel.com\/content\/dam\/www\/central-libraries\/us\/en\/documents\/2024-04\/automotive-sdv-solution-brief.pdf   <\/a><\/p>\n\n\n\n<p>[3] The Next step in E\/E architectures.\u202fWhitepaper Bosch Group <\/p>\n<\/div><\/div><\/div><\/div><\/div><\/section>\n\n\n\n<section class=\"wp-block-cg-blocks-wrapper-people-slider section section--expert-slider wrapper-people-slider undefined\"><div class=\"container\"><div class=\"content-title\"><h3 data-maxlength=\"34\">Autores<\/h3><\/div><\/div><div class=\"slider slider-boxed\"><div class=\"container\"><div class=\"slider-window\"><div class=\"slider-list\">\n\t\t<div class=\"slide\">\n\t\t\t<div class=\"box\">\n\t\t\t\t<div class=\"row\">\n\t\t\t\t\t<div class=\"col-md-6 col-lg-4 box-img-wrapper\">\n\t\t\t\t\t\t<img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.capgemini.com\/es-es\/wp-content\/uploads\/sites\/16\/2024\/10\/henry_portilla.jpg\" alt=\"Henry Portilla Rodr\u00edguez\"\/>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"col-md-6 col-lg-8 box-inner\">\n\t\t\t\t\t\t<div class=\"row title-social-media-header\">\n\t\t\t\t\t\t\t<div class=\"col-md-12 col-lg-6 mbl-social-icon\">\n\t\t\t\t\t\t\t\t<ul class=\"social-nav\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><a aria-label=\"Linkedin\" target=\"_blank\" title=\"Abrir en una nueva ventana\" href=\"https:\/\/www.linkedin.com\/in\/henryportilla\/\"><i aria-hidden=\"true\" class=\"icon-li\"><\/i><\/a><\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"col-md-12 col-lg-6 box-container\">\n\t\t\t\t\t\t\t\t<div class=\"box-title\">\n\t\t\t\t\t\t\t\t\t<h3 class=\"people-profile-title\">Henry Portilla Rodr\u00edguez<\/h3>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span>Mobility research and development engineer<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"col-md-12 col-lg-6 social-box-container dkt-social-icon\">\n\t\t\t\t\t\t\t\t<ul class=\"social-nav\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><a aria-label=\"Linkedin\" target=\"_blank\" title=\"Abrir en una nueva ventana\" href=\"https:\/\/www.linkedin.com\/in\/henryportilla\/\"><i aria-hidden=\"true\" class=\"icon-li\"><\/i><\/a><\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"modal\" id=\"WPB734b7be3_7ee7_4acd_9a54_69a053fa33f0\">\n\t\t\t\t\t<div class=\"modal-dialog modal-dialog-centered modal-lg modal-dialog-scrollable landing-page-modals\">\n\t\t\t\t\t\t<div class=\"modal-content\">\n\t\t\t\t\t\t\t<div class=\"modal-header\">\n\t\t\t\t\t\t\t\t<button type=\"button\" class=\"btn-close\" aria-label=\"close\" data-bs-dismiss=\"modal\"><\/button>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"modal-body\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"logo-wrapper\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.capgemini.com\/es-es\/wp-content\/themes\/capgemini2025\/assets\/images\/capgemini-engineering.svg\"\n\t\t\t\t\t\t\t\t\t\talt=\"Contact with us\" class=\"light\" \/>\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.capgemini.com\/es-es\/wp-content\/themes\/capgemini2025\/assets\/images\/capgemini-engineering-white.svg\"\n\t\t\t\t\t\t\t\t\t\talt=\"Contact with us\" class=\"dark\" \/>\n\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"form-title\">Contact with us<\/h4>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"mf_forms__container \">\n\t\t\t\t\t\t\t\t<form id=\"mf_form_344241_3677533916\" class=\"mf_form__form row needs-validation\" action=\"\" method=\"post\" enctype=\"multipart\/form-data\" data-nosnippet>\n\t\t\t<div class=\"col-12\">\n\t\t\t\t<div class=\"asterisk_title\">\n\t\t\t\t\t<p><span class=\"star-required\">*<\/span> Campo obligatorio<\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"col-12\">\n\t\t\t\t<div class=\"mf_form__errors mf_form__errors--top\" role=\"alert\" aria-live=\"polite\">\n\t\t\t\t\t<ul class=\"mf_form__errors__list\"><\/ul>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t<input type=\"hidden\" name=\"form_id\" data-validate=\"number\" class=\"mf_form__id\" value=\"344241\" \/>\n\t\t\t\t<input type=\"hidden\" name=\"form_title\" class=\"mf_form__title\" value=\"\" \/>\n\t\t\t\t<input type=\"hidden\" name=\"wp_rest_nonce\" class=\"mf_form__wp_rest_nonce\" value=\"3fb441f171\" \/>\n\n\t\t\t\t<input type=\"hidden\" name=\"mf_form_conditional_logic\" class=\"mf_form__title conditional_logic\" value=\"\" \/>\n\t\t\t\t\n\t\t\t\t<input type=\"hidden\" name=\"mf_form_fields_country_dpo_field\" class=\"mf_form__title conditional_logic mf_form_fields_country_dpo_field\" value=\"\" \/>\n\n\t\t\t\t<!-- Anti-spam field -->\n\t\t\t\t<input type=\"text\" \n\t\t\t\t\tname=\"website_url\" \n\t\t\t\t\tclass=\"mf_field__url\" \n\t\t\t\t\tautocomplete=\"off\"\n\t\t\t\t\ttabindex=\"-1\"\n\t\t\t\t\taria-hidden=\"true\"\n\t\t\t\t\tstyle=\"position:absolute;left:-9999px;width:1px;height:1px;opacity:0;pointer-events:none;\" \n\t\t\t\t\/>\n\t\t\t<\/form>\n\n\t\t\t<div class=\"mf_form__success\" tabindex=\"0\" role=\"alert\">\n\t\t\t\t\t\t\t\t<p>Gracias! Hemos recibido su formulario.\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t\t<div class=\"mf_form__errors\">\n\t\t\t\t<p>Lo sentimos, el env\u00edo del formulario fall\u00f3. Int\u00e9ntalo de nuevo.<\/p>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t<script>\n\t\t\twindow.MF_CONFIG344241 = {\"344241\":{\"errors\":[],\"redirect\":\"\"}};\n\t\t<\/script>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\n\t\t<div class=\"slide\">\n\t\t\t<div class=\"box\">\n\t\t\t\t<div class=\"row\">\n\t\t\t\t\t<div class=\"col-md-6 col-lg-4 box-img-wrapper\">\n\t\t\t\t\t\t<img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.capgemini.com\/es-es\/wp-content\/uploads\/sites\/16\/2024\/10\/jaime_santiago-e1727799372172.jpg\" alt=\"Jaime Santiago L\u00f3pez\"\/>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"col-md-6 col-lg-8 box-inner\">\n\t\t\t\t\t\t<div class=\"row title-social-media-header\">\n\t\t\t\t\t\t\t<div class=\"col-md-12 col-lg-6 mbl-social-icon\">\n\t\t\t\t\t\t\t\t<ul class=\"social-nav\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><a aria-label=\"Linkedin\" target=\"_blank\" title=\"Abrir en una nueva ventana\" href=\"https:\/\/www.linkedin.com\/in\/jaime-santiago-lpez-a6b87865\/\"><i aria-hidden=\"true\" class=\"icon-li\"><\/i><\/a><\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"col-md-12 col-lg-6 box-container\">\n\t\t\t\t\t\t\t\t<div class=\"box-title\">\n\t\t\t\t\t\t\t\t\t<h3 class=\"people-profile-title\">Jaime Santiago L\u00f3pez<\/h3>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span>Mobility research and development engineer<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"col-md-12 col-lg-6 social-box-container dkt-social-icon\">\n\t\t\t\t\t\t\t\t<ul class=\"social-nav\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><a aria-label=\"Linkedin\" target=\"_blank\" title=\"Abrir en una nueva ventana\" href=\"https:\/\/www.linkedin.com\/in\/jaime-santiago-lpez-a6b87865\/\"><i aria-hidden=\"true\" class=\"icon-li\"><\/i><\/a><\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\n\t\t<div class=\"slide\">\n\t\t\t<div class=\"box\">\n\t\t\t\t<div class=\"row\">\n\t\t\t\t\t<div class=\"col-md-6 col-lg-4 box-img-wrapper\">\n\t\t\t\t\t\t<img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.capgemini.com\/es-es\/wp-content\/uploads\/sites\/16\/2024\/10\/jorge_pinazo-e1727799595752.jpeg\" alt=\"Jorge Pinazo Donoso\"\/>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"col-md-6 col-lg-8 box-inner\">\n\t\t\t\t\t\t<div class=\"row title-social-media-header\">\n\t\t\t\t\t\t\t<div class=\"col-md-12 col-lg-6 mbl-social-icon\">\n\t\t\t\t\t\t\t\t<ul class=\"social-nav\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><a aria-label=\"Linkedin\" target=\"_blank\" title=\"Abrir en una nueva ventana\" href=\"https:\/\/www.linkedin.com\/in\/jorge-pinazo-donoso-755374104\/\"><i aria-hidden=\"true\" class=\"icon-li\"><\/i><\/a><\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"col-md-12 col-lg-6 box-container\">\n\t\t\t\t\t\t\t\t<div class=\"box-title\">\n\t\t\t\t\t\t\t\t\t<h3 class=\"people-profile-title\">Jorge Pinazo Donoso<\/h3>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span>Electronics R&amp;D Technical Lead<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"col-md-12 col-lg-6 social-box-container dkt-social-icon\">\n\t\t\t\t\t\t\t\t<ul class=\"social-nav\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><a aria-label=\"Linkedin\" target=\"_blank\" title=\"Abrir en una nueva ventana\" href=\"https:\/\/www.linkedin.com\/in\/jorge-pinazo-donoso-755374104\/\"><i aria-hidden=\"true\" class=\"icon-li\"><\/i><\/a><\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\n<\/div><\/div><\/div><div class=\"slider-nav\"><button class=\"slider-prev inactive\" aria-label=\"Anterior\" tabindex=\"-1\"><\/button><ul class=\"slider-paginator\"><\/ul><button class=\"slider-next\" aria-label=\"Siguiente\"><\/button><\/div><\/div><\/section>\n\n\n<section class=\"section section--expert-perspectives\"><div class=\"container\"><div class=\"row\"><div class=\"content-title col-12 col-md-8\"><h2 class=\"expert-heading\">Art\u00edculos relacionados<\/h2><\/div><\/div><div class=\"expert-prospective-container\"><div class=\"row\"><div class=\"col-12 col-md-4 row-space\"><div class=\"box\"><div class=\"box-img-wrapper\"><a href=\"https:\/\/www.capgemini.com\/es-es\/investigacion\/perspectivas-de-expertos\/evaluacion-experimental-radar-mimo-para-adas\/\" aria-label=\"Evaluaci\u00f3n experimental de las prestaciones de un radar MIMO para aplicaciones ADAS\" tabindex=\"-1\"><img decoding=\"async\" class=\"box-img\" alt=\"\" src=\"https:\/\/www.capgemini.com\/es-es\/wp-content\/uploads\/sites\/16\/2024\/07\/inpercept3.jpg?w=600&#038;quality=70\" style=\"object-position: 54% 34%; object-fit: cover;\" loading=\"lazy\" \/><\/a><\/div><div class=\"box-inner\"><div class=\"box-tag\"><\/div><a class=\"content-box-title\" href=\"https:\/\/www.capgemini.com\/es-es\/investigacion\/perspectivas-de-expertos\/evaluacion-experimental-radar-mimo-para-adas\/\" aria-label=\"Evaluaci\u00f3n experimental de las prestaciones de un radar MIMO para aplicaciones ADAS\"><h3 class=\"expert-subtitle\">Evaluaci\u00f3n experimental de las prestaciones de un radar MIMO para aplicaciones ADAS<\/h3><\/a><div class=\"box-bottom\">\n\t\t   <div class=\"box-logo\"><img decoding=\"async\" class=\"light\" loading=\"lazy\" alt=\"Capgemini\" src=\"https:\/\/www.capgemini.com\/es-es\/wp-content\/themes\/capgemini2025\/assets\/images\/cg-logo-blue.svg\" \/><img decoding=\"async\" class=\"dark\" loading=\"lazy\" alt=\"Capgemini\" src=\"https:\/\/www.capgemini.com\/es-es\/wp-content\/themes\/capgemini2025\/assets\/images\/cg-logo-white.svg\" \/><\/div><div class=\"date-name-info\"><div class=\"author-text\">Capgemini<\/div><div class=\"date-text\">jul. 16, 2024<\/div><\/div><\/div><\/div><\/div><\/div><div class=\"col-12 col-md-4 row-space\"><div class=\"box\"><div class=\"box-img-wrapper\"><a href=\"https:\/\/www.capgemini.com\/es-es\/investigacion\/perspectivas-de-expertos\/la-conduccion-autonoma-una-realidad-inminente\/\" aria-label=\"La conduccion aut\u00f3noma, \u00bfuna realidad inminente?\" tabindex=\"-1\"><img decoding=\"async\" class=\"box-img\" alt=\"\" src=\"https:\/\/www.capgemini.com\/es-es\/wp-content\/uploads\/sites\/16\/2023\/03\/1.jpeg?w=600&#038;quality=70\" style=\"object-position: 50% 50%; object-fit: cover;\" loading=\"lazy\" \/><\/a><\/div><div class=\"box-inner\"><div class=\"box-tag\"><\/div><a class=\"content-box-title\" href=\"https:\/\/www.capgemini.com\/es-es\/investigacion\/perspectivas-de-expertos\/la-conduccion-autonoma-una-realidad-inminente\/\" aria-label=\"La conduccion aut\u00f3noma, \u00bfuna realidad inminente?\"><h3 class=\"expert-subtitle\">La conduccion aut\u00f3noma, \u00bfuna realidad inminente?<\/h3><\/a><div class=\"box-bottom\">\n\t\t   <div class=\"box-logo\"><img decoding=\"async\" class=\"\" loading=\"lazy\" alt=\"\" src=\"https:\/\/www.capgemini.com\/es-es\/wp-content\/uploads\/sites\/16\/2023\/03\/adolfo_lerin.jpg?w=800\" \/><\/div><div class=\"date-name-info\"><div class=\"author-text\">Adolfo Ler\u00edn<\/div><div class=\"date-text\">mar. 8, 2023<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section>\n\n\n<section class=\"wp-block-cg-blocks-group undefined section section--article-content\"><div class=\"article-main-content\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-md-11 col-lg-10 offset-md-1 offset-lg-1\"><div class=\"article-text article-quote-text\">\n<h3 class=\"wp-block-heading\" id=\"h-\"><\/h3>\n\n\n\n<p><em>Este proyecto ha sido subvencionado por el CDTI, cofinanciado con fondos Europeos del Mecanismo de Recuperaci\u00f3n y Resiliencia y apoyado por el Ministerio de Ciencia e Innovaci\u00f3n. Este proyecto tiene&nbsp;n\u00famero de expediente PTAS-20211011<\/em><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"101\" src=\"https:\/\/www.capgemini.com\/es-es\/wp-content\/uploads\/sites\/16\/2023\/07\/Logos-IRON-NPE-001.jpg\" alt=\"\" class=\"wp-image-547626\" srcset=\"https:\/\/www.capgemini.com\/es-es\/wp-content\/uploads\/sites\/16\/2023\/07\/Logos-IRON-NPE-001.jpg 1024w, https:\/\/www.capgemini.com\/es-es\/wp-content\/uploads\/sites\/16\/2023\/07\/Logos-IRON-NPE-001.jpg?resize=300,30 300w, https:\/\/www.capgemini.com\/es-es\/wp-content\/uploads\/sites\/16\/2023\/07\/Logos-IRON-NPE-001.jpg?resize=768,76 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div><\/div><\/div><\/div><\/div><\/section>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":452,"featured_media":562532,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"cg_dt_proposed_to":[],"cg_seo_hreflang_relations":"[]","cg_seo_canonical_relation":"","cg_seo_hreflang_x_default_relation":"{\"uuid\":\"13eede0b-879a-464e-8db1-a1119c7ed9ca\",\"blogId\":\"\",\"domain\":\"\",\"sitePath\":\"\",\"postLink\":\"\",\"postId\":null,\"isSaved\":true,\"isCrossLink\":false,\"hasCrossLink\":false}","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"cg_dt_approved_content":true,"cg_dt_mandatory_content":false,"cg_dt_notes":"","cg_dg_source_changed":false,"cg_dt_link_disabled":false,"_yoast_wpseo_primary_brand":"108","_jetpack_memberships_contains_paid_content":false,"footnotes":"","featured_focal_points":"","jetpack_post_was_ever_published":false},"categories":[3],"tags":[113],"brand":[108],"service":[],"industry":[],"partners":[],"blog-topic":[726],"content-group":[],"class_list":["post-562518","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-innovation","tag-automocion","brand-capgemini-engineering","blog-topic-intelligent-industry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.8 (Yoast SEO v22.8) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Aumentando la percepci\u00f3n del veh\u00edculo: el proyecto INPERCEPT - Capgemini Spain<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.capgemini.com\/es-es\/investigacion\/perspectivas-de-expertos\/aumentando-la-percepcion-del-vehiculo-el-proyecto-inpercept\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aumentando la percepci\u00f3n del veh\u00edculo: el proyecto INPERCEPT\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.capgemini.com\/es-es\/investigacion\/perspectivas-de-expertos\/aumentando-la-percepcion-del-vehiculo-el-proyecto-inpercept\/\" \/>\n<meta property=\"og:site_name\" content=\"Capgemini Spain\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-01T14:23:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-11T07:21:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.capgemini.com\/es-es\/wp-content\/uploads\/sites\/16\/2024\/10\/prueba_frenado.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"967\" \/>\n\t<meta property=\"og:image:height\" content=\"635\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Henry Portilla \/ Jaime Santiago \/ Jorge Pinazo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"carolinamartineznavas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"14 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.capgemini.com\/es-es\/investigacion\/perspectivas-de-expertos\/aumentando-la-percepcion-del-vehiculo-el-proyecto-inpercept\/\",\"url\":\"https:\/\/www.capgemini.com\/es-es\/investigacion\/perspectivas-de-expertos\/aumentando-la-percepcion-del-vehiculo-el-proyecto-inpercept\/\",\"name\":\"Aumentando la percepci\u00f3n del veh\u00edculo: el proyecto INPERCEPT - Capgemini Spain\",\"isPartOf\":{\"@id\":\"https:\/\/www.capgemini.com\/es-es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.capgemini.com\/es-es\/investigacion\/perspectivas-de-expertos\/aumentando-la-percepcion-del-vehiculo-el-proyecto-inpercept\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.capgemini.com\/es-es\/investigacion\/perspectivas-de-expertos\/aumentando-la-percepcion-del-vehiculo-el-proyecto-inpercept\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.capgemini.com\/es-es\/wp-content\/uploads\/sites\/16\/2024\/10\/prueba_frenado.jpg\",\"datePublished\":\"2024-10-01T14:23:23+00:00\",\"dateModified\":\"2025-03-11T07:21:11+00:00\",\"author\":{\"@id\":\"https:\/\/www.capgemini.com\/es-es\/#\/schema\/person\/ba4897ab71ec9e539b552d8f678d66ee\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.capgemini.com\/es-es\/investigacion\/perspectivas-de-expertos\/aumentando-la-percepcion-del-vehiculo-el-proyecto-inpercept\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.capgemini.com\/es-es\/investigacion\/perspectivas-de-expertos\/aumentando-la-percepcion-del-vehiculo-el-proyecto-inpercept\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/www.capgemini.com\/es-es\/investigacion\/perspectivas-de-expertos\/aumentando-la-percepcion-del-vehiculo-el-proyecto-inpercept\/#primaryimage\",\"url\":\"https:\/\/www.capgemini.com\/es-es\/wp-content\/uploads\/sites\/16\/2024\/10\/prueba_frenado.jpg\",\"contentUrl\":\"https:\/\/www.capgemini.com\/es-es\/wp-content\/uploads\/sites\/16\/2024\/10\/prueba_frenado.jpg\",\"width\":967,\"height\":635},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.capgemini.com\/es-es\/investigacion\/perspectivas-de-expertos\/aumentando-la-percepcion-del-vehiculo-el-proyecto-inpercept\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.capgemini.com\/es-es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aumentando la percepci\u00f3n del veh\u00edculo: el proyecto INPERCEPT\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.capgemini.com\/es-es\/#website\",\"url\":\"https:\/\/www.capgemini.com\/es-es\/\",\"name\":\"Capgemini Espa\u00f1a\",\"description\":\"Capgemini\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.capgemini.com\/es-es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.capgemini.com\/es-es\/#\/schema\/person\/ba4897ab71ec9e539b552d8f678d66ee\",\"name\":\"carolinamartineznavas\",\"sameAs\":[\"tamas.lugosi@capgemini.com\"],\"url\":\"https:\/\/www.capgemini.com\/es-es\/author\/carolinamartineznavas\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Aumentando la percepci\u00f3n del veh\u00edculo: el proyecto INPERCEPT - Capgemini Spain","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.capgemini.com\/es-es\/investigacion\/perspectivas-de-expertos\/aumentando-la-percepcion-del-vehiculo-el-proyecto-inpercept\/","og_locale":"es_ES","og_type":"article","og_title":"Aumentando la percepci\u00f3n del veh\u00edculo: el proyecto INPERCEPT","og_url":"https:\/\/www.capgemini.com\/es-es\/investigacion\/perspectivas-de-expertos\/aumentando-la-percepcion-del-vehiculo-el-proyecto-inpercept\/","og_site_name":"Capgemini Spain","article_published_time":"2024-10-01T14:23:23+00:00","article_modified_time":"2025-03-11T07:21:11+00:00","og_image":[{"width":967,"height":635,"url":"https:\/\/www.capgemini.com\/es-es\/wp-content\/uploads\/sites\/16\/2024\/10\/prueba_frenado.jpg","type":"image\/jpeg"}],"author":"Henry Portilla \/ Jaime Santiago \/ Jorge Pinazo","twitter_card":"summary_large_image","twitter_misc":{"Written by":"carolinamartineznavas","Est. reading time":"14 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.capgemini.com\/es-es\/investigacion\/perspectivas-de-expertos\/aumentando-la-percepcion-del-vehiculo-el-proyecto-inpercept\/","url":"https:\/\/www.capgemini.com\/es-es\/investigacion\/perspectivas-de-expertos\/aumentando-la-percepcion-del-vehiculo-el-proyecto-inpercept\/","name":"Aumentando la percepci\u00f3n del veh\u00edculo: el proyecto INPERCEPT - Capgemini Spain","isPartOf":{"@id":"https:\/\/www.capgemini.com\/es-es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.capgemini.com\/es-es\/investigacion\/perspectivas-de-expertos\/aumentando-la-percepcion-del-vehiculo-el-proyecto-inpercept\/#primaryimage"},"image":{"@id":"https:\/\/www.capgemini.com\/es-es\/investigacion\/perspectivas-de-expertos\/aumentando-la-percepcion-del-vehiculo-el-proyecto-inpercept\/#primaryimage"},"thumbnailUrl":"https:\/\/www.capgemini.com\/es-es\/wp-content\/uploads\/sites\/16\/2024\/10\/prueba_frenado.jpg","datePublished":"2024-10-01T14:23:23+00:00","dateModified":"2025-03-11T07:21:11+00:00","author":{"@id":"https:\/\/www.capgemini.com\/es-es\/#\/schema\/person\/ba4897ab71ec9e539b552d8f678d66ee"},"breadcrumb":{"@id":"https:\/\/www.capgemini.com\/es-es\/investigacion\/perspectivas-de-expertos\/aumentando-la-percepcion-del-vehiculo-el-proyecto-inpercept\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.capgemini.com\/es-es\/investigacion\/perspectivas-de-expertos\/aumentando-la-percepcion-del-vehiculo-el-proyecto-inpercept\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/www.capgemini.com\/es-es\/investigacion\/perspectivas-de-expertos\/aumentando-la-percepcion-del-vehiculo-el-proyecto-inpercept\/#primaryimage","url":"https:\/\/www.capgemini.com\/es-es\/wp-content\/uploads\/sites\/16\/2024\/10\/prueba_frenado.jpg","contentUrl":"https:\/\/www.capgemini.com\/es-es\/wp-content\/uploads\/sites\/16\/2024\/10\/prueba_frenado.jpg","width":967,"height":635},{"@type":"BreadcrumbList","@id":"https:\/\/www.capgemini.com\/es-es\/investigacion\/perspectivas-de-expertos\/aumentando-la-percepcion-del-vehiculo-el-proyecto-inpercept\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.capgemini.com\/es-es\/"},{"@type":"ListItem","position":2,"name":"Aumentando la percepci\u00f3n del veh\u00edculo: el proyecto INPERCEPT"}]},{"@type":"WebSite","@id":"https:\/\/www.capgemini.com\/es-es\/#website","url":"https:\/\/www.capgemini.com\/es-es\/","name":"Capgemini Espa\u00f1a","description":"Capgemini","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.capgemini.com\/es-es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es-ES"},{"@type":"Person","@id":"https:\/\/www.capgemini.com\/es-es\/#\/schema\/person\/ba4897ab71ec9e539b552d8f678d66ee","name":"carolinamartineznavas","sameAs":["tamas.lugosi@capgemini.com"],"url":"https:\/\/www.capgemini.com\/es-es\/author\/carolinamartineznavas\/"}]}},"blog_topic_info":[{"id":726,"name":"Intelligent industry"}],"taxonomy_info":{"category":[{"id":3,"name":"Innovation","slug":"innovation"}],"post_tag":[{"id":113,"name":"Automoci\u00f3n","slug":"automocion"}],"brand":[{"id":108,"name":"Capgemini Engineering","slug":"capgemini-engineering"}],"blog-topic":[{"id":726,"name":"Intelligent industry","slug":"intelligent-industry"}],"following_users":[{"id":173,"name":"antoniojimeno","slug":"antoniojimeno"},{"id":167,"name":"automator","slug":"automator"}]},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/capgemini.com\/es-es\/investigacion\/perspectivas-de-expertos\/aumentando-la-percepcion-del-vehiculo-el-proyecto-inpercept\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Aumentando la percepci\u00f3n del veh\u00edculo: el proyecto INPERCEPT","url":"https:\/\/www.capgemini.com\/es-es\/investigacion\/perspectivas-de-expertos\/aumentando-la-percepcion-del-vehiculo-el-proyecto-inpercept\/","mainEntityOfPage":{"@type":"WebPage","@id":"https:\/\/www.capgemini.com\/es-es\/investigacion\/perspectivas-de-expertos\/aumentando-la-percepcion-del-vehiculo-el-proyecto-inpercept\/"},"thumbnailUrl":"https:\/\/www.capgemini.com\/es-es\/wp-content\/uploads\/sites\/16\/2024\/10\/prueba_frenado.jpg?w=150&h=150&crop=1","image":{"@type":"ImageObject","url":"https:\/\/www.capgemini.com\/es-es\/wp-content\/uploads\/sites\/16\/2024\/10\/prueba_frenado.jpg"},"articleSection":"Innovation","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Capgemini Spain","logo":""},"keywords":["automoci\u00f3n"],"dateCreated":"2024-10-01T14:23:23Z","datePublished":"2024-10-01T14:23:23Z","dateModified":"2025-03-11T07:21:11Z"},"rendered":"<meta name=\"parsely-title\" content=\"Aumentando la percepci\u00f3n del veh\u00edculo: el proyecto INPERCEPT\" \/>\n<meta name=\"parsely-link\" content=\"https:\/\/www.capgemini.com\/es-es\/investigacion\/perspectivas-de-expertos\/aumentando-la-percepcion-del-vehiculo-el-proyecto-inpercept\/\" \/>\n<meta name=\"parsely-type\" content=\"post\" \/>\n<meta name=\"parsely-image-url\" content=\"https:\/\/www.capgemini.com\/es-es\/wp-content\/uploads\/sites\/16\/2024\/10\/prueba_frenado.jpg?w=150&amp;h=150&amp;crop=1\" \/>\n<meta name=\"parsely-pub-date\" content=\"2024-10-01T14:23:23Z\" \/>\n<meta name=\"parsely-section\" content=\"Innovation\" \/>\n<meta name=\"parsely-tags\" content=\"automoci\u00f3n\" \/>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/capgemini.com\/p.js"},"jetpack_featured_media_url":"https:\/\/www.capgemini.com\/es-es\/wp-content\/uploads\/sites\/16\/2024\/10\/prueba_frenado.jpg","archive_status":false,"featured_image_src":"https:\/\/www.capgemini.com\/es-es\/wp-content\/uploads\/sites\/16\/2024\/10\/prueba_frenado.jpg","featured_image_alt":"","jetpack_sharing_enabled":true,"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"Capgemini Spain","distributor_original_site_url":"https:\/\/www.capgemini.com\/es-es","push-errors":false,"featured_image_url":"https:\/\/www.capgemini.com\/es-es\/wp-content\/uploads\/sites\/16\/2024\/10\/prueba_frenado.jpg","_links":{"self":[{"href":"https:\/\/www.capgemini.com\/es-es\/wp-json\/wp\/v2\/posts\/562518","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.capgemini.com\/es-es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.capgemini.com\/es-es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.capgemini.com\/es-es\/wp-json\/wp\/v2\/users\/452"}],"replies":[{"embeddable":true,"href":"https:\/\/www.capgemini.com\/es-es\/wp-json\/wp\/v2\/comments?post=562518"}],"version-history":[{"count":9,"href":"https:\/\/www.capgemini.com\/es-es\/wp-json\/wp\/v2\/posts\/562518\/revisions"}],"predecessor-version":[{"id":567279,"href":"https:\/\/www.capgemini.com\/es-es\/wp-json\/wp\/v2\/posts\/562518\/revisions\/567279"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.capgemini.com\/es-es\/wp-json\/wp\/v2\/media\/562532"}],"wp:attachment":[{"href":"https:\/\/www.capgemini.com\/es-es\/wp-json\/wp\/v2\/media?parent=562518"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.capgemini.com\/es-es\/wp-json\/wp\/v2\/categories?post=562518"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.capgemini.com\/es-es\/wp-json\/wp\/v2\/tags?post=562518"},{"taxonomy":"brand","embeddable":true,"href":"https:\/\/www.capgemini.com\/es-es\/wp-json\/wp\/v2\/brand?post=562518"},{"taxonomy":"service","embeddable":true,"href":"https:\/\/www.capgemini.com\/es-es\/wp-json\/wp\/v2\/service?post=562518"},{"taxonomy":"industry","embeddable":true,"href":"https:\/\/www.capgemini.com\/es-es\/wp-json\/wp\/v2\/industry?post=562518"},{"taxonomy":"partners","embeddable":true,"href":"https:\/\/www.capgemini.com\/es-es\/wp-json\/wp\/v2\/partners?post=562518"},{"taxonomy":"blog-topic","embeddable":true,"href":"https:\/\/www.capgemini.com\/es-es\/wp-json\/wp\/v2\/blog-topic?post=562518"},{"taxonomy":"content-group","embeddable":true,"href":"https:\/\/www.capgemini.com\/es-es\/wp-json\/wp\/v2\/content-group?post=562518"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}