{"id":5278,"date":"2022-11-14T13:49:00","date_gmt":"2022-11-14T13:49:00","guid":{"rendered":"https:\/\/www.capgemini.com\/?page_id=744033"},"modified":"2025-12-04T18:42:48","modified_gmt":"2025-12-04T17:42:48","slug":"futuros-descentralizados","status":"publish","type":"page","link":"https:\/\/www.capgemini.com\/es-es\/soluciones\/futuros-descentralizados\/","title":{"rendered":"Futuros descentralizados"},"content":{"rendered":"\n<header class=\"wp-block-cg-blocks-hero-reusable header heroReusable  \"><div class=\"header-bgs\"><picture><source srcset=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2021\/12\/Capgemini_Industries_Capital-Markets_Investment-Banking_2.jpg?w=2880&amp;quality=70 1x, https:\/\/www.capgemini.com\/wp-content\/uploads\/2021\/12\/Capgemini_Industries_Capital-Markets_Investment-Banking_2.jpg?w=2880&amp;quality=70 2x\" media=\"(min-width: 1500px)\"\/><source srcset=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2021\/12\/Capgemini_Industries_Capital-Markets_Investment-Banking_2.jpg?w=1440&amp;quality=70 1x, https:\/\/www.capgemini.com\/wp-content\/uploads\/2021\/12\/Capgemini_Industries_Capital-Markets_Investment-Banking_2.jpg?w=2880&amp;quality=70 2x\" media=\"(min-width: 992px)\"\/><source srcset=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2021\/12\/Capgemini_Industries_Capital-Markets_Investment-Banking_2.jpg?w=1024&amp;quality=70 1x, https:\/\/www.capgemini.com\/wp-content\/uploads\/2021\/12\/Capgemini_Industries_Capital-Markets_Investment-Banking_2.jpg?w=1024&amp;quality=70 2x\" media=\"(min-width: 768px)\"\/><source srcset=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2021\/12\/Capgemini_Industries_Capital-Markets_Investment-Banking_2.jpg?w=768&amp;quality=70 1x, https:\/\/www.capgemini.com\/wp-content\/uploads\/2021\/12\/Capgemini_Industries_Capital-Markets_Investment-Banking_2.jpg?w=768&amp;quality=70 2x\" media=\"(min-width: 0)\"\/><img decoding=\"async\" src=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2021\/12\/Capgemini_Industries_Capital-Markets_Investment-Banking_2.jpg\" class=\"header-img header-img-d\" alt=\"\" style=\"object-fit:cover;object-position:50% 50%\" loading=\"eager\"\/><\/picture><\/div><div class=\"heroPictureCardHeaderShape\"><\/div><div class=\"container\"><div class=\"row\"><div class=\"col-md-12\"><div class=\"box\"><div class=\"boxTagWrapper\"><div class=\"tagInfo\"><div><span class=\"box-tag\">Solution<\/span><\/div><\/div><\/div><div class=\"box-title\"><h1 data-maxlength=\"34\">Futuros descentralizados<\/h1><\/div><div class=\"inner-row-insight download-btn\"><\/div><\/div><\/div><\/div><\/div><\/header>\n\n\n\n<section class=\"wp-block-cg-blocks-intro-para undefined section section--intro\"><div class=\"intro-para\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-md-1\"><nav class=\"article-social\"><ul class=\"social-nav\"><li class=\"ip-order-fb\"><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https:\/\/www.capgemini.com\/es-es\/soluciones\/futuros-descentralizados\/\" target=\"_blank\" rel=\"noopener noreferrer\" title=\"abrir en una nueva ventana\"><i aria-hidden=\"true\" class=\"icon-fb\"><\/i><span class=\"sr-only\">Facebook<\/span><\/a><\/li><li class=\"ip-order-li\"><a href=\"https:\/\/www.linkedin.com\/sharing\/share-offsite\/?url=https:\/\/www.capgemini.com\/es-es\/soluciones\/futuros-descentralizados\/\" target=\"_blank\" rel=\"noopener noreferrer\" title=\"abrir en una nueva ventana\"><i aria-hidden=\"true\" class=\"icon-li\"><\/i><span class=\"sr-only\">Linkedin<\/span><\/a><\/li><\/ul><\/nav><\/div><div class=\"col-12 col-md-11 col-lg-10\"><h2 class=\"intro-para-title\">Creemos que el futuro de los servicios financieros comprender\u00e1 un equilibrio entre los sistemas y componentes financieros centralizados y descentralizados, impulsando la innovaci\u00f3n constante y r\u00e1pida al tiempo que garantiza el cumplimiento normativo.<\/h2><p class=\"intro-para-content\">Blockchain y otras tecnolog\u00edas de registros distribuidos (DLT) est\u00e1n en el coraz\u00f3n de los futuros descentralizados, y despu\u00e9s de un per\u00edodo prolongado de escepticismo y proyectos de alcance limitado a pruebas de concepto o peque\u00f1os pilotos, ha habido un aumento significativo en los nuevos proyectos de blockchain implementados a escala. durante los \u00faltimos dos a\u00f1os, especialmente dentro de los servicios financieros.<br>\u00a0<br>\u00bfC\u00f3mo deben prepararse las instituciones financieras para un futuro descentralizado? A trav\u00e9s de nuestro trabajo con socios, participantes de la industria y clientes que navegan por el panorama de futuros descentralizados que cambia r\u00e1pidamente, Capgemini ha identificado seis \u00e1reas clave de enfoque estrat\u00e9gico, que se destacan a continuaci\u00f3n.<\/p><\/div><\/div><\/div><\/div><\/section>\n\n\n\n\t\t\t\t<section\n\t\t\t\t\tclass=\"section section--lifeatcap-learning section--event-slider-careerInvent \">\n\n\t\t\t\t\t<div class=\"container\">\n\t\t\t\t\t\t<div class='career-invent-header'>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"slider slider-fader 0edaf78d-4cb3-4d9c-9f0d-adea98105def\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"slider-nav-wrapper smallDevice\">\n\t\t\t\t\t\t\t\t\t<div class=\"row\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"col-md-12 text-center\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"slider-nav\">\n\t\t\t\t\t\t\t\t\t\t\t\t<button class=\"slider-prev inactive\"\n\t\t\t\t\t\t\t\t\t\t\t\t\taria-label=\"anterior\"><\/button>\n\t\t\t\t\t\t\t\t\t\t\t\t<ul class=\"slider-paginator\"><\/ul>\n\t\t\t\t\t\t\t\t\t\t\t\t<button class=\"slider-next \"\n\t\t\t\t\t\t\t\t\t\t\t\t\taria-label=\"siguiente\"><\/button>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div\n\t\t\t\t\t\t\tclass=\"slider-list \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div\n\t\t\t\t\t\t\t\t\t\tclass=\"slide active \">\n\t\t\t\t\t\t\t\t\t\t<div\n\t\t\t\t\t\t\t\t\t\t\tclass=\"slide-bg-wrapper wp-block-cg-blocks-career-invent is-style-sapphire2\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"bgImagesection\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"bgColor\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"container slide-info-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"col-md-6 col-sm-12 box-inner \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"bgColor\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"content-title \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"explore-header\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tdata-maxlength=\"68\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\ttitle=\"Preparando el camino para CBDC y activos tokenizados\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tPreparando el camino para CBDC y activos tokenizados\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"box-title \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h4 data-maxlength=\"144\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\ttitle=\"Interconexi\u00f3n de CBDC para pagos transfronterizos sin problemas\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tstyle=\"white-space: pre-wrap;\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tInterconexi\u00f3n de CBDC para pagos transfronterizos sin problemas\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div >\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"btnDiv\"> <a class=\"more2\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tdata-maxlength=\"24\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\taria-label=\"M\u00e1s informaci\u00f3n sobre Preparando el camino para CBDC y activos tokenizados\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\ttitle=\"Opens in new window\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\ttabindex=\"0\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"https:\/\/www.swift.com\/news-events\/news\/connecting-digital-islands-paving-way-global-use-cbdcs-and-tokenised-assets\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\ttarget=\"_blank\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tM\u00e1s informaci\u00f3n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a> <\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-md-6 col-sm-12 text-right box-img-wrapper escaper escaper-right\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<picture>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<source\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tsrcset=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2022\/09\/shutterstock_1601074858.jpg?w=1200&amp;quality=90 1x, https:\/\/www.capgemini.com\/wp-content\/uploads\/2022\/09\/shutterstock_1601074858.jpg?w=1200&amp;quality=90 2x\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tmedia=\"(min-width: 1500px)\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<source\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tsrcset=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2022\/09\/shutterstock_1601074858.jpg?w=600&amp;quality=90 1x, https:\/\/www.capgemini.com\/wp-content\/uploads\/2022\/09\/shutterstock_1601074858.jpg?w=1200&amp;quality=90 2x\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tmedia=\"(min-width: 992px)\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<source\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tsrcset=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2022\/09\/shutterstock_1601074858.jpg?w=400&amp;quality=90 1x, https:\/\/www.capgemini.com\/wp-content\/uploads\/2022\/09\/shutterstock_1601074858.jpg?w=800&amp;quality=90 2x\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tmedia=\"(min-width: 768px)\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<source\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tsrcset=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2022\/09\/shutterstock_1601074858.jpg?w=400&amp;quality=90 1x, https:\/\/www.capgemini.com\/wp-content\/uploads\/2022\/09\/shutterstock_1601074858.jpg?w=800&amp;quality=90 2x\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tmedia=\"(min-width: 0)\" \/>\n\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" class=\"box-img\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tsrc=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2022\/09\/shutterstock_1601074858.jpg\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tstyle=\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\tobject-position: 50% 50%; object-fit: cover;\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\" alt=\"\" \/>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/picture>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<!-- <img decoding=\"async\" class=\"box-img\" src=\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\"\n\t\t\t\t\t\t\t\t\t\t\tstyle=\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\" alt=\"\"\n\t\t\t\t\t\t\t\t\t\t\/> -->\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div\n\t\t\t\t\t\t\t\t\t\t\t\tclass=\"\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"slide-reveal\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div\n\t\t\t\t\t\t\t\t\t\tclass=\"slide active \">\n\t\t\t\t\t\t\t\t\t\t<div\n\t\t\t\t\t\t\t\t\t\t\tclass=\"slide-bg-wrapper wp-block-cg-blocks-career-invent is-style-sapphire2\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"bgImagesection\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"bgColor\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"container slide-info-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"col-md-6 col-sm-12 box-inner \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"bgColor\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"content-title \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"explore-header\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tdata-maxlength=\"68\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\ttitle=\"Metaverso seguro: m\u00e1s grande de lo que piensas\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tMetaverso seguro: m\u00e1s grande de lo que piensas\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"box-title \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h4 data-maxlength=\"144\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\ttitle=\"\u00bfD\u00f3nde encaja el seguro?\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tstyle=\"white-space: pre-wrap;\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\u00bfD\u00f3nde encaja el seguro?\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div >\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"btnDiv\"> <a class=\"more2\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tdata-maxlength=\"24\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\taria-label=\"M\u00e1s informaci\u00f3n sobre Metaverso seguro: m\u00e1s grande de lo que piensas\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\ttitle=\"Opens in new window\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\ttabindex=\"-1\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"https:\/\/member.fintech.global\/2022\/09\/07\/why-metaverse-insurance-is-bigger-than-you-think\/\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\ttarget=\"_blank\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tM\u00e1s informaci\u00f3n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a> <\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-md-6 col-sm-12 text-right box-img-wrapper escaper escaper-right\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<picture>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<source\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tsrcset=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2022\/09\/metaverse-insurance.jpg?w=1200&amp;quality=90 1x, https:\/\/www.capgemini.com\/wp-content\/uploads\/2022\/09\/metaverse-insurance.jpg?w=1200&amp;quality=90 2x\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tmedia=\"(min-width: 1500px)\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<source\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tsrcset=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2022\/09\/metaverse-insurance.jpg?w=600&amp;quality=90 1x, https:\/\/www.capgemini.com\/wp-content\/uploads\/2022\/09\/metaverse-insurance.jpg?w=1200&amp;quality=90 2x\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tmedia=\"(min-width: 992px)\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<source\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tsrcset=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2022\/09\/metaverse-insurance.jpg?w=400&amp;quality=90 1x, https:\/\/www.capgemini.com\/wp-content\/uploads\/2022\/09\/metaverse-insurance.jpg?w=800&amp;quality=90 2x\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tmedia=\"(min-width: 768px)\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<source\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tsrcset=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2022\/09\/metaverse-insurance.jpg?w=400&amp;quality=90 1x, https:\/\/www.capgemini.com\/wp-content\/uploads\/2022\/09\/metaverse-insurance.jpg?w=800&amp;quality=90 2x\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tmedia=\"(min-width: 0)\" \/>\n\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" class=\"box-img\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tsrc=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2022\/09\/metaverse-insurance.jpg\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tstyle=\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\tobject-position: 57% 34%; object-fit: cover;\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\" alt=\"\" \/>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/picture>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<!-- <img decoding=\"async\" class=\"box-img\" src=\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\"\n\t\t\t\t\t\t\t\t\t\t\tstyle=\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\" alt=\"\"\n\t\t\t\t\t\t\t\t\t\t\/> -->\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div\n\t\t\t\t\t\t\t\t\t\t\t\tclass=\"\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"slide-reveal\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"slider-nav-wrapper largeDevice\">\n\t\t\t\t\t\t\t\t\t<div class=\"row\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"col-md-12 text-center\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"slider-nav\">\n\t\t\t\t\t\t\t\t\t\t\t\t<button class=\"slider-prev inactive\"\n\t\t\t\t\t\t\t\t\t\t\t\t\taria-label=\"anterior\"><\/button>\n\t\t\t\t\t\t\t\t\t\t\t\t<ul class=\"slider-paginator\"><\/ul>\n\t\t\t\t\t\t\t\t\t\t\t\t<button class=\"slider-next\"\n\t\t\t\t\t\t\t\t\t\t\t\t\taria-label=\"siguiente\"><\/button>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t<\/section>\n\n\t\t\t\t\n\n\n<section class=\"wp-block-cg-blocks-group undefined section section--article-content\"><div class=\"article-main-content\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-md-11 col-lg-10 offset-md-1 offset-lg-1\"><div class=\"article-text article-quote-text\">\n<section class=\"wp-block-cg-blocks-how-we-do-it section section--howwedoit block-howwedoit\"><div class=\"container\"><div class=\"section-content\">\n<div class=\"wp-block-cg-blocks-card-howwedoit expanders\"><div class=\"box card-regulated-agreements card-howwedoit\"><div class=\"expander-box filter-box tag-active \"><div class=\"expander-title\" role=\"button\"><h4><strong>Moneda digital del banco central (CBDC)<\/strong><\/h4><\/div><div class=\"expander-subtitle\"><h5>Los bancos centrales de todo el mundo est\u00e1n explorando las CBDC para acelerar la pr\u00f3xima ola de transformaci\u00f3n de la econom\u00eda digital.<\/h5><\/div><div class=\"expander-content\"><p>Las demandas de dinero digital y una sociedad sin efectivo se est\u00e1n acelerando. Los bancos centrales est\u00e1n bajo presi\u00f3n para mejorar la eficiencia de los sistemas de pagos; varios proyectos de CBDC ya se encuentran en un entorno piloto antes de su lanzamiento formal, y las monedas estables est\u00e1n encontrando casos de uso para optimizar los pagos transfronterizos de CBDC.<br \/>\u00a0<br \/>Hoy, Capgemini participa en varias oportunidades en el espacio de CBDC, en \u00e1reas que incluyen investigaci\u00f3n, consultor\u00eda y asesoramiento, y desarrollo de prueba de concepto. El r\u00e1pido aumento de los experimentos de CDBC tambi\u00e9n ha desencadenado trabajos en torno a la infraestructura tecnol\u00f3gica y la interoperabilidad de las monedas.<\/p><div class=\"bg-color video-align-right\"><div class=\"container\"><div class=\"row video-align-left\"><div class=\"col-md-12\"><div class=\"video-align-left row box box--4 box--mini\"><div class=\"col-md-3\"><\/div><div class=\"col-md-8 box-img-wrapper\"><div class=\"video-box\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"content-more\"><\/div><\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-cg-blocks-card-howwedoit expanders\"><div class=\"box card-regulated-agreements card-howwedoit\"><div class=\"expander-box filter-box tag-active \"><div class=\"expander-title\" role=\"button\"><h4><strong>Activos digitales y tokens<\/strong><\/h4><\/div><div class=\"expander-subtitle\"><h5>La tokenizaci\u00f3n de activos ofrece una importante rentabilidad en los mercados de capitales y permite el fraccionamiento y el acceso a nuevas clases de activos.<\/h5><\/div><div class=\"expander-content\"><p>Los activos digitales permiten la creaci\u00f3n de tipos completamente nuevos de productos financieros y permiten ciclos comerciales m\u00e1s r\u00e1pidos y eficientes para los instrumentos financieros. La tokenizaci\u00f3n desbloquea un enorme valor comercial atrapado hoy en d\u00eda en activos il\u00edquidos como arte, bienes ra\u00edces, etc.<br \/>\u00a0<br \/>La custodia digital tambi\u00e9n puede presentar una oportunidad comercial atractiva para las instituciones financieras tradicionales, ya que su alcance en el mercado y sus conocimientos t\u00e9cnicos las posicionan para el \u00e9xito una vez que la tecnolog\u00eda, los negocios y las regulaciones converjan para crear la futura infraestructura del mercado financiero digital. Capgemini est\u00e1 bien equipado para orquestar soluciones DLT de nivel empresarial para clientes a trav\u00e9s de nuestra oferta de Custodia de Activos Digitales.<\/p><div class=\"bg-color video-align-right\"><div class=\"container\"><div class=\"row video-align-left\"><div class=\"col-md-12\"><div class=\"video-align-left row box box--4 box--mini\"><div class=\"col-md-3\"><\/div><div class=\"col-md-8 box-img-wrapper\"><div class=\"video-box\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"content-more\"><\/div><\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-cg-blocks-card-howwedoit expanders\"><div class=\"box card-regulated-agreements card-howwedoit\"><div class=\"expander-box filter-box tag-active \"><div class=\"expander-title\" role=\"button\"><h4><strong>Criptomonedas y pagos<\/strong><\/h4><\/div><div class=\"expander-subtitle\"><h5>Las criptomonedas han ganado una adopci\u00f3n generalizada constante, no solo en el mundo de los pagos, sino tambi\u00e9n como un medio innovador de recaudaci\u00f3n de fondos.<\/h5><\/div><div class=\"expander-content\"><p>A pesar de los numerosos beneficios de las criptomonedas en m\u00faltiples partes de la cadena de valor de los pagos, su volatilidad sigue siendo un desaf\u00edo clave, con cambios bruscos de precios que no son infrecuentes. Los pagos respaldados por cripto est\u00e1n en aumento, los casos de uso de lealtad est\u00e1n encontrando m\u00e1s aplicaciones y los marcos regulatorios est\u00e1n evolucionando para abarcar el comercio y el intercambio de criptoactivos.<br \/>\u00a0<br \/>Para seguir siendo relevantes, los bancos y los actores de los mercados de capitales deben reorientarse hacia un mundo cada vez m\u00e1s impulsado por las criptomonedas: explorar oportunidades para ayudar a los clientes a seleccionar las inversiones en criptomonedas adecuadas, o tal vez investigar los servicios de comercio de criptomonedas o los pagos digitales o la administraci\u00f3n de billeteras.<\/p><div class=\"bg-color video-align-right\"><div class=\"container\"><div class=\"row video-align-left\"><div class=\"col-md-12\"><div class=\"video-align-left row box box--4 box--mini\"><div class=\"col-md-3\"><\/div><div class=\"col-md-8 box-img-wrapper\"><div class=\"video-box\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"content-more\"><\/div><\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-cg-blocks-card-howwedoit expanders\"><div class=\"box card-regulated-agreements card-howwedoit\"><div class=\"expander-box filter-box tag-active \"><div class=\"expander-title\" role=\"button\"><h4><strong>Finanzas descentralizadas (DeFi)<\/strong><\/h4><\/div><div class=\"expander-subtitle\"><h5>DeFi redefinir\u00e1 el papel de las instituciones financieras para facilitar las transacciones. \u00bfCu\u00e1l es su estrategia empresarial para hacer avanzar a DeFi?<\/h5><\/div><div class=\"expander-content\"><p>DeFi puede ayudar a mejorar la accesibilidad, la interoperabilidad, la transparencia, la seguridad y la integridad del ecosistema de servicios financieros. Si bien los sistemas financieros centralizados tradicionales ciertamente no van a desaparecer, o no en el corto plazo, la descentralizaci\u00f3n va a redefinir los roles de muchas grandes instituciones financieras establecidas: deber\u00e1n adaptarse para proporcionar nuevos productos y servicios, o corren el riesgo de volverse obsoletas.<br \/>\u00a0<br \/>Los desarrollos del mercado demuestran la necesidad de sistemas avanzados de gesti\u00f3n de riesgos para resistir la volatilidad, y los bancos y las instituciones financieras est\u00e1n bien posicionados para facilitar el acceso seguro a las aplicaciones DeFi.<\/p><div class=\"bg-color video-align-right\"><div class=\"container\"><div class=\"row video-align-left\"><div class=\"col-md-12\"><div class=\"video-align-left row box box--4 box--mini\"><div class=\"col-md-3\"><\/div><div class=\"col-md-8 box-img-wrapper\"><div class=\"video-box\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"content-more\"><\/div><\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-cg-blocks-card-howwedoit expanders\"><div class=\"box card-regulated-agreements card-howwedoit\"><div class=\"expander-box filter-box tag-active \"><div class=\"expander-title\" role=\"button\"><h4><strong>El metaverso y los tokens no fungibles (NFT)<\/strong><\/h4><\/div><div class=\"expander-subtitle\"><h5>Si bien es tentador descartar el metaverso como otra moda pasajera, no lo haga. Y los NFT pueden ocupar un lugar central en el desbloqueo de su valor.<\/h5><\/div><div class=\"expander-content\"><p>A medida que el metaverso se convierta en un h\u00e1bitat natural para trabajar, jugar y socializar, aumentar\u00e1 la demanda de un mecanismo de intercambio de valor confiable. Los NFT podr\u00edan actuar como la base para la creaci\u00f3n de valor en el metaverso y estimular la econom\u00eda del creador.<br \/>\u00a0<br \/>Los NFT abren mercados sin liquidez y crean nuevas plataformas para la propiedad y el intercambio de muchos activos, incluidos el arte y la m\u00fasica. Adem\u00e1s, los NFT tambi\u00e9n pueden encontrar aplicaci\u00f3n en varias otras \u00e1reas, incluida la identidad digital y los pr\u00e9stamos respaldados por NFT.<\/p><div class=\"bg-color video-align-right\"><div class=\"container\"><div class=\"row video-align-left\"><div class=\"col-md-12\"><div class=\"video-align-left row box box--4 box--mini\"><div class=\"col-md-3\"><\/div><div class=\"col-md-8 box-img-wrapper\"><div class=\"video-box\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"content-more\"><\/div><\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-cg-blocks-card-howwedoit expanders\"><div class=\"box card-regulated-agreements card-howwedoit\"><div class=\"expander-box filter-box tag-active \"><div class=\"expander-title\" role=\"button\"><h4>Web 3.0<\/h4><\/div><div class=\"expander-subtitle\"><h5>La Web 3.0 tiene como objetivo descentralizar Internet distribuyendo la propiedad de los datos, haciendo que cada usuario sea el propietario soberano de sus datos.<\/h5><\/div><div class=\"expander-content\"><p>La Web 3.0 est\u00e1 preparada para ser la pr\u00f3xima generaci\u00f3n de Internet, basada en una infraestructura descentralizada y brindando a los usuarios y creadores de contenido m\u00e1s autonom\u00eda de datos y un alto grado de seguridad. Blockchain jugar\u00e1 un papel clave en esta evoluci\u00f3n de Internet, en combinaci\u00f3n con otras tecnolog\u00edas como la inteligencia artificial y el aprendizaje autom\u00e1tico.<br \/>\u00a0<br \/>La Web 3.0 ser\u00e1 un habilitador clave en la convergencia de las finanzas centralizadas y descentralizadas, creando una interfaz de red inteligente y aut\u00f3noma para el intercambio de informaci\u00f3n, que es abierta, confiable e inmutable.<\/p><div class=\"bg-color video-align-right\"><div class=\"container\"><div class=\"row video-align-left\"><div class=\"col-md-12\"><div class=\"video-align-left row box box--4 box--mini\"><div class=\"col-md-3\"><\/div><div class=\"col-md-8 box-img-wrapper\"><div class=\"video-box\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"content-more\"><\/div><\/div><\/div><\/div><\/div>\n<\/div><\/div><\/section>\n<\/div><\/div><\/div><\/div><\/div><\/section>\n\n\n\n\n\n\t\t\t\t<section\n\t\t\t\t\tclass=\"section section--lifeatcap-learning section--event-slider-careerInvent \">\n\n\t\t\t\t\t<div class=\"container\">\n\t\t\t\t\t\t<div class='career-invent-header'>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"slider slider-fader f96b46c3-7c07-4646-9465-cfd4ba419333\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div\n\t\t\t\t\t\t\tclass=\"slider-list \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div\n\t\t\t\t\t\t\t\t\t\tclass=\"slide active \">\n\t\t\t\t\t\t\t\t\t\t<div\n\t\t\t\t\t\t\t\t\t\t\tclass=\"slide-bg-wrapper wp-block-cg-blocks-career-invent is-style-sapphire2\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"bgImagesection\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"bgColor\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"container slide-info-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"col-md-6 col-sm-12 box-inner \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"bgColor\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"content-title \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"explore-header\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tdata-maxlength=\"68\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\ttitle=\"Nuestro enfoque para crear ofertas de DeFi\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tNuestro enfoque para crear ofertas de DeFi\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"box-title \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h4 data-maxlength=\"144\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\ttitle=\"NelsonHall comenta nuestros servicios en su blog de informaci\u00f3n de analistas.\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tstyle=\"white-space: pre-wrap;\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tNelsonHall comenta nuestros servicios en su blog de informaci\u00f3n de analistas.\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div >\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"btnDiv\"> <a class=\"more2\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tdata-maxlength=\"24\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\taria-label=\"Leer blog sobre Nuestro enfoque para crear ofertas de DeFi\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\ttitle=\"Opens in new window\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\ttabindex=\"0\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"https:\/\/research.nelson-hall.com\/blogs-webcasts\/nelsonhall-blog\/?avpage-views=blog&#038;type=post&#038;post_id=1124\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\ttarget=\"_blank\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tLeer blog\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a> <\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-md-6 col-sm-12 text-right box-img-wrapper escaper escaper-right\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<picture>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<source\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tsrcset=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2021\/11\/Capgemini_BSv_NelsonHall_learning-services.jpg?w=1200&amp;quality=90 1x, https:\/\/www.capgemini.com\/wp-content\/uploads\/2021\/11\/Capgemini_BSv_NelsonHall_learning-services.jpg?w=1200&amp;quality=90 2x\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tmedia=\"(min-width: 1500px)\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<source\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tsrcset=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2021\/11\/Capgemini_BSv_NelsonHall_learning-services.jpg?w=600&amp;quality=90 1x, https:\/\/www.capgemini.com\/wp-content\/uploads\/2021\/11\/Capgemini_BSv_NelsonHall_learning-services.jpg?w=1200&amp;quality=90 2x\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tmedia=\"(min-width: 992px)\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<source\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tsrcset=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2021\/11\/Capgemini_BSv_NelsonHall_learning-services.jpg?w=400&amp;quality=90 1x, https:\/\/www.capgemini.com\/wp-content\/uploads\/2021\/11\/Capgemini_BSv_NelsonHall_learning-services.jpg?w=800&amp;quality=90 2x\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tmedia=\"(min-width: 768px)\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<source\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tsrcset=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2021\/11\/Capgemini_BSv_NelsonHall_learning-services.jpg?w=400&amp;quality=90 1x, https:\/\/www.capgemini.com\/wp-content\/uploads\/2021\/11\/Capgemini_BSv_NelsonHall_learning-services.jpg?w=800&amp;quality=90 2x\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tmedia=\"(min-width: 0)\" \/>\n\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" class=\"box-img\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tsrc=\"https:\/\/www.capgemini.com\/wp-content\/uploads\/2021\/11\/Capgemini_BSv_NelsonHall_learning-services.jpg\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tstyle=\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\tobject-position: 44% 53%; object-fit: cover;\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\" alt=\"\" \/>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/picture>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<!-- <img decoding=\"async\" class=\"box-img\" src=\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\"\n\t\t\t\t\t\t\t\t\t\t\tstyle=\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\" alt=\"\"\n\t\t\t\t\t\t\t\t\t\t\/> -->\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div\n\t\t\t\t\t\t\t\t\t\t\t\tclass=\"\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"slide-reveal\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t<\/section>\n\n\t\t\t\t\n\n<section class=\"section section--expert-perspectives\"><div class=\"container\"><div class=\"row\"><div class=\"content-title col-12 col-md-8\"><h2 class=\"expert-heading\">Expert perspectives<\/h2><\/div><\/div><div class=\"expert-prospective-container\"><div class=\"row\"><\/div><\/div><\/div><\/section>\n\n\n<section class=\"wp-block-cg-blocks-call-to-action undefined is-style-cg-secondary-3 call-to-action-block\"><div class=\"container\"><div class=\"call-to-action-block-content-wrapper has-description\"><div class=\"text-wrapper has-description\"><h3 class=\"title\" data-maxlength=\"144\">\u00danete a la conversaci\u00f3n en LinkedIn<\/h3><p class=\"description\" data-maxlength=\"210\">Conecta con nuestros expertos y consulta las \u00faltimas perspectivas de la industria<\/p><\/div><div class=\"button-wrapper has-description\"><a class=\"cta-btn action-valid\" href=\"https:\/\/www.linkedin.com\/showcase\/capgemini-fs\/\" target=\"_blank\" rel=\"noopener noreferrer\" aria-label=\"Sigue nuestra pagina sobre \u00danete a la conversaci\u00f3n en LinkedIn\" title=\"Abrir en una nueva ventana\" data-maxlength=\"24\" tabindex=\"0\"> Sigue nuestra pagina <\/a><\/div><\/div><\/div><\/section>\n\n\n\n<div class=\"wp-block-cg-blocks-autocloud-form undefined autocloudform\"><div class=\"section--autoCloud-form\"><div class=\"wrapperAutoCloudSection\" id=\"linkToForm\"><div class=\"container\"><div class=\"row\"><div class=\"col-md-12 col-lg-6 left-img align-self-center escaper-left\"><\/div><div class=\"col-md-12 \"><div class=\"autoCloudForm\"><h3 class=\"formHelpText\">Contact us<\/h3>\t\t<div class=\"mf_forms__container \">\n\t\t\t\t\t\t\t\t<form id=\"mf_form_627823_3052349716\" class=\"mf_form__form row needs-validation\" action=\"\" method=\"post\" enctype=\"multipart\/form-data\" data-nosnippet>\n\t\t\t<div class=\"col-12\">\n\t\t\t\t<div class=\"asterisk_title\">\n\t\t\t\t\t<p><span class=\"star-required\">*<\/span> Campo obligatorio<\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"col-12\">\n\t\t\t\t<div class=\"mf_form__errors mf_form__errors--top\" role=\"alert\" aria-live=\"polite\">\n\t\t\t\t\t<ul class=\"mf_form__errors__list\"><\/ul>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t<input type=\"hidden\" name=\"form_id\" data-validate=\"number\" class=\"mf_form__id\" value=\"627823\" \/>\n\t\t\t\t<input type=\"hidden\" name=\"form_title\" class=\"mf_form__title\" value=\"\" \/>\n\t\t\t\t<input type=\"hidden\" name=\"wp_rest_nonce\" class=\"mf_form__wp_rest_nonce\" value=\"3fb441f171\" \/>\n\n\t\t\t\t<input type=\"hidden\" name=\"mf_form_conditional_logic\" class=\"mf_form__title conditional_logic\" value=\"\" \/>\n\t\t\t\t\n\t\t\t\t<input type=\"hidden\" name=\"mf_form_fields_country_dpo_field\" class=\"mf_form__title conditional_logic mf_form_fields_country_dpo_field\" value=\"\" \/>\n\n\t\t\t\t<!-- Anti-spam field -->\n\t\t\t\t<input type=\"text\" \n\t\t\t\t\tname=\"website_url\" \n\t\t\t\t\tclass=\"mf_field__url\" \n\t\t\t\t\tautocomplete=\"off\"\n\t\t\t\t\ttabindex=\"-1\"\n\t\t\t\t\taria-hidden=\"true\"\n\t\t\t\t\tstyle=\"position:absolute;left:-9999px;width:1px;height:1px;opacity:0;pointer-events:none;\" \n\t\t\t\t\/>\n\t\t\t<\/form>\n\n\t\t\t<div class=\"mf_form__success\" tabindex=\"0\" role=\"alert\">\n\t\t\t\t\t\t\t\t<p>Gracias! Hemos recibido su formulario.\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t\t<div class=\"mf_form__errors\">\n\t\t\t\t<p>Lo sentimos, el env\u00edo del formulario fall\u00f3. Int\u00e9ntalo de nuevo.<\/p>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t<script>\n\t\t\twindow.MF_CONFIG627823 = {\"627823\":{\"errors\":[],\"redirect\":\"\"}};\n\t\t<\/script>\n\t\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>How should financial institutions prepare for a decentralized future? <\/p>\n","protected":false},"author":35,"featured_media":12038,"parent":537594,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"cg_dt_proposed_to":[0],"cg_seo_hreflang_relations":"[]","cg_seo_canonical_relation":"","cg_seo_hreflang_x_default_relation":"","cg_dt_approved_content":false,"cg_dt_mandatory_content":false,"cg_dt_notes":"","cg_dg_source_changed":false,"cg_dt_link_disabled":false,"_yoast_wpseo_primary_brand":"","footnotes":"","featured_focal_points":"","partner_card_description":"","gsap_animation":0},"brand":[],"partner_type":[],"service":[],"industry":[27,154],"partners":[],"page-type":[339],"content-group":[],"class_list":["post-5278","page","type-page","status-publish","has-post-thumbnail","hentry","industry-banking","industry-banking-capital-markets","page-type-solutions"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.8 (Yoast SEO v22.8) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Futuros descentralizados - Capgemini Spain<\/title>\n<meta name=\"description\" content=\"El futuro de los servicios financieros comprender\u00e1 un equilibrio entre los sistemas y componentes financieros centralizados y descentralizados, impulsando la innovaci\u00f3n constante y r\u00e1pida al tiempo que garantiza el cumplimiento normativo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.capgemini.com\/es-es\/soluciones\/futuros-descentralizados\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Futuros descentralizados\" \/>\n<meta property=\"og:description\" content=\"El futuro de los servicios financieros comprender\u00e1 un equilibrio entre los sistemas y componentes financieros centralizados y descentralizados, impulsando la innovaci\u00f3n constante y r\u00e1pida al tiempo que garantiza el cumplimiento normativo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.capgemini.com\/es-es\/soluciones\/futuros-descentralizados\/\" \/>\n<meta property=\"og:site_name\" content=\"Capgemini Spain\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-04T17:42:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.capgemini.com\/es-es\/wp-json\/wp\/v2\/pages\/5278\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"627\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.capgemini.com\/es-es\/soluciones\/futuros-descentralizados\/\",\"url\":\"https:\/\/www.capgemini.com\/es-es\/soluciones\/futuros-descentralizados\/\",\"name\":\"Futuros descentralizados - Capgemini Spain\",\"isPartOf\":{\"@id\":\"https:\/\/www.capgemini.com\/es-es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.capgemini.com\/es-es\/soluciones\/futuros-descentralizados\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.capgemini.com\/es-es\/soluciones\/futuros-descentralizados\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2022-11-14T13:49:00+00:00\",\"dateModified\":\"2025-12-04T17:42:48+00:00\",\"description\":\"El futuro de los servicios financieros comprender\u00e1 un equilibrio entre los sistemas y componentes financieros centralizados y descentralizados, impulsando la innovaci\u00f3n constante y r\u00e1pida al tiempo que garantiza el cumplimiento normativo.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.capgemini.com\/es-es\/soluciones\/futuros-descentralizados\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.capgemini.com\/es-es\/soluciones\/futuros-descentralizados\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/www.capgemini.com\/es-es\/soluciones\/futuros-descentralizados\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.capgemini.com\/es-es\/soluciones\/futuros-descentralizados\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.capgemini.com\/es-es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Soluciones\",\"item\":\"https:\/\/www.capgemini.com\/es-es\/soluciones\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Futuros descentralizados\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.capgemini.com\/es-es\/#website\",\"url\":\"https:\/\/www.capgemini.com\/es-es\/\",\"name\":\"Capgemini Espa\u00f1a\",\"description\":\"Capgemini\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.capgemini.com\/es-es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es-ES\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Futuros descentralizados - Capgemini Spain","description":"El futuro de los servicios financieros comprender\u00e1 un equilibrio entre los sistemas y componentes financieros centralizados y descentralizados, impulsando la innovaci\u00f3n constante y r\u00e1pida al tiempo que garantiza el cumplimiento normativo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.capgemini.com\/es-es\/soluciones\/futuros-descentralizados\/","og_locale":"es_ES","og_type":"article","og_title":"Futuros descentralizados","og_description":"El futuro de los servicios financieros comprender\u00e1 un equilibrio entre los sistemas y componentes financieros centralizados y descentralizados, impulsando la innovaci\u00f3n constante y r\u00e1pida al tiempo que garantiza el cumplimiento normativo.","og_url":"https:\/\/www.capgemini.com\/es-es\/soluciones\/futuros-descentralizados\/","og_site_name":"Capgemini Spain","article_modified_time":"2025-12-04T17:42:48+00:00","og_image":[{"width":1200,"height":627,"url":"https:\/\/www.capgemini.com\/es-es\/wp-json\/wp\/v2\/pages\/5278","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.capgemini.com\/es-es\/soluciones\/futuros-descentralizados\/","url":"https:\/\/www.capgemini.com\/es-es\/soluciones\/futuros-descentralizados\/","name":"Futuros descentralizados - Capgemini Spain","isPartOf":{"@id":"https:\/\/www.capgemini.com\/es-es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.capgemini.com\/es-es\/soluciones\/futuros-descentralizados\/#primaryimage"},"image":{"@id":"https:\/\/www.capgemini.com\/es-es\/soluciones\/futuros-descentralizados\/#primaryimage"},"thumbnailUrl":"","datePublished":"2022-11-14T13:49:00+00:00","dateModified":"2025-12-04T17:42:48+00:00","description":"El futuro de los servicios financieros comprender\u00e1 un equilibrio entre los sistemas y componentes financieros centralizados y descentralizados, impulsando la innovaci\u00f3n constante y r\u00e1pida al tiempo que garantiza el cumplimiento normativo.","breadcrumb":{"@id":"https:\/\/www.capgemini.com\/es-es\/soluciones\/futuros-descentralizados\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.capgemini.com\/es-es\/soluciones\/futuros-descentralizados\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/www.capgemini.com\/es-es\/soluciones\/futuros-descentralizados\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/www.capgemini.com\/es-es\/soluciones\/futuros-descentralizados\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.capgemini.com\/es-es\/"},{"@type":"ListItem","position":2,"name":"Soluciones","item":"https:\/\/www.capgemini.com\/es-es\/soluciones\/"},{"@type":"ListItem","position":3,"name":"Futuros descentralizados"}]},{"@type":"WebSite","@id":"https:\/\/www.capgemini.com\/es-es\/#website","url":"https:\/\/www.capgemini.com\/es-es\/","name":"Capgemini Espa\u00f1a","description":"Capgemini","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.capgemini.com\/es-es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es-ES"}]}},"brand_term":[],"parsely":{"version":"1.1.0","canonical_url":"https:\/\/capgemini.com\/es-es\/soluciones\/futuros-descentralizados\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"WebPage","headline":"Futuros descentralizados","url":"https:\/\/www.capgemini.com\/es-es\/soluciones\/futuros-descentralizados\/","mainEntityOfPage":{"@type":"WebPage","@id":"https:\/\/www.capgemini.com\/es-es\/soluciones\/futuros-descentralizados\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Uncategorized","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Capgemini Spain","logo":""},"keywords":[],"dateCreated":"2022-11-14T13:49:00Z","datePublished":"2022-11-14T13:49:00Z","dateModified":"2025-12-04T17:42:48Z"},"rendered":"<meta name=\"parsely-title\" content=\"Futuros descentralizados\" \/>\n<meta name=\"parsely-link\" content=\"https:\/\/www.capgemini.com\/es-es\/soluciones\/futuros-descentralizados\/\" \/>\n<meta name=\"parsely-type\" content=\"index\" \/>\n<meta name=\"parsely-pub-date\" content=\"2022-11-14T13:49:00Z\" \/>\n<meta name=\"parsely-section\" content=\"Uncategorized\" \/>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/capgemini.com\/p.js"},"archive_status":false,"featured_image_src":"https:\/\/www.capgemini.com\/es-es\/wp-content\/themes\/capgemini2025\/assets\/images\/mockup.png","featured_image_alt":"","jetpack_sharing_enabled":true,"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"Capgemini Spain","distributor_original_site_url":"https:\/\/www.capgemini.com\/es-es","push-errors":false,"_links":{"self":[{"href":"https:\/\/www.capgemini.com\/es-es\/wp-json\/wp\/v2\/pages\/5278","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.capgemini.com\/es-es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.capgemini.com\/es-es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.capgemini.com\/es-es\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/www.capgemini.com\/es-es\/wp-json\/wp\/v2\/comments?post=5278"}],"version-history":[{"count":3,"href":"https:\/\/www.capgemini.com\/es-es\/wp-json\/wp\/v2\/pages\/5278\/revisions"}],"predecessor-version":[{"id":577377,"href":"https:\/\/www.capgemini.com\/es-es\/wp-json\/wp\/v2\/pages\/5278\/revisions\/577377"}],"up":[{"embeddable":true,"href":"https:\/\/www.capgemini.com\/es-es\/wp-json\/wp\/v2\/pages\/537594"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.capgemini.com\/es-es\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.capgemini.com\/es-es\/wp-json\/wp\/v2\/media?parent=5278"}],"wp:term":[{"taxonomy":"brand","embeddable":true,"href":"https:\/\/www.capgemini.com\/es-es\/wp-json\/wp\/v2\/brand?post=5278"},{"taxonomy":"partner_type","embeddable":true,"href":"https:\/\/www.capgemini.com\/es-es\/wp-json\/wp\/v2\/partner_type?post=5278"},{"taxonomy":"service","embeddable":true,"href":"https:\/\/www.capgemini.com\/es-es\/wp-json\/wp\/v2\/service?post=5278"},{"taxonomy":"industry","embeddable":true,"href":"https:\/\/www.capgemini.com\/es-es\/wp-json\/wp\/v2\/industry?post=5278"},{"taxonomy":"partners","embeddable":true,"href":"https:\/\/www.capgemini.com\/es-es\/wp-json\/wp\/v2\/partners?post=5278"},{"taxonomy":"page-type","embeddable":true,"href":"https:\/\/www.capgemini.com\/es-es\/wp-json\/wp\/v2\/page-type?post=5278"},{"taxonomy":"content-group","embeddable":true,"href":"https:\/\/www.capgemini.com\/es-es\/wp-json\/wp\/v2\/content-group?post=5278"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}