{"id":528201,"date":"2024-01-17T09:00:00","date_gmt":"2024-01-17T09:00:00","guid":{"rendered":"https:\/\/www.capgemini.com\/de-de\/?p=528201"},"modified":"2026-07-09T08:57:21","modified_gmt":"2026-07-09T08:57:21","slug":"lebenslauf-it-job","status":"publish","type":"post","link":"https:\/\/www.capgemini.com\/de-de\/insights\/blog\/lebenslauf-it-job\/","title":{"rendered":"Der perfekte Lebenslauf f\u00fcr den IT-Job"},"content":{"rendered":"\n<header class=\"wp-block-cg-blocks-hero-blogs header-hero-blogs\"><div class=\"container\"><div class=\"hero-blogs\"><div class=\"hero-blogs-content-wrapper\"><div class=\"row\"><div class=\"col-12\"><div class=\"header-title\"><h1>Der perfekte Lebenslauf f\u00fcr den IT-Job<\/h1><\/div><\/div><\/div><\/div><div class=\"hero-blogs-bottom\"><div class=\"header-author\"><div class=\"author-img\"><img decoding=\"async\" src=\"https:\/\/www.capgemini.com\/de-de\/wp-content\/uploads\/sites\/8\/2022\/07\/Spade_Thumbnail_03.jpg?w=200?w=200&amp;quality=10\" alt=\"Capgemini Karriere\" loading=\"lazy\"\/><\/div><div class=\"author-name-date\"><h5 class=\"author-name\">Capgemini Karriere<\/h5><h5 class=\"blog-date\">30. Sep. 2019, aktualisiert am 17. Januar 2024<\/h5><\/div><\/div><div class=\"brand-image\"><\/div><\/div><\/div><\/div><\/header>\n\n\n\n<section class=\"wp-block-cg-blocks-intro-para undefined section section--intro\"><div class=\"intro-para\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-md-2\"><nav class=\"article-social\"><ul class=\"social-nav\"><li class=\"ip-order-fb\"><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https:\/\/www.capgemini.com\/de-de\/insights\/blog\/lebenslauf-it-job\/\" target=\"_blank\" rel=\"noopener noreferrer\" title=\"opens in a new window\"><i aria-hidden=\"true\" class=\"icon-fb\"><\/i><span class=\"sr-only\">Facebook<\/span><\/a><\/li><li class=\"ip-order-li\"><a href=\"https:\/\/www.linkedin.com\/sharing\/share-offsite\/?url=https:\/\/www.capgemini.com\/de-de\/insights\/blog\/lebenslauf-it-job\/\" target=\"_blank\" rel=\"noopener noreferrer\" title=\"opens in a new window\"><i aria-hidden=\"true\" class=\"icon-li\"><\/i><span class=\"sr-only\">Linkedin<\/span><\/a><\/li><\/ul><\/nav><\/div><div class=\"col-12 col-md-8\"><h2 class=\"intro-para-title\">Er ist das zentrale Kernst\u00fcck einer Bewerbung und das erste, was ein Personaler in die H\u00e4nde bekommt: Der Lebenslauf. Doch wie sieht der perfekte Lebenslauf f\u00fcr einen IT-Job aus? Was gilt es zu ber\u00fccksichtigen? Eine Recruiterin gibt Tipps.<br><\/h2><p class=\"intro-para-content\">Der Lebenslauf ist das Dokument, das ausschlaggebend daf\u00fcr ist, ob es f\u00fcr Kandidat*innen im Bewerbungsprozess weitergeht oder nicht. Im Interview gibt eine Capgemini Recruiterin Einblicke, wie ein guter Lebenslauf aussieht und was f\u00fcr IT-Jobs besonders wichtig ist.<\/p><\/div><\/div><\/div><\/div><\/section>\n\n\n\n<section class=\"wp-block-cg-blocks-group undefined section section--article-content\"><div class=\"article-main-content\"><div class=\"container\"><div class=\"grid-container\"><div><div class=\"article-text article-quote-text\">\n<h2 class=\"wp-block-heading\" id=\"h-lebenslauf-informatiker\"><strong>Lebenslauf Informatiker<\/strong><\/h2>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-auf-was-achten-personaler-bei-einem-lebenslauf-besonders\">Auf was achten Personaler bei einem Lebenslauf besonders?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Zun\u00e4chst achten Personaler darauf, ob die F\u00e4higkeiten und Kenntnisse im Lebenslauf zu der entsprechenden ausgeschriebenen Vakanz passen. Zudem muss der Lebenslauf nachvollziehbar und der Inhalt verst\u00e4ndlich dargestellt sein. Gibt es beispielsweise L\u00fccken im Lebenslauf, die erkl\u00e4rungsbed\u00fcrftig sind? Ist die fachliche Entwicklung dargestellt? Solche Kriterien sind im Lebenslauf besonders entscheidend.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-was-macht-einen-guten-it-lebenslauf-aus\">Was macht einen guten IT-Lebenslauf aus?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">F\u00fcr einen IT-Job muss der Lebenslauf nicht besonders kreativ gestaltet oder aufwendig gelayoutet sein. Vielmehr ist es wichtig, dass die technischen Kenntnisse dargestellt und auch im Detail aufgef\u00fchrt werden. Zudem sollten die F\u00e4higkeiten mit Praxiserfahrung belegt werden. Wichtig ist, dass der Lebenslauf als solcher \u00fcbersichtlich gestaltet ist und der Personaler nicht lange nach Kenntnissen und F\u00e4higkeiten suchen muss. Denn im Schnitt hat ein Recruiter nur zwei bis drei Minuten Zeit, eine Bewerbung zu sichten.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-was-gehort-in-einen-lebenslauf\"><strong>Was geh\u00f6rt in einen Lebenslauf?<\/strong><\/h2>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-wie-sollte-man-einen-lebenslauf-fur-den-job-als-informatiker-inhaltlich-strukturieren\">Wie sollte man einen Lebenslauf f\u00fcr den Job als Informatiker inhaltlich strukturieren?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Das wichtigste ist eine \u00fcbersichtliche Struktur \u2013 das ist die Grundregel f\u00fcr jeden Lebenslauf. Ein tabellarischer Aufbau ist daf\u00fcr meist die beste Form, auf keinen Fall sollte ein Lebenslauf in Flie\u00dftext ausarten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Am besten beginnt man mit <strong><em>pers\u00f6nlichen Angaben<\/em><\/strong>, wie Adresse und Geburtsdatum. Danach kann man mit den aktuellsten und wichtigsten Punkten beginnen, wie der <strong><em>praktischen Erfahrung<\/em><\/strong>, die dann \u00fcbergeht zum Kapitel <em><strong>Studium<\/strong><\/em>. Bei dem Baustein Studium sollte auch der Notendurchschnitt und der Zeitraum bzw. die Dauer des Studiums aufgef\u00fchrt werden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gerade bei einem IT-Lebenslauf ist es besonders wichtig, die <strong><em>technischen Kenntnisse<\/em><\/strong> darzustellen. Dabei sollte aufgef\u00fchrt werden, mit welchen Technologien man sich auskennt (bspw. Programmiersprachen, Datenbanken etc.). Ein weiterer wichtiger Punkt sind die Sprachkenntnisse jenseits der Programmiersprache. Da sollte man die Muttersprache nicht vergessen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Um noch einen pers\u00f6nlichen Eindruck zu integrieren, sind <strong><em>Hobbys<\/em><\/strong> ein guter Abschluss f\u00fcr die Vita. Dabei sollten Bewerber authentisch bleiben und in ein, zwei Stichpunkten angeben, was sie wirklich gerne machen, bspw. E-Sports.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-welche-inhalte-sind-in-einem-informatiker-lebenslauf-besonders-wichtig\">Welche Inhalte sind in einem Informatiker Lebenslauf besonders wichtig?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Die Technologien sind besonders wichtig, daher sollte der Bewerber auf diese im Detail eingehen, am besten in einem eigenen Abschnitt. Hier sollte man nicht nur auflisten, dass man Java, SQL und \u00e4hnliches kann, sondern auch eine Wertung der Kenntnisse angeben. Zudem bietet es sich an, das Fachwissen in Cluster zu untergliedern, wie beispielsweise in <strong><em>Programmiersprachen<\/em><\/strong>,<strong><em> Datenbanken<\/em><\/strong> etc. Auch praktische Beispiele, die die eigenen Fachkenntnisse untermauern \u2013 die beispielsweise bei GitHub online sind oder auf einer eigenen Homepage \u2013 k\u00f6nnen gerne angebracht werden. Wenn man seine praktischen Kenntnisse oder sein Studium beschreibt, sollte man hier nat\u00fcrlich auch erw\u00e4hnen, mit welchen Technologien man gearbeitet hat.<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/section>\n\n\n\n<section class=\"wp-block-cg-blocks-card-tabs section--social-explore card-tabs-block undefined\"><div class=\"container\"><\/div><div class=\"tabs\"><div class=\"container\"><div class=\"row\"><div class=\"col-md-6 leftDiv\" id=\"leftDivId\"><div class=\"content-title\"><h2 class=\"card-tabs-heading\">Du m\u00f6chtest mit deinem perfekten Lebenslauf direkt einen spannenden IT-Job ergattern? Dann bewirb dich jetzt als:<\/h2><\/div><ul class=\"tabs-nav\"><li data-tab=\"51cddcf6-7b6b-478c-af47-cb77d0c2af55\"><a href=\"#\" role=\"button\"><h3 class=\"infoitem-title\">Softwareentwickler (w\/m\/d)<\/h3><\/a><\/li><li data-tab=\"874ecaa6-230b-4c7d-a2bc-da54f3aa7288\"><a href=\"#\" role=\"button\"><h3 class=\"infoitem-title\">IT Business Analyst (w\/m\/d)<\/h3><\/a><\/li><li data-tab=\"9c8185f3-d407-4fc6-9947-2ba464159e4c\"><a href=\"#\" role=\"button\"><h3 class=\"infoitem-title\">Junior Berater IT Projekte (w\/m\/d)<\/h3><\/a><\/li><\/ul><\/div><div class=\"col-md-6 rightDiv\"><div class=\"tabs-content\"><div class=\"tab\" data-tab=\"51cddcf6-7b6b-478c-af47-cb77d0c2af55\"><div class=\"tab-title\"><a href=\"#\" role=\"button\"><span><h3 class=\"infoitem-title\">Softwareentwickler (w\/m\/d)<\/h3><\/span><\/a><\/div><div class=\"tab-inner\"><p>Du m\u00f6chtest den gesamten Software-Entwicklungsprozess verstehen und gesch\u00e4ftskritische Individualsoftware auf h\u00f6chstem Niveau gestalten? Du sucht eine Zukunft im Software Engineering in einem global agierenden Unternehmen? Dann werde als Softwareentwickler (w\/m\/d) Teil unseres Teams!<\/p><a class=\"more2\" data-maxlength=\"24\" aria-label=\"Jetzt bewerben about Softwareentwickler (w\/m\/d)\" target=\"\" href=\"https:\/\/emp.jobylon.com\/jobs\/150612-capgemini-deutschland-softwareentwickler-wmd\/\" rel=\"noopener noreferrer\"><span class=\"btnHide\">Jetzt bewerben<\/span><\/a><\/div><\/div><div class=\"tab\" data-tab=\"874ecaa6-230b-4c7d-a2bc-da54f3aa7288\"><div class=\"tab-title\"><a href=\"#\" role=\"button\"><span><h3 class=\"infoitem-title\">IT Business Analyst (w\/m\/d)<\/h3><\/span><\/a><\/div><div class=\"tab-inner\"><p>Du \u00fcbernimmst gerne Verantwortung und m\u00f6chtest die digitale Transformation unserer Kunden aus Bereichen wie Automotive, \u00d6ffentlicher Sektor, Distribution, Manufacturing oder Retail mitgestalten? Du m\u00f6chtest als Teil eines Teams erleben wie aus einer Idee Wirklichkeit wird? Dann werde als IT Business Analyst (w\/m\/d) Teil unseres Teams!<\/p><a class=\"more2\" data-maxlength=\"24\" aria-label=\"Jetzt bewerben about IT Business Analyst (w\/m\/d)\" target=\"\" href=\"https:\/\/emp.jobylon.com\/jobs\/150614-capgemini-deutschland-it-business-analyst-wmd\/\" rel=\"noopener noreferrer\"><span class=\"btnHide\">Jetzt bewerben<\/span><\/a><\/div><\/div><div class=\"tab\" data-tab=\"9c8185f3-d407-4fc6-9947-2ba464159e4c\"><div class=\"tab-title\"><a href=\"#\" role=\"button\"><span><h3 class=\"infoitem-title\">Junior Berater IT Projekte (w\/m\/d)<\/h3><\/span><\/a><\/div><div class=\"tab-inner\"><p>Als Junior IT Consultant (w\/m\/d) entwickelst du gemeinsam mit deinen Kolleg*innen innovative L\u00f6sungen f\u00fcr unsere Kunden zu allen Fragen der Strategie-, Prozess- und IT-Optimierung in einem abwechslungsreichen Projektumfeld.<br>Diese Stelle ist in Vollzeit sowie in Teilzeit zu besetzen.<\/p><a class=\"more2\" data-maxlength=\"24\" aria-label=\"Jetzt bewerben about Junior Berater IT Projekte (w\/m\/d)\" target=\"\" href=\"https:\/\/emp.jobylon.com\/jobs\/144714-capgemini-deutschland-junior-berater-it-projekte-wmd\/\" rel=\"noopener noreferrer\"><span class=\"btnHide\">Jetzt bewerben<\/span><\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section>\n\n\n\n<section class=\"wp-block-cg-blocks-group undefined section section--article-content\"><div class=\"article-main-content\"><div class=\"container\"><div class=\"grid-container\"><div><div class=\"article-text article-quote-text\">\n<h3 class=\"wp-block-heading\" id=\"h-welche-it-kenntnisse-konnen-integriert-werden-und-in-welcher-detailtiefe-sollten-diese-dargestellt-werden\">Welche IT-Kenntnisse k\u00f6nnen integriert werden und in welcher Detailtiefe sollten diese dargestellt werden?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Es ist sinnvoll, eine Bewertung bzw. Einstufung der eigenen Kenntnisse in einer Auflistung aufzuf\u00fchren \u2013 beispielsweise durch die Angabe von \u201evertiefte Kenntnisse\u201c oder \u201eGrundkenntnisse\u201c. Manchmal tut man sich damit schwer, da die Bewertung nicht besonders objektiv und valide ist, aber man sollte es einfach nach eigenem Ermessen bewerten. Da rei\u00dft einem keiner den Kopf ab, da es kein offizielles Bewertungsschema gibt, ab wann man z. B. gut oder sehr gut in Java ist. Wenn man m\u00f6chte, kann man auch ein grafisches Bewertungs-Ranking mit Symbolen erstellen und muss sich nicht auf eine Skala wie \u201egut\u201c oder \u201esehr gut\u201c festlegen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es ist zudem empfehlenswert, den IT-Lebenslauf individuell f\u00fcr die jeweilige Stelle zu gestalten. Bei einer Generalisten-Stelle kann man wirklich alle Kenntnisse auff\u00fchren, die man w\u00e4hrend seines Studiums oder der praktischen T\u00e4tigkeit angesammelt hat. Bei einer spezifischen Position, wie z. B. dem Java-Entwickler, sollte man bei den Java-Kenntnissen mehr ins Detail gehen als bei anderen Programmiersprachen oder Technologien, in denen Kenntnisse vorhanden sind.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-welche-praktischen-erfahrungen-konnen-unter-berufserfahrung-aufgefuhrt-werden\">Welche praktischen Erfahrungen k\u00f6nnen unter \u201eBerufserfahrung\u201c aufgef\u00fchrt werden?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Ein Bewerber kann auf jeden Fall alles auff\u00fchren, was er praktisch gemacht hat. Man kann diesen klassischen Lebenslauf-Bereich \u201eBerufserfahrung\u201c einfach in \u201ePraktische T\u00e4tigkeiten\u201c oder \u201ePraktische Erfahrungen\u201c umbenennen, dann ist das etwas weiter gefasst. Dort k\u00f6nnen die studentischen T\u00e4tigkeiten, Praktika, Werkstudenten-Jobs etc. aufgef\u00fchrt werden. Ebenso k\u00f6nnen in einem extra Abschnitt die Projekte an der Universit\u00e4t abgebildet werden, an denen praktisch mitgewirkt wurde. Wenn man in seiner Freizeit etwas selbst programmiert oder eine Homepage gestaltet hat, dann ist das durchaus auch ein Projekt, das f\u00fcr einen spricht und den Lebenslauf bereichert.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-welche-formalen-kriterien-sollte-ein-lebenslauf-von-einem-informatiker-erfullen\">Welche formalen Kriterien sollte ein Lebenslauf von einem Informatiker erf\u00fcllen?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Eine einheitliche, \u00fcbersichtliche Form ist das Wichtigste. Wer ein bisschen kreativer ist kann beispielsweise Themen wie Hobbys mit Icons abbilden oder IT- und Sprachkenntnisse \u2013 beispielsweise mit einer Sternchenskala bewerten. Alles was f\u00fcr den Leser gut verst\u00e4ndlich und leicht zu interpretieren ist, ist willkommen. Weniger sinnvoll sind zu viele verschiedene Schriftfarben und -arten, denn damit wird der CV schwer lesbar, was nur zum Nachteil f\u00fcr den Bewerber ist.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Viele Bewerber versuchen den Lebenslauf so kurz wie m\u00f6glich zu halten und auf eine Seite zu reduzieren. Das ist jedoch kein Muss. Zwei Seiten sind eine optimale L\u00e4nge f\u00fcr einen IT-Lebenslauf, da so ausreichend Platz vorhanden ist, bei den praktischen T\u00e4tigkeiten ins Detail zu gehen. So kann sich der Personaler, der den Lebenslauf sichtet, besser vorstellen, was der Bewerber genau gemacht hat. Im Verlauf der Karriere lagert man dann bestimmte Themen auch aus, damit der CV nicht \u00fcberfrachtet ist, beispielsweise in eine Projektliste.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-wird-ein-bewerbungsfoto-im-lebenslauf-gewunscht\">Wird ein Bewerbungsfoto im Lebenslauf gew\u00fcnscht?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Heutzutage ist ein Bewerbungsfoto definitiv kein Muss mehr. Wenn man sich wohler damit f\u00fchlt, den Lebenslauf ohne Foto abzugeben, dann ist das vollkommen in Ordnung. Vor allem dann, wenn Bewerber gerade kein professionelles oder professionell wirkendes Foto zur Hand haben. Urlaubsfotos sind hier nicht gew\u00fcnscht. Wenn man ein gutes Foto hat, dann gibt es dem ganzen noch eine pers\u00f6nliche Note, aber das entscheidende sind letztendlich die technischen und praktischen Kenntnisse.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-welche-unterlagen-sind-neben-dem-lebenslauf-bei-einer-bewerbung-wichtig\">Welche Unterlagen sind neben dem Lebenslauf bei einer Bewerbung wichtig?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Wichtig ist nat\u00fcrlich, dass die <strong>gesamte Bewerbung<\/strong> vollst\u00e4ndig ist und weitere relevanten Unterlagen wie beispielsweise Hochschulzeugnisse, Noten\u00fcbersicht, Arbeitszeugnisse oder vor allem bei Absolventen ein Anschreiben mit eingereicht werden. Das Anschreiben ist insbesondere f\u00fcr Quereinsteiger eine gute M\u00f6glichkeit, um die eigene Motivation f\u00fcr den fachlichen Wechsel auszudr\u00fccken.<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/section>\n\n\n\n<section class=\"wp-block-cg-blocks-call-to-action undefined call-to-action-block\"><div class=\"container\"><div class=\"call-to-action-block-content-wrapper no-description\"><div class=\"text-wrapper no-description\"><h3 class=\"title\" data-maxlength=\"144\">Dein Lebenslauf ist bereit? Dann finde alle unsere IT-Jobs im Jobportal!<\/h3> <\/div><div class=\"button-wrapper no-description\"><a class=\"cta-btn action-valid\" href=\"https:\/\/www.capgemini.com\/de-de\/karriere\/jobs\/#country_code=de-de&amp;brand=Capgemini&amp;size=15\" target=\"\" rel=\"noopener noreferrer\" aria-label=\"Jetzt bewerben about Dein Lebenslauf ist bereit? Dann finde alle unsere IT-Jobs im Jobportal!\" title=\"Opens in a new window\" data-maxlength=\"24\" tabindex=\"0\"> Jetzt bewerben <\/a><\/div><\/div><\/div><\/section>\n\n\n<section class=\"section section--expert-perspectives\"><div class=\"container\"><div class=\"row\"><div class=\"content-title col-12 col-md-8\"><h2 class=\"expert-heading\">Jetzt auf dem Karriereblog weiterlesen:<\/h2><\/div><\/div><div class=\"expert-prospective-container\"><div class=\"row\"><div class=\"col-12 col-md-4 row-space\"><div class=\"box\"><div class=\"box-img-wrapper\"><a href=\"https:\/\/www.capgemini.com\/de-de\/insights\/blog\/online-vorstellungsgespraech-tipps\/\" aria-label=\"Tipps f\u00fcr das Online-Vorstellungsgespr\u00e4ch und Onboarding bei Capgemini\" tabindex=\"-1\"><img decoding=\"async\" class=\"box-img\" alt=\"\" src=\"https:\/\/www.capgemini.com\/de-de\/wp-content\/uploads\/sites\/8\/2022\/04\/online-vorstellungsgespraech-2.jpg?w=600&#038;quality=70\" style=\"object-position: 50% 50%; object-fit: cover;\" loading=\"lazy\" \/><\/a><\/div><div class=\"box-inner\"><div class=\"box-tag\"><\/div><a class=\"content-box-title\" href=\"https:\/\/www.capgemini.com\/de-de\/insights\/blog\/online-vorstellungsgespraech-tipps\/\" aria-label=\"Tipps f\u00fcr das Online-Vorstellungsgespr\u00e4ch und Onboarding bei Capgemini\"><h3 class=\"expert-subtitle\">Tipps f\u00fcr das Online-Vorstellungsgespr\u00e4ch und Onboarding bei Capgemini<\/h3><\/a><div class=\"box-bottom\">\n\t\t   <div class=\"box-logo\"><img decoding=\"async\" class=\"\" loading=\"lazy\" alt=\"Capgemini Karriere\" src=\"https:\/\/www.capgemini.com\/de-de\/wp-content\/uploads\/sites\/8\/2022\/07\/Spade_Thumbnail_03.jpg?w=200\" \/><\/div><div class=\"date-name-info\"><div class=\"author-text\">Capgemini Karriere<\/div><div class=\"date-text\">Jan. 25, 2021<\/div><\/div><\/div><\/div><\/div><\/div><div class=\"col-12 col-md-4 row-space\"><div class=\"box\"><div class=\"box-img-wrapper\"><a href=\"https:\/\/www.capgemini.com\/de-de\/insights\/blog\/einstieg-it-getstarted\/\" aria-label=\"Training on the Job: Einstieg in die IT mit GetStarted\" tabindex=\"-1\"><img decoding=\"async\" class=\"box-img\" alt=\"training-on-the-job-einstieg-it\" src=\"https:\/\/www.capgemini.com\/de-de\/wp-content\/uploads\/sites\/8\/2023\/07\/training-on-the-job-einstieg-it.jpg?w=600&#038;quality=70\" style=\"object-position: 50% 50%; object-fit: cover;\" loading=\"lazy\" \/><\/a><\/div><div class=\"box-inner\"><div class=\"box-tag\"><\/div><a class=\"content-box-title\" href=\"https:\/\/www.capgemini.com\/de-de\/insights\/blog\/einstieg-it-getstarted\/\" aria-label=\"Training on the Job: Einstieg in die IT mit GetStarted\"><h3 class=\"expert-subtitle\">Training on the Job: Einstieg in die IT mit GetStarted<\/h3><\/a><div class=\"box-bottom\">\n\t\t   <div class=\"box-logo\"><img decoding=\"async\" class=\"\" loading=\"lazy\" alt=\"Capgemini Karriere\" src=\"https:\/\/www.capgemini.com\/de-de\/wp-content\/uploads\/sites\/8\/2022\/07\/Spade_Thumbnail_03.jpg?w=200\" \/><\/div><div class=\"date-name-info\"><div class=\"author-text\">Capgemini Karriere<\/div><div class=\"date-text\">Juli 28, 2023<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"cta-wrapper\"><a class=\"cta-link\" target=\"\" aria-label=\"Zum Karriereblog about Jetzt auf dem Karriereblog weiterlesen:\" href=\"https:\/\/www.capgemini.com\/de-de\/insights\/blog\/#theme=karriere-bei-capgemini\" rel=\"noopener noreferrer\">Zum Karriereblog<\/a><\/div><\/div><\/section>\n\n\n<section class=\"wp-block-cg-blocks-learn-more updated-new-sample-amal learnMoreBlock\"><div class=\"container\"><div class=\"row\"><div class=\"content-title col-12 col-md-8\"><h2 class=\"learnmore-heading\">Mehr \u00fcber Capgemini erfahren:<\/h2><\/div><\/div><div class=\"row\"><div class=\"col-md-4\"><div class=\"box\"><div class=\"box-wrapper\"><a class=\"box-title\" href=\"https:\/\/www.capgemini.com\/de-de\/karriere\/warum-capgemini\/benefits\/\" target=\"\" aria-label=\"Flexible Benefits bei Capgemini\" rel=\"noopener noreferrer\"><div class=\"box-img-wrapper\"><img decoding=\"async\" src=\"https:\/\/www.capgemini.com\/de-de\/wp-content\/uploads\/sites\/8\/2022\/08\/GettyImages-1347652268.jpg?w=500&amp;quality=70\" srcset=\"https:\/\/www.capgemini.com\/de-de\/wp-content\/uploads\/sites\/8\/2022\/08\/GettyImages-1347652268.jpg?w=500&amp;quality=70 1x, https:\/\/www.capgemini.com\/de-de\/wp-content\/uploads\/sites\/8\/2022\/08\/GettyImages-1347652268.jpg?w=1000&amp;quality=70 2x\" class=\"box-img\" alt=\"capgemini-benefits\" style=\"object-fit:cover;object-position:50% 50%\" loading=\"lazy\"\/><\/div><h3 class=\"titleWithoutLink_learnMore\">Flexible Benefits bei Capgemini<\/h3><\/a><\/div><\/div><div class=\"box-inner\"><p class=\"box-desc\">Erfahre mehr \u00fcber die flexiblen M\u00f6glichkeiten, die Capgemini dir bietet, um eine gute Work-Life-Balance zu schaffen.<\/p><\/div><\/div><div class=\"col-md-4\"><div class=\"box\"><div class=\"box-wrapper\"><a class=\"box-title\" href=\"https:\/\/www.capgemini.com\/de-de\/karriere\/karrierewege\/it-berufe\/was-macht-ein-software-engineer\/\" target=\"\" aria-label=\"Als Software Engineer bei Capgemini einsteigen\" rel=\"noopener noreferrer\"><div class=\"box-img-wrapper\"><img decoding=\"async\" src=\"https:\/\/www.capgemini.com\/de-de\/wp-content\/uploads\/sites\/8\/2022\/09\/einstieg-als-software-engineer.jpg?w=500&amp;quality=70\" srcset=\"https:\/\/www.capgemini.com\/de-de\/wp-content\/uploads\/sites\/8\/2022\/09\/einstieg-als-software-engineer.jpg?w=500&amp;quality=70 1x, https:\/\/www.capgemini.com\/de-de\/wp-content\/uploads\/sites\/8\/2022\/09\/einstieg-als-software-engineer.jpg?w=1000&amp;quality=70 2x\" class=\"box-img\" alt=\"einstieg-als-software-engineer\" style=\"object-fit:cover;object-position:50% 50%\" loading=\"lazy\"\/><\/div><h3 class=\"titleWithoutLink_learnMore\">Als Software Engineer bei Capgemini einsteigen<\/h3><\/a><\/div><\/div><div class=\"box-inner\"><p class=\"box-desc\">Erfahre hier, was ein Software Engineer bei Capgemini macht und welche spannenden IT-Herausforderungen dich im Projektumfeld erwarten.<\/p><\/div><\/div><div class=\"col-md-4\"><div class=\"box\"><div class=\"box-wrapper\"><a class=\"box-title\" href=\"https:\/\/www.capgemini.com\/de-de\/karriere\/karrierewege\/absolventen\/\" target=\"\" aria-label=\"Als Absolvent*in bei Capgemini durchstarten\" rel=\"noopener noreferrer\"><div class=\"box-img-wrapper\"><img decoding=\"async\" src=\"https:\/\/www.capgemini.com\/de-de\/wp-content\/uploads\/sites\/8\/2022\/09\/GettyImages-1320278120_bearbeitet.webp?w=500&amp;quality=70\" srcset=\"https:\/\/www.capgemini.com\/de-de\/wp-content\/uploads\/sites\/8\/2022\/09\/GettyImages-1320278120_bearbeitet.webp?w=500&amp;quality=70 1x, https:\/\/www.capgemini.com\/de-de\/wp-content\/uploads\/sites\/8\/2022\/09\/GettyImages-1320278120_bearbeitet.webp?w=1000&amp;quality=70 2x\" class=\"box-img\" alt=\"graduates\" style=\"object-fit:cover;object-position:50% 50%\" loading=\"lazy\"\/><\/div><h3 class=\"titleWithoutLink_learnMore\">Als Absolvent*in bei Capgemini durchstarten<\/h3><\/a><\/div><\/div><div class=\"box-inner\"><p class=\"box-desc\">Erfahre hier, wie du nach dem Studium erfolgreich in der IT durchstartest und wie du mit unseren IT-Jobs f\u00fcr Graduates dein Potenzial voll aussch\u00f6pfst.<\/p><\/div><\/div><\/div><\/div><\/section>\n\n\n\n<section class=\"wp-block-cg-blocks-wrapper-careers-cards undefined section section--career-learning\"><div class=\"container\"><div class=\"row\"><\/div><\/div><\/section>\n","protected":false},"excerpt":{"rendered":"<p>Erfahre, wie du deinen IT-Lebenslauf so gestaltest, dass du Recruiter*innen \u00fcberzeugst und orientiere dich an unserer Lebenslauf-Vorlage.<\/p>\n","protected":false},"author":103,"featured_media":528207,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"cg_dt_proposed_to":[],"cg_seo_hreflang_relations":"[]","cg_seo_canonical_relation":"","cg_seo_hreflang_x_default_relation":"{\"uuid\":\"8b32ee9b-973c-431a-8ce0-2ac22b99f274\",\"blogId\":\"\",\"domain\":\"\",\"sitePath\":\"\",\"postLink\":\"\",\"postId\":null,\"isSaved\":true,\"isCrossLink\":false,\"hasCrossLink\":false}","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"cg_dt_approved_content":true,"cg_dt_mandatory_content":false,"cg_dt_notes":"","cg_dg_source_changed":false,"cg_dt_link_disabled":false,"_yoast_wpseo_primary_brand":"30","_jetpack_memberships_contains_paid_content":false,"footnotes":"","featured_focal_points":"","jetpack_post_was_ever_published":false},"categories":[372],"tags":[311],"brand":[30],"service":[],"industry":[],"partners":[],"blog-topic":[423],"content-group":[],"class_list":["post-528201","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-karriere","tag-karriere","brand-capgemini","blog-topic-karriere-bei-capgemini"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.7 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Der perfekte Lebenslauf f\u00fcr deinen IT-Job \u2013 Tipps einer Recruiterin<\/title>\n<meta name=\"description\" content=\"Erfahre, wie du deinen IT-Lebenslauf so gestaltest, dass du Recruiter*innen \u00fcberzeugst und orientiere dich an unserer Lebenslauf-Vorlage.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.capgemini.com\/de-de\/insights\/blog\/lebenslauf-it-job\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Der perfekte Lebenslauf f\u00fcr deinen IT-Job \u2013 Tipps einer Recruiterin\" \/>\n<meta property=\"og:description\" content=\"Erfahre, wie du deinen IT-Lebenslauf so gestaltest, dass du Recruiter*innen \u00fcberzeugst und orientiere dich an unserer Lebenslauf-Vorlage.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.capgemini.com\/de-de\/insights\/blog\/lebenslauf-it-job\/\" \/>\n<meta property=\"og:site_name\" content=\"Capgemini Germany\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-17T09:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-09T08:57:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.capgemini.com\/de-de\/wp-content\/uploads\/sites\/8\/2022\/04\/lebenslauf-it-jobs-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"569\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Capgemini Karriere\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sai Kiran\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.capgemini.com\\\/de-de\\\/insights\\\/blog\\\/lebenslauf-it-job\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.capgemini.com\\\/de-de\\\/insights\\\/blog\\\/lebenslauf-it-job\\\/\"},\"author\":{\"name\":\"Sai Kiran\",\"@id\":\"https:\\\/\\\/www.capgemini.com\\\/de-de\\\/#\\\/schema\\\/person\\\/e18c469582cc4e2dd2649041406912d2\"},\"headline\":\"Der perfekte Lebenslauf f\u00fcr den IT-Job\",\"datePublished\":\"2024-01-17T09:00:00+00:00\",\"dateModified\":\"2026-07-09T08:57:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.capgemini.com\\\/de-de\\\/insights\\\/blog\\\/lebenslauf-it-job\\\/\"},\"wordCount\":1428,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.capgemini.com\\\/de-de\\\/insights\\\/blog\\\/lebenslauf-it-job\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.capgemini.com\\\/de-de\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2022\\\/04\\\/lebenslauf-it-jobs-1.png\",\"keywords\":[\"Karriere\"],\"articleSection\":[\"Karriere\"],\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.capgemini.com\\\/de-de\\\/insights\\\/blog\\\/lebenslauf-it-job\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.capgemini.com\\\/de-de\\\/insights\\\/blog\\\/lebenslauf-it-job\\\/\",\"url\":\"https:\\\/\\\/www.capgemini.com\\\/de-de\\\/insights\\\/blog\\\/lebenslauf-it-job\\\/\",\"name\":\"Der perfekte Lebenslauf f\u00fcr deinen IT-Job \u2013 Tipps einer Recruiterin\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.capgemini.com\\\/de-de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.capgemini.com\\\/de-de\\\/insights\\\/blog\\\/lebenslauf-it-job\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.capgemini.com\\\/de-de\\\/insights\\\/blog\\\/lebenslauf-it-job\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.capgemini.com\\\/de-de\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2022\\\/04\\\/lebenslauf-it-jobs-1.png\",\"datePublished\":\"2024-01-17T09:00:00+00:00\",\"dateModified\":\"2026-07-09T08:57:21+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.capgemini.com\\\/de-de\\\/#\\\/schema\\\/person\\\/e18c469582cc4e2dd2649041406912d2\"},\"description\":\"Erfahre, wie du deinen IT-Lebenslauf so gestaltest, dass du Recruiter*innen \u00fcberzeugst und orientiere dich an unserer Lebenslauf-Vorlage.\",\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.capgemini.com\\\/de-de\\\/insights\\\/blog\\\/lebenslauf-it-job\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/www.capgemini.com\\\/de-de\\\/insights\\\/blog\\\/lebenslauf-it-job\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.capgemini.com\\\/de-de\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2022\\\/04\\\/lebenslauf-it-jobs-1.png\",\"contentUrl\":\"https:\\\/\\\/www.capgemini.com\\\/de-de\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2022\\\/04\\\/lebenslauf-it-jobs-1.png\",\"width\":1280,\"height\":569,\"caption\":\"lebenslauf-it\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.capgemini.com\\\/de-de\\\/#website\",\"url\":\"https:\\\/\\\/www.capgemini.com\\\/de-de\\\/\",\"name\":\"Capgemini Deutschland\",\"description\":\"Make it real\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.capgemini.com\\\/de-de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.capgemini.com\\\/de-de\\\/#\\\/schema\\\/person\\\/e18c469582cc4e2dd2649041406912d2\",\"name\":\"Sai Kiran\",\"url\":\"https:\\\/\\\/www.capgemini.com\\\/de-de\\\/author\\\/saikiranb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Der perfekte Lebenslauf f\u00fcr deinen IT-Job \u2013 Tipps einer Recruiterin","description":"Erfahre, wie du deinen IT-Lebenslauf so gestaltest, dass du Recruiter*innen \u00fcberzeugst und orientiere dich an unserer Lebenslauf-Vorlage.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.capgemini.com\/de-de\/insights\/blog\/lebenslauf-it-job\/","og_locale":"de_DE","og_type":"article","og_title":"Der perfekte Lebenslauf f\u00fcr deinen IT-Job \u2013 Tipps einer Recruiterin","og_description":"Erfahre, wie du deinen IT-Lebenslauf so gestaltest, dass du Recruiter*innen \u00fcberzeugst und orientiere dich an unserer Lebenslauf-Vorlage.","og_url":"https:\/\/www.capgemini.com\/de-de\/insights\/blog\/lebenslauf-it-job\/","og_site_name":"Capgemini Germany","article_published_time":"2024-01-17T09:00:00+00:00","article_modified_time":"2026-07-09T08:57:21+00:00","og_image":[{"width":1280,"height":569,"url":"https:\/\/www.capgemini.com\/de-de\/wp-content\/uploads\/sites\/8\/2022\/04\/lebenslauf-it-jobs-1.png","type":"image\/png"}],"author":"Capgemini Karriere","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Sai Kiran","Est. reading time":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.capgemini.com\/de-de\/insights\/blog\/lebenslauf-it-job\/#article","isPartOf":{"@id":"https:\/\/www.capgemini.com\/de-de\/insights\/blog\/lebenslauf-it-job\/"},"author":{"name":"Sai Kiran","@id":"https:\/\/www.capgemini.com\/de-de\/#\/schema\/person\/e18c469582cc4e2dd2649041406912d2"},"headline":"Der perfekte Lebenslauf f\u00fcr den IT-Job","datePublished":"2024-01-17T09:00:00+00:00","dateModified":"2026-07-09T08:57:21+00:00","mainEntityOfPage":{"@id":"https:\/\/www.capgemini.com\/de-de\/insights\/blog\/lebenslauf-it-job\/"},"wordCount":1428,"commentCount":0,"image":{"@id":"https:\/\/www.capgemini.com\/de-de\/insights\/blog\/lebenslauf-it-job\/#primaryimage"},"thumbnailUrl":"https:\/\/www.capgemini.com\/de-de\/wp-content\/uploads\/sites\/8\/2022\/04\/lebenslauf-it-jobs-1.png","keywords":["Karriere"],"articleSection":["Karriere"],"inLanguage":"de-DE","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.capgemini.com\/de-de\/insights\/blog\/lebenslauf-it-job\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.capgemini.com\/de-de\/insights\/blog\/lebenslauf-it-job\/","url":"https:\/\/www.capgemini.com\/de-de\/insights\/blog\/lebenslauf-it-job\/","name":"Der perfekte Lebenslauf f\u00fcr deinen IT-Job \u2013 Tipps einer Recruiterin","isPartOf":{"@id":"https:\/\/www.capgemini.com\/de-de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.capgemini.com\/de-de\/insights\/blog\/lebenslauf-it-job\/#primaryimage"},"image":{"@id":"https:\/\/www.capgemini.com\/de-de\/insights\/blog\/lebenslauf-it-job\/#primaryimage"},"thumbnailUrl":"https:\/\/www.capgemini.com\/de-de\/wp-content\/uploads\/sites\/8\/2022\/04\/lebenslauf-it-jobs-1.png","datePublished":"2024-01-17T09:00:00+00:00","dateModified":"2026-07-09T08:57:21+00:00","author":{"@id":"https:\/\/www.capgemini.com\/de-de\/#\/schema\/person\/e18c469582cc4e2dd2649041406912d2"},"description":"Erfahre, wie du deinen IT-Lebenslauf so gestaltest, dass du Recruiter*innen \u00fcberzeugst und orientiere dich an unserer Lebenslauf-Vorlage.","inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.capgemini.com\/de-de\/insights\/blog\/lebenslauf-it-job\/"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.capgemini.com\/de-de\/insights\/blog\/lebenslauf-it-job\/#primaryimage","url":"https:\/\/www.capgemini.com\/de-de\/wp-content\/uploads\/sites\/8\/2022\/04\/lebenslauf-it-jobs-1.png","contentUrl":"https:\/\/www.capgemini.com\/de-de\/wp-content\/uploads\/sites\/8\/2022\/04\/lebenslauf-it-jobs-1.png","width":1280,"height":569,"caption":"lebenslauf-it"},{"@type":"WebSite","@id":"https:\/\/www.capgemini.com\/de-de\/#website","url":"https:\/\/www.capgemini.com\/de-de\/","name":"Capgemini Deutschland","description":"Make it real","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.capgemini.com\/de-de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Person","@id":"https:\/\/www.capgemini.com\/de-de\/#\/schema\/person\/e18c469582cc4e2dd2649041406912d2","name":"Sai Kiran","url":"https:\/\/www.capgemini.com\/de-de\/author\/saikiranb\/"}]}},"blog_topic_info":[{"id":423,"name":"Karriere bei Capgemini"}],"taxonomy_info":{"category":[{"id":372,"name":"Karriere","slug":"karriere"}],"post_tag":[{"id":311,"name":"Karriere","slug":"karriere"}],"brand":[{"id":30,"name":"Capgemini","slug":"capgemini"}],"blog-topic":[{"id":423,"name":"Karriere bei Capgemini","slug":"karriere-bei-capgemini"}]},"archive_status":false,"featured_image_src":"https:\/\/www.capgemini.com\/de-de\/wp-content\/uploads\/sites\/8\/2022\/04\/lebenslauf-it-jobs-1.png","featured_image_alt":"lebenslauf-it","jetpack_sharing_enabled":true,"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"Capgemini Germany","distributor_original_site_url":"https:\/\/www.capgemini.com\/de-de","push-errors":false,"jetpack_featured_media_url":"https:\/\/www.capgemini.com\/de-de\/wp-content\/uploads\/sites\/8\/2022\/04\/lebenslauf-it-jobs-1.png","featured_image_url":"https:\/\/www.capgemini.com\/de-de\/wp-content\/uploads\/sites\/8\/2022\/04\/lebenslauf-it-jobs-1.png","author_title":"Capgemini Karriere","author_thumbnail_url":"https:\/\/www.capgemini.com\/de-de\/wp-content\/uploads\/sites\/8\/2022\/07\/Spade_Thumbnail_03.jpg?w=200","author_thumbnail_alt":"Capgemini Karriere","_links":{"self":[{"href":"https:\/\/www.capgemini.com\/de-de\/wp-json\/wp\/v2\/posts\/528201","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.capgemini.com\/de-de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.capgemini.com\/de-de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.capgemini.com\/de-de\/wp-json\/wp\/v2\/users\/103"}],"replies":[{"embeddable":true,"href":"https:\/\/www.capgemini.com\/de-de\/wp-json\/wp\/v2\/comments?post=528201"}],"version-history":[{"count":19,"href":"https:\/\/www.capgemini.com\/de-de\/wp-json\/wp\/v2\/posts\/528201\/revisions"}],"predecessor-version":[{"id":897407,"href":"https:\/\/www.capgemini.com\/de-de\/wp-json\/wp\/v2\/posts\/528201\/revisions\/897407"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.capgemini.com\/de-de\/wp-json\/wp\/v2\/media\/528207"}],"wp:attachment":[{"href":"https:\/\/www.capgemini.com\/de-de\/wp-json\/wp\/v2\/media?parent=528201"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.capgemini.com\/de-de\/wp-json\/wp\/v2\/categories?post=528201"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.capgemini.com\/de-de\/wp-json\/wp\/v2\/tags?post=528201"},{"taxonomy":"brand","embeddable":true,"href":"https:\/\/www.capgemini.com\/de-de\/wp-json\/wp\/v2\/brand?post=528201"},{"taxonomy":"service","embeddable":true,"href":"https:\/\/www.capgemini.com\/de-de\/wp-json\/wp\/v2\/service?post=528201"},{"taxonomy":"industry","embeddable":true,"href":"https:\/\/www.capgemini.com\/de-de\/wp-json\/wp\/v2\/industry?post=528201"},{"taxonomy":"partners","embeddable":true,"href":"https:\/\/www.capgemini.com\/de-de\/wp-json\/wp\/v2\/partners?post=528201"},{"taxonomy":"blog-topic","embeddable":true,"href":"https:\/\/www.capgemini.com\/de-de\/wp-json\/wp\/v2\/blog-topic?post=528201"},{"taxonomy":"content-group","embeddable":true,"href":"https:\/\/www.capgemini.com\/de-de\/wp-json\/wp\/v2\/content-group?post=528201"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}