{"id":765404,"date":"2022-08-02T03:49:23","date_gmt":"2022-08-02T03:49:23","guid":{"rendered":"https:\/\/www.capgemini.com\/de-de\/?page_id=765404"},"modified":"2026-08-28T06:28:55","modified_gmt":"2026-08-28T06:28:55","slug":"financial-services","status":"publish","type":"page","link":"https:\/\/www.capgemini.com\/de-de\/karriere\/karrierewege\/branchen\/it-jobs-financial-services\/","title":{"rendered":"Financial Services"},"content":{"rendered":"\n<div class=\"wp-block-cg-blocks-hero-picture-card undefined is-style-default  heroPictureCard\"><div class=\"heroPictureCardBgs\"><picture><source srcset=\"https:\/\/www.capgemini.com\/de-de\/wp-content\/uploads\/sites\/8\/2021\/01\/financial-services-digital-customer-service.png?w=2880&amp;quality=70 1x, https:\/\/www.capgemini.com\/de-de\/wp-content\/uploads\/sites\/8\/2021\/01\/financial-services-digital-customer-service.png?w=2880&amp;quality=70 2x\" media=\"(min-width: 1500px)\"\/><source srcset=\"https:\/\/www.capgemini.com\/de-de\/wp-content\/uploads\/sites\/8\/2021\/01\/financial-services-digital-customer-service.png?w=1440&amp;quality=70 1x, https:\/\/www.capgemini.com\/de-de\/wp-content\/uploads\/sites\/8\/2021\/01\/financial-services-digital-customer-service.png?w=2880&amp;quality=70 2x\" media=\"(min-width: 992px)\"\/><source srcset=\"https:\/\/www.capgemini.com\/de-de\/wp-content\/uploads\/sites\/8\/2021\/01\/financial-services-digital-customer-service.png?w=1024&amp;quality=70 1x, https:\/\/www.capgemini.com\/de-de\/wp-content\/uploads\/sites\/8\/2021\/01\/financial-services-digital-customer-service.png?w=1024&amp;quality=70 2x\" media=\"(min-width: 768px)\"\/><source srcset=\"https:\/\/www.capgemini.com\/de-de\/wp-content\/uploads\/sites\/8\/2021\/01\/financial-services-digital-customer-service.png?w=768&amp;quality=70 1x, https:\/\/www.capgemini.com\/de-de\/wp-content\/uploads\/sites\/8\/2021\/01\/financial-services-digital-customer-service.png?w=768&amp;quality=70 2x\" media=\"(min-width: 0)\"\/><img decoding=\"async\" src=\"https:\/\/www.capgemini.com\/de-de\/wp-content\/uploads\/sites\/8\/2021\/01\/financial-services-digital-customer-service.png\" class=\"desktopImage\" alt=\"financial-services\" style=\"object-fit:cover;object-position:24% 35%\" loading=\"eager\"\/><\/picture><picture><source srcset=\"https:\/\/www.capgemini.com\/de-de\/wp-content\/uploads\/sites\/8\/2021\/01\/financial-services-digital-customer-service.png?w=2880&amp;quality=70 1x, https:\/\/www.capgemini.com\/de-de\/wp-content\/uploads\/sites\/8\/2021\/01\/financial-services-digital-customer-service.png?w=2880&amp;quality=70 2x\" media=\"(min-width: 1500px)\"\/><source srcset=\"https:\/\/www.capgemini.com\/de-de\/wp-content\/uploads\/sites\/8\/2021\/01\/financial-services-digital-customer-service.png?w=1440&amp;quality=70 1x, https:\/\/www.capgemini.com\/de-de\/wp-content\/uploads\/sites\/8\/2021\/01\/financial-services-digital-customer-service.png?w=2880&amp;quality=70 2x\" media=\"(min-width: 992px)\"\/><source srcset=\"https:\/\/www.capgemini.com\/de-de\/wp-content\/uploads\/sites\/8\/2021\/01\/financial-services-digital-customer-service.png?w=1024&amp;quality=70 1x, https:\/\/www.capgemini.com\/de-de\/wp-content\/uploads\/sites\/8\/2021\/01\/financial-services-digital-customer-service.png?w=1024&amp;quality=70 2x\" media=\"(min-width: 768px)\"\/><source srcset=\"https:\/\/www.capgemini.com\/de-de\/wp-content\/uploads\/sites\/8\/2021\/01\/financial-services-digital-customer-service.png?w=768&amp;quality=70 1x, https:\/\/www.capgemini.com\/de-de\/wp-content\/uploads\/sites\/8\/2021\/01\/financial-services-digital-customer-service.png?w=768&amp;quality=70 2x\" media=\"(min-width: 0)\"\/><img decoding=\"async\" src=\"https:\/\/www.capgemini.com\/de-de\/wp-content\/uploads\/sites\/8\/2021\/01\/financial-services-digital-customer-service.png\" class=\"mobileImage\" alt=\"financial-services\" style=\"object-fit:cover;object-position:24% 35%\" loading=\"eager\"\/><\/picture><\/div><div class=\"heroPictureCardHeaderShape\"><\/div><div class=\"container\"><div class=\"row\"><div class=\"col-md-8 col-lg-6\"><div class=\"heroPictureCardBox\"><div class=\"heroPictureCardBoxTitle\"><h1 data-maxlength=\"144\">Financial Services Jobs: Unterst\u00fctze die vielf\u00e4ltige IT in der Finanzbranche<\/h1><\/div><\/div><\/div><\/div><\/div><div class=\"small-device\"><div class=\"brandLogoWrapper\"> <\/div><\/div><\/div>\n\n\n\n<section class=\"wp-block-cg-blocks-intro-para undefined section section--intro\"><div class=\"intro-para\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-md-2\"><nav class=\"article-social\"><ul class=\"social-nav\"><li class=\"ip-order-fb\"><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https:\/\/www.capgemini.com\/de-de\/karriere\/karrierewege\/branchen\/it-jobs-financial-services\/\" target=\"_blank\" rel=\"noopener noreferrer\" title=\"opens in a new window\"><i aria-hidden=\"true\" class=\"icon-fb\"><\/i><span class=\"sr-only\">Facebook<\/span><\/a><\/li><li class=\"ip-order-li\"><a href=\"https:\/\/www.linkedin.com\/sharing\/share-offsite\/?url=https:\/\/www.capgemini.com\/de-de\/karriere\/karrierewege\/branchen\/it-jobs-financial-services\/\" target=\"_blank\" rel=\"noopener noreferrer\" title=\"opens in a new window\"><i aria-hidden=\"true\" class=\"icon-li\"><\/i><span class=\"sr-only\">Linkedin<\/span><\/a><\/li><\/ul><\/nav><\/div><div class=\"col-12 col-md-8\"><h2 class=\"intro-para-title\">Ob im Versicherungssektor oder im Bankenwesen: Die Capgemini-Projekte im Bereich Financial Services halten zahlreiche interessante Jobs f\u00fcr dich bereit.<br> <\/h2><p class=\"intro-para-content\">Informiere dich hier \u00fcber Trends der Branche, Vorteile f\u00fcr Bewerber*innen und Einstiegsm\u00f6glichkeiten.<\/p><\/div><\/div><\/div><\/div><\/section>\n\n\n\n<section class=\"wp-block-cg-blocks-group undefined section section--article-content\"><div class=\"article-main-content\"><div class=\"container\"><div class=\"grid-container\"><div><div class=\"article-text article-quote-text\">\n<h2 id=\"h-tech-und-consulting-wie-wir-die-finanzbranche-unterstutzen\" class=\"wp-block-heading\">Tech und Consulting: Wie wir die Finanzbranche unterst\u00fctzen <\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Der Bereich Financial Services gliedert sich grob in zwei Segmente bei Capgemini: Die Versicherungsbranche und das Bankenwesen. Die IT-Expert*innen bei Capgemini beraten Kunden in beiden Segmenten von der Strategie \u00fcber die Optimierung von Prozessen und IT bis hin zur Umsetzung und den Betrieb von L\u00f6sungen \u2013 ein besonderer Fokus liegt dabei auf der Digitalen Transformation und IT-Security. <\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Im <strong>Versicherungssektor<\/strong> besteht das Kerngesch\u00e4ft unserer Kunden in der sog. kollektiven Risiko\u00fcbernahme in den Bereichen Lebens-, Sach-, Kranken- und Rechtsschutzversicherung. In unseren IT-Projekten befassen wir uns z.B. mit der Verbesserung des Kundenservice, der Risikominimierung mithilfe des Internet of Things und der Automatisierung von Gesch\u00e4ftsprozessen, z. B. bei der Schadensabwicklung.<\/li>\n\n\n\n<li>Der <strong>Bankensektor<\/strong> bietet klassische Produkte in den Gesch\u00e4ftsfeldern Zahlungsverkehr, Einlagen, Kredit und Wertpapier sowie Beratungsdienstleistungen an. Auch Banken m\u00fcssen auf gestiegene Anforderungen reagieren: Kunden wollen ihre Bankgesch\u00e4fte heute global, mobil und rund um die Uhr abwickeln. Hinzu kommt der Umgang mit gesetzlichen\/regulatorischen Auflagen sowie die Konkurrenz durch branchenfremde Wettbewerber*innen wie FinTechs oder die GAFAs (Google, Apple, Facebook, Amazon), die selbst verst\u00e4rkt Bezahlfunktionen, Kartenprodukte und Kredite anbieten. In diesem Themenumfeld bieten wir IT-Consulting-Leistungen an und entwickeln innovative L\u00f6sungen f\u00fcr unsere Kunden.<\/li>\n<\/ul>\n<\/div><\/div><\/div><\/div><\/div><\/section>\n\n\n\n<section class=\"wp-block-cg-blocks-card-tabs section--social-explore card-tabs-block undefined\"><div class=\"container\"><\/div><div class=\"tabs\"><div class=\"container\"><div class=\"row\"><div class=\"col-md-6 leftDiv\" id=\"leftDivId\"><div class=\"content-title\"><h2 class=\"card-tabs-heading\">Financial Services Jobs bei Capgemini:<\/h2><\/div><ul class=\"tabs-nav\"><li data-tab=\"11def81a-3264-43c4-b1a2-499b5f66754b\"><a href=\"#\" role=\"button\"><h3 class=\"infoitem-title\"><span class=\"has-inline-color has-white-color\">Cloud Architect (w\/m\/d)<\/span> <\/h3><\/a><\/li><\/ul><\/div><div class=\"col-md-6 rightDiv\"><div class=\"tabs-content\"><div class=\"tab\" data-tab=\"11def81a-3264-43c4-b1a2-499b5f66754b\"><div class=\"tab-title\"><a href=\"#\" role=\"button\"><span><h3 class=\"infoitem-title\"><span class=\"has-inline-color has-white-color\">Cloud Architect (w\/m\/d)<\/span> <\/h3><\/span><\/a><\/div><div class=\"tab-inner\"><p>Du bist ein Impulsgeber in Fragen der Prozessautomation, Digitalisierung, Artificial Intelligence, Microservices und DevOps und gedanklich immer einen Schritt voraus? Du inspirierst Softwareentwickler*innen und steckst mit deiner Begeisterung f\u00fcr Innovationen dein Team und unsere Kunden an? Dann gestalte als IT Architekt (w\/m\/d) mit uns die Zukunft der Finanzbranche. <\/p><a class=\"more2\" data-maxlength=\"24\" aria-label=\"Jetzt bewerben about &lt;span class=&quot;has-inline-color has-white-color&quot;&gt;Cloud Architect (w\/m\/d)&lt;\/span&gt; \" target=\"_blank\" href=\"https:\/\/www.capgemini.com\/de-de\/jobs\/342530-de_DE+sap_btp\/\" rel=\"noopener noreferrer\"><span class=\"btnHide\">Jetzt bewerben<\/span><\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section>\n\n\n\n<section class=\"wp-block-cg-blocks-group undefined section section--article-content\"><div class=\"article-main-content\"><div class=\"container\"><div class=\"grid-container\"><div><div class=\"article-text article-quote-text\"><\/div><\/div><\/div><\/div><\/div><\/section>\n\n\n\n<section class=\"wp-block-cg-blocks-group undefined section section--article-content\"><div class=\"article-main-content\"><div class=\"container\"><div class=\"grid-container\"><div><div class=\"article-text article-quote-text\">\n<h2 id=\"h-unsere-kundenprojekte-vielfaltige-jobs-im-bereich-financial-services\" class=\"wp-block-heading\">Unsere Kundenprojekte: Vielf\u00e4ltige Jobs im Bereich Financial Services<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Im Versicherungssektor unterst\u00fctzt Capgemini verschiedene gro\u00dfe und mittelgro\u00dfe Gesellschaften bei der Core-Transformation, also der Anpassung des Kerngesch\u00e4fts f\u00fcr die digitale Welt. Daraus ergeben sich interessante Chancen f\u00fcr eine besonders pers\u00f6nliche Betreuung des Kunden: Der Faktor \u201eConvenience\u201c wird immer mehr zum Differenzierungsmerkmal. Serviceorientierte Prozesse sind dabei eng an das Thema k\u00fcnstliche Intelligenz gekoppelt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Im Bankensektor unterst\u00fctzen wir Universalbanken, gro\u00dfe genossenschaftliche Institute, Landesbanken und gro\u00dfe Sparkassen sowie die deutschen Ableger internationaler Finanzinstitute. Auch f\u00fcr Captive-Financial-Services-Kunden z. B. Automobilbanken und Finanzt\u00f6chter anderer Industrieunternehmen entwickeln wir innovative Gesch\u00e4ftsmodelle und IT-L\u00f6sungen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">F\u00fcr die Umsetzung solcher Projekte setzen wir auf agile Teamstrukturen, bei denen Business Analysten und Software Engineers sich eng mit den Kunden austauschen. Auch beim Erfahrungsgrad setzen wir auf gemischte Teams: Senior- und Junior-Kolleginnen und Kollegen arbeiten bei uns Seite an Seite. In gro\u00dfen Implementierungsprojekten werden signifikante Teile der Leistung auch durch internationale Zusammenarbeit erbracht \u2013 hier nutzen wir unser erprobtes Rightshore\u00ae-Modell, d. h. den optimalen Mix von Teams aus Onshore (Deutschland), Nearshore (Polen, deutschsprachig) und Offshore (z. B. Indien, China und Vietnam).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h2 id=\"h-it-herausforderungen-und-trends-in-den-financial-services\" class=\"wp-block-heading\">IT-Herausforderungen und -Trends in den Financial Services<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Die gr\u00f6\u00dfte IT-Herausforderung in der Financial Services Branche besteht aktuell in der Anpassung historisch gewachsener IT-Landschaften an die Anforderungen der Digitalisierung. Dies umfasst z. B. den Umbau der IT-Organisation unter DevOps-Gesichtspunkten, die Automatisierung von Gesch\u00e4ftsprozessen und die Migration auf neue Technologien wie die Cloud. Gleichzeitig m\u00fcssen Ver\u00e4nderungen des Gesch\u00e4ftsmodells und neue gesetzliche Anforderungen ber\u00fccksichtigt werden. Bei den verwendeten Technologien setzen wir \u00fcblicherweise auf eine Basis aus Java, JEE und webbasierten Oberfl\u00e4chen.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>F\u00fcr bestimmte Gesch\u00e4ftsbereiche im Segment&nbsp;Versicherungen&nbsp;kommen au\u00dferdem L\u00f6sungen wie Guidewire zum Einsatz, z. B. f\u00fcr die Vertragsverwaltung oder das Schadensmanagement.<\/li>\n\n\n\n<li>Im Segment&nbsp;Banken&nbsp;hat fast jedes Institut spezifische Software im Einsatz. Das reicht von Standardl\u00f6sungen wie SAP bis hin zu Eigenentwicklungen auf Grundlage verschiedener Technologie-Stacks.<\/li>\n\n\n\n<li>Segment\u00fcbergreifend&nbsp;sind des Weiteren L\u00f6sungen zur Integration von Software in bestehende IT-Landschaften (ESB, BPM und API-Management) von gro\u00dfer Bedeutung.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Ein wichtiger IT-Trend besteht in der Bereitstellung von High-End-Standardl\u00f6sungen f\u00fcr Financial Services. Diese sind kosteneffizient und verk\u00fcrzen die Time-to-Market-Zeitspanne f\u00fcr die Bereitstellung neuer Produkte f\u00fcr die Endkunden. Au\u00dferdem erlaubt dieses Modell den flexiblen Zukauf von Modulen und Kompetenzen. Weiterhin steht das Thema digitale Kommunikation mit Kunden und Vertriebspartnern bei vielen Unternehmen auf der Agenda. Und nicht zuletzt geht es um die Aussch\u00f6pfung von Automatisierungspotenzialen auf Basis von BPM, Robotics und k\u00fcnstlicher Intelligenz. Unsere Teams unterst\u00fctzen Kunden bei der Realisierung all dieser Trends durch ihr neuestes Know-how und ihre relevante Erfahrung aus internationalen Projekten.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><em>\u201eDer Bankensektor befindet sich in einem tiefgreifenden, strukturellen Wandel \u2013 getrieben von den aktuellen technologischen Innovationen wird eine Trennung in Produkt-, Risiko- und Vertriebseinheiten (Plattformanbieter\/ FinTechs) immer offensichtlicher. Eine sehr spannende Zeit mit ungeahnten M\u00f6glichkeiten f\u00fcr (IT-)Expert*innen im Bereich Financial Services.\u201c<\/em><\/p>\n<cite>Jens Korb, Head of Business Technology Solutions Banking<\/cite><\/blockquote>\n\n\n\n<h2 id=\"h-was-eine-it-karriere-im-bereich-financial-services-fur-dich-bereithalt\" class=\"wp-block-heading\"><strong>Was eine IT-Karriere im Bereich Financial Services f\u00fcr dich bereith\u00e4lt<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Der <a href=\"\/de-de\/insights\/blog\/digitalisierung-banken-und-versicherungen\">Bereich Financial Services<\/a> ist derzeit einer der innovativsten und technologisch vielf\u00e4ltigsten \u00fcberhaupt. Durch den enormen Digitalisierungsdruck werden hier weiterhin signifikante Investitionen in die IT get\u00e4tigt. Wenn du dich f\u00fcr neue Technologien begeisterst und echte intellektuelle Herausforderungen suchst, bieten sich dir im Bereich Financial Services zahlreiche Chancen. Du kannst die Branche aktiv und unter Verwendung neuester Technologien beim Wandel begleiten. Du arbeitest international und kannst schnell Verantwortung \u00fcbernehmen \u2013 aber gleichzeitig auf das Know-how von erfahrenen Kolleg*innen zur\u00fcckgreifen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Um in dieser vielseitigen Branche durchstarten zu k\u00f6nnen, solltest du als <a href=\"\/de-de\/karriere\/karrierewege\/it-berufe\/was-macht-ein-business-analyst\/\">Business-\/Technology-Berater*in<\/a> idealerweise \u00fcber einen BWL- oder Wirtschaftsinformatik-Hochschulabschluss verf\u00fcgen. Als <a href=\"\/de-de\/karriere\/karrierewege\/it-berufe\/was-macht-ein-software-engineer\/\">Softwareingenieur*in<\/a> oder Solution-Architekt*in solltest du einen MINT-Hochschulabschluss sowie Entwicklungs-Expertise besitzen. Eine rasche Auffassungsgabe und gute Kommunikationsf\u00e4higkeiten sowie Praktika in der Branche sind ein weiteres Plus.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aber keine Sorge: Mit unserem projektbegleitenden <a href=\"\/de-de\/karriere\/karrierewege\/absolventen\">GetStarted-Programm<\/a> machen wir es Berufseinsteiger*innen sehr leicht, sich in ihre neue Rolle hineinzufinden. Kolleginnen und Kollegen im Bereich Financial Services suchen wir vor allem f\u00fcr <a href=\"\/de-de\/karriere\/lets-connect\/it-jobs-deutschland\">unsere Capgemini-Offices<\/a> in Hannover, K\u00f6ln\/D\u00fcsseldorf, Frankfurt und M\u00fcnchen. Hier erh\u00e4ltst du einen Einblick in unsere aktuellen Stellenangebote. <\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/www.capgemini.com\/de-de\/jobs\">Zum Jobportal<\/a><\/div>\n<\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 id=\"h-du-hast-noch-fragen\" class=\"wp-block-heading\">Du hast noch Fragen?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Dann wende dich an folgende Capgemini-Ansprechpartner*innen f\u00fcr Financial Services:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Kontakt<\/strong><\/p>\n\n\n\n<div class=\"wp-block-jetpack-contact-info\">\n<p class=\"wp-block-paragraph\"><strong><a href=\"mailto:klaus-georg.meyer@capgemini.com\" target=\"_blank\" rel=\"noreferrer noopener\">Klaus-Georg Meyer<\/a><\/strong>                                                  <br><a href=\"mailto:klaus-georg.meyer@capgemini.com\" target=\"_blank\" rel=\"noreferrer noopener\">Head of Business Technology Innovation<\/a><br>klaus-georg.meyer@capgemini.com<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"mailto:joachim.rawolle@capgemini.com\"><strong>Joachim Rawolle<\/strong><\/a><br><a href=\"mailto:joachim.rawolle@capgemini.com\" target=\"_blank\" rel=\"noreferrer noopener\">Head of Business Technology Core<\/a><br>joachim.rawolle@capgemini.com<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"mailto:silke.reisch@capgemini.com\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Silke Reisch<\/strong><\/a><br><a href=\"mailto:silke.reisch@capgemini.com\">Head of Cloud Cust<\/a><a href=\"mailto:silke.reisch@capgemini.com\" target=\"_blank\" rel=\"noreferrer noopener\">om Applications<\/a><br>silke.reisch@capgemini.com<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"mailto:stuart.arlott@capgemini.com\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Stuart Arlott<\/strong><\/a><br><a href=\"mailto:stuart.arlott@capgemini.com\" target=\"_blank\" rel=\"noreferrer noopener\">Head of ADM<\/a><br>stuart.arlott@capgemini.com<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<\/div>\n\n\n\n<section class=\"wp-block-cg-blocks-learn-more updated-new-sample-amal learnMoreBlock\"><div class=\"container\"><div class=\"row\"><div class=\"content-title col-12 col-md-8\"><h2 class=\"learnmore-heading\">Erfahre mehr \u00fcber Capgemini:<\/h2><\/div><\/div><div class=\"row\"><div class=\"col-md-4\"><div class=\"box\"><div class=\"box-wrapper\"><a class=\"box-title\" href=\"\/de-de\/karriere\/karrierewege\/it-berufe\" target=\"_blank\" aria-label=\"Deine Karriere in der IT\" rel=\"noopener noreferrer\"><div class=\"box-img-wrapper\"><img decoding=\"async\" src=\"https:\/\/www.capgemini.com\/de-de\/wp-content\/uploads\/sites\/8\/2021\/05\/Capgemini_About-Us_Innovation-Ecosystem.jpg?w=500&amp;quality=70\" srcset=\"https:\/\/www.capgemini.com\/de-de\/wp-content\/uploads\/sites\/8\/2021\/05\/Capgemini_About-Us_Innovation-Ecosystem.jpg?w=500&amp;quality=70 1x, https:\/\/www.capgemini.com\/de-de\/wp-content\/uploads\/sites\/8\/2021\/05\/Capgemini_About-Us_Innovation-Ecosystem.jpg?w=1000&amp;quality=70 2x\" class=\"box-img\" alt=\"\" style=\"object-fit:cover;object-position:50% 50%\" loading=\"lazy\"\/><\/div><h3 class=\"titleWithoutLink_learnMore\">Deine Karriere in der IT<\/h3><\/a><\/div><\/div><div class=\"box-inner\"><p class=\"box-desc\">Diese vielf\u00e4ltigen IT-Berufe k\u00f6nnten deine Zukunft sein. Das Spektrum der IT-Berufe bei Capgemini ist gro\u00df. Verschaffe dir hier einen \u00dcberblick \u00fcber unsere Jobprofile. <\/p><\/div><\/div><div class=\"col-md-4\"><div class=\"box\"><div class=\"box-wrapper\"><a class=\"box-title\" href=\"\/de-de\/karriere\/warum-capgemini\/flexible-benefits\/\" target=\"_blank\" aria-label=\"Capgemini Benefits\" rel=\"noopener noreferrer\"><div class=\"box-img-wrapper\"><img decoding=\"async\" src=\"https:\/\/www.capgemini.com\/de-de\/wp-content\/uploads\/sites\/8\/2022\/08\/GettyImages-1347652268.jpg?w=500&amp;quality=70\" srcset=\"https:\/\/www.capgemini.com\/de-de\/wp-content\/uploads\/sites\/8\/2022\/08\/GettyImages-1347652268.jpg?w=500&amp;quality=70 1x, https:\/\/www.capgemini.com\/de-de\/wp-content\/uploads\/sites\/8\/2022\/08\/GettyImages-1347652268.jpg?w=1000&amp;quality=70 2x\" class=\"box-img\" alt=\"\" style=\"object-fit:cover;object-position:50% 50%\" loading=\"lazy\"\/><\/div><h3 class=\"titleWithoutLink_learnMore\">Capgemini Benefits<\/h3><\/a><\/div><\/div><div class=\"box-inner\"><p class=\"box-desc\">Profitiere als Capgemini-Mitarbeiter*in von attraktiven Benefits in verschiedenen Bereichen \u2013 erfahre hier mehr \u00fcber unsere Vorteile.<\/p><\/div><\/div><div class=\"col-md-4\"><div class=\"box\"><div class=\"box-wrapper\"><a class=\"box-title\" href=\"\/de-de\/karriere\/warum-capgemini\/weiterbildung\" target=\"_blank\" aria-label=\"Weiterbildung bei Capgemini\" rel=\"noopener noreferrer\"><div class=\"box-img-wrapper\"><img decoding=\"async\" src=\"https:\/\/www.capgemini.com\/de-de\/wp-content\/uploads\/sites\/8\/2022\/09\/betriebliche-weiterbildung-capgemini.jpg?w=500&amp;quality=70\" srcset=\"https:\/\/www.capgemini.com\/de-de\/wp-content\/uploads\/sites\/8\/2022\/09\/betriebliche-weiterbildung-capgemini.jpg?w=500&amp;quality=70 1x, https:\/\/www.capgemini.com\/de-de\/wp-content\/uploads\/sites\/8\/2022\/09\/betriebliche-weiterbildung-capgemini.jpg?w=1000&amp;quality=70 2x\" class=\"box-img\" alt=\"\" style=\"object-fit:cover;object-position:50% 50%\" loading=\"lazy\"\/><\/div><h3 class=\"titleWithoutLink_learnMore\">Weiterbildung bei Capgemini<\/h3><\/a><\/div><\/div><div class=\"box-inner\"><p class=\"box-desc\">Uns ist lebenslanges Lernen wichtig. Erfahre mehr \u00fcber unser Karrieremodell und unsere Weiterbildungsangebote.<\/p><\/div><\/div><\/div><\/div><\/section>\n<\/div><\/div><\/div><\/div><\/div><\/section>\n\n\n\n<section class=\"wp-block-cg-blocks-group undefined section section--article-content\"><div class=\"article-main-content\"><div class=\"container\"><div class=\"grid-container\"><div><div class=\"article-text article-quote-text\"><\/div><\/div><\/div><\/div><\/div><\/section>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":52,"featured_media":764441,"parent":765402,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"cg_dt_proposed_to":[],"cg_seo_hreflang_relations":"[]","cg_seo_canonical_relation":"","cg_seo_hreflang_x_default_relation":"{\"uuid\":\"eca1d2e6-f852-4495-bd47-0101337b229d\",\"blogId\":\"\",\"domain\":\"\",\"sitePath\":\"\",\"postLink\":\"\",\"postId\":null,\"isSaved\":true,\"isCrossLink\":false,\"hasCrossLink\":false}","cg_dt_approved_content":true,"cg_dt_mandatory_content":false,"cg_dt_notes":"","cg_dg_source_changed":false,"cg_dt_link_disabled":false,"_yoast_wpseo_primary_brand":"","footnotes":"","featured_focal_points":"{\"x\":\"0.22\",\"y\":\"0.53\"}","partner_card_description":"","gsap_animation":0},"brand":[],"partner_type":[],"service":[],"industry":[],"partners":[],"page-type":[188],"content-group":[],"class_list":["post-765404","page","type-page","status-publish","has-post-thumbnail","hentry","page-type-careers"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.7 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Financial Services Jobs: Consulting, IT-Security und mehr<\/title>\n<meta name=\"description\" content=\"Der Bereich Financial Services bietet IT-Expert*innen bei Capgemini ein spannendes Umfeld. Erfahre mehr \u00fcber IT-Projekte in der Finanzbranche.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.capgemini.com\/de-de\/karriere\/karrierewege\/branchen\/it-jobs-financial-services\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Financial Services Jobs: Consulting, IT-Security und mehr\" \/>\n<meta property=\"og:description\" content=\"Der Bereich Financial Services bietet IT-Expert*innen bei Capgemini ein spannendes Umfeld. Erfahre mehr \u00fcber IT-Projekte in der Finanzbranche.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.capgemini.com\/de-de\/karriere\/karrierewege\/branchen\/it-jobs-financial-services\/\" \/>\n<meta property=\"og:site_name\" content=\"Capgemini Germany\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-28T06:28:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.capgemini.com\/de-de\/wp-content\/uploads\/sites\/8\/2021\/01\/financial-services-digital-customer-service.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1440\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.capgemini.com\\\/de-de\\\/karriere\\\/karrierewege\\\/branchen\\\/it-jobs-financial-services\\\/\",\"url\":\"https:\\\/\\\/www.capgemini.com\\\/de-de\\\/karriere\\\/karrierewege\\\/branchen\\\/it-jobs-financial-services\\\/\",\"name\":\"Financial Services Jobs: Consulting, IT-Security und mehr\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.capgemini.com\\\/de-de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.capgemini.com\\\/de-de\\\/karriere\\\/karrierewege\\\/branchen\\\/it-jobs-financial-services\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.capgemini.com\\\/de-de\\\/karriere\\\/karrierewege\\\/branchen\\\/it-jobs-financial-services\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.capgemini.com\\\/de-de\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2021\\\/01\\\/financial-services-digital-customer-service.png\",\"datePublished\":\"2022-08-02T03:49:23+00:00\",\"dateModified\":\"2026-08-28T06:28:55+00:00\",\"description\":\"Der Bereich Financial Services bietet IT-Expert*innen bei Capgemini ein spannendes Umfeld. Erfahre mehr \u00fcber IT-Projekte in der Finanzbranche.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.capgemini.com\\\/de-de\\\/karriere\\\/karrierewege\\\/branchen\\\/it-jobs-financial-services\\\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.capgemini.com\\\/de-de\\\/karriere\\\/karrierewege\\\/branchen\\\/it-jobs-financial-services\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/www.capgemini.com\\\/de-de\\\/karriere\\\/karrierewege\\\/branchen\\\/it-jobs-financial-services\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.capgemini.com\\\/de-de\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2021\\\/01\\\/financial-services-digital-customer-service.png\",\"contentUrl\":\"https:\\\/\\\/www.capgemini.com\\\/de-de\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2021\\\/01\\\/financial-services-digital-customer-service.png\",\"width\":1440,\"height\":900,\"caption\":\"financial-services\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.capgemini.com\\\/de-de\\\/karriere\\\/karrierewege\\\/branchen\\\/it-jobs-financial-services\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Karriere\",\"item\":\"https:\\\/\\\/www.capgemini.com\\\/de-de\\\/karriere\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Karrierewege\",\"item\":\"https:\\\/\\\/www.capgemini.com\\\/de-de\\\/karriere\\\/karrierewege\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Karriere-Branchen\",\"item\":\"https:\\\/\\\/www.capgemini.com\\\/de-de\\\/karriere\\\/karrierewege\\\/branchen\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Financial Services\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.capgemini.com\\\/de-de\\\/#website\",\"url\":\"https:\\\/\\\/www.capgemini.com\\\/de-de\\\/\",\"name\":\"Capgemini Deutschland\",\"description\":\"Make it real\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.capgemini.com\\\/de-de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Financial Services Jobs: Consulting, IT-Security und mehr","description":"Der Bereich Financial Services bietet IT-Expert*innen bei Capgemini ein spannendes Umfeld. Erfahre mehr \u00fcber IT-Projekte in der Finanzbranche.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.capgemini.com\/de-de\/karriere\/karrierewege\/branchen\/it-jobs-financial-services\/","og_locale":"de_DE","og_type":"article","og_title":"Financial Services Jobs: Consulting, IT-Security und mehr","og_description":"Der Bereich Financial Services bietet IT-Expert*innen bei Capgemini ein spannendes Umfeld. Erfahre mehr \u00fcber IT-Projekte in der Finanzbranche.","og_url":"https:\/\/www.capgemini.com\/de-de\/karriere\/karrierewege\/branchen\/it-jobs-financial-services\/","og_site_name":"Capgemini Germany","article_modified_time":"2026-08-28T06:28:55+00:00","og_image":[{"width":1440,"height":900,"url":"https:\/\/www.capgemini.com\/de-de\/wp-content\/uploads\/sites\/8\/2021\/01\/financial-services-digital-customer-service.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.capgemini.com\/de-de\/karriere\/karrierewege\/branchen\/it-jobs-financial-services\/","url":"https:\/\/www.capgemini.com\/de-de\/karriere\/karrierewege\/branchen\/it-jobs-financial-services\/","name":"Financial Services Jobs: Consulting, IT-Security und mehr","isPartOf":{"@id":"https:\/\/www.capgemini.com\/de-de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.capgemini.com\/de-de\/karriere\/karrierewege\/branchen\/it-jobs-financial-services\/#primaryimage"},"image":{"@id":"https:\/\/www.capgemini.com\/de-de\/karriere\/karrierewege\/branchen\/it-jobs-financial-services\/#primaryimage"},"thumbnailUrl":"https:\/\/www.capgemini.com\/de-de\/wp-content\/uploads\/sites\/8\/2021\/01\/financial-services-digital-customer-service.png","datePublished":"2022-08-02T03:49:23+00:00","dateModified":"2026-08-28T06:28:55+00:00","description":"Der Bereich Financial Services bietet IT-Expert*innen bei Capgemini ein spannendes Umfeld. Erfahre mehr \u00fcber IT-Projekte in der Finanzbranche.","breadcrumb":{"@id":"https:\/\/www.capgemini.com\/de-de\/karriere\/karrierewege\/branchen\/it-jobs-financial-services\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.capgemini.com\/de-de\/karriere\/karrierewege\/branchen\/it-jobs-financial-services\/"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.capgemini.com\/de-de\/karriere\/karrierewege\/branchen\/it-jobs-financial-services\/#primaryimage","url":"https:\/\/www.capgemini.com\/de-de\/wp-content\/uploads\/sites\/8\/2021\/01\/financial-services-digital-customer-service.png","contentUrl":"https:\/\/www.capgemini.com\/de-de\/wp-content\/uploads\/sites\/8\/2021\/01\/financial-services-digital-customer-service.png","width":1440,"height":900,"caption":"financial-services"},{"@type":"BreadcrumbList","@id":"https:\/\/www.capgemini.com\/de-de\/karriere\/karrierewege\/branchen\/it-jobs-financial-services\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Karriere","item":"https:\/\/www.capgemini.com\/de-de\/karriere\/"},{"@type":"ListItem","position":2,"name":"Karrierewege","item":"https:\/\/www.capgemini.com\/de-de\/karriere\/karrierewege\/"},{"@type":"ListItem","position":3,"name":"Karriere-Branchen","item":"https:\/\/www.capgemini.com\/de-de\/karriere\/karrierewege\/branchen\/"},{"@type":"ListItem","position":4,"name":"Financial Services"}]},{"@type":"WebSite","@id":"https:\/\/www.capgemini.com\/de-de\/#website","url":"https:\/\/www.capgemini.com\/de-de\/","name":"Capgemini Deutschland","description":"Make it real","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.capgemini.com\/de-de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"}]}},"brand_term":[],"archive_status":false,"featured_image_src":"https:\/\/www.capgemini.com\/de-de\/wp-content\/uploads\/sites\/8\/2021\/01\/financial-services-digital-customer-service.png","featured_image_alt":"financial-services","jetpack_sharing_enabled":true,"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"Capgemini Germany","distributor_original_site_url":"https:\/\/www.capgemini.com\/de-de","push-errors":false,"_links":{"self":[{"href":"https:\/\/www.capgemini.com\/de-de\/wp-json\/wp\/v2\/pages\/765404","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.capgemini.com\/de-de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.capgemini.com\/de-de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.capgemini.com\/de-de\/wp-json\/wp\/v2\/users\/52"}],"replies":[{"embeddable":true,"href":"https:\/\/www.capgemini.com\/de-de\/wp-json\/wp\/v2\/comments?post=765404"}],"version-history":[{"count":19,"href":"https:\/\/www.capgemini.com\/de-de\/wp-json\/wp\/v2\/pages\/765404\/revisions"}],"predecessor-version":[{"id":898732,"href":"https:\/\/www.capgemini.com\/de-de\/wp-json\/wp\/v2\/pages\/765404\/revisions\/898732"}],"up":[{"embeddable":true,"href":"https:\/\/www.capgemini.com\/de-de\/wp-json\/wp\/v2\/pages\/765402"}],"wp:attachment":[{"href":"https:\/\/www.capgemini.com\/de-de\/wp-json\/wp\/v2\/media?parent=765404"}],"wp:term":[{"taxonomy":"brand","embeddable":true,"href":"https:\/\/www.capgemini.com\/de-de\/wp-json\/wp\/v2\/brand?post=765404"},{"taxonomy":"partner_type","embeddable":true,"href":"https:\/\/www.capgemini.com\/de-de\/wp-json\/wp\/v2\/partner_type?post=765404"},{"taxonomy":"service","embeddable":true,"href":"https:\/\/www.capgemini.com\/de-de\/wp-json\/wp\/v2\/service?post=765404"},{"taxonomy":"industry","embeddable":true,"href":"https:\/\/www.capgemini.com\/de-de\/wp-json\/wp\/v2\/industry?post=765404"},{"taxonomy":"partners","embeddable":true,"href":"https:\/\/www.capgemini.com\/de-de\/wp-json\/wp\/v2\/partners?post=765404"},{"taxonomy":"page-type","embeddable":true,"href":"https:\/\/www.capgemini.com\/de-de\/wp-json\/wp\/v2\/page-type?post=765404"},{"taxonomy":"content-group","embeddable":true,"href":"https:\/\/www.capgemini.com\/de-de\/wp-json\/wp\/v2\/content-group?post=765404"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}