{"id":551686,"date":"2026-05-12T04:11:34","date_gmt":"2026-05-12T04:11:34","guid":{"rendered":"https:\/\/www.capgemini.com\/co-es\/?post_type=press-release&#038;p=551686"},"modified":"2026-05-12T04:12:42","modified_gmt":"2026-05-12T04:12:42","slug":"el-momento-decisivo-de-la-ia-para-los-seguros-de-danos-y-accidentes-los-pioneros-registran-un-crecimiento-de-ingresos-21-superior-mientras-el-resto-del-sector-se-queda-atras","status":"publish","type":"press-release","link":"https:\/\/www.capgemini.com\/co-es\/news\/press-releases\/el-momento-decisivo-de-la-ia-para-los-seguros-de-danos-y-accidentes-los-pioneros-registran-un-crecimiento-de-ingresos-21-superior-mientras-el-resto-del-sector-se-queda-atras\/","title":{"rendered":"El momento decisivo de la IA para los seguros de da\u00f1os y accidentes: los pioneros registran un crecimiento de ingresos 21% superior mientras el resto del sector se queda atr\u00e1s"},"content":{"rendered":"\t\t<div class=\"wp-block-cg-blocks-hero-press-release\">\n\t\t\t<header class=\"header-hero-press-release\" role=\"main\" id=\"main-content-press-release\">\n\t\t\t\t<div class=\"container\">\n\t\t\t\t\t<div class=\"hero-press-release\">\n\t\t\t\t\t\t<div class=\"hero-press-release-content-wrapper\">\n\t\t\t\t\t\t\t<div class=\"row\">\n\t\t\t\t\t\t\t\t<div class=\"col-12\">\n\t\t\t\t\t\t\t\t\t<div class=\"header-title\">\n\t\t\t\t\t\t\t\t\t\t<h1>\n\t\t\t\t\t\t\t\t\t\t\tEl momento decisivo de la IA para los seguros de da\u00f1os y accidentes: los pioneros registran un crecimiento de ingresos 21% superior mientras el resto del sector se queda atr\u00e1s\t\t\t\t\t\t\t\t\t\t<\/h1>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"header-description\">\n\t\t\t\t\t\t\t\t\t\t<p><\/p>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"header-date\">\n\t\t\t\t\t\t\t\t\t\t<span>may. 12, 2026<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"hero-press-release-downloads\">\n\t\t\t\t\t\t\t\t<div class=\"row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-12 col-md-6 col-lg-3\">\n\t\t\t\t\t\t\t\t\t\t\t<a class=\"download-item\" type=\"download\" href=\"https:\/\/www.capgemini.com\/mx-es\/wp-content\/uploads\/sites\/28\/2026\/05\/ESP_Capgemini_World-Property-Casualty-Insurance-Report_2026_-comunicado-de-prensa.pdf\" target=\"_blank\" rel=\"noopener noreferrer\" title=\"abrir en una nueva ventana\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"download-icon\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"download-details\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"download-title\">Descargar comunicado de prensa<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"download-props\">169 KB  pdf<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/header>\n\t\t<\/div>\n\t\t\n\n\n<section class=\"wp-block-cg-blocks-group undefined section section--article-content\"><div class=\"article-main-content\"><div class=\"container\"><div class=\"grid-container\"><div class=\"col-12 col-md-2\"><nav class=\"article-social\"><ul class=\"social-nav\"><li class=\"ip-order-fb\"><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?=http:\/\/capgeminiucwe.develop\/?post_type=press-release&amp;p=179\" target=\"_blank\" rel=\"noopener noreferrer\" title=\"Abrir en una nueva ventana\"><i aria-hidden=\"true\" class=\"icon-fb\"><\/i><span class=\"sr-only\">Facebook<\/span><\/a><\/li><li class=\"ip-order-tw\"><a href=\"https:\/\/twitter.com\/intent\/tweet?=http:\/\/capgeminiucwe.develop\/?post_type=press-release&amp;p=179\" target=\"_blank\" rel=\"noopener noreferrer\" title=\"Abrir en una nueva ventana\"><i aria-hidden=\"true\" class=\"icon-tw\"><\/i><span class=\"sr-only\">Twitter<\/span><\/a><\/li><li class=\"ip-order-li\"><a href=\"https:\/\/www.linkedin.com\/shareArticle?=http:\/\/capgeminiucwe.develop\/?post_type=press-release&amp;p=179\" target=\"_blank\" rel=\"noopener noreferrer\" title=\"Abrir en una nueva ventana\"><i aria-hidden=\"true\" class=\"icon-li\"><\/i><span class=\"sr-only\">Linkedin<\/span><\/a><\/li><\/ul><\/nav><\/div><div><div class=\"article-text article-quote-text\">\n<ul class=\"wp-block-list\">\n<li><em>El 10% de las aseguradoras con capacidades avanzadas de IA superan a sus pares en crecimiento de ingresos y precio de la acci\u00f3n<\/em><\/li>\n\n\n\n<li><em>Los pioneros escalan m\u00e1s all\u00e1 de los pilotos de IA mediante implementaci\u00f3n estrat\u00e9gica, capacitaci\u00f3n integral y herramientas de IA explicable<\/em><\/li>\n<\/ul>\n\n\n\n<p><strong>Par\u00eds, 5 de mayo de 2026 \u2013 Las aseguradoras de da\u00f1os y accidentes (P&amp;C, por sus siglas en ingl\u00e9s) enfrentan una brecha competitiva creciente: solo el 10% de la industria escala la IA con \u00e9xito, mientras que las dem\u00e1s tienen dificultades para capturar beneficios reales. En su 19\u00aa edici\u00f3n, el <a href=\"\/co-es\/insights\/biblioteca-de-investigacion\/informe-mundial-sobre-seguros-de-danos\/\">Informe mundial sobre seguros de propiedad y accidentes 2026<\/a>, del Instituto de Investigaci\u00f3n de <a href=\"https:\/\/www.capgemini.com\/co-es\/\">Capgemini<\/a>, sugiere que la brecha de madurez en IA puede explicarse en parte por el hecho de que 42% de las aseguradoras no registran ninguna m\u00e9trica de IA. Sin una forma de medir y validar lo que funciona, 60% de las aseguradoras permanece en la etapa de exploraci\u00f3n o prueba de concepto.<\/strong><\/p>\n\n\n\n<p>El informe muestra que solo un peque\u00f1o grupo de aseguradoras trata actualmente la IA como una capacidad operativa central, no como un conjunto de herramientas, al garantizar la alineaci\u00f3n simult\u00e1nea entre estrategia y talento, infraestructura tecnol\u00f3gica y adopci\u00f3n organizacional. Estas aseguradoras se definen como \u201cpioneras en inteligencia\u201d y alcanzan hasta 21% m\u00e1s de crecimiento en ingresos y aproximadamente 51% mayor aumento en el precio de la acci\u00f3n en tres a\u00f1os.<a id=\"_ftnref1\" href=\"#_ftn1\">[1]<\/a><\/p>\n\n\n\n<p>De acuerdo con el informe, los pioneros se distinguen de las aseguradoras del sector en varios aspectos. Estas organizaciones tienen casi cuatro veces m\u00e1s probabilidades de invertir en gesti\u00f3n del cambio m\u00e1s all\u00e1 de la capacitaci\u00f3n b\u00e1sica; casi tres veces m\u00e1s probabilidades de contar con infraestructura de IA explicable que genera confianza en toda la empresa, y casi el doble de probabilidades de incorporar las responsabilidades de IA directamente en las descripciones de puestos, creando as\u00ed una rendici\u00f3n de cuentas real.<\/p>\n\n\n\n<p>Los pioneros contrastan notablemente con una industria que enfrenta lo que el informe denomina una \u201cdesconexi\u00f3n arquitect\u00f3nica\u201d: un patr\u00f3n en el que los avances tecnol\u00f3gicos superan la capacidad de las organizaciones para integrarlos de manera efectiva. En promedio, las aseguradoras de da\u00f1os destinan 72% de sus inversiones en IA a tecnolog\u00eda e infraestructura, y solo 28% a la gesti\u00f3n del cambio, incluida la capacitaci\u00f3n b\u00e1sica para empleados y directivos. Como resultado, muchas iniciativas de IA tienen dificultades para alcanzar su pleno potencial, lo que limita el impacto a escala empresarial.<\/p>\n\n\n\n<p><strong>Retorno de la inversi\u00f3n en IA: a\u00fan sin medici\u00f3n sistem\u00e1tica<\/strong><\/p>\n\n\n\n<p>M\u00e1s de la mitad (55%) de las aseguradoras de da\u00f1os reconoce la ausencia de un ROI claro en las iniciativas de IA, y el mismo porcentaje afirma que no queda claro qui\u00e9n es el due\u00f1o de estas iniciativas dentro de la empresa. Como consecuencia, la responsabilidad suele recaer en individuos o equipos peque\u00f1os, lo que hace imposible lograr un impacto a nivel organizacional. Incluso a nivel de equipo, el impacto ha sido limitado: dos tercios (67%) de las aseguradoras de da\u00f1os citan escasez de habilidades en IA, y casi la mitad (47%) de los empleados con acceso a herramientas de IA reporta que su jornada laboral no ha cambiado, incluso despu\u00e9s de 18 meses de uso.<\/p>\n\n\n\n<p><em>\u201cLa industria aseguradora enfrenta su momento de la verdad con la IA. Los pioneros son prueba de que, cuando las aseguradoras integran la IA en su estrategia de negocio desde el inicio, deja de ser una herramienta de eficiencia para convertirse en una ventaja competitiva real con impacto directo en los resultados,\u201d <\/em>afirm\u00f3 Kartik Ramakrishnan, CEO de la Unidad de Negocio Estrat\u00e9gico de Servicios Financieros de Capgemini y miembro del Consejo de Direcci\u00f3n del Grupo.\u201c<em>Muchas aseguradoras navegan los obst\u00e1culos t\u00e9cnicos y culturales que ya conocen, pero la oportunidad es clara. Al fortalecer las bases de datos, definir la responsabilidad y apostar por el desarrollo de habilidades y la gobernanza, las aseguradoras pueden ir m\u00e1s all\u00e1 de los pilotos y liberar valor a escala\u2011empresarial. El enfoque ahora debe estar en construir la disciplina organizacional que sostenga el impacto de la IA en todo el negocio.\u201d<\/em><\/p>\n\n\n\n<p><strong><strong>La colaboraci\u00f3n entre humanos e IA: clave para la aseguradora del futuro<\/strong><\/strong><\/p>\n\n\n\n<p>Si bien los pioneros han establecido una ventaja inmediata gracias a su uso de la IA, el resto de la industria a\u00fan enfrenta retos. Casi la mitad (49%) del tiempo de los empleados se dedica a la colaboraci\u00f3n entre equipos, pero la mayor\u00eda de las herramientas de IA todav\u00eda operan a nivel de tareas individuales. La preparaci\u00f3n de datos tambi\u00e9n rezaga: solo 12% de las aseguradoras reporta una madurez muy alta, a pesar de la fuerte dependencia de datos no estructurados. A esto se suma una brecha de confianza creciente: 43% de los empleados cita la seguridad laboral como principal preocupaci\u00f3n, y solo 14% tiene claro c\u00f3mo encaja la IA en su trabajo.<\/p>\n\n\n\n<p>El informe identifica una oportunidad para reimaginar la aseguradora del futuro: un modelo en el que el liderazgo ejecutivo define la direcci\u00f3n estrat\u00e9gica y establece los l\u00edmites de la colaboraci\u00f3n humano-IA, los empleados especializados toman decisiones operativas complejas con base en informaci\u00f3n en tiempo real, y los agentes de IA automatizan tareas rutinarias y repetitivas. Dentro de este modelo, los gestores de orquestaci\u00f3n pueden trabajar activamente para alinear la estrategia de negocio y los principios de IA de manera que la inteligencia escale en grandes empresas. Para hacer realidad esta visi\u00f3n, las aseguradoras deben integrar la IA en la colaboraci\u00f3n y la toma de decisiones cotidianas, fortalecer sus bases de datos y redise\u00f1ar sus flujos de trabajo para la era de la IA ag\u00e9ntica.<\/p>\n\n\n\n<p><strong>Metodolog\u00eda del informe<\/strong><\/p>\n\n\n\n<p>El Informe mundial sobre seguros de propiedad y accidentes 2026 de Capgemini obtiene informaci\u00f3n de tres fuentes primarias: entrevistas globales a ejecutivos del sector asegurador 2026, encuestas globales a empleados del sector asegurador 2026 y la encuesta global de voz del cliente 2026. Estas fuentes de investigaci\u00f3n consultaron a 344 altos directivos de las principales aseguradoras de da\u00f1os, a 809 empleados del sector en funciones de suscripci\u00f3n, siniestros, agentes y servicio al cliente, y a 1,113 asegurados. Se les pregunt\u00f3 sobre la implementaci\u00f3n de IA, las barreras organizacionales para escalar y las preferencias de los clientes respecto a los servicios de seguros proactivos. Los participantes representan mercados relevantes de tres regiones globales: Am\u00e9ricas, Europa y Asia-Pac\u00edfico.<\/p>\n\n\n\n<p><strong>Acerca de Capgemini<\/strong><\/p>\n\n\n\n<p>Capgemini es un socio global de transformaci\u00f3n empresarial y tecnol\u00f3gica impulsada por la IA, que ofrece valor empresarial tangible. Imaginamos el futuro de las organizaciones y lo hacemos realidad a trav\u00e9s de la inteligencia artificial, la tecnolog\u00eda y las personas. Con una s\u00f3lida herencia de casi 60 a\u00f1os, somos un grupo responsable y diverso de m\u00e1s de 420,000 profesionales en m\u00e1s de 50 pa\u00edses. Brindamos servicios y soluciones integrales con nuestra profunda experiencia en la industria y un s\u00f3lido ecosistema de socios, aprovechando nuestras capacidades en estrategia, tecnolog\u00eda, dise\u00f1o, ingenier\u00eda y operaciones empresariales. En 2025, el Grupo registr\u00f3 ingresos globales de 22,500 millones de euros.<\/p>\n\n\n\n<p>Make it real | <a href=\"https:\/\/www.capgemini.com\/co-es\/\">www.capgemini.com\/co-es\/<\/a><\/p>\n\n\n\n<p><strong>Acerca del Instituto de Investigaci\u00f3n Capgemini<\/strong><\/p>\n\n\n\n<p>El Instituto de Investigaci\u00f3n Capgemini es un centro de estudios interno dedicado a cuestiones relacionadas con el \u00e1mbito digital, la innovaci\u00f3n y la tecnolog\u00eda, incluido su impacto en bancos, empresas de gesti\u00f3n patrimonial, operadores de pagos y aseguradoras. El Instituto publica anualmente su emblem\u00e1tica serie de informes Financial Services World Reports, que se basa en encuestas de opini\u00f3n de los clientes, entrevistas a directivos y colaboraciones con empresas tecnol\u00f3gicas y el mundo acad\u00e9mico para descubrir tendencias emergentes y explorar c\u00f3mo la inteligencia artificial, la nube, los datos y la digitalizaci\u00f3n est\u00e1n impulsando resultados empresariales transformadores. Con el respaldo de series temporales de datos globales, nuestros expertos del sector ofrecen informaci\u00f3n pr\u00e1ctica, an\u00e1lisis de tendencias y soluciones innovadoras para abordar los retos din\u00e1micos a los que se enfrentan las instituciones financieras en una econom\u00eda global en r\u00e1pida evoluci\u00f3n.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p><a id=\"_ftn1\" href=\"#_ftnref1\">[1]<\/a> Estas cifras son el resultado del an\u00e1lisis de Capgemini sobre la madurez autoevaluada de las aseguradorasen m\u00faltiples dimensiones, combinada con el desempe\u00f1o financiero autoinformadoentre 2021 y 2024. Este per\u00edodo abarca el ciclo completo de inversi\u00f3n en IA, incluida la IA\/ML tradicional (p. ej., modelos predictivos, sistemas basados en reglasy algoritmos estad\u00edsticos) y las capacidades fundamentales que posibilitaron la adopci\u00f3n posterior de IA generativa e IA ag\u00e9ntica.<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/section>\n\n\n<div class=\"wp-block-cg-blocks-cg-block-related-content\"><section class=\"relatedContentBlock\"><div class=\"container\"><div class=\"row\"><div class=\"content-title col-12 col-md-8\"><h2 class=\"related-content-heading\">Noticias relacionadas<\/h2><\/div><\/div><div class=\"row relatedContent\"><div class=\"col-lg-4 col-md-6 col-xs-12\">\n\t\t\t\t\t\t\t<div class=\"box\">\n\t\t\t\t\t\t\t\t<a aria-label=\"Leer m\u00e1s sobre La reindustrializaci\u00f3n entra en una fase m\u00e1s selectiva y estrat\u00e9gica en Europa y Estados Unidos\" href=\"https:\/\/www.capgemini.com\/co-es\/news\/press-releases\/la-reindustrializacion-entra-en-una-fase-mas-selectiva-y-estrategica-en-europa-y-estados-unidos\/\" class=\"anchorWrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"box-tag\"><span>Reports<\/span><\/span>\n\t\t\t\t\t\t\t\t\t<div class=\"box-title\"><h3 class=\"box-subtitle\">La reindustrializaci\u00f3n entra en una fase m\u00e1s selectiva y estrat\u00e9gica en Europa y Estados Unidos<\/h3><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"box-date\">\n\t\t\t\t\t\t\t\t\t\t<span>Apr 25, 2026<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"box-bottom\">\n\t\t\t\t\t\t\t\t\t\t&lt;a class=&quot;link-download&quot; href=&quot;https:\/\/www.capgemini.com\/mx-es\/wp-content\/uploads\/sites\/28\/2026\/04\/Capgemini_Reindustrializacion_comunicado-de-prensa.pdf&quot; aria-label=&quot;Descargar nota de prensa&quot; target=&quot;_blank&quot;  type=&quot;download&quot; title=&quot;Opens in a new window&quot;&gt;\n\t\t\t\t\t\t\t&lt;span&gt;Descargar nota de prensa&lt;\/span&gt;\n\t\t\t\t\t\t\t&lt;span&gt;169 KB PDF&lt;\/span&gt;\n\t\t\t\t\t\t&lt;\/a&gt;\n\t\t\t\t\t\t\t\t\t\t<a class=\"more\" aria-label=\"Leer m\u00e1s sobre La reindustrializaci\u00f3n entra en una fase m\u00e1s selectiva y estrat\u00e9gica en Europa y Estados Unidos\" href=\"https:\/\/www.capgemini.com\/co-es\/news\/press-releases\/la-reindustrializacion-entra-en-una-fase-mas-selectiva-y-estrategica-en-europa-y-estados-unidos\/\">Leer m\u00e1s sobre<\/a>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div><div class=\"col-lg-4 col-md-6 col-xs-12\">\n\t\t\t\t\t\t\t<div class=\"box\">\n\t\t\t\t\t\t\t\t<a aria-label=\"Leer m\u00e1s sobre Dos tercios de las organizaciones califican la IA f\u00edsica como una alta prioridad para los pr\u00f3ximos tres a cinco a\u00f1os\" href=\"https:\/\/www.capgemini.com\/co-es\/news\/press-releases\/dos-tercios-de-las-organizaciones-califican-la-ia-fisica-como-una-alta-prioridad-para-los-proximos-tres-a-cinco-anos\/\" class=\"anchorWrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"box-tag\"><span>Reports<\/span><\/span>\n\t\t\t\t\t\t\t\t\t<div class=\"box-title\"><h3 class=\"box-subtitle\">Dos tercios de las organizaciones califican la IA f\u00edsica como una alta prioridad para los pr\u00f3ximos tres a cinco a\u00f1os<\/h3><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"box-date\">\n\t\t\t\t\t\t\t\t\t\t<span>Apr 21, 2026<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"box-bottom\">\n\t\t\t\t\t\t\t\t\t\t&lt;a class=&quot;link-download&quot; href=&quot;https:\/\/www.capgemini.com\/mx-es\/wp-content\/uploads\/sites\/28\/2026\/04\/ESP_04_20_Capgemini_Physical_AI_Capgemini_comunicado-de-prensa.pdf&quot; aria-label=&quot;Descargar nota de prensa&quot; target=&quot;_blank&quot;  type=&quot;download&quot; title=&quot;Opens in a new window&quot;&gt;\n\t\t\t\t\t\t\t&lt;span&gt;Descargar nota de prensa&lt;\/span&gt;\n\t\t\t\t\t\t\t&lt;span&gt;163 KB PDF&lt;\/span&gt;\n\t\t\t\t\t\t&lt;\/a&gt;\n\t\t\t\t\t\t\t\t\t\t<a class=\"more\" aria-label=\"Leer m\u00e1s sobre Dos tercios de las organizaciones califican la IA f\u00edsica como una alta prioridad para los pr\u00f3ximos tres a cinco a\u00f1os\" href=\"https:\/\/www.capgemini.com\/co-es\/news\/press-releases\/dos-tercios-de-las-organizaciones-califican-la-ia-fisica-como-una-alta-prioridad-para-los-proximos-tres-a-cinco-anos\/\">Leer m\u00e1s sobre<\/a>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div><div class=\"col-lg-4 col-md-6 col-xs-12\">\n\t\t\t\t\t\t\t<div class=\"box\">\n\t\t\t\t\t\t\t\t<a aria-label=\"Leer m\u00e1s sobre El 85% de los clientes corporativos de los bancos tienen previsto recurrir a una instituci\u00f3n financiera no bancaria en el pr\u00f3ximo a\u00f1o, a medida que se intensifica la competencia con el capital privado\" href=\"https:\/\/www.capgemini.com\/co-es\/news\/press-releases\/el-85-de-los-clientes-corporativos-de-los-bancos-tienen-previsto-recurrir-a-una-institucion-financiera-no-bancaria-en-el-proximo-ano-a-medida-que-se-intensifica-la-competencia-con-el-capital-privado\/\" class=\"anchorWrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"box-tag\"><span>Reports<\/span><\/span>\n\t\t\t\t\t\t\t\t\t<div class=\"box-title\"><h3 class=\"box-subtitle\">El 85% de los clientes corporativos de los bancos tienen previsto recurrir a una instituci\u00f3n financiera no bancaria en el pr\u00f3ximo a\u00f1o, a medida que se intensifica la competencia con el capital privado<\/h3><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"box-date\">\n\t\t\t\t\t\t\t\t\t\t<span>Mar 24, 2026<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"box-bottom\">\n\t\t\t\t\t\t\t\t\t\t&lt;a class=&quot;link-download&quot; href=&quot;https:\/\/www.capgemini.com\/co-es\/wp-content\/uploads\/sites\/25\/2026\/03\/Informe-mundial-de-Capgemini-sobre-banca-corporativa-y-de-inversion-2026-Comunicado-de-prensa.pdf&quot; aria-label=&quot;Descargar nota de prensa&quot; target=&quot;_blank&quot;  type=&quot;download&quot; title=&quot;Opens in a new window&quot;&gt;\n\t\t\t\t\t\t\t&lt;span&gt;Descargar nota de prensa&lt;\/span&gt;\n\t\t\t\t\t\t\t&lt;span&gt;167 KB PDF&lt;\/span&gt;\n\t\t\t\t\t\t&lt;\/a&gt;\n\t\t\t\t\t\t\t\t\t\t<a class=\"more\" aria-label=\"Leer m\u00e1s sobre El 85% de los clientes corporativos de los bancos tienen previsto recurrir a una instituci\u00f3n financiera no bancaria en el pr\u00f3ximo a\u00f1o, a medida que se intensifica la competencia con el capital privado\" href=\"https:\/\/www.capgemini.com\/co-es\/news\/press-releases\/el-85-de-los-clientes-corporativos-de-los-bancos-tienen-previsto-recurrir-a-una-institucion-financiera-no-bancaria-en-el-proximo-ano-a-medida-que-se-intensifica-la-competencia-con-el-capital-privado\/\">Leer m\u00e1s sobre<\/a>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div><\/div><\/div><\/section><\/div>","protected":false},"excerpt":{"rendered":"<p>Las aseguradoras de da\u00f1os y accidentes (P&#038;C, por sus siglas en ingl\u00e9s) enfrentan una brecha competitiva creciente: solo el 10% de la industria escala la IA con \u00e9xito, mientras que las dem\u00e1s tienen dificultades para capturar beneficios reales. En su 19\u00aa edici\u00f3n, el Informe mundial sobre seguros de propiedad y accidentes 2026, del Instituto de Investigaci\u00f3n de Capgemini.<\/p>\n","protected":false},"author":208,"featured_media":0,"template":"","meta":{"cg_dt_proposed_to":[],"cg_seo_hreflang_relations":"[]","cg_seo_canonical_relation":"","cg_seo_hreflang_x_default_relation":"","cg_dt_approved_content":true,"cg_dt_mandatory_content":false,"cg_dt_notes":"","cg_dg_source_changed":true,"cg_dt_link_disabled":false,"footnotes":"","related_resource_url":"https:\/\/www.capgemini.com\/mx-es\/wp-content\/uploads\/sites\/28\/2026\/05\/ESP_Capgemini_World-Property-Casualty-Insurance-Report_2026_-comunicado-de-prensa.pdf","related_resource_id":564247,"related_resource_size":"169 KB","related_resource_type":"pdf","cg_author":0,"featured_focal_points":""},"tags":[],"press-release-type":[129],"brand":[],"class_list":["post-551686","press-release","type-press-release","status-publish","hentry","press-release-type-reports"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.8 (Yoast SEO v22.8) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>IA en Seguros de Da\u00f1os: Crecimiento y Ventaja | Capgemini<\/title>\n<meta name=\"description\" content=\"La IA marca un punto decisivo en los seguros de da\u00f1os y accidentes, impulsando mayor crecimiento de ingresos para los pioneros.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.capgemini.com\/co-es\/news\/press-releases\/el-momento-decisivo-de-la-ia-para-los-seguros-de-danos-y-accidentes-los-pioneros-registran-un-crecimiento-de-ingresos-21-superior-mientras-el-resto-del-sector-se-queda-atras\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El momento decisivo de la IA para los seguros de da\u00f1os y accidentes: los pioneros registran un crecimiento de ingresos 21% superior mientras el resto del sector se queda atr\u00e1s\" \/>\n<meta property=\"og:description\" content=\"La IA marca un punto decisivo en los seguros de da\u00f1os y accidentes, impulsando mayor crecimiento de ingresos para los pioneros.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.capgemini.com\/co-es\/news\/press-releases\/el-momento-decisivo-de-la-ia-para-los-seguros-de-danos-y-accidentes-los-pioneros-registran-un-crecimiento-de-ingresos-21-superior-mientras-el-resto-del-sector-se-queda-atras\/\" \/>\n<meta property=\"og:site_name\" content=\"Capgemini Colombia\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-12T04:12:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.capgemini.com\/co-es\/wp-content\/uploads\/sites\/25\/2025\/10\/New-Web-preview-global.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"627\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.capgemini.com\/co-es\/news\/press-releases\/el-momento-decisivo-de-la-ia-para-los-seguros-de-danos-y-accidentes-los-pioneros-registran-un-crecimiento-de-ingresos-21-superior-mientras-el-resto-del-sector-se-queda-atras\/\",\"url\":\"https:\/\/www.capgemini.com\/co-es\/news\/press-releases\/el-momento-decisivo-de-la-ia-para-los-seguros-de-danos-y-accidentes-los-pioneros-registran-un-crecimiento-de-ingresos-21-superior-mientras-el-resto-del-sector-se-queda-atras\/\",\"name\":\"IA en Seguros de Da\u00f1os: Crecimiento y Ventaja | Capgemini\",\"isPartOf\":{\"@id\":\"https:\/\/www.capgemini.com\/co-es\/#website\"},\"datePublished\":\"2026-05-12T04:11:34+00:00\",\"dateModified\":\"2026-05-12T04:12:42+00:00\",\"description\":\"La IA marca un punto decisivo en los seguros de da\u00f1os y accidentes, impulsando mayor crecimiento de ingresos para los pioneros.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.capgemini.com\/co-es\/news\/press-releases\/el-momento-decisivo-de-la-ia-para-los-seguros-de-danos-y-accidentes-los-pioneros-registran-un-crecimiento-de-ingresos-21-superior-mientras-el-resto-del-sector-se-queda-atras\/#breadcrumb\"},\"inLanguage\":\"es-MX\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.capgemini.com\/co-es\/news\/press-releases\/el-momento-decisivo-de-la-ia-para-los-seguros-de-danos-y-accidentes-los-pioneros-registran-un-crecimiento-de-ingresos-21-superior-mientras-el-resto-del-sector-se-queda-atras\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.capgemini.com\/co-es\/news\/press-releases\/el-momento-decisivo-de-la-ia-para-los-seguros-de-danos-y-accidentes-los-pioneros-registran-un-crecimiento-de-ingresos-21-superior-mientras-el-resto-del-sector-se-queda-atras\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.capgemini.com\/co-es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Press Releases\",\"item\":\"https:\/\/www.capgemini.com\/co-es\/news\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"El momento decisivo de la IA para los seguros de da\u00f1os y accidentes: los pioneros registran un crecimiento de ingresos 21% superior mientras el resto del sector se queda atr\u00e1s\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.capgemini.com\/co-es\/#website\",\"url\":\"https:\/\/www.capgemini.com\/co-es\/\",\"name\":\"Capgemini Colombia\",\"description\":\"Capgemini\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.capgemini.com\/co-es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es-MX\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"IA en Seguros de Da\u00f1os: Crecimiento y Ventaja | Capgemini","description":"La IA marca un punto decisivo en los seguros de da\u00f1os y accidentes, impulsando mayor crecimiento de ingresos para los pioneros.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.capgemini.com\/co-es\/news\/press-releases\/el-momento-decisivo-de-la-ia-para-los-seguros-de-danos-y-accidentes-los-pioneros-registran-un-crecimiento-de-ingresos-21-superior-mientras-el-resto-del-sector-se-queda-atras\/","og_locale":"es_MX","og_type":"article","og_title":"El momento decisivo de la IA para los seguros de da\u00f1os y accidentes: los pioneros registran un crecimiento de ingresos 21% superior mientras el resto del sector se queda atr\u00e1s","og_description":"La IA marca un punto decisivo en los seguros de da\u00f1os y accidentes, impulsando mayor crecimiento de ingresos para los pioneros.","og_url":"https:\/\/www.capgemini.com\/co-es\/news\/press-releases\/el-momento-decisivo-de-la-ia-para-los-seguros-de-danos-y-accidentes-los-pioneros-registran-un-crecimiento-de-ingresos-21-superior-mientras-el-resto-del-sector-se-queda-atras\/","og_site_name":"Capgemini Colombia","article_modified_time":"2026-05-12T04:12:42+00:00","og_image":[{"width":1200,"height":627,"url":"https:\/\/www.capgemini.com\/co-es\/wp-content\/uploads\/sites\/25\/2025\/10\/New-Web-preview-global.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.capgemini.com\/co-es\/news\/press-releases\/el-momento-decisivo-de-la-ia-para-los-seguros-de-danos-y-accidentes-los-pioneros-registran-un-crecimiento-de-ingresos-21-superior-mientras-el-resto-del-sector-se-queda-atras\/","url":"https:\/\/www.capgemini.com\/co-es\/news\/press-releases\/el-momento-decisivo-de-la-ia-para-los-seguros-de-danos-y-accidentes-los-pioneros-registran-un-crecimiento-de-ingresos-21-superior-mientras-el-resto-del-sector-se-queda-atras\/","name":"IA en Seguros de Da\u00f1os: Crecimiento y Ventaja | Capgemini","isPartOf":{"@id":"https:\/\/www.capgemini.com\/co-es\/#website"},"datePublished":"2026-05-12T04:11:34+00:00","dateModified":"2026-05-12T04:12:42+00:00","description":"La IA marca un punto decisivo en los seguros de da\u00f1os y accidentes, impulsando mayor crecimiento de ingresos para los pioneros.","breadcrumb":{"@id":"https:\/\/www.capgemini.com\/co-es\/news\/press-releases\/el-momento-decisivo-de-la-ia-para-los-seguros-de-danos-y-accidentes-los-pioneros-registran-un-crecimiento-de-ingresos-21-superior-mientras-el-resto-del-sector-se-queda-atras\/#breadcrumb"},"inLanguage":"es-MX","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.capgemini.com\/co-es\/news\/press-releases\/el-momento-decisivo-de-la-ia-para-los-seguros-de-danos-y-accidentes-los-pioneros-registran-un-crecimiento-de-ingresos-21-superior-mientras-el-resto-del-sector-se-queda-atras\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.capgemini.com\/co-es\/news\/press-releases\/el-momento-decisivo-de-la-ia-para-los-seguros-de-danos-y-accidentes-los-pioneros-registran-un-crecimiento-de-ingresos-21-superior-mientras-el-resto-del-sector-se-queda-atras\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.capgemini.com\/co-es\/"},{"@type":"ListItem","position":2,"name":"Press Releases","item":"https:\/\/www.capgemini.com\/co-es\/news\/"},{"@type":"ListItem","position":3,"name":"El momento decisivo de la IA para los seguros de da\u00f1os y accidentes: los pioneros registran un crecimiento de ingresos 21% superior mientras el resto del sector se queda atr\u00e1s"}]},{"@type":"WebSite","@id":"https:\/\/www.capgemini.com\/co-es\/#website","url":"https:\/\/www.capgemini.com\/co-es\/","name":"Capgemini Colombia","description":"Capgemini","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.capgemini.com\/co-es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es-MX"}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/capgemini.com\/co-es\/news\/press-releases\/el-momento-decisivo-de-la-ia-para-los-seguros-de-danos-y-accidentes-los-pioneros-registran-un-crecimiento-de-ingresos-21-superior-mientras-el-resto-del-sector-se-queda-atras\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"El momento decisivo de la IA para los seguros de da\u00f1os y accidentes: los pioneros registran un crecimiento de ingresos 21% superior mientras el resto del sector se queda atr\u00e1s","url":"https:\/\/www.capgemini.com\/co-es\/news\/press-releases\/el-momento-decisivo-de-la-ia-para-los-seguros-de-danos-y-accidentes-los-pioneros-registran-un-crecimiento-de-ingresos-21-superior-mientras-el-resto-del-sector-se-queda-atras\/","mainEntityOfPage":{"@type":"WebPage","@id":"https:\/\/www.capgemini.com\/co-es\/news\/press-releases\/el-momento-decisivo-de-la-ia-para-los-seguros-de-danos-y-accidentes-los-pioneros-registran-un-crecimiento-de-ingresos-21-superior-mientras-el-resto-del-sector-se-queda-atras\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Uncategorized","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Capgemini Colombia","logo":""},"keywords":[],"dateCreated":"2026-05-12T04:11:34Z","datePublished":"2026-05-12T04:11:34Z","dateModified":"2026-05-12T04:12:42Z"},"rendered":"<meta name=\"parsely-title\" content=\"El momento decisivo de la IA para los seguros de da\u00f1os y accidentes: los pioneros registran un crecimiento de ingresos 21% superior mientras el resto del sector se queda atr\u00e1s\" \/>\n<meta name=\"parsely-link\" content=\"https:\/\/www.capgemini.com\/co-es\/news\/press-releases\/el-momento-decisivo-de-la-ia-para-los-seguros-de-danos-y-accidentes-los-pioneros-registran-un-crecimiento-de-ingresos-21-superior-mientras-el-resto-del-sector-se-queda-atras\/\" \/>\n<meta name=\"parsely-type\" content=\"post\" \/>\n<meta name=\"parsely-pub-date\" content=\"2026-05-12T04:11:34Z\" \/>\n<meta name=\"parsely-section\" content=\"Uncategorized\" \/>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/capgemini.com\/p.js"},"archive_status":false,"featured_image_src":"https:\/\/www.capgemini.com\/co-es\/wp-content\/themes\/capgemini2025\/assets\/images\/mockup.png","featured_image_alt":false,"jetpack_sharing_enabled":true,"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"Capgemini Colombia","distributor_original_site_url":"https:\/\/www.capgemini.com\/co-es","push-errors":false,"tag_names":[],"_links":{"self":[{"href":"https:\/\/www.capgemini.com\/co-es\/wp-json\/wp\/v2\/press-release\/551686","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.capgemini.com\/co-es\/wp-json\/wp\/v2\/press-release"}],"about":[{"href":"https:\/\/www.capgemini.com\/co-es\/wp-json\/wp\/v2\/types\/press-release"}],"author":[{"embeddable":true,"href":"https:\/\/www.capgemini.com\/co-es\/wp-json\/wp\/v2\/users\/208"}],"version-history":[{"count":3,"href":"https:\/\/www.capgemini.com\/co-es\/wp-json\/wp\/v2\/press-release\/551686\/revisions"}],"predecessor-version":[{"id":551690,"href":"https:\/\/www.capgemini.com\/co-es\/wp-json\/wp\/v2\/press-release\/551686\/revisions\/551690"}],"wp:attachment":[{"href":"https:\/\/www.capgemini.com\/co-es\/wp-json\/wp\/v2\/media?parent=551686"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.capgemini.com\/co-es\/wp-json\/wp\/v2\/tags?post=551686"},{"taxonomy":"press-release-type","embeddable":true,"href":"https:\/\/www.capgemini.com\/co-es\/wp-json\/wp\/v2\/press-release-type?post=551686"},{"taxonomy":"brand","embeddable":true,"href":"https:\/\/www.capgemini.com\/co-es\/wp-json\/wp\/v2\/brand?post=551686"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}