{"id":16828,"date":"2022-08-03T12:43:00","date_gmt":"2022-08-03T12:43:00","guid":{"rendered":"https:\/\/www.capgemini.com\/ar-es\/?post_type=press-release&#038;p=16828"},"modified":"2026-01-09T14:06:30","modified_gmt":"2026-01-09T14:06:30","slug":"capgemini-y-unity-anuncian-una-alianza-global-para-ayudar-a-las-organizaciones-a-aprovechar-el-valor-empresarial-de-las-experiencias-inmersivas-y-del-metaverso","status":"publish","type":"press-release","link":"https:\/\/www.capgemini.com\/ar-es\/news\/press-releases\/capgemini-y-unity-anuncian-una-alianza-global-para-ayudar-a-las-organizaciones-a-aprovechar-el-valor-empresarial-de-las-experiencias-inmersivas-y-del-metaverso\/","title":{"rendered":"Capgemini y Unity anuncian una alianza global para ayudar a las organizaciones a aprovechar el valor empresarial de las experiencias inmersivas y del metaverso"},"content":{"rendered":"\n<p><\/p>\n\n\n\t\t<div class=\"wp-block-cg-blocks-hero-press-release\">\n\t\t\t<header class=\"header-hero-press-release\" role=\"main\" id=\"main-content-press-release\">\n\t\t\t\t<div class=\"container\">\n\t\t\t\t\t<div class=\"hero-press-release\">\n\t\t\t\t\t\t<div class=\"hero-press-release-content-wrapper\">\n\t\t\t\t\t\t\t<div class=\"row\">\n\t\t\t\t\t\t\t\t<div class=\"col-12\">\n\t\t\t\t\t\t\t\t\t<div class=\"header-title\">\n\t\t\t\t\t\t\t\t\t\t<h1>\n\t\t\t\t\t\t\t\t\t\t\tCapgemini y Unity anuncian una alianza global para ayudar a las organizaciones a aprovechar el valor empresarial de las experiencias inmersivas y del metaverso\t\t\t\t\t\t\t\t\t\t<\/h1>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"header-description\">\n\t\t\t\t\t\t\t\t\t\t<p><\/p>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"header-date\">\n\t\t\t\t\t\t\t\t\t\t<span>ago. 3, 2022<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"hero-press-release-downloads\">\n\t\t\t\t\t\t\t\t<div class=\"row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-12 col-md-6 col-lg-3\">\n\t\t\t\t\t\t\t\t\t\t\t<a class=\"download-item\" type=\"download\" href=\"https:\/\/www.capgemini.com\/ar-es\/wp-content\/uploads\/sites\/28\/2022\/12\/CAPGEM1.pdf\" target=\"_blank\" rel=\"noopener noreferrer\" title=\"abrir en una nueva ventana\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"download-icon\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"download-details\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"download-title\">Download press release<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"download-props\">140 KB  pdf<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/header>\n\t\t<\/div>\n\t\t\n\n\n<section class=\"wp-block-cg-blocks-group undefined section section--article-content\"><div class=\"article-main-content\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-md-1\"><nav class=\"article-social\"><ul class=\"social-nav\"><li class=\"ip-order-fb\"><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https:\/\/www.capgemini.com\/ar-es\/?post_type=press-release&amp;p=16828\" target=\"_blank\" rel=\"noopener noreferrer\" title=\"Abrir en una nueva ventana\"><i aria-hidden=\"true\" class=\"icon-fb\"><\/i><span class=\"sr-only\">Facebook<\/span><\/a><\/li><li class=\"ip-order-tw\"><a href=\"https:\/\/twitter.com\/intent\/tweet?url=https:\/\/www.capgemini.com\/ar-es\/?post_type=press-release&amp;p=16828&amp;text=\" target=\"_blank\" rel=\"noopener noreferrer\" title=\"Abrir en una nueva ventana\"><i aria-hidden=\"true\" class=\"icon-tw\"><\/i><span class=\"sr-only\">Twitter<\/span><\/a><\/li><li class=\"ip-order-li\"><a href=\"https:\/\/www.linkedin.com\/sharing\/share-offsite\/?url=https:\/\/www.capgemini.com\/ar-es\/?post_type=press-release&amp;p=16828&amp;text=\" target=\"_blank\" rel=\"noopener noreferrer\" title=\"Abrir en una nueva ventana\"><i aria-hidden=\"true\" class=\"icon-li\"><\/i><span class=\"sr-only\">Linkedin<\/span><\/a><\/li><\/ul><\/nav><\/div><div class=\"col-12 col-md-11 col-lg-10\"><div class=\"article-text article-quote-text\">\n<p><strong>Par\u00eds\/San Francisco, 14 de septiembre de 2022 \u2013 <a href=\"\/ar-es\/\">Capgemini<\/a> y <a href=\"https:\/\/unity.com\/\">Unity<\/a> (NYSE: U), la plataforma l\u00edder en la creaci\u00f3n y explotaci\u00f3n de contenidos 3D en tiempo real (RT3D), se unen para ayudar a las organizaciones de todo el mundo a explorar y aprovechar las oportunidades de negocio, adem\u00e1s de los beneficios de las experiencias inmersivas y del metaverso en todos los sectores.<\/strong><\/p>\n\n\n\n<p>Durante a\u00f1os, Capgemini y Unity han trabajado de manera conjunta en numerosos proyectos de creaci\u00f3n de valor para las principales compa\u00f1\u00edas globales, como en el desarrollo de una aplicaci\u00f3n interactiva para una importante empresa de bienes de consumo que permite a los equipos de ventas visualizar la disposici\u00f3n de los estantes en 3D, adem\u00e1s han desarrollado un simulador inmersivo para que un fabricante de veh\u00edculos contra incendios capacite a sus operadores.<\/p>\n\n\n\n<section class=\"wp-block-cg-blocks-intro-para-video section section--info-2cols section-invent-info\"><div class=\"container article-text\"><div class=\"video-box\"><div class=\"video-wrapper\"><iframe title=\"video section\" src=\"https:\/\/www.youtube.com\/embed\/IPeLrDk8ckQ\" frameborder=\"0\" rel=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/div><\/div><\/section>\n\n\n\n<p>A partir de estas colaboraciones, las dos compa\u00f1\u00edas definir\u00e1n y ejecutar\u00e1n de manera conjunta soluciones y servicios profesionales espec\u00edficos para cada sector, con el fin de ofrecer plataformas adaptadas para cada cliente. En el marco de esta nueva alianza mundial plurianual, ambas empresas:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Definir\u00e1n enfoques y metodolog\u00edas, y llevar\u00e1n a cabo proyectos conjuntos de I+D como parte del Capgemini Metaverse Lab, contribuyendo conjuntamente a la construcci\u00f3n del futuro metaverso\/Web3.<\/li>\n\n\n\n<li>Se apoyar\u00e1n mutuamente en t\u00e9rminos de desarrollo de negocios, de soluciones e iniciativas de ventas, aprovechando la experiencia y los conocimientos del mercado de ambas organizaciones.<\/li>\n\n\n\n<li>Aumentar\u00e1n el n\u00famero de talentos certificados en la tecnolog\u00eda RT3D de Unity a trav\u00e9s de iniciativas conjuntas de contrataci\u00f3n y capacitaci\u00f3n, con el fin de ampliar la reserva mundial de talentos en estos campos.<\/li>\n<\/ul>\n\n\n\n<p>Esta nueva alianza global se centrar\u00e1 en los sectores y casos pr\u00e1cticos en los que las experiencias digitales de los clientes o empleados ser\u00e1n m\u00e1s ventajosas: bienes de consumo y venta al por menor, fabricaci\u00f3n, ciencias de la vida, telecomunicaciones, medios de comunicaci\u00f3n y tecnolog\u00eda, energ\u00eda y servicios p\u00fablicos y servicios financieros.<\/p>\n\n\n\n<p><em>\u201cEl metaverso y las experiencias inmersivas abren todo un universo de posibilidades para nuestros clientes en todos los sectores, desde habilitar conexiones m\u00e1s emotivas con los consumidores, y reinventar la experiencia y la colaboraci\u00f3n de los empleados, hasta optimizar la ingenier\u00eda, la fabricaci\u00f3n y las operaciones mediante el uso de gemelos digitales\u201d<\/em>, afirm\u00f3 Pascal Brier, Director de Innovaci\u00f3n de Capgemini e integrante del Comit\u00e9 Ejecutivo del Grupo. <em>\u201cConformar casos de uso espec\u00edficos del sector y desarrollarlos a escala requerir\u00e1 capacidades t\u00e9cnicas y operativas especializadas. Estamos entusiasmados de asociarnos con Unity, uno de los principales motores del metaverso, para que nuestros clientes puedan aprovechar su verdadero valor empresarial\u201d.<\/em><\/p>\n\n\n\n<p><em>\u201cEstamos encantados de aliarnos con Capgemini para acelerar la adopci\u00f3n de las tecnolog\u00edas 3D en tiempo real en una gran variedad de industrias\u201d<\/em>, se\u00f1al\u00f3 Marc Whitten, Vicepresidente S\u00e9nior y Director General de Unity Create Solutions. <em>\u201cLas soluciones 3D en tiempo real de Unity permitir\u00e1n que muchas empresas nuevas accedan a la nueva generaci\u00f3n de Internet, o metaverso, ayud\u00e1ndoles a lograr una mayor interacci\u00f3n con sus clientes\u201d.<\/em><\/p>\n\n\n\n<p>Unity, el l\u00edder global en experiencias inmersivas y 3D en tiempo real, mejorar\u00e1 las capacidades de Capgemini desde la estrategia y el dise\u00f1o de la experiencia del cliente y del empleado (CX\/EX) hasta el desarrollo y la integraci\u00f3n del <em>front-end<\/em>. Con su presencia mundial, su profunda experiencia en el sector y su comprensi\u00f3n de las necesidades de los clientes, as\u00ed como su capacidad para llevar a cabo proyectos de transformaci\u00f3n digital a gran escala, Capgemini ayudar\u00e1 a acelerar el crecimiento de la plataforma tecnol\u00f3gica de Unity. Capgemini tambi\u00e9n compartir\u00e1 las tendencias del mercado y el conocimiento de los clientes que permitir\u00e1n a Unity mejorar a\u00fan m\u00e1s su hoja de ruta de productos. Los proyectos conjuntos de los clientes se beneficiar\u00e1n de las capacidades hol\u00edsticas de Capgemini para configurar modelos y estrategias de negocio, as\u00ed como de su experiencia tecnol\u00f3gica en componentes que ser\u00e1n fundamentales para desplegar y escalar el futuro metaverso\/la Web3 descentralizada, entre los que se encuentran la RA, la RV y la RM<a href=\"#_ftn1\" id=\"_ftnref1\"><sup>[1]<\/sup><\/a>, el <em>blockchain<\/em> y las NFT, el 5G\/6G, la IA, el internet de las cosas y la seguridad cibern\u00e9tica.<\/p>\n\n\n\n<p><strong>El nuevo Metaverse-Lab de Capgemini ayudar\u00e1 a los clientes a dise\u00f1ar y ejecutar sus estrategias del metaverso<\/strong><\/p>\n\n\n\n<p>Capgemini est\u00e1 avanzando en sus aspiraciones en esta nueva era emergente de Internet a trav\u00e9s de su Metaverse-Lab, integrado por un equipo de expertos en tecnolog\u00eda de alto nivel procedentes de todo el Grupo con una s\u00f3lida trayectoria en las tecnolog\u00edas clave subyacentes de la Web3 \/ metaverso. El Laboratorio tiene como objetivo configurar las estrategias del metaverso espec\u00edficas de la industria y desarrollar\u00e1 soluciones y plataformas accionables y disruptivas con sus socios, entre los que se encuentra Unity. Sus programas de I+D abarcar\u00e1n el futuro de las interfaces hombre-m\u00e1quina inmersivas y los controladores, el futuro del trabajo en el metaverso, el futuro de los gemelos digitales y el futuro de la cadena de bloques y la Organizaci\u00f3n Aut\u00f3noma Descentralizada (DAO, por sus siglas en ingl\u00e9s).<\/p>\n\n\n\n<p><strong>Acerca de Unity<\/strong><\/p>\n\n\n\n<p>Unity (NYSE: U) es la plataforma l\u00edder en el mundo para la creaci\u00f3n y explotaci\u00f3n de contenidos 3D en tiempo real (RT3D). Los creadores, desde los desarrolladores de juegos hasta los artistas, arquitectos, dise\u00f1adores de autom\u00f3viles y cineastas, entre otros, utilizan Unity para dar vida a su imaginaci\u00f3n. Unity es la base sobre la que se crean los contenidos digitales m\u00e1s potentes del mundo. En concreto, la plataforma de Unity ofrece un conjunto completo de soluciones de software para crear, ejecutar y monetizar contenidos interactivos en 2D y 3D en tiempo real para tel\u00e9fonos m\u00f3viles, tabletas, PC, consolas y dispositivos de realidad aumentada y virtual. En el cuarto trimestre de 2021, Unity contaba, de media, con 3.900 millones de usuarios finales activos mensuales que consum\u00edan contenidos creados o explotados con sus soluciones. Las aplicaciones desarrolladas por estos creadores se descargaron, de media, cinco mil millones de veces al mes en 2021.<\/p>\n\n\n\n<p>Para m\u00e1s informaci\u00f3n, visite <a href=\"http:\/\/www.unity.com\">www.unity.com<\/a><\/p>\n\n\n\n<p>Unity utiliza su sitio web (investors.unity.com), los archivos de la SEC, los comunicados de prensa, las conferencias telef\u00f3nicas p\u00fablicas y los webcasts p\u00fablicos como medios para divulgar informaci\u00f3n material no p\u00fablica y para cumplir con sus obligaciones de divulgaci\u00f3n en virtud de la Regulaci\u00f3n FD.<\/p>\n\n\n\n<p><strong>Acerca de Capgemini<\/strong><\/p>\n\n\n\n<p>Capgemini es l\u00edder mundial en asociaci\u00f3n con empresas para transformar y gestionar negocios aprovechando el poder de la tecnolog\u00eda. El Grupo se gu\u00eda por su prop\u00f3sito de liberar la energ\u00eda humana a trav\u00e9s de la tecnolog\u00eda para crear un futuro inclusivo y sostenible. Es una organizaci\u00f3n responsable y diversa que cuenta con 340,000 empleados en m\u00e1s de 50 pa\u00edses. Con una s\u00f3lida herencia de 55 a\u00f1os y profunda experiencia en la industria, Capgemini cuenta con la confianza de sus clientes para abordar toda la gama de sus necesidades empresariales, desde la estrategia y el dise\u00f1o hasta las operaciones, impulsada por la r\u00e1pida evoluci\u00f3n y el innovador mundo de la nube, los datos, inteligencia artificial, conectividad, software, ingenier\u00eda digital y plataformas. En 2021 el Grupo report\u00f3 ingresos globales de 18,000 millones de euros.<\/p>\n\n\n\n<p>Get The Future You Want | <a href=\"\/ar-es\/\">www.capgemini.com\/ar-es\/<\/a><\/p>\n\n\n\n<p><sup><a id=\"_ftn1\" href=\"#_ftnref1\">[1]<\/a> Realidad aumentada, virtual y mixta<\/sup><\/p>\n<\/div><\/div><\/div><\/div><\/div><\/section>\n\n\n<div class=\"wp-block-cg-blocks-cg-block-related-content\"><section class=\"relatedContentBlock\"><div class=\"container\"><div class=\"row\"><div class=\"content-title col-12 col-md-8\"><h2 class=\"related-content-heading\">Related News<\/h2><\/div><\/div><div class=\"row relatedContent\"><div class=\"col-lg-4 col-md-6 col-xs-12\">\n\t\t\t\t\t\t\t<div class=\"box\">\n\t\t\t\t\t\t\t\t<a aria-label=\"Leer m\u00e1s sobre Capgemini Y Unity Anuncian Una Alianza Global Para Ayudar A Las Organizaciones A Aprovechar El Valor Comercial De Las Experiencias Inmersivas Y Metaversos\" href=\"https:\/\/www.capgemini.com\/ar-es\/news\/press-releases\/capgemini-y-unity-anuncian-una-alianza-global-para-ayudar-a-las-organizaciones-a-aprovechar-el-valor-comercial-de-las-experiencias-inmersivas-y-metaversos\/\" class=\"anchorWrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"box-tag\"><span>Partners<\/span><\/span>\n\t\t\t\t\t\t\t\t\t<div class=\"box-title\"><h3 class=\"box-subtitle\">Capgemini Y Unity Anuncian Una Alianza Global Para Ayudar A Las Organizaciones A Aprovechar El Valor Comercial De Las Experiencias Inmersivas Y Metaversos<\/h3><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"box-date\">\n\t\t\t\t\t\t\t\t\t\t<span>Sep 28, 2022<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"box-bottom\">\n\t\t\t\t\t\t\t\t\t\t&lt;a class=&quot;link-download&quot; href=&quot;https:\/\/www.capgemini.com\/ar-es\/wp-content\/uploads\/sites\/28\/2022\/12\/2022_08_03_.pdf&quot; aria-label=&quot;Descargar nota de prensa&quot; target=&quot;_blank&quot;  type=&quot;download&quot; title=&quot;Opens in a new window&quot;&gt;\n\t\t\t\t\t\t\t&lt;span&gt;Descargar nota de prensa&lt;\/span&gt;\n\t\t\t\t\t\t\t&lt;span&gt;143 KB PDF&lt;\/span&gt;\n\t\t\t\t\t\t&lt;\/a&gt;\n\t\t\t\t\t\t\t\t\t\t<a class=\"more\" aria-label=\"Leer m\u00e1s sobre Capgemini Y Unity Anuncian Una Alianza Global Para Ayudar A Las Organizaciones A Aprovechar El Valor Comercial De Las Experiencias Inmersivas Y Metaversos\" href=\"https:\/\/www.capgemini.com\/ar-es\/news\/press-releases\/capgemini-y-unity-anuncian-una-alianza-global-para-ayudar-a-las-organizaciones-a-aprovechar-el-valor-comercial-de-las-experiencias-inmersivas-y-metaversos\/\">Leer m\u00e1s sobre<\/a>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div><div class=\"col-lg-4 col-md-6 col-xs-12\">\n\t\t\t\t\t\t\t<div class=\"box\">\n\t\t\t\t\t\t\t\t<a aria-label=\"Leer m\u00e1s sobre Capgemini anuncia que Microsoft Azure Private 5G Core se integrar\u00e1 con sus soluciones de red privada dise\u00f1adas en su Laboratorio 5G, basadas en productos 5G de Qualcomm Technologies\" href=\"https:\/\/www.capgemini.com\/ar-es\/news\/press-releases\/capgemini-anuncia-que-microsoft-azure-private-5g-core-se-integrara-con-sus-soluciones-de-red-privada-disenadas-en-su-laboratorio-5g-basadas-en-productos-5g-de-qualcomm-technologies\/\" class=\"anchorWrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"box-tag\"><span>Partners<\/span><\/span>\n\t\t\t\t\t\t\t\t\t<div class=\"box-title\"><h3 class=\"box-subtitle\">Capgemini anuncia que Microsoft Azure Private 5G Core se integrar\u00e1 con sus soluciones de red privada dise\u00f1adas en su Laboratorio 5G, basadas en productos 5G de Qualcomm Technologies<\/h3><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"box-date\">\n\t\t\t\t\t\t\t\t\t\t<span>Feb 28, 2022<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"box-bottom\">\n\t\t\t\t\t\t\t\t\t\t&lt;a class=&quot;link-download&quot; href=&quot;https:\/\/www.capgemini.com\/ar-es\/wp-content\/uploads\/sites\/28\/2022\/02\/2022_02_28_Capgemini_Microsoft_-Qualcomm_5G-Private-Network-1.pdf&quot; aria-label=&quot;Descargar nota de prensa&quot; target=&quot;_blank&quot;  type=&quot;download&quot; title=&quot;Opens in a new window&quot;&gt;\n\t\t\t\t\t\t\t&lt;span&gt;Descargar nota de prensa&lt;\/span&gt;\n\t\t\t\t\t\t\t&lt;span&gt;116 KB PDF&lt;\/span&gt;\n\t\t\t\t\t\t&lt;\/a&gt;\n\t\t\t\t\t\t\t\t\t\t<a class=\"more\" aria-label=\"Leer m\u00e1s sobre Capgemini anuncia que Microsoft Azure Private 5G Core se integrar\u00e1 con sus soluciones de red privada dise\u00f1adas en su Laboratorio 5G, basadas en productos 5G de Qualcomm Technologies\" href=\"https:\/\/www.capgemini.com\/ar-es\/news\/press-releases\/capgemini-anuncia-que-microsoft-azure-private-5g-core-se-integrara-con-sus-soluciones-de-red-privada-disenadas-en-su-laboratorio-5g-basadas-en-productos-5g-de-qualcomm-technologies\/\">Leer m\u00e1s sobre<\/a>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div><div class=\"col-lg-4 col-md-6 col-xs-12\">\n\t\t\t\t\t\t\t<div class=\"box\">\n\t\t\t\t\t\t\t\t<a aria-label=\"Leer m\u00e1s sobre Capgemini implementa una nueva plataforma de gesti\u00f3n de relaciones con los clientes (CRM) de Salesforce en 22 pa\u00edses para la empresa escandinava de dispositivos m\u00e9dicos, Atos Medical\" href=\"https:\/\/www.capgemini.com\/ar-es\/news\/press-releases\/capgemini-implementa-una-nueva-plataforma-de-gestion-de-relaciones-con-los-clientes-crm-de-salesforce-en-22-paises-para-la-empresa-escandinava-de-dispositivos-medicos-atos-medical\/\" class=\"anchorWrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"box-tag\"><span>Partners<\/span><\/span>\n\t\t\t\t\t\t\t\t\t<div class=\"box-title\"><h3 class=\"box-subtitle\">Capgemini implementa una nueva plataforma de gesti\u00f3n de relaciones con los clientes (CRM) de Salesforce en 22 pa\u00edses para la empresa escandinava de dispositivos m\u00e9dicos, Atos Medical<\/h3><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"box-date\">\n\t\t\t\t\t\t\t\t\t\t<span>Jan 18, 2022<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"box-bottom\">\n\t\t\t\t\t\t\t\t\t\t&lt;a class=&quot;link-download&quot; href=&quot;https:\/\/www.capgemini.com\/ar-es\/wp-content\/uploads\/sites\/28\/2022\/12\/Capgemini-implementa-Salesforce-en-Atos-Medical.pdf&quot; aria-label=&quot;Descargar nota de prensa&quot; target=&quot;_blank&quot;  type=&quot;download&quot; title=&quot;Opens in a new window&quot;&gt;\n\t\t\t\t\t\t\t&lt;span&gt;Descargar nota de prensa&lt;\/span&gt;\n\t\t\t\t\t\t\t&lt;span&gt;96 KB PDF&lt;\/span&gt;\n\t\t\t\t\t\t&lt;\/a&gt;\n\t\t\t\t\t\t\t\t\t\t<a class=\"more\" aria-label=\"Leer m\u00e1s sobre Capgemini implementa una nueva plataforma de gesti\u00f3n de relaciones con los clientes (CRM) de Salesforce en 22 pa\u00edses para la empresa escandinava de dispositivos m\u00e9dicos, Atos Medical\" href=\"https:\/\/www.capgemini.com\/ar-es\/news\/press-releases\/capgemini-implementa-una-nueva-plataforma-de-gestion-de-relaciones-con-los-clientes-crm-de-salesforce-en-22-paises-para-la-empresa-escandinava-de-dispositivos-medicos-atos-medical\/\">Leer m\u00e1s sobre<\/a>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div><\/div><\/div><\/section><\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":336,"featured_media":0,"template":"","meta":{"cg_dt_proposed_to":[],"cg_seo_hreflang_relations":"[]","cg_seo_canonical_relation":"","cg_seo_hreflang_x_default_relation":"","cg_dt_approved_content":true,"cg_dt_mandatory_content":false,"cg_dt_notes":"","cg_dg_source_changed":false,"cg_dt_link_disabled":false,"footnotes":"","related_resource_url":"https:\/\/www.capgemini.com\/ar-es\/wp-content\/uploads\/sites\/28\/2022\/12\/CAPGEM1.pdf","related_resource_id":16830,"related_resource_size":"140 KB","related_resource_type":"pdf","cg_author":0,"featured_focal_points":""},"tags":[],"press-release-type":[128],"brand":[],"class_list":["post-16828","press-release","type-press-release","status-publish","hentry","press-release-type-partners"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.8 (Yoast SEO v22.8) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Capgemini y Unity anuncian una alianza global para ayudar a las organizaciones a aprovechar el valor empresarial de las experiencias inmersivas y del metaverso | Capgemini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.capgemini.com\/ar-es\/news\/press-releases\/capgemini-y-unity-anuncian-una-alianza-global-para-ayudar-a-las-organizaciones-a-aprovechar-el-valor-empresarial-de-las-experiencias-inmersivas-y-del-metaverso\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Capgemini y Unity anuncian una alianza global para ayudar a las organizaciones a aprovechar el valor empresarial de las experiencias inmersivas y del metaverso\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.capgemini.com\/ar-es\/news\/press-releases\/capgemini-y-unity-anuncian-una-alianza-global-para-ayudar-a-las-organizaciones-a-aprovechar-el-valor-empresarial-de-las-experiencias-inmersivas-y-del-metaverso\/\" \/>\n<meta property=\"og:site_name\" content=\"Capgemini Argentina\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-09T14:06:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.capgemini.com\/ar-es\/wp-json\/wp\/v2\/press-release\/16828\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"627\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.capgemini.com\/ar-es\/news\/press-releases\/capgemini-y-unity-anuncian-una-alianza-global-para-ayudar-a-las-organizaciones-a-aprovechar-el-valor-empresarial-de-las-experiencias-inmersivas-y-del-metaverso\/\",\"url\":\"https:\/\/www.capgemini.com\/ar-es\/news\/press-releases\/capgemini-y-unity-anuncian-una-alianza-global-para-ayudar-a-las-organizaciones-a-aprovechar-el-valor-empresarial-de-las-experiencias-inmersivas-y-del-metaverso\/\",\"name\":\"Capgemini y Unity anuncian una alianza global para ayudar a las organizaciones a aprovechar el valor empresarial de las experiencias inmersivas y del metaverso | Capgemini\",\"isPartOf\":{\"@id\":\"https:\/\/www.capgemini.com\/ar-es\/#website\"},\"datePublished\":\"2022-08-03T12:43:00+00:00\",\"dateModified\":\"2026-01-09T14:06:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.capgemini.com\/ar-es\/news\/press-releases\/capgemini-y-unity-anuncian-una-alianza-global-para-ayudar-a-las-organizaciones-a-aprovechar-el-valor-empresarial-de-las-experiencias-inmersivas-y-del-metaverso\/#breadcrumb\"},\"inLanguage\":\"es-MX\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.capgemini.com\/ar-es\/news\/press-releases\/capgemini-y-unity-anuncian-una-alianza-global-para-ayudar-a-las-organizaciones-a-aprovechar-el-valor-empresarial-de-las-experiencias-inmersivas-y-del-metaverso\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.capgemini.com\/ar-es\/news\/press-releases\/capgemini-y-unity-anuncian-una-alianza-global-para-ayudar-a-las-organizaciones-a-aprovechar-el-valor-empresarial-de-las-experiencias-inmersivas-y-del-metaverso\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.capgemini.com\/ar-es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Capgemini y Unity anuncian una alianza global para ayudar a las organizaciones a aprovechar el valor empresarial de las experiencias inmersivas y del metaverso\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.capgemini.com\/ar-es\/#website\",\"url\":\"https:\/\/www.capgemini.com\/ar-es\/\",\"name\":\"Capgemini Argentina\",\"description\":\"Capgemini\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.capgemini.com\/ar-es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es-MX\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Capgemini y Unity anuncian una alianza global para ayudar a las organizaciones a aprovechar el valor empresarial de las experiencias inmersivas y del metaverso | Capgemini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.capgemini.com\/ar-es\/news\/press-releases\/capgemini-y-unity-anuncian-una-alianza-global-para-ayudar-a-las-organizaciones-a-aprovechar-el-valor-empresarial-de-las-experiencias-inmersivas-y-del-metaverso\/","og_locale":"es_MX","og_type":"article","og_title":"Capgemini y Unity anuncian una alianza global para ayudar a las organizaciones a aprovechar el valor empresarial de las experiencias inmersivas y del metaverso","og_url":"https:\/\/www.capgemini.com\/ar-es\/news\/press-releases\/capgemini-y-unity-anuncian-una-alianza-global-para-ayudar-a-las-organizaciones-a-aprovechar-el-valor-empresarial-de-las-experiencias-inmersivas-y-del-metaverso\/","og_site_name":"Capgemini Argentina","article_modified_time":"2026-01-09T14:06:30+00:00","og_image":[{"width":1200,"height":627,"url":"https:\/\/www.capgemini.com\/ar-es\/wp-json\/wp\/v2\/press-release\/16828","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.capgemini.com\/ar-es\/news\/press-releases\/capgemini-y-unity-anuncian-una-alianza-global-para-ayudar-a-las-organizaciones-a-aprovechar-el-valor-empresarial-de-las-experiencias-inmersivas-y-del-metaverso\/","url":"https:\/\/www.capgemini.com\/ar-es\/news\/press-releases\/capgemini-y-unity-anuncian-una-alianza-global-para-ayudar-a-las-organizaciones-a-aprovechar-el-valor-empresarial-de-las-experiencias-inmersivas-y-del-metaverso\/","name":"Capgemini y Unity anuncian una alianza global para ayudar a las organizaciones a aprovechar el valor empresarial de las experiencias inmersivas y del metaverso | Capgemini","isPartOf":{"@id":"https:\/\/www.capgemini.com\/ar-es\/#website"},"datePublished":"2022-08-03T12:43:00+00:00","dateModified":"2026-01-09T14:06:30+00:00","breadcrumb":{"@id":"https:\/\/www.capgemini.com\/ar-es\/news\/press-releases\/capgemini-y-unity-anuncian-una-alianza-global-para-ayudar-a-las-organizaciones-a-aprovechar-el-valor-empresarial-de-las-experiencias-inmersivas-y-del-metaverso\/#breadcrumb"},"inLanguage":"es-MX","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.capgemini.com\/ar-es\/news\/press-releases\/capgemini-y-unity-anuncian-una-alianza-global-para-ayudar-a-las-organizaciones-a-aprovechar-el-valor-empresarial-de-las-experiencias-inmersivas-y-del-metaverso\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.capgemini.com\/ar-es\/news\/press-releases\/capgemini-y-unity-anuncian-una-alianza-global-para-ayudar-a-las-organizaciones-a-aprovechar-el-valor-empresarial-de-las-experiencias-inmersivas-y-del-metaverso\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.capgemini.com\/ar-es\/"},{"@type":"ListItem","position":2,"name":"Capgemini y Unity anuncian una alianza global para ayudar a las organizaciones a aprovechar el valor empresarial de las experiencias inmersivas y del metaverso"}]},{"@type":"WebSite","@id":"https:\/\/www.capgemini.com\/ar-es\/#website","url":"https:\/\/www.capgemini.com\/ar-es\/","name":"Capgemini Argentina","description":"Capgemini","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.capgemini.com\/ar-es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es-MX"}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/capgemini.com\/ar-es\/news\/press-releases\/capgemini-y-unity-anuncian-una-alianza-global-para-ayudar-a-las-organizaciones-a-aprovechar-el-valor-empresarial-de-las-experiencias-inmersivas-y-del-metaverso\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Capgemini y Unity anuncian una alianza global para ayudar a las organizaciones a aprovechar el valor empresarial de las experiencias inmersivas y del metaverso","url":"https:\/\/www.capgemini.com\/ar-es\/news\/press-releases\/capgemini-y-unity-anuncian-una-alianza-global-para-ayudar-a-las-organizaciones-a-aprovechar-el-valor-empresarial-de-las-experiencias-inmersivas-y-del-metaverso\/","mainEntityOfPage":{"@type":"WebPage","@id":"https:\/\/www.capgemini.com\/ar-es\/news\/press-releases\/capgemini-y-unity-anuncian-una-alianza-global-para-ayudar-a-las-organizaciones-a-aprovechar-el-valor-empresarial-de-las-experiencias-inmersivas-y-del-metaverso\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Uncategorized","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Capgemini Argentina","logo":""},"keywords":[],"dateCreated":"2022-08-03T12:43:00Z","datePublished":"2022-08-03T12:43:00Z","dateModified":"2026-01-09T14:06:30Z"},"rendered":"<meta name=\"parsely-title\" content=\"Capgemini y Unity anuncian una alianza global para ayudar a las organizaciones a aprovechar el valor empresarial de las experiencias inmersivas y del metaverso\" \/>\n<meta name=\"parsely-link\" content=\"https:\/\/www.capgemini.com\/ar-es\/news\/press-releases\/capgemini-y-unity-anuncian-una-alianza-global-para-ayudar-a-las-organizaciones-a-aprovechar-el-valor-empresarial-de-las-experiencias-inmersivas-y-del-metaverso\/\" \/>\n<meta name=\"parsely-type\" content=\"post\" \/>\n<meta name=\"parsely-pub-date\" content=\"2022-08-03T12:43:00Z\" \/>\n<meta name=\"parsely-section\" content=\"Uncategorized\" \/>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/capgemini.com\/p.js"},"archive_status":false,"featured_image_src":"https:\/\/www.capgemini.com\/ar-es\/wp-content\/themes\/capgemini2025\/assets\/images\/mockup.png","featured_image_alt":false,"jetpack_sharing_enabled":true,"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"Capgemini Argentina","distributor_original_site_url":"https:\/\/www.capgemini.com\/ar-es","push-errors":false,"tag_names":[],"_links":{"self":[{"href":"https:\/\/www.capgemini.com\/ar-es\/wp-json\/wp\/v2\/press-release\/16828","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.capgemini.com\/ar-es\/wp-json\/wp\/v2\/press-release"}],"about":[{"href":"https:\/\/www.capgemini.com\/ar-es\/wp-json\/wp\/v2\/types\/press-release"}],"author":[{"embeddable":true,"href":"https:\/\/www.capgemini.com\/ar-es\/wp-json\/wp\/v2\/users\/336"}],"version-history":[{"count":6,"href":"https:\/\/www.capgemini.com\/ar-es\/wp-json\/wp\/v2\/press-release\/16828\/revisions"}],"predecessor-version":[{"id":520703,"href":"https:\/\/www.capgemini.com\/ar-es\/wp-json\/wp\/v2\/press-release\/16828\/revisions\/520703"}],"wp:attachment":[{"href":"https:\/\/www.capgemini.com\/ar-es\/wp-json\/wp\/v2\/media?parent=16828"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.capgemini.com\/ar-es\/wp-json\/wp\/v2\/tags?post=16828"},{"taxonomy":"press-release-type","embeddable":true,"href":"https:\/\/www.capgemini.com\/ar-es\/wp-json\/wp\/v2\/press-release-type?post=16828"},{"taxonomy":"brand","embeddable":true,"href":"https:\/\/www.capgemini.com\/ar-es\/wp-json\/wp\/v2\/brand?post=16828"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}